{"id":342630,"date":"2015-10-12T02:00:00","date_gmt":"2015-10-12T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-rinascita-del-peeling-chimico\/"},"modified":"2015-10-12T02:00:00","modified_gmt":"2015-10-12T00:00:00","slug":"la-rinascita-del-peeling-chimico","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/la-rinascita-del-peeling-chimico\/","title":{"rendered":"La rinascita del peeling chimico"},"content":{"rendered":"<p><strong>Il peeling chimico \u00e8 uno dei metodi estetici pi\u00f9 antichi e attualmente sta vivendo un revival. Nonostante le continue innovazioni sul mercato dei laser con dispositivi interessanti, i cui costi di acquisizione sono ovviamente considerevoli e per i quali si attende prima l&#8217;ammortamento dei costi di questi dispositivi, il peeling chimico rimane un metodo estremamente efficace con costi di consumo molto bassi per il medico. I risultati parlano da soli e i pazienti accompagnano fedelmente il loro medico curante per mesi o anni, a seconda dell&#8217;indicazione.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>\u00c8 importante fornire informazioni molto dettagliate e valide, in modo che i pazienti sappiano cosa si pu\u00f2 ottenere con quale peeling e che la loro collaborazione con i prodotti per la cura domiciliare \u00e8 fondamentale per il risultato del trattamento. \u00c8 obbligatorio l&#8217;uso di creme solari con un elevato fattore di protezione solare. Durante la consultazione, si deve spiegare chiaramente che il trattamento delle cicatrici non \u00e8 ottimale con un peeling superficiale, ma che il melasma e l&#8217;iperpigmentazione, cos\u00ec come l&#8217;acne e la rosacea, sono le indicazioni appropriate. Anche il miglioramento dell&#8217;aspetto della pelle \u00e8 un&#8217;indicazione adatta per un peeling superficiale. Il trattamento delle rughe parte dal peeling medio profondo ed \u00e8 estremamente efficace con un peeling profondo al fenolo.<\/p>\n<p>L&#8217;International Peeling Society (IPS), il cui consiglio direttivo comprende nomi illustri della scena del peeling e della dermatologia estetica internazionale come Harold Brody, Gary Monheit, Marina Landau e Luitgard Wiest, si impegna a educare i dermatologi al metodo del peeling chimico e a compilare e migliorare i dati sull&#8217;argomento.<\/p>\n<p>Una linea guida in lingua tedesca sul tema del &#8220;peeling chimico&#8221; \u00e8 stata da me registrata e sar\u00e0 redatta nei prossimi anni. Anche e soprattutto i metodi della dermatologia estetica devono essere basati sull&#8217;evidenza e le linee guida sono un buon inizio per presentare la situazione dei dati e definire il quadro entro il quale si pu\u00f2 trattare in modo sensato. L&#8217;IPS realizza anche sessioni in occasione di congressi internazionali, come l&#8217;IMCAS a Parigi (fine gennaio 2016), l&#8217;AAD a Washington DC (marzo 2016) e il Congresso 5CC di quest&#8217;anno a Cannes (settembre 2015). L&#8217;interesse per il metodo del &#8220;peeling chimico&#8221; \u00e8 molto alto a livello internazionale. Se ci fossero pi\u00f9 dermatologi in Svizzera, Germania e Austria che non lasciano il peeling come metodo alle loro estetiste e assistenti di studio, ma che vogliono accompagnare e trattare i pazienti stessi e formarsi ulteriormente in questo settore, ne sarei felice!<\/p>\n<p>Cordiali saluti<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il peeling chimico \u00e8 uno dei metodi estetici pi\u00f9 antichi e attualmente sta vivendo un revival. Nonostante le continue innovazioni sul mercato dei laser con dispositivi interessanti, i cui costi&hellip;<\/p>\n","protected":false},"author":7,"featured_media":52812,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Il metodo estetico pi\u00f9 antico porta ottimi risultati  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11351,11519,11550],"tags":[44804,44795],"powerkit_post_featured":[],"class_list":["post-342630","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dermatologia-e-venereologia","category-formazione-continua","category-rx-it","tag-ips-it","tag-peeling-chimico","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:59:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":342593,"slug":"renascimento-da-casca-quimica","post_title":"Renascimento da casca qu\u00edmica","href":"https:\/\/medizinonline.com\/pt-pt\/renascimento-da-casca-quimica\/"},"es_ES":{"locale":"es_ES","id":342600,"slug":"el-renacimiento-de-la-exfoliacion-quimica","post_title":"El renacimiento de la exfoliaci\u00f3n qu\u00edmica","href":"https:\/\/medizinonline.com\/es\/el-renacimiento-de-la-exfoliacion-quimica\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/342630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=342630"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/342630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/52812"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=342630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=342630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=342630"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=342630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}