{"id":343250,"date":"2015-06-26T02:00:00","date_gmt":"2015-06-26T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/antidoto-universale-del-futuro\/"},"modified":"2015-06-26T02:00:00","modified_gmt":"2015-06-26T00:00:00","slug":"antidoto-universale-del-futuro","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/antidoto-universale-del-futuro\/","title":{"rendered":"&#8220;Antidoto universale&#8221; del futuro?"},"content":{"rendered":"<p><strong>Un antidoto agli inibitori del Fattore Xa sta facendo grandi progressi negli studi clinici: Andexanet alfa. I nuovi risultati sono stati presentati al Congresso dell&#8217;American College of Cardiology a San Diego: Secondo questi, l&#8217;antidoto pu\u00f2 anche ottenere un&#8217;inversione rapida e quasi completa dell&#8217;anticoagulazione nei pazienti che assumono rivaroxaban.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Milioni di persone sono gi\u00e0 in trattamento con gli inibitori del Fattore Xa ed \u00e8 probabile che il mercato degli anticoagulanti continui a crescere. Questo aumenta anche l&#8217;interesse dei produttori di poter finalmente offrire antidoti specifici efficaci contro i nuovi anticoagulanti orali. Si stima che circa l&#8217;1-4% delle persone trattate con inibitori del Fattore Xa subisca un&#8217;emorragia grave ogni anno, e un altro 1% richiede un intervento chirurgico d&#8217;emergenza. Per entrambe le situazioni, \u00e8 urgente un antidoto specifico per invertire rapidamente l&#8217;anticoagulazione.<\/p>\n<p>Una soluzione di questo tipo \u00e8 promessa dal nuovo antidoto Andexanet alfa, che agisce come una sorta di &#8220;esca&#8221; per gli inibitori del Fattore Xa nel sangue. La molecola ricombinante assomiglia al fattore Xa umano (ma non ha la sua funzione di coagulazione). In questo modo, &#8220;attira&#8221; l&#8217;agente anticoagulante che circola nel sangue e si lega ad esso con elevata affinit\u00e0 e in modo competitivo. L&#8217;anticoagulazione si inverte rapidamente, poich\u00e9 gli inibitori non sono pi\u00f9 in grado di agganciarsi e bloccare il fattore Xa umano. In futuro, Andexanet alfa dovrebbe poter essere utilizzato sia a breve termine, attraverso la somministrazione di un bolo endovenoso, sia a lungo termine, aggiungendo un&#8217;infusione prolungata. Ci\u00f2 consente il suo utilizzo in diversi scenari clinici.<\/p>\n<h2 id=\"programma-annexa\">Programma ANNEXA\u2122<\/h2>\n<p>Il cosiddetto programma ANNEXA\u2122 consiste in vari studi randomizzati e controllati di fase III che utilizzano endpoint accettati dalla FDA.<\/p>\n<p>Per la prima parte dello studio ANNEXA-A, in cui l&#8217;antidoto \u00e8 stato testato contro apixaban in 33 volontari sani e dosato come singolo bolo endovenoso, \u00e8 stato possibile presentare un effetto significativo (inversione dell&#8217;effetto di apixaban da due a cinque minuti dopo il bolo di circa il 94%). La tollerabilit\u00e0 \u00e8 stata molto buona, con solo tre lievi reazioni all&#8217;infusione. All&#8217;inizio di aprile, il produttore ha annunciato che anche la seconda parte dello studio, in cui Andexanet \u00e8 stato somministrato in bolo e in infusione continua per mantenere l&#8217;inversione dell&#8217;anticoagulazione, ha raggiunto gli endpoint stabiliti. L&#8217;effetto \u00e8 quindi persistito durante l&#8217;infusione continua di due ore.<\/p>\n<p>Inoltre, esistono quattro studi separati di fase II su volontari sani, che hanno anche dimostrato che l&#8217;antidoto inverte immediatamente e in modo persistente l&#8217;effetto degli anticoagulanti (oltre ad apixaban e rivaroxaban, \u00e8 stato testato anche edoxaban). La tollerabilit\u00e0 \u00e8 stata buona, non si sono verificati eventi trombotici nel totale dei 140 partecipanti.<\/p>\n<h2 id=\"effetto-antidoto-contro-rivaroxaban\">Effetto antidoto contro rivaroxaban<\/h2>\n<p>I risultati presentati al Congresso ACC riguardano ANNEXA-R, uno studio di fase III che testa l&#8217;effetto dell&#8217;antidoto al rivaroxaban. Analogamente allo studio ANNEXA-A, il disegno \u00e8 in due parti, con una somministrazione a breve termine e una a lungo termine. Nella prima parte, sono stati inclusi 41 volontari sani di et\u00e0 compresa tra 50 e 75 anni. Hanno ricevuto rivaroxaban 20&nbsp;mg\/d per quattro giorni e poi &#8211; quattro ore dopo l&#8217;ultima dose di rivaroxaban, cio\u00e8 al momento della massima concentrazione plasmatica (Cmax) &#8211; o andexanet come bolo i.v. da 800&nbsp;mg o placebo in un rapporto 2:1.<\/p>\n<p>L&#8217;efficacia \u00e8 stata valutata utilizzando endpoint di biomarcatori. L&#8217;endpoint primario era il livello di anti-fattore Xa da due a cinque minuti dopo il bolo (rispetto al livello di picco prima della somministrazione del bolo). Gli endpoint secondari includevano le concentrazioni plasmatiche di rivaroxaban non legato e i livelli di generazione di trombina (determinati dal potenziale di trombina endogena [ETP]).<\/p>\n<h2 id=\"inversione-significativa-dellanticoagulazione\">Inversione significativa dell&#8217;anticoagulazione<\/h2>\n<p>In totale, 27 pazienti hanno ricevuto andexanet e 14 persone hanno ricevuto un placebo. L&#8217;endpoint primario \u00e8 stato raggiunto con un&#8217;elevata significativit\u00e0 statistica e in breve tempo &#8211; inoltre, il farmaco \u00e8 stato ben tollerato. In particolare, Andexanet ha ridotto l&#8217;attivit\u00e0 di rivaroxaban di oltre il 90% nel punto di misurazione pi\u00f9 basso. Un numero significativamente maggiore di persone ha raggiunto questo nadir con l&#8217;antidoto (n=26) rispetto al placebo (n=0), p&lt;0,0001. Anche il rivaroxaban non legato \u00e8 stato ridotto in modo altamente significativo nel sangue rispetto al placebo. L&#8217;ETP, a sua volta, \u00e8 aumentata significativamente con l&#8217;antidoto, raggiungendo livelli normali di generazione di trombina in 26 dei 27 soggetti entro 10 minuti dal bolo. Non si sono verificati effetti collaterali gravi o severi, n\u00e9 eventi trombotici.<\/p>\n<p>Nella seconda parte di ANNEXA-R, circa 40 soggetti sani riceveranno un bolo di 800 mg di andexanet seguito da un&#8217;infusione continua di 8&nbsp;mg\/min per 120 minuti oppure un placebo dopo la stessa fase iniziale con rivaroxaban. I risultati dovrebbero essere pubblicati quest&#8217;anno.<\/p>\n<h2 id=\"studio-di-conferma-in-corso\">Studio di conferma in corso<\/h2>\n<p>Nell&#8217;ambito del deposito accelerato previsto per la fine del 2015, \u00e8 in corso anche uno studio di fase IV per valutare i risultati clinici di andexanet nei pazienti con emorragie acute gravi. Sulla base dell&#8217;inversione immediata e quasi completa dell&#8217;anticoagulazione in ANNEXA-A e ANNEXA-R, si prevede fortemente che andexanet sar\u00e0 il primo antidoto universale specifico a ricevere l&#8217;approvazione contro gli inibitori del fattore Xa. Ha gi\u00e0 ottenuto lo status di farmaco orfano alla fine di febbraio 2015.<\/p>\n<p><em>Fonte: Collegio Americano di Cardiologia 14-16 marzo 2015, San Diego<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>CARDIOVASC 2015; 14(3): 34-35<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un antidoto agli inibitori del Fattore Xa sta facendo grandi progressi negli studi clinici: Andexanet alfa. I nuovi risultati sono stati presentati al Congresso dell&#8217;American College of Cardiology a San&hellip;<\/p>\n","protected":false},"author":7,"featured_media":51335,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Congresso ACC a San Diego","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11366,11522,11550,11515],"tags":[45157,46556,46548,46561,46554,15423],"powerkit_post_featured":[],"class_list":["post-343250","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia-it","category-rapporti-del-congresso","category-rx-it","category-studi","tag-allegato","tag-andexanet-alfa-it","tag-antidoto","tag-bolo","tag-inibitore-xa","tag-rivaroxaban-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:29:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":343256,"slug":"antidoto-universal-do-futuro","post_title":"\"Ant\u00eddoto universal\" do futuro?","href":"https:\/\/medizinonline.com\/pt-pt\/antidoto-universal-do-futuro\/"},"es_ES":{"locale":"es_ES","id":343258,"slug":"antidoto-universal-del-futuro","post_title":"\u00bf\"Ant\u00eddoto universal\" del futuro?","href":"https:\/\/medizinonline.com\/es\/antidoto-universal-del-futuro\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/343250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=343250"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/343250\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/51335"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=343250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=343250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=343250"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=343250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}