{"id":344431,"date":"2014-10-11T00:00:00","date_gmt":"2014-10-10T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/trattamento-curativo-del-carcinoma-prostatico-localizzato\/"},"modified":"2014-10-11T00:00:00","modified_gmt":"2014-10-10T22:00:00","slug":"trattamento-curativo-del-carcinoma-prostatico-localizzato","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/trattamento-curativo-del-carcinoma-prostatico-localizzato\/","title":{"rendered":"Trattamento curativo del carcinoma prostatico localizzato"},"content":{"rendered":"<p><strong>Oggi, il 90% dei carcinomi della prostata viene rilevato allo stadio localizzato e quindi potenzialmente curabile. Trovare la strategia di trattamento ottimale per il carcinoma localizzato \u00e8 una sfida per medici e pazienti. Sono disponibili la<em> sorveglianza attiva, la<\/em> vescicolectomia prostatica radicale, la radioterapia percutanea esterna e la brachiterapia della prostata. La decisione terapeutica deve sempre essere presa individualmente, tenendo conto delle caratteristiche del tumore (biologia o aggressivit\u00e0 del tumore) e delle caratteristiche del paziente (et\u00e0, comorbidit\u00e0, preferenze). Molti pazienti non richiedono un trattamento attivo immediato, ma per un numero non trascurabile di pazienti, un trattamento attivo tempestivo \u00e8 salvavita.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Con quasi un terzo di tutti i nuovi casi di cancro rilevati negli uomini, il carcinoma prostatico (PCa) \u00e8 il tumore pi\u00f9 comune negli uomini e la seconda causa di decessi correlati al cancro, dopo il cancro ai polmoni. A un uomo su sei verr\u00e0 diagnosticato il PCa nel corso della sua vita, e uno su sette di questi uomini morir\u00e0 a causa del PCa [1]. L&#8217;introduzione del test del PSA come test di screening ha, da un lato, aumentato in modo significativo l&#8217;incidenza del PCa negli ultimi decenni; dall&#8217;altro, il test del PSA porta anche al fatto che oggi pi\u00f9 del 90% dei casi di PCa vengono individuati nella fase localizzata e quindi potenzialmente curabile (&#8220;stage shift&#8221;) [2].<\/p>\n<h2 id=\"biologia-dei-tumori\">Biologia dei tumori<\/h2>\n<p>Il PCa ha una variabilit\u00e0 sorprendentemente ampia di aggressivit\u00e0 biologica. Per lo pi\u00f9 &#8211; rispetto ad altri tipi di cancro &#8211; si riscontra una crescita molto lenta nel corso di decenni. Gli uomini con una forma di PCa poco aggressiva spesso non sviluppano mai sintomi e muoiono con la PCa piuttosto che a causa della PCa. Uno studio osservazionale a lungo termine su pazienti non trattati con PCa poco aggressivo ha mostrato un tasso di mortalit\u00e0 cancro-specifica di solo il 17% in un periodo di 20 anni [3]. In generale, gli uomini con un&#8217;aspettativa di vita inferiore a 10-15 anni difficilmente beneficiano di un trattamento curativo.<\/p>\n<h2 id=\"morbosita-e-mortalita\">Morbosit\u00e0 e mortalit\u00e0<\/h2>\n<p>La letalit\u00e0 relativamente bassa del PCa rispetto ad altri tumori, che pu\u00f2 essere spiegata dalle numerose varianti poco aggressive, non dovrebbe oscurare il fatto che circa tre volte pi\u00f9 uomini soffrono di problemi legati al PCa che non ne muoiono [4]. La morbilit\u00e0 \u00e8 quindi notevole. I problemi pi\u00f9 comuni che possono influire pesantemente sulla qualit\u00e0 della vita sono la macroematuria, le disfunzioni del tratto urinario inferiore e superiore, le fratture ossee patologiche e gli effetti collaterali delle terapie sistemiche. Soprattutto sullo sfondo dello sviluppo demografico della popolazione, questo punto non deve essere dimenticato nella discussione sul PCa.<\/p>\n<h2 id=\"terapie-curative-e-palliative\">Terapie curative e palliative<\/h2>\n<p>Esistono terapie efficaci che possono prevenire o almeno ritardare notevolmente la mortalit\u00e0 e soprattutto la morbilit\u00e0 del PCa. In genere si fa una distinzione tra trattamenti curativi e palliativi, per cui ancora oggi solo le forme localizzate di PCa sono curabili.&nbsp;  Gli approcci terapeutici palliativi per la malattia metastatica comprendono trattamenti sistemici con ablazione ormonale, chemioterapia e talvolta radioterapia. La decisione terapeutica deve sempre essere presa individualmente, tenendo conto delle caratteristiche del tumore (biologia o aggressivit\u00e0 del tumore) e delle caratteristiche del paziente (et\u00e0, comorbidit\u00e0, preferenze). Le modalit\u00e0 di trattamento potenzialmente curative per il PCa localizzato sono presentate di seguito.<\/p>\n<h2 id=\"sorveglianza-attiva\"><em>Sorveglianza attiva<\/em><\/h2>\n<p>La <em>sorveglianza attiva (AS)<\/em> \u00e8 una strategia di osservazione con intento curativo nel PCa a bassa malignit\u00e0, con l&#8217;obiettivo di ridurre il sovratrattamento. I pazienti vengono monitorati da vicino attraverso la progressione del PSA e le biopsie prostatiche ripetute, al fine di rilevare la progressione del tumore o addirittura l&#8217;errata classificazione del tumore in una fase precoce e quindi avviare la terapia curativa. La corretta selezione dei pazienti \u00e8 particolarmente cruciale in questa strategia.<\/p>\n<p>I risultati finora sono promettenti: la sopravvivenza complessiva dei pazienti nel decorso a lungo termine \u00e8 la stessa dei pazienti che hanno ricevuto direttamente la terapia curativa. Circa il 25% dei pazienti con AS riceve una terapia curativa nel corso del trattamento [5]. L&#8217;AS non deve essere equiparato alla cosiddetta Attesa vigile. Quest&#8217;ultima \u00e8 una strategia di osservazione e trattamento palliativo per i pazienti che difficilmente trarrebbero beneficio da un approccio terapeutico.<\/p>\n<h2 id=\"vescicolectomia-prostatica-radicale\">Vescicolectomia prostatica radicale<\/h2>\n<p>Nella vescicolectomia prostatica radicale (rPVE), l&#8217;intera prostata, compresa la capsula e le vescicole seminali, viene rimossa chirurgicamente. Oltre alla tecnica aperta, la procedura viene ora sempre pi\u00f9 offerta in laparoscopia assistita da robot (tecnica DaVinci). Nei pazienti con PCa clinicamente localizzato, la rPVE \u00e8 associata a una migliore sopravvivenza cancro-specifica rispetto ai pazienti in vigile attesa (livello di evidenza 1) [6]. Nei tumori aggressivi, la rPVE \u00e8 anche superiore alle radiazioni, in particolare, con un profilo di effetti collaterali comparabile (incontinenza, impotenza) [7].<\/p>\n<p>Durante la rPVE, viene spesso eseguita una linfoadenectomia pelvica; se questa misura contribuisca a migliorare il controllo del tumore, oltre a una stadiazione pi\u00f9 precisa, non \u00e8 stato chiarito in modo definitivo.<\/p>\n<p>In caso di recidiva locale dopo la rPVE, l&#8217;irradiazione locale aggiuntiva \u00e8 una potente opzione post-trattamento con una morbilit\u00e0 relativamente bassa. In generale, pi\u00f9 giovane \u00e8 il paziente e pi\u00f9 aggressivo \u00e8 il tumore, pi\u00f9 \u00e8 probabile che la rPVE sia la modalit\u00e0 di trattamento di scelta.<\/p>\n<h2 id=\"radioterapia-percutanea-esterna-della-ghiandola-prostatica\">Radioterapia percutanea esterna della ghiandola prostatica<\/h2>\n<p>La radioterapia percutanea esterna della prostata (EPRP) \u00e8 una forma di terapia curativa non invasiva. Oltre alla rPVE, la EPRP \u00e8 la forma di trattamento meglio studiata, con un&#8217;efficacia comprovata negli studi a lungo termine. Non esistono studi randomizzati che confrontino direttamente la EPRP con la rPVE, tuttavia il controllo complessivo del tumore sembra essere leggermente peggiore con la EPRP rispetto alla rPVE, soprattutto nel PCa aggressivo&nbsp; [8,9]. Nel PCa localmente avanzato, la combinazione di EPRP e deprivazione androgenica aggiuntiva \u00e8 associata a un beneficio di sopravvivenza rispetto alla sola deprivazione androgenica (livello di evidenza 1) [10].<\/p>\n<p>Negli ultimi anni, sono stati compiuti importanti progressi tecnici nel campo dell&#8217;EPRP, con la minimizzazione degli effetti collaterali attraverso l&#8217;ottimizzazione dei campi di radiazione e un migliore controllo dell&#8217;applicazione della dose. Il trattamento della recidiva locale dopo l&#8217;EPRP \u00e8 impegnativo perch\u00e9 la RPVE di salvataggio, sebbene tecnicamente possibile, \u00e8 associata a risultati funzionali relativamente scarsi. Inoltre, non \u00e8 chiaro se e quanto spesso si verifichino secondi tumori radiogeni dopo l&#8217;EPRP.<\/p>\n<h2 id=\"brachiterapia-della-prostata\">Brachiterapia della prostata<\/h2>\n<p>La brachiterapia \u00e8 una forma di radioterapia curativa interna. Vengono inserite nella prostata delle sorgenti di radiazioni molto piccole (i cosiddetti semi), realizzate in titanio e iodio-125. I semi rimangono nella prostata per dispiegare il loro effetto radiante &#8211; altamente dosato e mirato &#8211; sul tessuto tumorale. Essendo una procedura piuttosto recente, la brachiterapia \u00e8 meno studiata scientificamente rispetto all&#8217;EPRP o alla rPVE, anche in questo caso mancano studi randomizzati con un confronto diretto con altre terapie curative. Negli studi di serie di casi, la brachiterapia mostra un buon controllo del tumore a lungo termine [11].<\/p>\n<p>Anche in questo caso, \u00e8 importante un&#8217;attenta selezione dei pazienti: I tumori devono essere di bassa o media aggressivit\u00e0, ma non aggressivi, il volume della prostata non deve superare i 50 ml, e la minzione deve essere possibile senza fastidio. Con le recidive locali esistono gli stessi problemi dell&#8217;EPRP.&nbsp;  Nel complesso, in pazienti ben selezionati, la brachiterapia \u00e8 una procedura concettualmente interessante, minimamente invasiva e con un profilo di effetti collaterali pi\u00f9 favorevole rispetto alla rPVE o alla EPRP.<\/p>\n<h2 id=\"cosa-ci-riserva-il-futuro\">Cosa ci riserva il futuro?<\/h2>\n<p>Una possibile rivoluzione nel trattamento del PCa \u00e8 potenzialmente all&#8217;orizzonte grazie ai miglioramenti tecnici delle tecniche di imaging con una visualizzazione ottimizzata della prostata. Se in futuro sar\u00e0 possibile visualizzare con precisione i focolai di carcinoma all&#8217;interno della prostata (cosa che oggi \u00e8 generalmente ancora troppo inaffidabile), si potr\u00e0 effettuare un trattamento locale mirato con la conservazione di altri organi. Tali terapie sono gi\u00e0 in parte utilizzate oggi (ad esempio, prostatectomia parziale o ablazione con radiofrequenza della prostata [HIFU]), ma i risultati oncologici a lungo termine sono ancora del tutto assenti.<br \/>\nSi sta conducendo un&#8217;intensa ricerca anche nel campo dei biomarcatori prognostici per distinguere il PCa significativo da quello insignificante. Tali marcatori sarebbero di enorme valore per la selezione della modalit\u00e0 di trattamento.<\/p>\n<p>Nel complesso, tutti gli sforzi sono volti a ridurre il sovratrattamento nel PCa poco aggressivo e quindi a ridurre anche la morbilit\u00e0 e i costi associati al trattamento. D&#8217;altra parte, i pazienti con forme pi\u00f9 aggressive di PCa dovrebbero essere identificati in tempo e trattati in modo efficace per ridurre la mortalit\u00e0 e la morbilit\u00e0 ancora significative del PCa.<\/p>\n<h2 id=\"conclusione\">Conclusione<\/h2>\n<p>Trovare la strategia di trattamento ottimale per il PCa localizzato \u00e8 una sfida per tutti i medici coinvolti e anche per i pazienti. La biologia tumorale del PCa e i vantaggi e gli svantaggi delle varie forme di terapia devono essere discussi criticamente con il paziente. La decisione sul trattamento deve essere individualizzata, tenendo conto delle caratteristiche del tumore e del paziente. Molti pazienti affetti da PCa non necessitano di un trattamento attivo immediato, ma per un numero non trascurabile di pazienti, un trattamento attivo tempestivo \u00e8 salvavita.<\/p>\n<h2 id=\"messaggi-da-portare-a-casa\">Messaggi da portare a casa<\/h2>\n<ul>\n<li>Il PCa \u00e8 un carcinoma molto comune con un&#8217;aggressivit\u00e0 biologica molto variabile.<\/li>\n<li>La prevalenza e l&#8217;incidenza gi\u00e0 elevate del PCa aumenteranno in modo significativo a causa degli sviluppi demografici.<\/li>\n<li>Non tutti gli uomini a cui viene diagnosticato il PCa ne moriranno; pertanto, non tutti gli uomini con PCa localizzato necessitano di un trattamento immediato.<\/li>\n<li>Il processo decisionale individualizzato \u00e8 la grande sfida clinica di oggi.  &nbsp;<\/li>\n<li>Esistono diverse opzioni di terapia curativa per il PCa localizzato, che raggiungono tutte un livello relativamente alto di controllo del tumore, se indicate correttamente.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Letteratura:<\/p>\n<ol>\n<li>Jemal A, et al: Statistiche sul cancro, 2010. CA Cancer J Clin 2010; 60: 277-300.<\/li>\n<li>Schroder FH, et al: Screening e mortalit\u00e0 per cancro alla prostata in uno studio europeo randomizzato. N Engl J Med 2009; 360: 1320-1328.<\/li>\n<li>Lu-Yao GL, et al: Esiti del cancro alla prostata localizzato dopo la gestione conservativa. JAMA 2009; 302: 1202-1209.<\/li>\n<li>Popiolek M, et al: Storia naturale del cancro alla prostata precoce e localizzato: una relazione finale di tre decenni di follow-up. Eur Urol 2013; 63: 428-435.<\/li>\n<li>Klotz L: Sorveglianza attiva per il cancro alla prostata: per chi? J Clin Oncol 2005; 23: 8165-8169.<\/li>\n<li>Bill-Axelson A, et al: Prostatectomia radicale rispetto alla vigile attesa nel cancro alla prostata in fase iniziale. N Engl J Med 2011; 364: 1708-1717.<\/li>\n<li>Resnick MJ, et al: Esiti funzionali a lungo termine dopo il trattamento del cancro alla prostata localizzato. N Engl J Med 2013; 368: 436-445.<\/li>\n<li>Merglen A, et al: Mortalit\u00e0 a breve e a lungo termine con il cancro alla prostata localizzato. Arch Intern Med 2007; 167: 1944-1950.<\/li>\n<li>Hoffman RM, et al: Mortalit\u00e0 dopo prostatectomia radicale o radioterapia a fasci esterni per il cancro alla prostata localizzato. J Natl Cancer Inst 2013; 105: 711-718.<\/li>\n<li>Warde P, et al: Terapia combinata di deprivazione di androgeni e radioterapia per il tumore alla prostata localmente avanzato: uno studio randomizzato di fase 3. Lancet 2011; 378: 2104-2111.<\/li>\n<li>Potters L, et al: Esiti a 12 anni dopo la brachiterapia prostatica permanente nei pazienti con cancro alla prostata clinicamente localizzato. J Urol 2008; 179(5 Suppl): S20-24.<\/li>\n<\/ol>\n<p>\n<em>InFo ONCOLOGIA &amp; EMATOLOGIA 2014; 2(8): 15-17<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi, il 90% dei carcinomi della prostata viene rilevato allo stadio localizzato e quindi potenzialmente curabile. Trovare la strategia di trattamento ottimale per il carcinoma localizzato \u00e8 una sfida per&hellip;<\/p>\n","protected":false},"author":7,"featured_media":47166,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Terapia del cancro alla prostata","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11376,11550,11502],"tags":[48875,50389,50425,50406,50400,50396,33163,37697,50383,50419,38874,50414],"powerkit_post_featured":[],"class_list":["post-344431","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-oncologia-it","category-rx-it","category-urologia-it","tag-as-it","tag-brachiterapia","tag-conservazione-degli-organi","tag-eprp-it","tag-macroematuria","tag-ostruzione-del-deflusso-dellurina","tag-pca-it","tag-prostata-it","tag-recidiva-locale","tag-rpve-it","tag-sorveglianza-attiva","tag-storia-del-psa","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:01:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":344441,"slug":"tratamento-curativo-do-carcinoma-da-prostata-localizado","post_title":"Tratamento curativo do carcinoma da pr\u00f3stata localizado","href":"https:\/\/medizinonline.com\/pt-pt\/tratamento-curativo-do-carcinoma-da-prostata-localizado\/"},"es_ES":{"locale":"es_ES","id":344448,"slug":"tratamiento-curativo-del-carcinoma-de-prostata-localizado","post_title":"Tratamiento curativo del carcinoma de pr\u00f3stata localizado","href":"https:\/\/medizinonline.com\/es\/tratamiento-curativo-del-carcinoma-de-prostata-localizado\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/344431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=344431"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/344431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/47166"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=344431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=344431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=344431"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=344431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}