{"id":345601,"date":"2014-04-16T00:00:00","date_gmt":"2014-04-15T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/concentrarsi-sullarticolazione\/"},"modified":"2014-04-16T00:00:00","modified_gmt":"2014-04-15T22:00:00","slug":"concentrarsi-sullarticolazione","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/concentrarsi-sullarticolazione\/","title":{"rendered":"Concentrarsi sull&#8217;articolazione"},"content":{"rendered":"<p><strong>Il focus del numero attuale \u00e8 su tre diverse questioni diagnostiche e terapeutiche relative alle articolazioni.  <\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La diagnosi di gonfiore al ginocchio \u00e8 sempre una sfida diagnostica interessante nella pratica. Soprattutto in reumatologia, l&#8217;anamnesi accurata e l&#8217;esame clinico rimangono centrali anche nella medicina di oggi, che \u00e8 caratterizzata da molti esami aggiuntivi. Permettono una prima delimitazione diagnostica differenziale e dovrebbero essere la base per una ragionevole chiarificazione. Insieme a un semplice esame aggiuntivo, l&#8217;analisi del puntato articolare, spesso si pu\u00f2 gi\u00e0 fare una diagnosi provvisoria, che permette di arrivare rapidamente a una diagnosi con pochi e mirati ulteriori chiarimenti.<\/p>\n<p>Adrian Forster, MD, riassume l&#8217;attuale strategia terapeutica per l&#8217;artrite reumatoide. L&#8217;obiettivo realistico del trattamento \u00e8 la remissione dell&#8217;infiammazione. Il prerequisito per questo \u00e8 la diagnosi pi\u00f9 precoce possibile e il successivo inizio di una terapia di base efficace senza ritardi. Il metotrexato rimane il farmaco di prima scelta; sono disponibili alternative in caso di controindicazioni o intolleranze. Oggi le terapie combinate vengono utilizzate sempre pi\u00f9 spesso. Gli steroidi servono solo a colmare il divario fino all&#8217;effetto della terapia di base. Se non si ottiene un controllo sufficiente dell&#8217;attivit\u00e0 infiammatoria dopo tre-sei mesi, la terapia deve essere prolungata o cambiata, e di solito si ricorre ai cosiddetti biologici, che intervengono in modo molto specifico nel processo infiammatorio, ma che a causa dei loro costi e dell&#8217;aumento del rischio di infezione richiedono un&#8217;indicazione e un monitoraggio della terapia altrettanto attenti.<\/p>\n<p>L&#8217;articolo di Luzi Dubs, MD, esamina un argomento controverso dal punto di vista ortopedico: il senso o il non senso dell&#8217;artroscopia del ginocchio per la gonartrosi (o lesioni degenerative del menisco). Da una prospettiva biomeccanica, \u00e8 importante ricordare che i menischi sono parte integrante dell&#8217;articolazione del ginocchio. Questo spiega perch\u00e9 \u00e8 noto che ogni resezione (parziale) del menisco favorisce o accelera lo sviluppo di una successiva gonartrosi, e anche che il cambiamento degenerativo dell&#8217;articolazione del ginocchio coinvolge sempre contemporaneamente sia la cartilagine che i menischi. Pertanto, l&#8217;osteoartrite e la lesione meniscale degenerativa (ed eventualmente anche l&#8217;osso subcondrale) spesso costituiscono insieme la fonte del dolore. Inoltre, l&#8217;esperienza ha dimostrato che con un po&#8217; di pazienza (e un trattamento conservativo), questi episodi di dolore o irritazione spesso migliorano spontaneamente dopo alcune settimane o mesi. \u00c8 quindi molto gradito che il chirurgo ortopedico o il chirurgo del ginocchio sia molto cauto nell&#8217;indicare l&#8217;artroscopia in un ginocchio osteoartritico. L&#8217;articolo evidenzia le carenze metodologiche degli studi citati &#8211; ma pu\u00f2 anche sorgere la domanda se non esistano studi che dimostrino chiaramente un beneficio dell&#8217;artroscopia (l&#8217;autore argomenta qui soprattutto con la sua esperienza personale nel senso di &#8220;medicina basata sull&#8217;eminenza&#8221;).&nbsp;<\/p>\n<p>Le auguriamo una lettura stimolante e arricchente per la sua pratica quotidiana!<\/p>\n<p><em><strong>Andreas Krebs, MD<br \/>\nAndrea St\u00e4rkle-B\u00e4r, MD<\/strong><\/em><\/p>\n<p><em>PRATICA GP 2014; 9(4): 11<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il focus del numero attuale \u00e8 su tre diverse questioni diagnostiche e terapeutiche relative alle articolazioni.<\/p>\n","protected":false},"author":4,"featured_media":42841,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Reumatologia","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11494,11550],"tags":[42029,13795],"powerkit_post_featured":[],"class_list":["post-345601","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-reumatologia-it","category-rx-it","tag-giunto","tag-reumatismo","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 16:07:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":345605,"slug":"foco-na-articulacao","post_title":"Foco na articula\u00e7\u00e3o","href":"https:\/\/medizinonline.com\/pt-pt\/foco-na-articulacao\/"},"es_ES":{"locale":"es_ES","id":345612,"slug":"centrarse-en-la-articulacion","post_title":"Centrarse en la articulaci\u00f3n","href":"https:\/\/medizinonline.com\/es\/centrarse-en-la-articulacion\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/345601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=345601"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/345601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/42841"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=345601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=345601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=345601"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=345601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}