{"id":345762,"date":"2014-03-20T00:00:00","date_gmt":"2014-03-19T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/nel-posto-giusto-al-momento-giusto-quanto-e-importante-il-concetto-di-il-tempo-e-cervello\/"},"modified":"2014-03-20T00:00:00","modified_gmt":"2014-03-19T23:00:00","slug":"nel-posto-giusto-al-momento-giusto-quanto-e-importante-il-concetto-di-il-tempo-e-cervello","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/nel-posto-giusto-al-momento-giusto-quanto-e-importante-il-concetto-di-il-tempo-e-cervello\/","title":{"rendered":"Nel posto giusto al momento giusto: Quanto \u00e8 importante il concetto di &#8220;il tempo \u00e8 cervello&#8221;?"},"content":{"rendered":"<p><strong>L&#8217;ictus \u00e8 l&#8217;emergenza neurologica pi\u00f9 comune e una delle principali cause di mortalit\u00e0 e morbilit\u00e0 a livello mondiale. In questo contesto, l&#8217;85% di tutti gli ictus sono ischemici e l&#8217;entit\u00e0 del danno tissutale e l&#8217;esito funzionale, che \u00e8 decisivo per il paziente, dipendono in modo significativo dal tempo di ischemia e dalla collateralizzazione disponibile. L&#8217;espressione &#8220;il tempo \u00e8 cervello&#8221; si basa sul concetto di penombra ischemica, che \u00e8 definita come un&#8217;area cerebrale funzionalmente invecchiata ma strutturalmente (ancora) intatta che di solito circonda il nucleo dell&#8217;infarto.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Oltre alla terapia trombolitica endovenosa basata sull&#8217;evidenza in una finestra temporale di 4,5 ore, esistono anche approcci di terapia endovascolare interventistica per le occlusioni dei vasi prossimali, ad esempio. Allo stesso tempo, la qualit\u00e0 degli esami e le decisioni terapeutiche che ne derivano non devono soffrire in nessun caso a causa della pressione temporale. In particolare, l&#8217;eccesso di zelo non deve portare a trattamenti di lisi indifferenziata dei cosiddetti mimici dell&#8217;ictus, come le crisi epilettiche focali. Inoltre, con il miglioramento delle capacit\u00e0 di imaging cerebrale, di recente sono aumentate le prove che la localizzazione del tessuto della penombra \u00e8 critica per l&#8217;esito funzionale dopo l&#8217;ictus almeno quanto il fattore tempo.<\/p>\n<p>Ci\u00f2 rende ancora pi\u00f9 importante la valutazione e il trattamento acuto da parte di esperti dei pazienti colpiti da ictus. In modo ottimale, ci\u00f2 dovrebbe avvenire nell&#8217;ambito di centri ictus e stroke unit certificate e gestite da neurologi o, negli ospedali periferici pi\u00f9 piccoli, nell&#8217;ambito di una cooperazione telematica con i centri ictus, al fine di fornire a tutti i cittadini l&#8217;accesso a una medicina interdisciplinare di alta qualit\u00e0 sull&#8217;ictus nel modo pi\u00f9 completo possibile.<\/p>\n<p>Il fattore tempo \u00e8 molto importante nel trattamento dei pazienti con ictus acuto; il concetto &#8220;il tempo \u00e8 cervello&#8221; \u00e8 valido. Ma il tempo non \u00e8 tutto; il paziente deve anche arrivare nel posto giusto il pi\u00f9 rapidamente possibile!<\/p>\n<p>Le auguriamo una buona lettura di questo numero di InFo NEUROLOGIE &amp; PSYCHIATRIE!<\/p>\n<p><strong>Prof. Dr. med. Erich Seifritz<br \/>\nProf. Dr. med. Barbara Tettenborn<\/strong><\/p>\n<p><em>InFo Neurologia e Psichiatria 2014; 12(2): 1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ictus \u00e8 l&#8217;emergenza neurologica pi\u00f9 comune e una delle principali cause di mortalit\u00e0 e morbilit\u00e0 a livello mondiale. In questo contesto, l&#8217;85% di tutti gli ictus sono ischemici e l&#8217;entit\u00e0&hellip;<\/p>\n","protected":false},"author":4,"featured_media":41943,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Trattamento dell'ictus","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11519,11371,11479,11550],"tags":[54280,12711,12725,38882,29156,23880,18184,11800,54274],"powerkit_post_featured":[],"class_list":["post-345762","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formazione-continua","category-neurologia-it","category-psichiatria-e-psicoterapia","category-rx-it","tag-fattore-tempo","tag-ictus","tag-ictus-it","tag-il-tempo-e-cervello","tag-morbosita","tag-mortalita","tag-neurologia","tag-terapia","tag-terapia-trombolitica-it-2","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:55:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":345768,"slug":"no-lugar-certo-na-altura-certa-quao-importante-e-o-conceito-tempo-e-cerebro","post_title":"No lugar certo, na altura certa: Qu\u00e3o importante \u00e9 o conceito \"tempo \u00e9 c\u00e9rebro\"?","href":"https:\/\/medizinonline.com\/pt-pt\/no-lugar-certo-na-altura-certa-quao-importante-e-o-conceito-tempo-e-cerebro\/"},"es_ES":{"locale":"es_ES","id":345774,"slug":"en-el-lugar-adecuado-en-el-momento-adecuado-que-importancia-tiene-el-concepto-el-tiempo-es-cerebro","post_title":"En el lugar adecuado en el momento adecuado: \u00bfQu\u00e9 importancia tiene el concepto \"el tiempo es cerebro\"?","href":"https:\/\/medizinonline.com\/es\/en-el-lugar-adecuado-en-el-momento-adecuado-que-importancia-tiene-el-concepto-el-tiempo-es-cerebro\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/345762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=345762"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/345762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/41943"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=345762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=345762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=345762"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=345762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}