{"id":347445,"date":"2013-09-17T00:00:00","date_gmt":"2013-09-16T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/perche-non-siamo-schiavi-dei-nostri-geni\/"},"modified":"2013-09-17T00:00:00","modified_gmt":"2013-09-16T22:00:00","slug":"perche-non-siamo-schiavi-dei-nostri-geni","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/perche-non-siamo-schiavi-dei-nostri-geni\/","title":{"rendered":"Perch\u00e9 non siamo schiavi dei nostri geni"},"content":{"rendered":"<p><strong>n biochimico che riesce a spiegare in modo generalmente comprensibile, senza un manoscritto o una presentazione in PowerPoint, come ogni essere umano sia unico, pu\u00f2 essere definito particolarmente dotato. Al congresso SGIM di Basilea, il Prof. em. Gottfried Schatz, MD, non solo affascina il pubblico, ma gli trasmette anche un senso di unicit\u00e0.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Gli esseri umani non sono solo macchine biochimiche pre-programmate, soggette solo ai dettami del patrimonio genetico, ma hanno la possibilit\u00e0 di apportare cambiamenti per la loro vita e per i loro discendenti, secondo il messaggio centrale dell&#8217;ex direttore del Biozentrum di Basilea. &#8220;Ogni essere umano \u00e8 un individuo molecolare distintivo&#8221;, perch\u00e9 il principio pi\u00f9 alto della natura \u00e8 quello di produrre il maggior numero possibile di fenotipi.<\/p>\n<p>Come spiegato dal Prof. em. Gottfried Schatz, MD, questa visione ottimistica? Nella ricchezza di informazioni del nostro genoma, non solo un&#8217;espressione \u00e8 fissa in ogni caso, ma \u00e8 possibile una moltitudine di processi complessi: se il genoma viene letto, con quale frequenza e in quale momento &#8211; solo queste varianti sono un&#8217;espressione di questa diversit\u00e0. Il nostro genoma \u00e8 conservato nel nucleo di ogni cellula e conta 3,2&nbsp;miliardi di lettere, oltre il 95% delle quali sono geni che non sono ancora riconoscibili per noi. Grazie alle varianti materne e paterne, potremmo teoricamente formare oltre 50.000 proteine diverse. In realt\u00e0, la diversit\u00e0 \u00e8 molto maggiore attraverso i processi successivi alla lettura, per cui si possono creare fino a 70.000 proteine da un solo gene attraverso la diversit\u00e0, come letto e ulteriormente modificato chimicamente.<\/p>\n<p>Inoltre, l&#8217;ambiente pu\u00f2 modificare i geni: Le mutazioni sono riarrangiamenti della sequenza di lettere, come la perdita o la duplicazione. I cambiamenti epigenetici sono modifiche alle lettere stesse, la pi\u00f9 comune delle quali \u00e8 la metilazione. Il nostro stile di vita, la dieta, le malattie, i farmaci e persino le interazioni sociali lasciano tracce di metilazione.<\/p>\n<p>&#8220;La ricchezza del nostro patrimonio genetico non risiede solo nelle sue dimensioni, ma anche nella virtuosit\u00e0 con cui lo utilizziamo&#8221;, ha detto il Prof. Schatz. Le nostre cellule cerebrali, ad esempio, sono in grado di modificare chimicamente le proteine in risposta agli stimoli ambientali. \u00c8 anche interessante notare il fenomeno per cui i gemelli identici sviluppano sempre pi\u00f9 &#8220;peculiarit\u00e0&#8221; individuali nel corso della loro vita. Questa \u00e8 una chiara indicazione che l&#8217;ambiente pu\u00f2 effettivamente influenzare la &#8220;macchina biochimica&#8221;. Utilizzando altri esempi tratti dalla ricerca genetica, il Prof. Schatz ha mostrato quanto siano flessibili l&#8217;impronta e il contenuto informativo del genoma delle singole specie. L&#8217;Homo sapiens \u00e8 in cima alla gerarchia. &#8220;Gli esseri umani, in quanto materia altamente complessa, sono un miracolo in un universo chimicamente primordiale. Noi interpretiamo i geni, ognuno di noi \u00e8 un sogno dei propri geni&#8221;.<\/p>\n<p><em>Fonte: 81esima Riunione annuale del SGIM, 29-31 maggio 2013, Basilea.<\/em><\/p>\n<p><strong>Letteratura:<\/strong><\/p>\n<ol>\n<li><em>Schatz, G: Oltre i geni. Saggi sul nostro essere, sul nostro mondo e sui nostri sogni. 2012; Verlag Neue Z\u00fcrcher Zeitung, Zurigo.<\/em><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>n biochimico che riesce a spiegare in modo generalmente comprensibile, senza un manoscritto o una presentazione in PowerPoint, come ogni essere umano sia unico, pu\u00f2 essere definito particolarmente dotato. Al&hellip;<\/p>\n","protected":false},"author":4,"featured_media":33649,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Tendenza Lezione Novartis","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11405,11522,11550],"tags":[58615,62443,45903],"powerkit_post_featured":[],"class_list":["post-347445","post","type-post","status-publish","format-standard","has-post-thumbnail","category-genetica-it","category-rapporti-del-congresso","category-rx-it","tag-gene-it","tag-genoma","tag-sgim-it","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:16:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":347689,"slug":"porque-nao-somos-escravos-dos-nossos-genes","post_title":"Porque n\u00e3o somos escravos dos nossos genes","href":"https:\/\/medizinonline.com\/pt-pt\/porque-nao-somos-escravos-dos-nossos-genes\/"},"es_ES":{"locale":"es_ES","id":347703,"slug":"por-que-no-somos-esclavos-de-nuestros-genes","post_title":"Por qu\u00e9 no somos esclavos de nuestros genes","href":"https:\/\/medizinonline.com\/es\/por-que-no-somos-esclavos-de-nuestros-genes\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/347445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=347445"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/347445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/33649"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=347445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=347445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=347445"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=347445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}