{"id":352310,"date":"2023-03-18T01:00:00","date_gmt":"2023-03-18T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/quale-metodo-raggiunge-i-migliori-tassi-di-crescita-dei-capelli\/"},"modified":"2023-04-03T16:47:02","modified_gmt":"2023-04-03T14:47:02","slug":"quale-metodo-raggiunge-i-migliori-tassi-di-crescita-dei-capelli","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/quale-metodo-raggiunge-i-migliori-tassi-di-crescita-dei-capelli\/","title":{"rendered":"Quale metodo raggiunge i migliori tassi di crescita dei capelli?"},"content":{"rendered":"\n<p><strong>L&#8217;alopecia areata (AA) si manifesta con una perdita di capelli acuta o cronica non cicatriziale. Il difenilciclopropenone e gli inibitori della Janus chinasi hanno un tasso di remissione significativamente pi\u00f9 alto rispetto al decorso spontaneo, soprattutto nell&#8217;AA grave. Per le infestazioni meno gravi, gli steroidi in varie forme di applicazione sono considerati il trattamento di prima linea; occasionalmente viene utilizzata anche la soluzione di minoxidil. Inoltre, ci sono molte altre opzioni terapeutiche nell&#8217;area off-label.<\/strong><\/p>\n\n<!--more-->\n\n<p>Secondo le conoscenze attuali, l&#8217;alopecia areata (AA) \u00e8 una malattia autoimmune cronica che porta alla perdita di capelli circoscritta o disseminata, rompendo il privilegio immunitario del follicolo pilifero [1]. La riacutizzazione dell&#8217;AA \u00e8 associata a una fase anagen significativamente ridotta del ciclo di crescita dei capelli<strong> (Fig. 1)<\/strong> [3,11]. L&#8217;infiltrato infiammatorio e l&#8217;interruzione dell&#8217;attivit\u00e0 del follicolo pilifero (HF) nell&#8217;AA si verifica principalmente intorno e nell&#8217;area del bulbo, mentre la nicchia delle cellule staminali HF nell&#8217;area del rigonfiamento della parte permanente del follicolo pilifero viene risparmiata [2,3]. Spesso, in caso di remissione spontanea o indotta da farmaci, i capelli ricrescono non pigmentati [4]. In occasione dello Swiss Derma Day di quest&#8217;anno, Stephanie Marie Huber, MD, Dermatologia, Ospedale Universitario di Basilea, ha fornito una panoramica aggiornata sulle opzioni di trattamento dell&#8217;AA [5].<\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30.png\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-1160x1006.png\" alt=\"\" class=\"wp-image-351374\" width=\"580\" height=\"503\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-1160x1006.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-800x694.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-120x104.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-90x78.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-320x277.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-560x486.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-240x208.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-180x156.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-640x555.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30-1120x971.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/abb1_DP1_s30.png 1474w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/a><\/figure>\n\n<h3 id=\"gravita-ed-eta-come-importanti-criteri-di-selezione-per-la-terapia\" class=\"wp-block-heading\">Gravit\u00e0 ed et\u00e0 come importanti criteri di selezione per la terapia  <\/h3>\n\n<p>Il <em>Severity of Alopecia Tool <\/em>(punteggio SALT) \u00e8 stato sviluppato per valutare l&#8217;estensione e la progressione dell&#8217;AA [6]. Il punteggio SALT pu\u00f2 essere utilizzato non solo a scopo di ricerca, ma anche nella pratica clinica, come buona misura per valutare l&#8217;estensione dell&#8217;AA nell&#8217;area del cuoio capelluto [7]. Il punteggio SALT stimato pu\u00f2 essere utilizzato per distinguere tra diversi gradi di gravit\u00e0 della perdita di capelli, che vanno da 0 (nessuna perdita di capelli) a 100 (perdita di capelli del 100%) [3].  <\/p>\n\n<p>Gli attuali trattamenti per l&#8217;AA dipendono dall&#8217;et\u00e0 e dalla gravit\u00e0 iniziale dell&#8217;alopecia<strong> (Tabella 1)<\/strong> [3,5]. I corticosteroidi topici sono una terapia di prima linea per i bambini &lt;10 anni (indipendentemente dalla gravit\u00e0). L&#8217;iniezione intralesionale di corticosteroidi \u00e8 una raccomandazione di prima linea in &gt;bambini di 10 anni con SALT&lt;30, in monoterapia o in combinazione con corticosteroidi topici. L&#8217;uso a lungo termine di corticosteroidi sistemici non \u00e8 raccomandato a causa del rischio di effetti collaterali. In &gt;soggetti di 10 anni con AA estesa (SALT&gt;30), oltre alla soluzione di minoxidil e ai corticosteroidi sistemici, si raccomanda anche la sensibilizzazione topica con DPCP o l&#8217;uso di inibitori della Janus chinasi (JAK-i). I corticosteroidi topici possono essere utilizzati come terapia aggiuntiva nell&#8217;AA grave. Il trattamento con le opzioni terapeutiche sopra citate deve essere effettuato in modo costante per almeno 12 settimane, per poter valutare la risposta [5]. Negli studi clinici, i JAK-i hanno dimostrato di essere un&#8217;opzione terapeutica efficace per le forme gravi di AA, con un rapido inizio d&#8217;azione. L&#8217;AA promuove la produzione di IFN-\u03b3 e IL-15 mediata da JAK e un ciclo di feedback infiammatorio che mantiene la risposta infiammatoria locale. Le JAK-i interferiscono con la via di segnalazione JAK-STAT e bloccano la segnalazione a valle di varie citochine pro-infiammatorie.<\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31.png\"><img decoding=\"async\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-1160x728.png\" alt=\"\" class=\"wp-image-351375 lazyload\" width=\"580\" height=\"364\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-1160x728.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-800x502.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-120x75.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-90x56.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-320x201.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-560x352.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-240x151.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-180x113.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-640x402.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31-1120x703.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/02\/tab1_DP1_s31.png 1464w\" data-sizes=\"(max-width: 580px) 100vw, 580px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 580px; --smush-placeholder-aspect-ratio: 580\/364;\" \/><\/a><\/figure>\n\n<h3 id=\"dpcp-per-gli-ultradecennali-con-grave-infestazione\" class=\"wp-block-heading\">DPCP &#8211; per gli ultradecennali con grave infestazione  <\/h3>\n\n<p>Nei pazienti di et\u00e0 superiore ai 10 anni con perdita di capelli superiore al 30%, l&#8217;immunoterapia topica con difenilciclopropenone (DPCP) \u00e8 stata considerata finora il gold standard. &#8220;La DPCP rappresenta l&#8217;unica opzione di trattamento, oltre alla JAK-i, che ha un tasso di remissione pi\u00f9 elevato rispetto al decorso spontaneo&#8221;, afferma il dottor Huber [5]. Il tasso di remissione dipende dall&#8217;estensione iniziale dell&#8217;alopecia. Il DPCP \u00e8 controindicato nelle donne in gravidanza e in fase di allattamento e occorre prestare particolare cautela nei pazienti con carnagione scura, in quanto esiste il rischio di depigmentazione. La sensibilizzazione iniziale con il 2% \u00e8 seguita da un aumento settimanale della dose fino al raggiungimento dell&#8217;eczema da contatto terapeutico desiderato. &#8220;Se non c&#8217;\u00e8 crescita dei capelli dopo circa 6-12 mesi di terapia, si dovrebbe interrompere la terapia&#8221;, ha detto il relatore [5]. Le reazioni avverse includono cambiamenti pigmentari, diffusione dell&#8217;eczema, linfoadenopatia nucale reattiva e reazioni vescicolose locali.<\/p>\n\n<h3 id=\"baricitinib-gli-adulti-con-punteggio-salt-%e2%89%a550-possono-trarne-beneficio\" class=\"wp-block-heading\">Baricitinib &#8211; gli adulti con punteggio SALT \u226550 possono trarne beneficio<\/h3>\n\n<p>Soprattutto nell&#8217;alopecia areata grave, gli inibitori della JAK rappresentano una nuova interessante opzione terapeutica, ha riferito il Dr. Huber [5]. I JAK-i sono stati utilizzati con successo per molto tempo nelle malattie infiammatorie croniche. Baricitinib \u00e8 il primo inibitore JAK approvato nell&#8217;UE per il trattamento dell&#8217;AA grave (punteggio SALT \u226550) dal 06\/2022.  <\/p>\n\n<p>Nei due studi di fase III BRAVE-AA1 e BRAVE-AA2, progettati in modo identico, 654 e 546 pazienti con perdita di capelli \u226550% (punteggio SALT \u226550), rispettivamente, sono stati randomizzati in un rapporto 3:2:2 ai bracci di studio baricitinib 4 mg\/d vs. barictinib 2 mg\/d vs. placebo [8]. L&#8217;endpoint primario era la perdita di capelli \u226420% (punteggio SALT \u226420). I risultati sono stati pubblicati sul <em>New England Journal of Medicine <\/em>. In BRAVE-AA1, dopo 36 settimane, circa il 39% dei pazienti che assumevano baricitinib 4 mg, circa il 23% dei pazienti che assumevano baricitinib 2 mg e circa il 6% dei pazienti che assumevano placebo mostravano un punteggio SALT pari a 20.  <\/p>\n\n<p>In BRAVE-AA2, le cifre corrispondenti erano rispettivamente del 36% e del 19% nei due bracci di trattamento, e del 3% nel placebo. Quindi, il baricitinib somministrato per via orale era chiaramente superiore al placebo in termini di ricrescita dei capelli dopo 36 settimane. Gli effetti collaterali pi\u00f9 comuni sono stati acne, aumento della creatinina chinasi e aumento dei livelli di colesterolo HDL\/LDL. Per poter valutare l&#8217;efficacia e la sicurezza a lungo termine di baricitinib nell&#8217;alopecia areata, sarebbero auspicabili studi pi\u00f9 lunghi, poich\u00e9 l&#8217;alopecia di per s\u00e9 ha un decorso molto variabile tra ricrescita e caduta dei capelli, ha spiegato il relatore.  <\/p>\n\n<h3 id=\"ritlecitinib-e-brepocitinib-dati-informativi-della-sperimentazione\" class=\"wp-block-heading\">Ritlecitinib e brepocitinib &#8211; dati informativi della sperimentazione  <\/h3>\n\n<p>Uno studio di estensione di fase II pubblicato nel 2022 ha analizzato gli effetti a lungo termine di altri due JAK-i per il trattamento dell&#8217;AA [9]: Ritlecitinib (inibitore JAK3\/TEC) e Brepocitinib (inibitore Tyk2\/JAK1). Lo studio era in doppio cieco nella prima fase (24 settimane), dopodich\u00e9 i soggetti sono stati assegnati ai bracci di studio successivi in modo singolo, a seconda della risposta alla terapia:  <\/p>\n\n<ul class=\"wp-block-list\">\n<li><em>Non risposta al placebo: <\/em>Passare al trattamento attivo con ritlecitinib\/brepocitinib<\/li>\n\n\n\n<li><em>Non rispondenti attivi (nessun miglioramento \u226530% alla settimana 24 nonostante il trattamento attivo): <\/em>Continuazione del trattamento attivo con ritlecitinib\/brepocitinib<\/li>\n\n\n\n<li><em>Rispondenti attivi (in trattamento attivo un miglioramento di \u226530% dopo 24 settimane):<\/em> Passare al placebo fino al raggiungimento del criterio di ritiro (perdita di \u226530% dei capelli ricresciuti nella fase in doppio cieco).  <\/li>\n<\/ul>\n\n<p>\u00c8 stato riscontrato che circa il 64% dei responder attivi con ritlecinib e circa il 61% con brepocitinib ha richiesto un ritrattamento con JAK-i dopo una media di 16,1 settimane (n=22) e 24,1 settimane (n=24), rispettivamente. Pertanto, i dati suggeriscono che \u00e8 necessario un trattamento a lungo termine con la JAK-i, ha spiegato il dottor Huber.  <\/p>\n\n<h3 id=\"terapia-con-inibitore-della-jak-si-raccomanda-la-vaccinazione-contro-la-varicella-zoster\" class=\"wp-block-heading\">Terapia con inibitore della JAK: si raccomanda la vaccinazione contro la varicella zoster.  <\/h3>\n\n<p>I possibili effetti collaterali di JAK-i sono molto noti in reumatologia e si possono trovare nelle informazioni sul farmaco del rispettivo preparato. Nelle infezioni acute, la JAK-i deve essere messa in pausa, cosa che pu\u00f2 essere facilmente ottenuta grazie alla somministrazione orale e alla breve emivita dei farmaci [12]. Oltre a escludere le malattie infettive croniche prima di iniziare la terapia (ad esempio, epatite, tubercolosi), occorre prestare particolare attenzione alle infezioni associate all&#8217;herpes virus. L&#8217;uso di vaccini vivi immediatamente prima o durante il trattamento con JAK-i non \u00e8 raccomandato. Le vaccinazioni con vaccini inattivati sono possibili durante il trattamento con JAK-i. Per prevenire la riattivazione della varicella-zoster, si raccomanda la vaccinazione con il vaccino varicella-tot <sup>Shingrix\u00ae <\/sup>.<\/p>\n\n<p><em>Congresso: Swiss Derma Day<\/em><\/p>\n\n<p><\/p>\n\n<p>Letteratura: <\/p>\n\n<ol class=\"wp-block-list\">\n<li>Busch D, Sticherling M: Die Alopecia areata \u2013 klinisches Bild und Therapieansprechen einer heterogenen Erkrankung. P091, <a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/full\/10.1111\/ddg.13796\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/onlinelibrary.wiley.com\/doi\/full\/10.1111\/ddg.13796<\/a>, (letzter Abruf 13.01.2023)<\/li>\n\n\n\n<li>Lee YB, Jun M, Lee WS: Alopecia areata and poliosis: A retrospective analysis of 258 cases. JAAD 2019; 80: 1776\u20131778.<\/li>\n\n\n\n<li>Lintzeri DA, et al.: Alopecia areata \u2013 Aktuelles Verst\u00e4ndnis und Management. JDDG 2022; 20(1): 59\u201393.<\/li>\n\n\n\n<li>Bruhn I, Frenzel U-R, Landeck L: Pigmentierter Haarwuchs nach kombinierter systemischer Kortikosteroidtherapie mit intral\u00e4sionaler Triamcinoloninjektion bei Alopecia areata. P090, <a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/full\/10.1111\/ddg.13796\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/onlinelibrary.wiley.com\/doi\/full\/10.1111\/ddg.13796<\/a>, (letzter Abruf 13.01.2023) <\/li>\n\n\n\n<li>\u00abAlopecia areata \u2013 neue Evidenz\u00bb, Dr. med. Stephanie Marie Huber, Swiss Derma Day and STI reviews and updates, 12.01.2023<\/li>\n\n\n\n<li>Olsen EA, et al.: Alopecia areata investigational assessment guidelines \u2013 Part II. National Alopecia Areata Foundation. JAAD 2004; 51: 440\u2013447.<\/li>\n\n\n\n<li>Meah N, et al.: The Alopecia Areata Consensus of Experts (ACE) study part II: Results of an international expert opinion on diagnosis and laboratory evaluation for alopecia areata. JAAD 2021; 84: 1594\u20131601.<\/li>\n\n\n\n<li>King B, et al.: BRAVE-AA Investigators. Two Phase 3 Trials of Baricitinib for Alopecia Areata. N Engl J Med 2022; 386(18): 1687\u20131699. <\/li>\n\n\n\n<li>Peeva E, et al.: Maintenance, withdrawal, and re-treatment with ritlecitinib and brepocitinib in patients with alopecia areata in a single-blind extension of a phase 2a randomized clinical trial. JAAD 2022; 87(2): 390\u2013393.<\/li>\n\n\n\n<li>Messenger AG, et al.: British Association of Dermatologists\u2019 guidelines for the management of alopecia areata 2012. Br J Dermatol 2012; 166(5): 916\u2013926.<\/li>\n\n\n\n<li>Carrasco E, Soto-Heredero G, Mittelbrunn M: The Role of Extracellular Vesicles in Cutaneous Remodeling and Hair Follicle Dynamics. Int J Mol Sci 2019; 20(11): 2758.<\/li>\n\n\n\n<li>Klein B, Treudler R, Simon JC: JAK-Inhibitoren in der Dermatologie &#8211; kleine Molek\u00fcle, grosse Wirkung? \u00dcbersicht \u00fcber Wirkmechanismus, Studienergebnisse und m\u00f6gliche unerw\u00fcnschte Wirkungen. JDDG 2022; 20(1): 19\u201325.<\/li>\n\n\n\n<li>Swissmedic: Arzneimittelinformation, <a href=\"http:\/\/www.swissmedicinfo.ch\" target=\"_blank\" rel=\"noreferrer noopener\">www.swissmedicinfo.ch<\/a>, (letzter Abruf 16.01.2023) <\/li>\n<\/ol>\n\n<p><\/p>\n\n<p><em>DERMATOLOGIE PRAXIS 2023; 33(1): 30\u201331<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;alopecia areata (AA) si manifesta con una perdita di capelli acuta o cronica non cicatriziale. Il difenilciclopropenone e gli inibitori della Janus chinasi hanno un tasso di remissione significativamente pi\u00f9&hellip;<\/p>\n","protected":false},"author":7,"featured_media":351382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Alopecia areata: terapia farmacologica  ","footnotes":""},"category":[11343,11351,11415,11522,11550,11515],"tags":[19932,51419,17514,65828,65829,26826,65833,65835,65841,65827,65832,13475,28764,31137,20383,14042,12254,65838,12003,46160,11800,12000,65830],"powerkit_post_featured":[],"class_list":["post-352310","post","type-post","status-publish","format-standard","has-post-thumbnail","category-allergologia-e-immunologia-clinica","category-dermatologia-e-venereologia","category-infettivologia","category-rapporti-del-congresso","category-rx-it","category-studi","tag-alopecia-it-2","tag-alopecia-areata-it","tag-baricitinib-it","tag-brave-aa2-it","tag-brepocitinib-it","tag-corticosteroidi-topici","tag-difenilciclopropenone","tag-dpcp-it","tag-immunoterapia-topica","tag-inibitori-della-janus-chinasi","tag-jak-i-it","tag-malattia-autoimmune","tag-medicinale","tag-minoxidil-it","tag-off-label-it","tag-opzioni-di-trattamento","tag-perdita-di-capelli","tag-ritlecitinib-it","tag-shingrix-it","tag-swiss-derma-day-it","tag-terapia","tag-vaccinazione","tag-via-di-segnalazione-jak-stat","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:59:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":352305,"slug":"qual-o-metodo-que-atinge-as-melhores-taxas-de-crescimento-de-cabelo","post_title":"Qual o m\u00e9todo que atinge as melhores taxas de crescimento de cabelo?","href":"https:\/\/medizinonline.com\/pt-pt\/qual-o-metodo-que-atinge-as-melhores-taxas-de-crescimento-de-cabelo\/"},"es_ES":{"locale":"es_ES","id":352332,"slug":"que-metodo-consigue-las-mejores-tasas-de-crecimiento-del-cabello","post_title":"\u00bfQu\u00e9 m\u00e9todo consigue las mejores tasas de crecimiento del cabello?","href":"https:\/\/medizinonline.com\/es\/que-metodo-consigue-las-mejores-tasas-de-crecimiento-del-cabello\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/352310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=352310"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/352310\/revisions"}],"predecessor-version":[{"id":355198,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/352310\/revisions\/355198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/351382"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=352310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=352310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=352310"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=352310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}