{"id":352645,"date":"2023-02-04T01:00:00","date_gmt":"2023-02-04T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/trattare-con-gli-oppioidi-nuovi-dati-dallanalisi-dei-metodi-misti\/"},"modified":"2023-02-23T15:09:19","modified_gmt":"2023-02-23T14:09:19","slug":"trattare-con-gli-oppioidi-nuovi-dati-dallanalisi-dei-metodi-misti","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/trattare-con-gli-oppioidi-nuovi-dati-dallanalisi-dei-metodi-misti\/","title":{"rendered":"Trattare con gli oppioidi: nuovi dati dall&#8217;analisi dei &#8220;metodi misti"},"content":{"rendered":"\n<p><strong>Gli analgesici oppioidi sono un&#8217;opzione terapeutica importante per il dolore cronico, anche se occorre prestare attenzione per assicurarsi che vengano utilizzati come previsto. Al fine di comprendere la pratica assistenziale del &#8220;mondo reale&#8221; dell&#8217;uso a lungo termine di analgesici oppioidi, \u00e8 stato lanciato lo studio tedesco su larga scala &#8220;Op-US&#8221;. I dati del sondaggio e quelli di routine sono stati combinati per fare luce sulla situazione attuale dell&#8217;assistenza da diverse prospettive.<\/strong><\/p>\n\n<!--more-->\n\n<p>Questo studio mira a colmare una lacuna nella ricerca sull&#8217;uso a lungo termine di analgesici oppioidi per il dolore cronico non correlato al tumore, analizzando i fattori di rischio per l&#8217;uso dannoso di oppioidi e gli ostacoli all&#8217;assistenza basata sulle linee guida dal punto di vista dei pazienti e dei medici [1]. Il fatto che l&#8217;uso di analgesici oppioidi possa portare alla dipendenza fisica e il modo in cui questa pu\u00f2 essere contrastata \u00e8 affrontato, tra l&#8217;altro, nell&#8217;attuale linea guida S3 sull&#8217;uso a lungo termine degli oppioidi per il dolore cronico non tumorale (LONTS) [2]. Questo \u00e8 stato anche uno dei punti focali dello studio &#8220;Op-US&#8221;. I tre sottoprogetti riassunti di seguito sono stati presentati al Congresso tedesco sul dolore [1].  <\/p>\n\n<h3 id=\"interviste-ad-esperti-sui-fattori-di-rischio-per-il-consumo-dannoso-di-oppioidi\" class=\"wp-block-heading\">Interviste ad esperti sui fattori di rischio per il consumo dannoso di oppioidi  <\/h3>\n\n<p>La dottoressa Carina Abels, assistente di ricerca presso l&#8217;Universit\u00e0 di Duisburg-Essen, ha presentato i risultati di un sottoprogetto in cui sono state condotte otto interviste con medici di base, chirurghi ortopedici, neurologi e medici del dolore nel periodo compreso tra dicembre 2020 e gennaio 2021 e sono state valutate in base all&#8217;analisi qualitativa del contenuto di Mayring e Kuchartz. &#8220;Abbiamo esaminato quali sono gli aspetti che aumentano il rischio di abuso, uso improprio o dipendenza&#8221;, ha detto [1].  <\/p>\n\n<p>Una panoramica dei <strong>fattori di rischio generali per l&#8217;uso improprio <\/strong>rilevati nel processo:  <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Malattie mentali sottostanti<\/li>\n\n\n\n<li>Disturbi da dipendenza preesistenti  <\/li>\n\n\n\n<li>Aumenti rapidi della dose, farmaci non ritardanti (on-demand)  <\/li>\n\n\n\n<li>Contatti irregolari con i pazienti (reazione alla mancanza di risposta alla terapia)  <\/li>\n\n\n\n<li>Nessun rapporto di fiducia tra medico e paziente  <\/li>\n\n\n\n<li>Diversi medici (&#8220;doctor hopping&#8221;)  <\/li>\n\n\n\n<li>Mancanza di un&#8217;anamnesi e di informazioni adeguate all&#8217;inizio della terapia.  <\/li>\n\n\n\n<li>Mancanza di capacit\u00e0\/conoscenza da parte del paziente di assumere correttamente il farmaco  <\/li>\n\n\n\n<li>Il trattamento non viene fornito da operatori formati nella gestione del dolore o la linea guida non viene applicata.  <\/li>\n<\/ul>\n\n<p>\u00c8 emerso che, oltre ai pazienti con dosi elevate di oppioidi, i sottogruppi con comorbidit\u00e0 psicologiche o disturbi da dipendenza esistenti, nonch\u00e9 quelli con comorbidit\u00e0 che non consentirebbero la prescrizione di altri farmaci, come gli antinfiammatori non steroidei (FANS), sono particolarmente a rischio di uso improprio, abuso e dipendenza.<\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"1001\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26.jpg\" alt=\"\" class=\"wp-image-349392\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26.jpg 750w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26-120x160.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26-90x120.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26-320x427.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26-560x747.jpg 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26-240x320.jpg 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26-180x240.jpg 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/kasten_HP1_s26-640x854.jpg 640w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n<p><strong>Quali sono i fattori che facilitano l&#8217;identificazione dei pazienti a rischio?  <\/strong>Secondo le analisi dei ricercatori, questi includono contatti regolari con i pazienti, pianificati con una tempistica adeguata e l&#8217;uso di questionari sul dolore. Inoltre, \u00e8 necessario verificare la frequenza di prescrizione per ogni ricetta. Occorre prestare particolare attenzione ai pazienti che sono stati rilevati da un altro medico, poich\u00e9 potrebbero mancare importanti informazioni preliminari. Sebbene questi aspetti sembrino ovvi a prima vista, uno sguardo alla realt\u00e0 della pratica quotidiana mostra che ci sono alcuni ostacoli. Uno dei fornitori di servizi intervistati ha fatto la seguente dichiarazione [1]: &#8220;Quindi, quando ci si avvicina a qualcuno e si dice &#8216;Allora, senta, dobbiamo parlare della dose di oppioidi&#8217;. Poi si sa che questo pu\u00f2 durare mezz&#8217;ora e lasciare un paziente arrabbiato e dieci assistenti innervositi perch\u00e9 la cosa si \u00e8 protratta troppo a lungo&#8221;. Sebbene i medici di base abbiano riferito di indirizzare i pazienti con condizioni di dolore difficili da trattare ai medici del dolore, hanno riferito che spesso vengono coinvolti nel processo di trattamento solo quando molte opzioni terapeutiche sono gi\u00e0 state esaurite e la terapia con oppioidi \u00e8 l&#8217;unica opzione rimasta [1],  <\/p>\n\n<h3 id=\"barriere-allassistenza-basata-sulle-linee-guida-dal-punto-di-vista-della-professione-medica\" class=\"wp-block-heading\">Barriere all&#8217;assistenza basata sulle linee guida dal punto di vista della professione medica  <\/h3>\n\n<p>Il sottoprogetto presentato da Nils Frederik Schrader, M.Sc., Universit\u00e0 di Duisburg-Essen, riguarda la quantificazione della prospettiva dei medici [1]. A questo scopo, \u00e8 stata condotta un&#8217;indagine medica come prospettiva complementare sulla terapia a lungo termine con analgesici oppioidi per il dolore cronico non correlato al tumore in Germania. Si \u00e8 trattato di un sondaggio trasversale anonimo condotto nel settembre 2021. Sono stati intervistati 1300 medici accreditati SHI che lavorano in regime ambulatoriale e 554 membri dell&#8217;Associazione Professionale dei Medici e Psicoterapeuti Psicologi in Medicina del Dolore e Palliativa in Germania.  <\/p>\n\n<p><strong>Come fattori di rischio legati al paziente per l&#8217;uso dannoso di oppioidi<\/strong>, i medici hanno menzionato soprattutto le comorbidit\u00e0 psicologiche e le malattie da dipendenza esistenti. I fattori e i gruppi di rischio sono in gran parte in linea con la linea guida S3 per i disturbi correlati ai farmaci, ha spiegato il relatore, con questi aspetti che spiccano nel sondaggio <strong>(Tab. 1): <\/strong>farmaci non ritardanti, et\u00e0 pi\u00f9 giovane, comorbidit\u00e0 mentali e dipendenze esistenti, salto dal medico [1,3]. La maggioranza degli operatori sanitari intervistati era favorevole alla terapia multimodale [1]. Quindi, oltre il 90% dei partecipanti al sondaggio \u00e8 dell&#8217;opinione che le misure fisioterapiche siano utili. Una conclusione di questo sottostudio \u00e8 che esiste una discrepanza tra la valutazione della necessit\u00e0 e della fattibilit\u00e0 di ulteriori misure terapeutiche. Per quanto riguarda la prescrizione della fisioterapia, questa \u00e8 prevalentemente giustificata da restrizioni normative e da una carenza di operatori qualificati.  <\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26.png\"><img decoding=\"async\" width=\"2212\" height=\"769\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26.png\" alt=\"\" class=\"wp-image-349391 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26.png 2212w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-800x278.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-1160x403.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-2048x712.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-120x42.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-90x31.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-320x111.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-560x195.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-1920x667.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-240x83.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-180x63.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-640x222.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-1120x389.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s26-1600x556.png 1600w\" data-sizes=\"(max-width: 2212px) 100vw, 2212px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2212px; --smush-placeholder-aspect-ratio: 2212\/769;\" \/><\/a><\/figure>\n\n<h3 id=\"analisi-dei-dati-del-paziente-provenienti-dallassistenza-di-routine\" class=\"wp-block-heading\">Analisi dei dati del paziente provenienti dall&#8217;assistenza di routine  <\/h3>\n\n<p>Anja Niemann, anch&#8217;essa della Cattedra di Management Medico dell&#8217;Universit\u00e0 di Duisburg-Essen, ha presentato un sottoprogetto in cui sono stati analizzati i dati dei pazienti di un&#8217;ampia coorte di pazienti con assicurazione sanitaria in Germania [1]. Sono stati inclusi i pazienti di et\u00e0 superiore ai 17 anni con prescrizioni di oppioidi in almeno due trimestri (2018-2019). I criteri di esclusione includevano diagnosi di cancro e cure palliative. I 113.476 partecipanti allo studio selezionati (et\u00e0 media 71,8 anni) sono stati osservati per un periodo di due anni; circa tre quarti del campione totale erano donne.  <\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27.png\"><img decoding=\"async\" width=\"1479\" height=\"697\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27.png\" alt=\"\" class=\"wp-image-349393 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27.png 1479w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-800x377.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-1160x547.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-120x57.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-90x42.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-320x151.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-560x264.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-240x113.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-180x85.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-640x302.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s27-1120x528.png 1120w\" data-sizes=\"(max-width: 1479px) 100vw, 1479px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1479px; --smush-placeholder-aspect-ratio: 1479\/697;\" \/><\/a><\/figure>\n\n<p>Con il 44%, c&#8217;\u00e8 una percentuale sorprendentemente alta di assicurati con una diagnosi di disturbo affettivo in connessione temporale con la prescrizione di analgesici oppioidi. Mentre nella letteratura specializzata ci sono risultati comparabili. Per esempio, H\u00e4user et al. una correlazione con un disturbo affettivo nel 39% delle persone con &gt;120 mg di morfina equivalente\/giorno e nel 49% con dosi pi\u00f9 elevate [4]. Per quanto riguarda le controindicazioni formulate nella linea guida, la pratica prescrittiva analizzata in questo sottostudio mostra una certa contraddizione. Da un lato, si discute se questa discrepanza possa essere spiegata dalla realt\u00e0 dell&#8217;assistenza ai pazienti per i quali sono state esaurite tutte le altre opzioni terapeutiche; dall&#8217;altro, si chiede se la linea guida si rivolga davvero a tutti i codici ICD10 da F32 a F34 o solo alle manifestazioni gravi dei disturbi affettivi [1,2]. Esistono diverse spiegazioni per il collegamento tra dolore cronico e depressione [1,5,6]. Da un lato, il dolore cronico pu\u00f2 scatenare la depressione e, dall&#8217;altro, un disturbo depressivo \u00e8 spesso accompagnato da un&#8217;alterata percezione del dolore. Il dolore e la depressione si rafforzano a vicenda. Quindi, la soglia del dolore e la tolleranza al dolore diminuiscono quando la psiche viene colpita.<\/p>\n\n<p><em>Congresso: Congresso tedesco sul dolore<\/em><br\/><\/p>\n\n<p>Letteratura: <\/p>\n\n<ol class=\"wp-block-list\">\n<li>Analgesici oppioidi &#8211; Indagine sulle tendenze di sviluppo nella cura del dolore non tumorale (Op-US), SY01, Deutscher Schmerzkongress, 20.10.2022.  <\/li>\n\n\n\n<li>Linea guida S3 Uso a lungo termine degli oppioidi per il dolore cronico non tumorale (LONTS), numero di registro 145-003, 2020, <a href=\"https:\/\/register.awmf.org\/de\/leitlinien\/detail\/145-003\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/register.awmf.org\/de\/leitlinien\/detail\/145-003,<\/a>(ultimo accesso 03.01.2023).<\/li>\n\n\n\n<li>Linea guida S3 Disturbi correlati ai farmaci, numero di registro 038 &#8211; 025 <a href=\"https:\/\/register.awmf.org\/de\/leitlinien\/detail\/038-025\" target=\"_blank\" rel=\"noreferrer noopener\">, https:\/\/register.awmf.org\/de\/leitlinien\/detail\/038-025,<\/a>(ultimo accesso 03.01.2023).<\/li>\n\n\n\n<li>H\u00e4user W, et al.: La terapia con oppioidi a lungo termine raccomandata dalle linee guida rispetto a quella ad alto dosaggio per il dolore cronico non tumorale \u00e8 associata a migliori risultati di salute: dati di un campione rappresentativo della popolazione tedesca. PAIN 2018; 159(1): 85-91.  <\/li>\n\n\n\n<li>American Psychological Association: Linea guida di pratica clinica per il trattamento della depressione in tre coorti di et\u00e0. <a href=\"http:\/\/www.apa.org\/depression-guideline\" target=\"_blank\" rel=\"noreferrer noopener\">www.apa.org\/depression-guideline,<\/a>(ultimo accesso 03.01.2023)  <\/li>\n\n\n\n<li>S3-Leitlinie\/Nationale Versorgungsleitlinie Unipolare Depression, 2015, 2a edizione, versione lunga. DOI 10.6101\/AZQ\/000364.  <\/li>\n\n\n\n<li>Pharmawiki, <a href=\"http:\/\/www.pharmawiki.ch\/wiki\/index.php?wiki=opioide\" target=\"_blank\" rel=\"noreferrer noopener\">www.pharmawiki.ch\/wiki\/index.php?wiki=opioide,<\/a>(ultimo accesso 03.01.2023)  <\/li>\n<\/ol>\n\n<p><em>PRATICA GP 2023; 18(1): 26<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli analgesici oppioidi sono un&#8217;opzione terapeutica importante per il dolore cronico, anche se occorre prestare attenzione per assicurarsi che vengano utilizzati come previsto. Al fine di comprendere la pratica assistenziale&hellip;<\/p>\n","protected":false},"author":7,"featured_media":349407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Dolore cronico non correlato al tumore","footnotes":""},"category":[11452,11519,11306,11376,11522,11550,11515],"tags":[66305,66302,14941,19905,66299,66308,11593],"powerkit_post_featured":[],"class_list":["post-352645","post","type-post","status-publish","format-standard","has-post-thumbnail","category-farmacologia-e-tossicologia","category-formazione-continua","category-medicina-interna-generale","category-oncologia-it","category-rapporti-del-congresso","category-rx-it","category-studi","tag-analisi-con-metodi-misti","tag-analgesici-oppioidi","tag-dolori-cronici","tag-gli-oppioidi","tag-non-legato-al-tumore","tag-op-us-it","tag-terapia-del-dolore","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:00:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":352659,"slug":"utilizacao-de-opioides-novos-dados-de-analise-de-metodos-mistos","post_title":"Utiliza\u00e7\u00e3o de opioides: novos dados de an\u00e1lise de m\u00e9todos mistos","href":"https:\/\/medizinonline.com\/pt-pt\/utilizacao-de-opioides-novos-dados-de-analise-de-metodos-mistos\/"},"es_ES":{"locale":"es_ES","id":352662,"slug":"consumo-de-opiaceos-nuevos-datos-del-analisis-de-metodos-mixtos","post_title":"Consumo de opi\u00e1ceos: nuevos datos del an\u00e1lisis de m\u00e9todos mixtos","href":"https:\/\/medizinonline.com\/es\/consumo-de-opiaceos-nuevos-datos-del-analisis-de-metodos-mixtos\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/352645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=352645"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/352645\/revisions"}],"predecessor-version":[{"id":352656,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/352645\/revisions\/352656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/349407"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=352645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=352645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=352645"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=352645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}