{"id":368038,"date":"2023-11-30T00:01:00","date_gmt":"2023-11-29T23:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=368038"},"modified":"2023-12-20T13:16:30","modified_gmt":"2023-12-20T12:16:30","slug":"disturbi-del-cervello-del-midollo-spinale-e-della-funzione-nervosa","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/disturbi-del-cervello-del-midollo-spinale-e-della-funzione-nervosa\/","title":{"rendered":"Disturbi del cervello, del midollo spinale e della funzione nervosa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Le polineuropatie sono malattie generalizzate del sistema nervoso periferico. Con una prevalenza del 5-8%, i pazienti con abuso cronico di alcol, diabete o malattie maligne sono particolarmente colpiti. Oltre al trattamento della malattia causale, per alleviare i sintomi si utilizzano principalmente analgesici, antidepressivi o anticonvulsivanti.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">Nelle polineuropatie (PNP), sono colpite tutte le parti del sistema nervoso che si trovano al di fuori del sistema nervoso centrale, con i nervi motori, sensoriali e autonomici. La PNP a simmetria distale \u00e8 pi\u00f9 comune, inizia nelle gambe ed \u00e8 causata da un processo patologico dipendente dalla lunghezza degli assoni neuronali. Inoltre, possono verificarsi anche poliradiculoneuropatie con coinvolgimento prossimale e distale o mononeuropatie multiple con un quadro clinico asimmetrico. Il dolore che si verifica nella PNP \u00e8 causato dal danno o dalla distruzione delle fibre nervose, non da stimoli esterni come infiammazioni o lesioni. Gli stimoli sensoriali non vengono segnalati affatto, vengono ridotti o aumentati al cervello. I primi sintomi sono spesso percepiti come un disagio, come formicolio e bruciore. Nel decorso successivo, si verifica una riduzione della percezione del tatto e del dolore. Queste false sensazioni possono manifestarsi come false sensazioni di freddo o di calore o come sensazioni di dolore in risposta a stimoli non dolorosi.<\/p>\n\n<h3 id=\"risultato-di-altre-malattie\" class=\"wp-block-heading\">Risultato di altre malattie<\/h3>\n\n<p class=\"wp-block-paragraph\">La PNP \u00e8 di solito una conseguenza di altre malattie, come il diabete avanzato. La neuropatia diabetica pu\u00f2 essere rilevata in quasi la met\u00e0 di tutti i diabetici di tipo 2. L&#8217;aumento degli zuccheri nel sangue \u00e8 ritenuto responsabile e danneggia i nervi corrispondenti. Ma ci sono altri fattori di rischio. Nella PNP innescata dall&#8217;abuso cronico di alcol, i nervi sono tossicamente danneggiati. La durata dell&#8217;abuso e la quantit\u00e0 di alcol consumata nel corso della vita giocano un ruolo nello sviluppo della malattia. Le neuropatie indotte dalla chemioterapia sono l&#8217;effetto collaterale neurologico pi\u00f9 comune della terapia tumorale. Con l&#8217;aumento delle malattie maligne, l&#8217;incidenza sta aumentando anche qui. La neurotossicit\u00e0 dipende dalla quantit\u00e0 della dose singola, dalla dose totale cumulativa e dalla durata della chemioterapia. Ma anche altri farmaci e tossine ambientali possono scatenare la PNP.  <\/p>\n\n<h3 id=\"diagnosi-basate-su-linee-guida-e-possibili-fattori-scatenanti\" class=\"wp-block-heading\">Diagnosi basate su linee guida e possibili fattori scatenanti<\/h3>\n\n<p class=\"wp-block-paragraph\">La linea guida S1 &#8220;Diagnostica nelle polineuropatie&#8221; ha affrontato anche altri possibili fattori scatenanti e la loro gestione. Questi includono, ad esempio, i farmaci in oncologia, il virus Zika e le mutazioni genetiche. Gli inibitori del checkpoint immunitario, in particolare, possono causare effetti collaterali neurologici, come la polineuropatia demielinizzante o assonale infiammatoria acuta (AIDP\/ASMAN\/AMAN) e la polineuropatia demielinizzante infiammatoria cronica (CIDP). Tuttavia, anche i trapianti di organi, i virus dell&#8217;epatite E e Zika, l&#8217;anticorpo anti-FGF3 e le mutazioni dei geni SCN9A, SCN10A, SCN11A (neuropatie delle piccole fibre) e del gene GLA possono causare diversi tipi di PNP.  <\/p>\n\n<h3 id=\"rilevare-le-emergenze\" class=\"wp-block-heading\">Rilevare le emergenze<\/h3>\n\n<p class=\"wp-block-paragraph\">La PNP cronica di solito si riconosce dai sintomi. Un esame fisico, l&#8217;elettromiografia e la misurazione della conduttivit\u00e0 nervosa, oltre agli esami del sangue e delle urine, forniranno poi di solito informazioni sulla causa sottostante della PNP. Inoltre, si raccomanda un laboratorio esteso, la diagnostica del liquor, la biopsia muscolare\/nerva\/pelle, la genetica e la diagnostica per immagini. Soprattutto, devono essere riconosciute le emergenze neurologiche come la sindrome di Guillain-Barr\u00e9 o la vasculite.  <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1431\" height=\"858\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33.png\" alt=\"\" class=\"wp-image-367923\" style=\"width:500px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33.png 1431w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-800x480.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-1160x696.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-120x72.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-90x54.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-320x192.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-560x336.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-240x144.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-180x108.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-640x384.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/10\/Tab1_NP5_s33-1120x672.png 1120w\" sizes=\"(max-width: 1431px) 100vw, 1431px\" \/><\/a><\/figure>\n<\/div>\n<h3 id=\"terapia-coerente-della-malattia-di-base-e-controllo-efficace-dei-sintomi\" class=\"wp-block-heading\">Terapia coerente della malattia di base e controllo efficace dei sintomi.<\/h3>\n\n<p class=\"wp-block-paragraph\">La gestione del trattamento si basa principalmente sulla malattia di base. Questo dovrebbe essere trattato in modo ottimale. Una glicemia ben controllata o l&#8217;astinenza dall&#8217;alcol possono prevenire un&#8217;ulteriore progressione del danno nervoso. Inoltre, \u00e8 importante controllare efficacemente i sintomi, in primo luogo il dolore. Ma i meccanismi del dolore neuropatico sono fondamentalmente diversi da quelli del dolore nocicettivo. Pertanto, \u00e8 indicato un concetto terapeutico speciale. Gli analgesici spesso non sono efficaci. I farmaci di scelta sono principalmente gli antidepressivi triciclici, gli inibitori della ricaptazione della serotonina\/norepinefrina e gli anticonvulsivanti <strong>(Tabella 1) <\/strong>.  <\/p>\n\n<p class=\"wp-block-paragraph\">Ulteriori letture:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.neurologen-und-psychiater-im-netz.org\/neurologie\/erkrankungen\/polyneuropathie\" target=\"_blank\" rel=\"noopener\">www.neurologen-und-psychiater-im-netz.org\/neurologie\/erkrankungen\/polyneuropathie<\/a><br\/>(ultimo accesso 11.10.2023)<\/li>\n\n\n\n<li><a href=\"http:\/\/www.msdmanuals.com\/de-de\/heim\/st%C3%B6rungen-der-hirn-,-r%C3%BCckenmarks-und-nervenfunktion\/erkrankungen-der-peripheren-nerven-und-verwandte-erkrankungen\/polyneuropathie\" target=\"_blank\" rel=\"noopener\">www.msdmanuals.com\/de-de\/heim\/st%C3%B6rungen-der-hirn-,-r\u00fcckenmarks-und-nervenfunktion\/erkrankungen-der-peripheren-nerven-und-verwandte-erkrankungen\/polyneuropathie<\/a> (ultimo accesso 11.10.2023)<\/li>\n\n\n\n<li><a href=\"http:\/\/www.dgn.org\/leitlinien\/3754-ll-030-067-diagnostik-bei-polyneuropathien-2019\" target=\"_blank\" rel=\"noopener\">www.dgn.org\/leitlinien\/3754-ll-030-067-diagnostik-bei-polyneuropathien-2019<\/a> (ultimo accesso 11.10.2023)<\/li>\n\n\n\n<li>Sommer C, Geber C, Young P, et al: Polineuropatie &#8211; eziologia, diagnosi e opzioni di trattamento. Dtsch Arztebl Int 2018; 115: 83-90.  <\/li>\n\n\n\n<li>Petersen JA, Schlereth T: Diagnosi e terapia del dolore neuropatico. Psichiatria + Neurologia 2022; 3: 20-24.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>InFo NEUROLOGIA &amp; PSICHIATRIA 2023; 21(5): 33<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le polineuropatie sono malattie generalizzate del sistema nervoso periferico. Con una prevalenza del 5-8%, i pazienti con abuso cronico di alcol, diabete o malattie maligne sono particolarmente colpiti. Oltre al&hellip;<\/p>\n","protected":false},"author":7,"featured_media":214177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Polineuropatie","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11392,11519,11371,11550],"tags":[71624,16934,25878],"powerkit_post_featured":[],"class_list":["post-368038","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologia-e-diabetologia","category-formazione-continua","category-neurologia-it","category-rx-it","tag-funzione-nervosa","tag-polineuropatia-it","tag-sistema-nervoso-periferico","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 19:27:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":368059,"slug":"perturbacoes-do-cerebro-da-espinal-medula-e-da-funcao-nervosa","post_title":"Perturba\u00e7\u00f5es do c\u00e9rebro, da espinal medula e da fun\u00e7\u00e3o nervosa","href":"https:\/\/medizinonline.com\/pt-pt\/perturbacoes-do-cerebro-da-espinal-medula-e-da-funcao-nervosa\/"},"es_ES":{"locale":"es_ES","id":368071,"slug":"trastornos-cerebrales-de-la-medula-espinal-y-de-la-funcion-nerviosa","post_title":"Trastornos cerebrales, de la m\u00e9dula espinal y de la funci\u00f3n nerviosa","href":"https:\/\/medizinonline.com\/es\/trastornos-cerebrales-de-la-medula-espinal-y-de-la-funcion-nerviosa\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/368038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=368038"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/368038\/revisions"}],"predecessor-version":[{"id":368056,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/368038\/revisions\/368056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/214177"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=368038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=368038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=368038"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=368038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}