{"id":371515,"date":"2024-01-28T00:01:00","date_gmt":"2024-01-27T23:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/focus-sui-processi-genetici-sulla-diagnostica-precoce-e-sulle-diagnosi-differenziali\/"},"modified":"2024-01-28T00:01:39","modified_gmt":"2024-01-27T23:01:39","slug":"focus-sui-processi-genetici-sulla-diagnostica-precoce-e-sulle-diagnosi-differenziali","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/focus-sui-processi-genetici-sulla-diagnostica-precoce-e-sulle-diagnosi-differenziali\/","title":{"rendered":"Focus sui processi genetici, sulla diagnostica precoce e sulle diagnosi differenziali."},"content":{"rendered":"\n<p><strong>Nonostante i tempi difficili che ci sono stati negli ultimi anni, sia il trattamento che il percorso delle persone che vivono con la SM e ne sono affette hanno continuato a evolversi. In occasione della conferenza congiunta ECTRIMS e ACTRIMS sono stati presentati nuovi dati sulla gestione della SM e delle malattie correlate. La fisiopatologia viene gradualmente compresa meglio, portando a un trattamento pi\u00f9 mirato per le persone colpite.<\/strong><\/p>\n\n<!--more-->\n\n<p>La sclerosi multipla (SM) \u00e8 una malattia eterogenea il cui decorso \u00e8 difficile da prevedere. Molti modelli di previsione della SM utilizzano il sangue raccolto perifericamente, che \u00e8 informativo ma potrebbe non catturare i sottili cambiamenti della malattia nel sistema nervoso centrale che sono pi\u00f9 predittivi della progressione della malattia. Si \u00e8 ipotizzato che, misurando le proteine sintetizzate a livello intratecale coinvolte nell&#8217;infiammazione, nell&#8217;attivazione gliale e nel danno al SNC, si possano stabilire modelli predittivi dell&#8217;attivit\u00e0 della malattia. Per determinare il rapporto tra le proteine intratecali e l&#8217;attivit\u00e0 di malattia a breve termine nella SM recidivante-remittente (SMRR), \u00e8 stata misurata la sintesi intratecale di 46 mediatori infiammatori e di 14 marcatori di lesione del sistema nervoso centrale o di attivazione gliale, in campioni di siero e di liquor abbinati di 47 pazienti con SM sottoposti a puntura lombare diagnostica [1].  <\/p>\n\n<p>Tutti i pazienti sono stati seguiti per 12 mesi in uno studio di follow-up retrospettivo e infine sono stati classificati come attivi (sviluppo di attivit\u00e0 clinica e\/o radiologica della malattia entro il primo anno di follow-up) o inattivi (nessuna attivit\u00e0 della malattia). 27 pazienti con malattie neurologiche non infiammatorie (NIND) sono stati inclusi come controlli negativi. I dati sono stati sottoposti all&#8217;analisi dell&#8217;espressione differenziale e alla modellazione della rete per definire la neuroinfiammazione e i danni al sistema nervoso centrale rilevanti per l&#8217;attivit\u00e0 della malattia a breve termine nella SMRR. L&#8217;analisi di rete ha rivelato una chiara associazione positiva tra IgG1 e CXCL10, che \u00e8 correlata all&#8217;attivit\u00e0 della malattia entro 12 mesi. L&#8217;analisi della sopravvivenza libera da attivit\u00e0 di malattia ha mostrato che i pazienti senza correlazione IgG1-CXCL10 hanno un tasso di sopravvivenza libera da attivit\u00e0 di malattia migliore rispetto ai pazienti senza una correlazione significativa.  <\/p>\n\n<h3 id=\"diagnosi-differenziale-con-la-risonanza-magnetica\" class=\"wp-block-heading\">Diagnosi differenziale con la risonanza magnetica<\/h3>\n\n<p>La diagnosi differenziale tra la sindrome di Susac (SuS), la sclerosi multipla (SM) e l&#8217;angiite primaria del sistema nervoso centrale (PACNS) \u00e8 ancora difficile nella pratica clinica. La risonanza magnetica (RM) \u00e8 uno strumento prezioso per la diagnosi di queste malattie, ma l&#8217;interpretazione pu\u00f2 essere complessa. Pertanto, i pazienti SuS di una coorte latinoamericana sono stati confrontati con i dati dei pazienti con SM e PACNS [2]. Il campione \u00e8 stato diviso in un gruppo di formazione e in un gruppo di prova. Il gruppo di formazione \u00e8 stato addestrato con le variabili che hanno mostrato in modo indipendente un potere predittivo per l&#8217;esito &#8220;diagnosi di SuS&#8221; ed \u00e8 stato eseguito un modello di regressione logistica multivariata. I coefficienti ottenuti per ciascuna variabile nel modello di regressione logistica multivariata sono stati arrotondati a numeri interi per assegnare un valore di punteggio alla presenza di ciascuna caratteristica nella RM.  <\/p>\n\n<p>Lo studio ha incluso 46 pazienti SuS, 37 SM e 19 PACNS. L&#8217;analisi di regressione logistica ha mostrato che le &#8220;palle di neve&#8221;, i &#8220;raggi&#8221;, il coinvolgimento del corpo calloso e le lesioni capsulari interne che assomigliano a un filo di perline aumentano la probabilit\u00e0 di SuS come diagnosi finale, mentre la presenza di dita Dawson predice negativamente la diagnosi. Il punteggio diagnostico comprendeva tre punti per le palle di neve, due punti per i raggi, un punto ciascuno per la compromissione del corpo calloso e della capsula interna, e cinque punti venivano detratti se erano presenti le dita di Dawson. Il cut-off per la diagnosi di SuS \u00e8 stato fissato a \u22655 punti. Sono state riscontrate un&#8217;elevata sensibilit\u00e0 (83%), specificit\u00e0 (100%) e accuratezza (94,7%) nel discriminare tra SuS in condizioni di SM e PACNS.  <\/p>\n\n<h3 id=\"focus-sul-trattamento-nmosd\" class=\"wp-block-heading\">Focus sul trattamento NMOSD<\/h3>\n\n<p>La malattia dello spettro della neuromielite ottica (NMOSD) \u00e8 una malattia autoimmune cronica caratterizzata da crisi ricorrenti nel sistema nervoso centrale, che portano a danni neurologici permanenti e a una disabilit\u00e0 cumulativa che influisce sulla qualit\u00e0 della vita legata alla salute. \u00c8 stato eseguito un confronto sperimentale robusto e rigoroso tra due terapie attuali per la NMOSD, inebilizumab e satralizumab, con un <em> confronto indiretto aggiustato per corrispondenza (MAIC <\/em>), utilizzando le crisi epilettiche valutate dal comitato per supportare una decisione terapeutica informata e basata sulle prove [3]. Un MAIC ancorato ha confrontato l&#8217;efficacia relativa di inebilizumab con eculizumab e satralizumab sulla base dei dati pubblicati dagli studi randomizzati di controllo negli adulti con NMOSD sieropositiva all&#8217;acquaporina-4 (AQP4+).  <\/p>\n\n<p>Il rischio relativo di un attacco NMOSD con inebilizumab rispetto a eculizumab e satralizumab era rispettivamente di 1,51 e 0,49. Gli anni di vita calcolati hanno mostrato un vantaggio per inebilizumab (21,90) rispetto a eculizumab (16,02) e satralizumab (20,79). C&#8217;\u00e8 stato anche un vantaggio per inebilizumab (12,55) rispetto a eculizumab (8,23) e satralizumab (11,34) in termini di anni di vita aggiustati per la qualit\u00e0. L&#8217;utilizzo dell&#8217;IAA per analizzare il rischio relativo di un attacco di NMOSD ha mostrato risultati pi\u00f9 forti per il trattamento con inebilizumab rispetto a quanto riportato in precedenza. Inoltre, il trattamento con inebilizumab ha prodotto risultati migliori per quanto riguarda gli anni di vita attesi e gli anni di vita aggiustati per la qualit\u00e0 rispetto a satralizumab o eculizumab. L&#8217;efficacia relativa e l&#8217;interruzione del trattamento sono stati i fattori pi\u00f9 importanti per i risultati.<\/p>\n\n<h3 id=\"differenze-specifiche-di-genere-nella-sm\" class=\"wp-block-heading\">Differenze specifiche di genere nella SM<\/h3>\n\n<p>Esiste un forte dimorfismo sessuale nella sclerosi multipla (SM), che si riflette nel modello murino sperimentale TCR1640 della SM: Le femmine hanno una malattia recidivante-remittente, mentre i maschi hanno un fenotipo di malattia progressiva. Recentemente \u00e8 stato dimostrato che il sesso delle cellule immunitarie trasferite adottivamente e non il sesso del topo ricevente \u00e8 il principale determinante del fenotipo della malattia in questo modello. Per comprendere meglio i determinanti molecolari di questa osservazione sesso-specifica, \u00e8 necessario caratterizzare le firme trascrittomiche delle cellule immunitarie infiltranti del sistema nervoso centrale (SNC). Lo scopo di uno studio \u00e8 stato quindi quello di indagare le firme geniche responsabili delle differenze sesso-specifiche nelle cellule immunitarie infiltranti il SNC nel modello di encefalomielite autoimmune sperimentale (EAE) della SM [4]. A questo scopo, \u00e8 stato effettuato un trasferimento adottivo di cellule immunitarie da cinque topi maschi e sei femmine TCR1640 in topi SJL\/J di tipo selvatico. All&#8217;esordio della malattia, sette giorni dopo il trasferimento, le cellule immunitarie che si infiltrano nel SNC sono state isolate da topi maschi e femmine e processate per l&#8217;RNAseq a singola cellula (scRNAseq) con 10x Genomics e analizzate con Seurat.<\/p>\n\n<p>Dopo la pre-elaborazione, sono state trovate 87.121 cellule immunitarie che si infiltrano nel sistema nervoso centrale e sono stati identificati 18 diversi gruppi di cellule in base alla trascrittomica. Il raggruppamento gerarchico dei campioni basato sulla proporzione di questi 18 cluster ha mostrato una buona separazione tra uomini e donne. Dato il ruolo putativo delle cellule T nell&#8217;EAE, le cellule T sono state estratte, raggruppate e sei sottopopolazioni di cellule T sono state identificate con ScType. L&#8217;analisi delle componenti principali (PCA), basata sulla proporzione di queste nuove cellule T raggruppate, ha nuovamente rivelato una chiara separazione delle cellule immunitarie tra uomini e donne. \u00c8 interessante notare che un numero significativamente pi\u00f9 alto di cellule T CD8+ che infiltrano il SNC \u00e8 stato osservato nei maschi rispetto alle femmine. Al contrario, le donne avevano un numero significativamente pi\u00f9 alto di cellule T CD4+ e regolatorie rispetto agli uomini. Questi risultati indicano una forte determinante sesso-specifica nel trascrittoma e nella frequenza relativa delle cellule immunitarie che si infiltrano nel SNC.  <\/p>\n\n<h3 id=\"anticorpi-nel-liquor-nella-smpp\" class=\"wp-block-heading\">Anticorpi nel liquor nella SMPP<\/h3>\n\n<p>Recentemente, gli anticorpi del liquor dei pazienti con sclerosi multipla primariamente progressiva (SMPP), iniettati nei topi, sono risultati associati alle caratteristiche cliniche e patologiche della malattia. Questo non \u00e8 stato osservato con gli anticorpi del liquor dei pazienti con SM recidivante-remittente o secondaria progressiva. Tuttavia, la specificit\u00e0 di questi anticorpi associati alla SMPP o i loro meccanismi d&#8217;azione non sono ancora stati chiariti. Il liquor dei pazienti con SM \u00e8 stato ottenuto mediante puntura lombare e le singole cellule sono state isolate mediante FACS.  <\/p>\n\n<p>Le catene pesanti e leggere delle singole cellule sono state sequenziate mediante PCR ed espresse e purificate in vettori plasmidici per generare anticorpi ricombinanti. Gli anticorpi, che sono associati alla debolezza motoria, alla demielinizzazione e all&#8217;astrogliosi in modelli sperimentali, sono stati testati per la loro reattivit\u00e0 a una piattaforma di screening del microarray del proteoma umano. Tutte le molecole target identificate sono state poi analizzate ulteriormente per la reattivit\u00e0 mediante Western blot e immunoistochimica [5].<\/p>\n\n<p>\u00c8 stata rilevata la reattivit\u00e0 contro TIA1, una proteina che lega l&#8217;RNA associata ai granuli citotossici, AKR7A3, una proteina della famiglia delle aldo-chetoreduttasi, e LAPTM4A, una proteina lisosomiale della transmembrana 4. Ulteriori test con questi anticorpi patogeni nel modello sperimentale dei roditori potrebbero portare a una migliore comprensione del loro meccanismo d&#8217;azione.<\/p>\n\n<h3 id=\"infiammazione-nella-sindrome-premestruale\" class=\"wp-block-heading\">Infiammazione nella sindrome premestruale<\/h3>\n\n<p>L&#8217;infiammazione cronica compartimentale nelle nicchie del sistema nervoso centrale, come le leptomeningi, gli spazi perivascolari e il plesso coroideo, gioca un ruolo chiave nella patogenesi della sclerosi multipla progressiva (SMP). In particolare, sono stati riscontrati alti livelli di infiammazione meningea associati a un gradiente sostanziale &#8220;superficie-in&#8221; di perdita neuronale e di attivazione microgliale nella GML e nella NAGM con progressione precoce e grave della malattia. L&#8217;obiettivo era quello di caratterizzare meglio l&#8217;infiammazione creando profili genici immuno-correlati degli infiltrati meningei nella pMS [6].<\/p>\n\n<p>Le sezioni fissate in formalina e incluse in paraffina (FFPE) di 60 casi di SM progressiva post-mortem e di dieci donatori sani sono state utilizzate per le analisi immunoistochimiche e morfometriche del numero, del fenotipo e della localizzazione delle cellule immunitarie nelle meningi. Sei casi di SM con infiammazione meningea grave e tre soggetti di controllo sono stati selezionati per utilizzare una nuova tecnologia (CARTANA su un microscopio Nikon Ti2-E con risoluzione monocellulare) che consente l&#8217;analisi di sequenziamento genico in situ (ISS) di un pool selezionato di 157 geni correlati al sistema immunitario. In questa tecnica, l&#8217;mRNA viene sequenziato direttamente nella regione di interesse selezionata (ROI: infiltrato meningeo).  <\/p>\n\n<p>Un&#8217;analisi dettagliata del numero di cellule meningee ha mostrato un numero significativamente aumentato di cellule B in 26 dei 60 casi di SM esaminati (43%), che erano caratterizzati dal pi\u00f9 alto grado di infiammazione meningea. In particolare, il numero di cellule B era superiore a quello dei macrofagi e delle cellule T. L&#8217;analisi ISS ha rivelato un aumento significativo di 85 dei 157 geni analizzati nelle meningi infiammate dalla SM rispetto ai controlli. L&#8217;analisi dei percorsi di segnalazione KEGG ha rivelato che questi geni sono principalmente associati all&#8217;interazione delle proteine virali con i recettori delle citochine, alla segnalazione dei recettori delle cellule B, all&#8217;espressione di PD-L1 e ai percorsi di checkpoint PD-1, nonch\u00e9 alla segnalazione del TNF. L&#8217;analisi di Gene Ontology ha mostrato che la maggior parte dei processi biologici associati a queste molecole coinvolgono la regolazione della risposta immunitaria di tipo 2, la regolazione della chemiotassi delle cellule dendritiche, la fusione della membrana coinvolta nell&#8217;ingresso del virus nella cellula ospite e la regolazione dell&#8217;attivazione e della polarizzazione delle cellule T.  <\/p>\n\n<p>Ci\u00f2 suggerisce che le risposte immunitarie e infiammatorie altamente specializzate, che forse coinvolgono l&#8217;immunit\u00e0 antivirale, persistono nelle meningi della SM progressiva e mantengono l&#8217;infiammazione cronica intratecale.<\/p>\n\n<p><em>Congresso: 9. Kongress der European und American Committee for Treatment and Research in MS (ECTRIMS-ACTRIMS) 2023<\/em><\/p>\n\n<p><\/p>\n\n<p>Letteratura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Welsh N, et al.: Correlation of intrathecal levels of IgG1 and CXCL10 predict disease activity in multiple sclerosis. P004\/2117. MSMilan2023 \u2013 Paper Poster \u2013 Session 1. Multiple Sclerosis Journal 2023.<\/li>\n\n\n\n<li>Marrodan M, et al.: Diagnostic MRI score to differentiate Susac Syndrome from Multiple Sclerosis and Primary Angiitis of the Central Nervous System. P007\/864. MSMilan2023 \u2013 Paper Poster \u2013 Session 1. Multiple Sclerosis Journal 2023.<\/li>\n\n\n\n<li>Paul F, et al.: Matching-Adjusted Indirect Comparison of Current Treatments for NMOSD and Evaluation of Long-Term Effectiveness. P011\/1038. MSMilan2023 \u2013 Paper Poster \u2013 Session 1. Multiple Sclerosis Journal 2023.<\/li>\n\n\n\n<li>R\u00e9billard RM, et al.: Transciptomic signatures of infiltrating immune cells underpinning sex differences in experimental autoimmune encephalomyelitis. P111\/1380. MSMilan2023 \u2013 Paper Poster \u2013 Session 1. Multiple Sclerosis Journal 2023.<\/li>\n\n\n\n<li>Lin J, et al.: Investigation of cerebrospinal fluid antibody specificity in primary progressive MS. P120\/2316. MSMilan2023 \u2013 Paper Poster &#8211; Session 1. Multiple Sclerosis Journal 2023.<\/li>\n\n\n\n<li>Mastantuono M, et al.: Combined neuropathology and in situ sequencing characterization of meningeal inflammation in progressive multiple sclerosis. P121\/1630. MSMilan2023 \u2013 Paper Poster \u2013 Session 1. Multiple Sclerosis Journal 2023.<\/li>\n<\/ol>\n\n<p><\/p>\n\n<p class=\"has-small-font-size\"><em>InFo NEUROLOGIE &amp; PSYCHIATRIE 2023; 21(6): 34\u201335<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nonostante i tempi difficili che ci sono stati negli ultimi anni, sia il trattamento che il percorso delle persone che vivono con la SM e ne sono affette hanno continuato&hellip;<\/p>\n","protected":false},"author":7,"featured_media":371523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Sclerosi multipla","footnotes":""},"category":[11371,11522,11550,11515],"tags":[14819,12315,15547],"powerkit_post_featured":[],"class_list":["post-371515","post","type-post","status-publish","format-standard","has-post-thumbnail","category-neurologia-it","category-rapporti-del-congresso","category-rx-it","category-studi","tag-nmosd-it","tag-sclerosi-multipla","tag-sm","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:54:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":371527,"slug":"foco-nos-processos-geneticos-diagnosticos-precoces-e-diagnosticos-diferenciais","post_title":"Foco nos processos gen\u00e9ticos, diagn\u00f3sticos precoces e diagn\u00f3sticos diferenciais","href":"https:\/\/medizinonline.com\/pt-pt\/foco-nos-processos-geneticos-diagnosticos-precoces-e-diagnosticos-diferenciais\/"},"es_ES":{"locale":"es_ES","id":371541,"slug":"centrarse-en-los-procesos-geneticos-el-diagnostico-precoz-y-los-diagnosticos-diferenciales","post_title":"Centrarse en los procesos gen\u00e9ticos, el diagn\u00f3stico precoz y los diagn\u00f3sticos diferenciales","href":"https:\/\/medizinonline.com\/es\/centrarse-en-los-procesos-geneticos-el-diagnostico-precoz-y-los-diagnosticos-diferenciales\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/371515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=371515"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/371515\/revisions"}],"predecessor-version":[{"id":373352,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/371515\/revisions\/373352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/371523"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=371515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=371515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=371515"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=371515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}