{"id":378749,"date":"2024-05-31T23:25:31","date_gmt":"2024-05-31T21:25:31","guid":{"rendered":"https:\/\/medizinonline.com\/?p=378749"},"modified":"2024-05-31T23:38:47","modified_gmt":"2024-05-31T21:38:47","slug":"esercizio-fisico-e-dfs-ogni-passo-la-rende-in-forma-2","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/esercizio-fisico-e-dfs-ogni-passo-la-rende-in-forma-2\/","title":{"rendered":"Esercizio fisico e DFS \u2013 ogni passo la rende in forma?"},"content":{"rendered":"\n<p><strong>L&#8217;attivit\u00e0 fisica regolare e l&#8217;aumento dell&#8217;attivit\u00e0 fisica fanno parte della terapia di base per il trattamento del diabete di tipo 2 nelle linee guida nazionali e internazionali. Con l&#8217;allenamento aerobico strutturato, si pu\u00f2 osservare una riduzione media dell&#8217;HbA<sub>1c<\/sub> di \u20130,67%, con una durata della terapia di esercizio superiore a 150 min\/settimana di \u20130,89%. Anche una passeggiata giornaliera di cinque chilometri pu\u00f2 ottenere una riduzione dell&#8217;HbA<sub>1c<\/sub> dell&#8217;1,5% e una riduzione della pressione sanguigna di 10\/7 mmHg.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>L&#8217;attivit\u00e0 fisica regolare e l&#8217;aumento dell&#8217;attivit\u00e0 fisica fanno parte della terapia di base per il trattamento del diabete di tipo 2 nelle linee guida nazionali e internazionali. L&#8217;allenamento aerobico strutturato pu\u00f2 portare a una riduzione media dell&#8217;HbA<sub>1c<\/sub> di \u20130,67%, con una durata della terapia di esercizio superiore a 150 minuti\/settimana di \u20130,89% [1]. Anche una passeggiata giornaliera di cinque chilometri pu\u00f2 ottenere una riduzione dell&#8217;HbA<sub>1c<\/sub> dell&#8217;1,5% e una riduzione della pressione sanguigna di 10\/7 mmHg [2].<\/p>\n\n\n\n\n\n<p>L&#8217;attivit\u00e0 fisica regolare riduce il rischio cardiovascolare ed \u00e8 quindi raccomandata dall&#8217;<em>American Heart Association <\/em>nel 2019 per la prevenzione primaria delle malattie cardiovascolari [3]. L&#8217;esercizio fisico e lo sport sono utili per trattare i disturbi circolatori arteriosi e hanno un effetto positivo sullo sviluppo e sulle conseguenze della polineuropatia diabetica [4,5].<\/p>\n\n\n\n<p>Le lesioni ai piedi sono ancora una delle principali complicanze del diabete mellito. Il rischio di sviluppare la sindrome del piede diabetico (DFS) nel corso della vita \u00e8 fino al 34% per le persone con diabete. Il rischio di morire entro i cinque anni successivi alla diagnosi iniziale di DFS \u00e8 circa 2,5 volte pi\u00f9 alto per le persone colpite rispetto alle persone con diabete senza lesioni al piede. Una sindrome del piede diabetico infetto comporta ricoveri pi\u00f9 frequenti rispetto all&#8217;insufficienza cardiaca cronica e i costi per le complicazioni di una sindrome del piede diabetico sono in alcuni casi superiori a quelli per il trattamento dei tipi di cancro pi\u00f9 comuni. Il rischio di recidiva dell&#8217;ulcera \u00e8 di circa il 65% nei tre anni successivi alla diagnosi iniziale dell&#8217;ulcera [6]. Si tratta quindi di un problema serio, con elevata mortalit\u00e0, morbilit\u00e0, sofferenza per le persone colpite e costi considerevoli per il sistema sanitario.<\/p>\n\n\n\n<h3 id=\"la-sola-protezione-del-piede-non-e-piu-raccomandata-oggi\" class=\"wp-block-heading\">La sola protezione del piede non \u00e8 pi\u00f9 raccomandata oggi.<\/h3>\n\n\n\n<p>Dopo molti anni in cui si raccomandava prevalentemente il riposo e il sollievo per prevenire la sindrome del piede diabetico, negli ultimi anni sono aumentate le prove che un moderato aumento dell&#8217;esercizio fisico \u00e8 sicuro, anche se comporta un aumento del rischio di sindrome del piede diabetico.  [7,8]Pertanto, le attuali linee guida dell&#8217;IWGDF  <em>(Gruppo di Lavoro Internazionale del Piede Diabetico)<\/em> sulla prevenzione della sindrome del piede diabetico ha riscontrato che le persone con diabete e rischio di ulcerazione da basso a moderato (IWGDF rischio 1 e 2) e forse anche i pazienti con un alto rischio di ulcerazione (gruppo di rischio IWGDF 3) si pu\u00f2 raccomandare un moderato aumento del carico giornaliero sul piede attraverso la deambulazione (ad esempio, un totale di 1000 passi aggiuntivi al giorno rispetto al valore iniziale) <strong>(Tabella 1)<\/strong> [9].<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1800\" height=\"670\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10.png\" alt=\"\" class=\"wp-image-373801\" style=\"width:500px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10.png 1800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-800x298.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-1160x432.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-120x45.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-90x34.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-320x119.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-560x208.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-240x89.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-180x67.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-640x238.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-1120x417.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab1_HP1_s10-1600x596.png 1600w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>I fattori di rischio per lo sviluppo della sindrome del piede diabetico includono la polineuropatia diabetica con la perdita della percezione protettiva del dolore, i disturbi circolatori arteriosi e la ridotta mobilit\u00e0 articolare delle caviglie e delle articolazioni del piede, che porta a un&#8217;alterazione del processo di rotolamento del piede con lo sviluppo di picchi pressori plantari [10]. Per questo motivo, si sta valutando la possibilit\u00e0 di migliorare la funzionalit\u00e0 del piede e della caviglia attraverso esercizi di ginnastica e quindi, eventualmente, di prevenire lo sviluppo di ulcerazioni. Diversi studi hanno osservato un miglioramento del rotolamento del piede e una riduzione dei sintomi della polineuropatia come risultato degli esercizi di ginnastica [11\u201314].  <\/p>\n\n\n\n<p>Le attuali linee guida IWGDF per la prevenzione della sindrome del piede diabetico raccomandano quindi che le persone con un rischio da basso a moderato di sviluppare la sindrome del piede diabetico (gruppo di rischio IWGDF 1 o 2) partecipino a un programma di esercizi di 8-12 settimane con esercizi per la caviglia e il piede. Idealmente, questo dovrebbe essere introdotto sotto la guida di un professionista e poi continuato in modo indipendente [9].  <\/p>\n\n\n\n<p>I programmi di esercizio includono esercizi di stretching e di rafforzamento per il piede e la caviglia, oltre a esercizi funzionali con allenamento del passo e dell&#8217;equilibrio. Questi esercizi non aumentano il rischio di ulcerazione, ma migliorano la mobilit\u00e0 delle articolazioni del piede e della caviglia, i segni di polineuropatia e i disturbi neuropatici, nonch\u00e9 la distribuzione della pressione plantare. Il gruppo di lavoro brasiliano guidato dal Prof. Sacco ha prodotto un opuscolo con esercizi per piedi e caviglie facili da eseguire e li ha testati in un primo studio di fattibilit\u00e0. Questo ha dimostrato un alto livello di soddisfazione per il programma, nessuna complicazione, una riduzione significativa della gravit\u00e0 della polineuropatia, un miglioramento della mobilit\u00e0 dell&#8217;alluce e una riduzione della dorsiflessione del mesopiede durante l&#8217;andatura, che \u00e8 associata a un migliore rotolamento [15]. L&#8217;opuscolo \u00e8 stato tradotto e pubblicato dai membri del Gruppo di lavoro Diabete, Sport ed Esercizio fisico dell&#8217;Associazione tedesca del diabete (DDG) con l&#8217;autorizzazione degli autori. \u00c8 disponibile gratuitamente sui siti web del Gruppo di Lavoro Piedi del DDG e del Gruppo di Lavoro Diabete, Sport ed Esercizio <strong>(box)<\/strong>. Alle persone con lesioni pre-ulcerative o DFS attiva non \u00e8 attualmente raccomandato di eseguire esercizi che comportino uno stress meccanico sul piede [9].<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-background\" style=\"background-color:#abb7c24a\"><tbody><tr><td><strong>&gt; <a href=\"https:\/\/www.diabetes-bewegung.de\/fileadmin\/user_upload\/01_Die_DDG\/05_Arbeitsgemeinschaften\/AG_Sport_Bewegung\/Microsite\/Homepage\/Publikationen\/Broschuere_Fussuebungen.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Opuscolo sugli esercizi per i piedi (PDF)<\/a><\/strong><\/td><\/tr><tr><td><strong>&gt; <a href=\"https:\/\/ag-fuss-ddg.de\/die-ddg\/arbeitsgemeinschaften\/diabetischer-fuss\/leitlinien\" target=\"_blank\" rel=\"noreferrer noopener\">Linee guida e modelli del DDG<\/a><\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Attualmente ci sono poche raccomandazioni sul ruolo dell&#8217;esercizio fisico dopo una sindrome del piede diabetico o durante un&#8217;ulcera attiva. A causa della mancanza di prove, attualmente le linee guida non raccomandano alcuna terapia di esercizio specifica per questi gruppi.<\/p>\n\n\n\n<h3 id=\"meno-passaggi-associati-a-una-migliore-guarigione-della-ferita\" class=\"wp-block-heading\">Meno passaggi associati a una migliore guarigione della ferita<\/h3>\n\n\n\n<p>Una ricerca di studi che trattano la guarigione della DFS e il movimento rivela che non ci sono praticamente studi che si concentrano su questo tema. Ci sono studi in cui sono state analizzate diverse tecniche di rilievo e in cui \u00e8 stato registrato anche il numero di passi. Nella revisione di van Netten et al.  [16]  In due studi su questo tema che associavano il numero di passi alla guarigione della ferita, \u00e8 stato rilevato che un numero inferiore di passi era associato a una guarigione pi\u00f9 frequente della ferita. Tuttavia, i gruppi erano piccoli e sono stati utilizzati diversi ausili di soccorso, la maggior parte dei quali erano rimovibili, quindi \u00e8 possibile che siano stati fatti pi\u00f9 passi senza un adeguato soccorso [17,18].  <\/p>\n\n\n\n<p>Il gruppo di lavoro ceco di Vr\u00e1tn\u00e1 et al.  [19]  ha studiato gli effetti di un intervento strutturato di 12 settimane con esercizi di mobilizzazione, stabilizzazione e rafforzamento, oltre all&#8217;allenamento del cammino, su pazienti con DFS guarita. Sia nel gruppo di controllo che in quello di intervento, il 15% dei partecipanti ha avuto una recidiva di ulcera durante il periodo di studio. Sebbene l&#8217;aumento dell&#8217;esercizio fisico non abbia impedito l&#8217;ulcerazione in questo breve periodo, si \u00e8 registrato un aumento dell&#8217;attivit\u00e0 fisica, della forza muscolare dell&#8217;estremit\u00e0 inferiore e della mobilit\u00e0 delle grandi articolazioni nel gruppo di intervento, senza un rischio maggiore di ulcerazione rispetto al gruppo di controllo.  <\/p>\n\n\n\n<p>In uno studio condotto da Eraydin e Av\u015far [20] su pazienti con sindrome acuta del piede diabetico, \u00e8 stata osservata una riduzione significativa delle dimensioni della ferita durante il periodo di studio di 12 settimane, quando sono stati eseguiti esercizi per i piedi. Gli esercizi sono stati eseguiti in posizione seduta, cio\u00e8 non hanno comportato un aumento della pressione sulle piante dei piedi. Tuttavia, va notato che, nonostante la randomizzazione, le dimensioni della ferita nei gruppi di intervento e di controllo erano diverse all&#8217;inizio dello studio; la dimensione della ferita nel gruppo di intervento era gi\u00e0 pi\u00f9 piccola inizialmente. Poich\u00e9 le lesioni pi\u00f9 piccole hanno generalmente una tendenza alla guarigione pi\u00f9 rapida, questo potrebbe aver distorto i risultati dello studio.<\/p>\n\n\n\n<p>Negli ultimi anni, due studi pilota si sono concentrati sulla fattibilit\u00e0 e sulla sicurezza della terapia di esercizio per la sindrome del piede diabetico attivo. Nello studio di Lindberg et al.  [21]  cinque uomini con PNP e ulcere attive hanno partecipato a un programma di allenamento di 10 settimane con un cicloergometro, che ha portato a una riduzione delle dimensioni della ferita; la forza, la resistenza e l&#8217;indipendenza sono migliorate durante il periodo di studio. Nello studio di Aitken et al.  [22]  20 partecipanti hanno svolto un allenamento individuale di forza e resistenza, che \u00e8 stato messo insieme in base alla localizzazione della ferita e alle possibilit\u00e0 individuali di partecipare all&#8217;esercizio fisico. Questo ha dimostrato che tale intervento \u00e8 possibile e sicuro; restano da vedere ulteriori studi sui benefici individuali. Il gruppo di lavoro danese guidato da Lindberg ha recentemente sviluppato un programma di allenamento di 12 settimane per le persone con sindrome del piede diabetico, in cui l&#8217;allenamento di resistenza su un cicloergometro \u00e8 stato ampliato per includere l&#8217;allenamento della forza; \u00e8 stato condotto uno studio iniziale di fattibilit\u00e0 con tre partecipanti e pubblicato [23].  <\/p>\n\n\n\n<p>Poich\u00e9 finora sono mancate raccomandazioni specifiche sull&#8217;esatta attuazione dei programmi di esercizio fisico per le persone del gruppo di rischio 3 o per quelle con DFS attiva, il gruppo di lavoro spagnolo di Gracia-Sanchez et al.  [24]  raccomandazioni di esperti corrispondenti, utilizzando il metodo Delphi. Le raccomandazioni includono suggerimenti generali, come il controllo dei piedi per verificare la presenza di lesioni prima e dopo ogni attivit\u00e0, oltre a consigli sulla scelta di calze e scarpe adatte. Esistono anche raccomandazioni specifiche di allenamento adattate al rispettivo rischio del piede <strong>(Tabella 2)<\/strong>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12.png\"><img decoding=\"async\" width=\"2188\" height=\"2936\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12.png\" alt=\"\" class=\"wp-image-373800 lazyload\" style=\"--smush-placeholder-width: 2188px; --smush-placeholder-aspect-ratio: 2188\/2936;width:500px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12.png 2188w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-800x1073.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-1160x1557.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-1526x2048.png 1526w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-120x160.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-90x120.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-320x429.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-560x751.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-1920x2576.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-240x322.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-180x242.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-640x859.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-1120x1503.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/01\/tab2_Hp1_s12-1600x2147.png 1600w\" data-sizes=\"(max-width: 2188px) 100vw, 2188px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<h3 id=\"conclusione\" class=\"wp-block-heading\">Conclusione<\/h3>\n\n\n\n<p>Lo sport e l&#8217;esercizio fisico fanno parte della terapia di base per il diabete mellito. Le complicanze del piede sono una delle principali complicanze del diabete, che causano grandi sofferenze e costi considerevoli. Un moderato aumento del movimento e l&#8217;esecuzione di esercizi speciali per i piedi sono sicuri per i pazienti con un rischio di ulcerazione da basso a medio e possono potenzialmente prevenire o ritardare lo sviluppo della DFS. Per quanto riguarda il movimento nelle ferite del piede esistenti o dopo la guarigione delle ulcere, ad oggi esistono solo pochi studi, alcuni dei quali sono metodologicamente errati. Ci sono prove che gli esercizi senza carico e gli esercizi per i piedi per migliorare la mobilit\u00e0 e costruire la muscolatura possono essere utili anche nelle ulcere acute.<\/p>\n\n\n\n<p>Gruppi specializzati che eseguono esercizi adattati per le persone colpite sarebbero utili per prevenire potenzialmente la notevole sofferenza che le persone con ulcere ai piedi sperimentano. In Germania, lo strumento dello sport riabilitativo potrebbe essere un&#8217;opzione adeguata, che consente la partecipazione gratuita a gruppi di esercizi speciali per un periodo fino a tre anni. Purtroppo, attualmente non esistono gruppi di questo tipo a livello nazionale. Abbiamo urgentemente bisogno di ulteriori studi per poter formulare raccomandazioni ottimizzate per i pazienti con ulcere attive o dopo ulcere guarite.  <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Messaggi da portare a casa<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L&#8217;esercizio fisico \u00e8 utile alle persone con diabete per migliorare la situazione metabolica, il rischio cardiovascolare, il disturbo circolatorio arterioso periferico e la polineuropatia.<\/li>\n\n\n\n<li>Ai soggetti con polineuropatia e un rischio di ulcerazione da basso a medio, si pu\u00f2 raccomandare un moderato aumento del movimento e speciali esercizi per i piedi.<\/li>\n\n\n\n<li>Gli esercizi per migliorare la funzionalit\u00e0 della caviglia e del piede possono eventualmente contrastare lo sviluppo della sindrome del piede diabetico.<\/li>\n\n\n\n<li>Non ci sono dati sufficienti sull&#8217;esercizio fisico nella sindrome del piede diabetico acuto, ma \u00e8 possibile che i programmi di esercizio fisico che non sollecitano l&#8217;area della ferita possano aiutare a mantenere la forma fisica delle persone colpite.<\/li>\n<\/ul>\n\n\n\n<p>Letteratura:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Umpierre D, Ribeiro PAB, Kramer CK, et al.: Physical activity advice only or structured exercise training and association with HbA<sub>1c<\/sub> levels in type 2 diabetes: A systematic review and meta-analysis. JAMA 2011; 305(17): 1790\u20131799; doi: 10.1001\/jama.2011.576.<\/li>\n\n\n\n<li>Di Loreto C, Fanelli C, Lucidi P, et al.: Make Your Diabetic Patients Walk-Long-term impact of different amounts of physical activity on type 2 Diabetes. Diabetes Care 2005; 28(6): 1295\u20131302; doi: 10.2337\/diacare.28.6.1295.<\/li>\n\n\n\n<li>Arnett DK, Blumenthal RS, Albert MA, et al.: 2019 ACC\/AHA guideline on the primary prevention of cardiovascular disease: a report of the American College of Cardiology\/American Heart Association Task Force on Clinical Practice Guidelines. J Am Coll Cardiol 2019; 74: e177\u2013e232. <\/li>\n\n\n\n<li>Kanaley JA, Colberg SR, Corcoran MH, et al.: Exercise\/Physical Activity in Individuals with Type 2 Diabetes: A Consensus Statement from the American College of Sports Medicine. Med Sci Sports Exerc 2022; 54(2): 353\u2013368; doi: 10.1249\/MSS.0000000000002800. <\/li>\n\n\n\n<li>Balletshofer B, B\u00f6ckler D, Diener H, et al.: Positionspapier zur Diagnostik und Therapie der peripheren arteriellen Verschlusskrankheit (pAVK) bei Menschen mit Diabetes mellitus. Gemeinsame Stellungnahme der Deutschen Diabetes Gesellschaft (DDG), der Deutschen Gesellschaft f\u00fcr Angiologie (DGA), der Deutschen Gesellschaft f\u00fcr Interventionelle Radiologie und minimal-invasive Therapie (DeGIR) sowie der Deutschen Gesellschaft f\u00fcr Gef\u00e4\u00dfchirurgie und Gef\u00e4\u00dfmedizin (DGG). Diabetologie 2022; 17 (Suppl 2): S354\u2013S364.<\/li>\n\n\n\n<li>Armstrong DG, Boulton AJM, Bus SA: Diabetic Foot Ulcers and Their Recurrence. N Engl J Med 2017; 376(24): 2367\u20132375.<\/li>\n\n\n\n<li>Lemaster JW, Mueller MJ, Reiber GE, et a.: Effect of weight-bearing activity on foot ulcer incidence in people with diabetic peripheral neuropathy: feet first randomized controlled trial. Phys Ther 2008; 88(11): 1385\u20131398; doi: 10.2522\/ptj.20080019. <\/li>\n\n\n\n<li>Mueller MJ, Tuttle LJ, Lemaster JW, et al.: Weight-bearing versus nonweight-bearing exercise for persons with diabetes and peripheral neuropathy: a randomized controlled trial. Arch Phys Med Rehabil 2013; 94(5): 829\u2013838; doi: 10.1016\/j.apmr.2012.12.015. <\/li>\n\n\n\n<li>Bus SA, Sacco ICN, Monteiro-Soares M, et al.: Guidelines on the prevention of foot ulcers in persons with diabetes-IWGDF 2023 update. Diabetes Metab Res Rev 2023; doi: 10.1002\/dmrr.3651.<\/li>\n\n\n\n<li>Francia P, Anichini R, Seghieri G, et al.: History, Prevalence and Assessment of Limited Joint Mobility, From Stiff Hand Syndrome to Diabetic Foot Ulcer Prevention: A Narrative Review of the Literature. Curr Diabetes Rev 2018; 14(5): 411\u2013426; doi: 10.2174\/1573399813666170816142731.<\/li>\n\n\n\n<li>Sartor CD, et al.: Effects of strengthening, stretching and functional training on foot function in patients with diabetic neuropathy: results of a randomized controlled trial. BMC Musculoskeletal Disorders 2014; 15: 137.<\/li>\n\n\n\n<li>Fayed EE, et al.: Exercise Therapy Improves Planter Pressure Distribution in Patients with Diabetic Peripheral Neuropathy. International Journal of PharmTech Research 2016; 9(5): 151\u2013159.<\/li>\n\n\n\n<li>Cerrahoglu L, Kosan U, Sirin TC, Ulusoy A.: Range of Motion and Plantar Pressure Evaluation for the Effects of Self- Care Foot Exercises on Diabetic Patients with and Without Neuropathy. J Am Podiatr Med Assoc 2016; 106(3): 189\u2013200.<\/li>\n\n\n\n<li>Iunes DH, Rocha CBJ, Borges NCS, et al.: Self-Care Associated with Home Exercises in Patients with Type 2 Diabetes Mellitus. PLoS One 2014; 9(12): e114151.<\/li>\n\n\n\n<li>Silva \u00c9Q, Santos DP, Beteli RI, et al.: Feasibility of a home based foot\u2013ankle exercise programme for musculoskeletal dysfunctions in people with diabetes: randomised controlled FOotCAre (FOCA) Trial II. Scientifc Reports 2021; 11: 12404. <\/li>\n\n\n\n<li>van Netten JJ, Fijen VM, Bus SA: Weight-bearing physical activity in people with diabetes-related foot disease: A systematic review. Diabetes Metab Res Rev 2022; 38(6): e3552; doi: 10.1002\/dmrr.3552.<\/li>\n\n\n\n<li>Najafi B, Grewal GS, Bharara M, et al.: Can\u2019t stand the pressure: the association between unprotected standing, walking, and wound healing in people with diabetes. J Diabetes Sci Technol 2017; 11(4): 657\u2013667; doi: 10.1177\/1932296816662959.<\/li>\n\n\n\n<li>Bus SA, van Netten JJ, Kottink AIR, et al.: The efficacy of removable devices to offload and heal neuropathic plantar forefoot ulcers in people with diabetes: a single-blinded multicentre randomised controlled trial. Int Wound J 2018; 15(1): 65\u201374; doi: 10.1111\/iwj.12835.<\/li>\n\n\n\n<li>Vr\u00e1tn\u00e1 E, Hus\u00e1kov\u00e1 J, Jaros\u00edkov\u00e1 R, et al.: Effects of a 12-Week Interventional Exercise Programme on Muscle Strength, Mobility and Fitness in Patients With Diabetic Foot in Remission: Results From BIONEDIAN Randomised Controlled Trial. Front Endocrinol 2022; 13: 869128; doi: 10.3389\/fendo.2022.869128.<\/li>\n\n\n\n<li>Eraydin S, Av\u015far G.: The Effect of Foot Exercises on Wound Healing in Type 2 Diabetic Patients With a Foot Ulcer. A Randomized Control Study. Journal of Wound, Ostomy and Continence Nursing 2018; 45(2): 123\u2013130; doi: 10.1097\/WON.000000000000040.<\/li>\n\n\n\n<li>Lindberg K, M\u00f8ller BS, Kirketerp-M\u00f8ller K, Kristensen MT: An exercise program for people with severe peripheral neuropathy and diabetic foot ulcers \u2013 a case series on feasibility and safety. Disabil Rehabil 2020; 42(2): 183\u2013189; doi: 10.1080\/09638288.2018.1494212. <\/li>\n\n\n\n<li>Aitken E, Hiew J, Hamilton EJ, et al.: Exercise in adults admitted to hospital with diabetes-related foot ulcers: a pilot study of feasibility and safety. Journal of Foot and Ankle Research 2023; 16: 18; doi: 10.1186\/s13047-023-00616-0. <\/li>\n\n\n\n<li>Aagaard TV, Lindberg K, Brorson S, et al.: A 12-Week Supervised Exercise Therapy Program for Patients with Diabetic Foot Ulcers: Program Development and Preliminary Feasibility. The International Journal of Lower Extremity Wounds 2023; doi: 10.1177\/15347346221149786.<\/li>\n\n\n\n<li>Gracia-Sanchez A, Lopez-Pineda A, Lazaro-Mart\u00ednez JL, et al.: Con\u00adsensus-based recommendations on physical activity and exercise in patients with diabetes at risk of foot ulcerations: a Delphi study. Braz J Phys Ther 2023; 27(2): 100500; doi: 10.1016\/j.bjpt.2023.100500.<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-small-font-size\"><em><em><em>InFo DIABETOLOGIE &amp; ENDOKRINOLOGIE 2024; 1(2)<\/em>:<\/em>10\u201314<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;attivit\u00e0 fisica regolare e l&#8217;aumento dell&#8217;attivit\u00e0 fisica fanno parte della terapia di base per il trattamento del diabete di tipo 2 nelle linee guida nazionali e internazionali. Con l&#8217;allenamento aerobico&hellip;<\/p>\n","protected":false},"author":7,"featured_media":378766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Sindrome del piede diabetico","footnotes":""},"category":[11550,11392,22617,11317,11462,11306,11473,11515],"tags":[44385,12013,12379,73908,59774,50586,65264],"powerkit_post_featured":[],"class_list":["post-378749","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-it","category-endocrinologia-e-diabetologia","category-formazione-ecm","category-medicina-dello-sport","category-medicina-fisica-e-riabilitazione","category-medicina-interna-generale","category-prevenzione-e-assistenza-sanitaria","category-studi","tag-dfs-it","tag-diabete-di-tipo-2-it","tag-diabete-mellito","tag-rischio-cardiovascolare-it","tag-sindrome-del-piede-diabetico","tag-ulcera-del-piede","tag-ulcerazioni","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:45:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":378750,"slug":"exercicio-e-dfs-cada-passo-torna-o-apto-2","post_title":"Exerc\u00edcio e DFS \u2013 cada passo torna-o apto?","href":"https:\/\/medizinonline.com\/pt-pt\/exercicio-e-dfs-cada-passo-torna-o-apto-2\/"},"es_ES":{"locale":"es_ES","id":378751,"slug":"ejercicio-y-dfs-cada-paso-le-pone-en-forma-2","post_title":"Ejercicio y DFS: \u00bfcada paso le pone en forma?","href":"https:\/\/medizinonline.com\/es\/ejercicio-y-dfs-cada-paso-le-pone-en-forma-2\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/378749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=378749"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/378749\/revisions"}],"predecessor-version":[{"id":380350,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/378749\/revisions\/380350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/378766"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=378749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=378749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=378749"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=378749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}