{"id":381795,"date":"2024-07-02T14:00:00","date_gmt":"2024-07-02T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/quali-sono-le-novita-per-lo-studio\/"},"modified":"2024-07-05T14:39:17","modified_gmt":"2024-07-05T12:39:17","slug":"quali-sono-le-novita-per-lo-studio","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/it\/quali-sono-le-novita-per-lo-studio\/","title":{"rendered":"Quali sono le novit\u00e0 per lo studio?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L&#8217;interessamento renale \u00e8 una delle forme pi\u00f9 gravi di lupus e spesso \u00e8 pericoloso per la vita. Per riconoscere la nefrite lupica (LN) in una fase precoce, si raccomanda una biopsia renale ai pazienti con LES che presentano anomalie nelle urine. Le opzioni di trattamento sono migliorate grazie alla disponibilit\u00e0 di moderne sostanze aggiuntive. Nella linea guida KDIGO pubblicata all&#8217;inizio del 2024, la terapia combinata con l&#8217;aggiunta di belimumab o voclosporina \u00e8 raccomandata per le LN di classe 3 o 4. \u00c8 importante utilizzare un programma di trattamento basato sulle prove.  <\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">La nefrite da lupus (LN) si verifica fino alla met\u00e0 dei pazienti con lupus eritematoso sistemico (LES) [1]. &#8220;I pazienti con nefrite lupica hanno un esito significativamente peggiore&#8221;, ha riferito la Professoressa Julia Weinmann-Menke, Centro Medico Universitario dell&#8217;Universit\u00e0 Johannes Gutenberg di Mainz [2]. In uno studio basato sulla popolazione pubblicato nel 2019, tutti i pazienti con diagnosi di LES a Oslo nel periodo 1999-2008 (n=325) sono stati seguiti per un periodo di follow-up mediano di 14 anni. Il tasso di mortalit\u00e0 per i pazienti con LN era di 3,8 rispetto a 1,7 per i pazienti con LES senza LN (95% CI: 2,1-6,2 e 0,9-2,7, rispettivamente) [3]. Tuttavia, le opzioni terapeutiche per la LN sono migliorate negli ultimi anni e si spera che questo si rifletta anche nei risultati del trattamento. Oltre a migliorare l&#8217;aspettativa di vita, gli obiettivi terapeutici pi\u00f9 importanti sono la migliore protezione possibile degli organi e l&#8217;alleviamento dei sintomi che variano individualmente. La diagnosi precoce di LN \u00e8 un prerequisito per fornire ai pazienti un trattamento adeguato. Di conseguenza, i pazienti con LES noto o sospetto dovrebbero essere sottoposti a uno screening di routine con l&#8217;analisi del sedimento urinario, oltre a UPCR e UACR. Se il sospetto di LN viene confermato da una successiva biopsia renale, l&#8217;obiettivo \u00e8 raggiungere e mantenere la remissione il pi\u00f9 rapidamente possibile [2]. La linea guida KDIGO pubblicata quest&#8217;anno incorpora le ultime scoperte basate sull&#8217;evidenza sul trattamento della LN [4]. L&#8217;autorizzazione concessa dalla FDA, dall&#8217;EMA e da Swissmedic per belimumab e voclosporina come aggiunta al trattamento standard della LN rappresenta un ampliamento significativo dell&#8217;armamentario terapeutico e comporta un adeguamento dei regimi di trattamento esistenti.  [5\u20138]. Una terapia di base adeguata e, se necessario, un trattamento immunosoppressivo sono ancora importanti, ha sottolineato il Prof. Weinmann-Menke [2].<\/p>\n\n<figure class=\"wp-block-table\"><table class=\"has-background\" style=\"background-color:#8dd2fc5c\"><tbody><tr><td><strong>Abbreviazioni<\/strong><\/td><\/tr><tr><td>CKD = Malattia renale cronica  <\/td><\/tr><tr><td>EMA = Agenzia Europea dei Medicinali  <\/td><\/tr><tr><td>FDA = Amministrazione statunitense per gli alimenti e i farmaci  <\/td><\/tr><tr><td>KDIGO = Malattia renale: migliorare i risultati globali<\/td><\/tr><tr><td>UACR=Rapporto albumina\/creatinina<\/td><\/tr><tr><td>UPCR = rapporto proteine urinarie\/creatinina  <\/td><\/tr><tr><td>SGLT-2 = Sodio-Glucosio-Co-Trasportatore-2<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<h3 id=\"effettuare-una-biopsia-precoce-e-considerare-le-moderne-sostanze-aggiuntive-se-necessario\" class=\"wp-block-heading\">Effettuare una biopsia precoce e considerare le moderne sostanze aggiuntive, se necessario.  <\/h3>\n\n<p class=\"wp-block-paragraph\">&#8220;Facciamo la biopsia quando vediamo delle anomalie nelle urine&#8221;, dice il relatore [2]. [1,4]Questa procedura corrisponde alle raccomandazioni delle linee guida internazionali. [1,4]Se si sospetta un LN sulla base di UPCR e UACR, \u00e8 necessario eseguire una biopsia renale con valutazione della classe istopatologica. Se viene diagnosticato un LN di classe 3 o 4, la linea guida KDIGO raccomanda di aggiungere belimumab o voclosporina &#8220;in cima&#8221; al trattamento standard fin dall&#8217;inizio [4]. &#8220;Ogni riacutizzazione della nefrite lupica comporta la perdita di tessuto renale e quindi peggiora la sopravvivenza complessiva del paziente&#8221;, ha spiegato il Prof. Weinmann-Menke [2]. Belimumab (Benlysta\u00ae) \u00e8 stato autorizzato per il lupus sistemico senza LN per molti anni, per cui gli effetti a lungo termine e il profilo degli effetti collaterali sono noti [8]. Nello studio BLISS-LN, rilevante per l&#8217;approvazione di belimumab nella LN, belimumab non solo ha aumentato la risposta alla terapia, ma ha anche ridotto la perdita di eGFR e il tasso di ricaduta [6]. E nello studio AURORA 1, un numero maggiore di pazienti ha ottenuto una risposta completa nel braccio di trattamento con voclosporina rispetto a quello senza questa terapia aggiuntiva [9]. La voclosporina (Lupkynis\u00ae) ha ricevuto un&#8217;autorizzazione Swissmedic per la LN nel 2023 [8].  <\/p>\n\n<h3 id=\"non-trascuri-lo-standard-di-cura\" class=\"wp-block-heading\">Non trascuri lo &#8220;standard di cura&#8221;.  <\/h3>\n\n<p class=\"wp-block-paragraph\">Il trattamento della LN consiste in diversi pilastri terapeutici <strong>(Fig. 1)<\/strong>. &#8220;L&#8217;idrossiclorochina dovrebbe essere somministrata a tutti i pazienti con nefrite lupica&#8221;, ha detto il relatore [2]. [10,11]\u00c8 stato dimostrato che i pazienti con LN trattati con idrossiclorochina (HCQ) ottengono risultati significativamente migliori; ad esempio, gli studi osservazionali hanno dimostrato un miglioramento dei tassi di risposta renale, una riduzione del rischio di recidiva e la prevenzione della progressione della CKD. La tossicit\u00e0 retinica \u00e8 un effetto collaterale noto dell&#8217;uso a lungo termine di HCQ, motivo per cui si raccomanda un esame oftalmologico 5 anni dopo l&#8217;inizio del trattamento e successivamente ogni anno [1].  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1160\" height=\"915\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-1160x915.png\" alt=\"\" class=\"wp-image-381653\" style=\"width:500px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-1160x915.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-800x631.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-120x95.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-90x71.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-320x253.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-560x442.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-240x189.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-180x142.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-640x505.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24-1120x884.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/06\/abb1_HP6_s24.png 1494w\" sizes=\"(max-width: 1160px) 100vw, 1160px\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">I pilastri comprovati della terapia di base sono il blocco del sistema renina-angiotensina-aldosterone (RAAS) e l&#8217;uso di un inibitore SGLT-2 [2]. Il blocco del RAAS \u00e8 indicato per i suoi effetti antiproteinurici e antipertensivi e l&#8217;SGLT-2-i ha dimostrato di avere effetti nefroprotettivi e di miglioramento della prognosi nei grandi studi DAPA-CKD e EMPA-Kidney nella CKD. &#8220;I pazienti con nefrite lupica traggono beneficio se ricevono l&#8217;SGLT-2-i come add-on&#8221;, ha detto il relatore [2]. Mentre le classi LN I e II di solito richiedono solo una terapia conservativa, il trattamento immunosoppressivo \u00e8 necessario per le classi III e IV e, in alcuni casi, per la classe V [1]. La terapia di induzione immunosoppressiva comprende il micofenolato mofetile (MMF) o la cilofosfamide, nonch\u00e9 il trattamento steroideo alla dose pi\u00f9 bassa possibile. [2,4]Esiste un nuovo schema KDIGO per la riduzione degli steroidi, ha riferito il Prof. Weinmann-Menke. L&#8217;obiettivo \u00e8 quello di utilizzare la dose di steroidi pi\u00f9 bassa possibile, per ridurre gli effetti collaterali dell&#8217;uso a lungo termine, ma allo stesso tempo per non compromettere il mantenimento della remissione. [10]Uno studio pubblicato nel 2023 ha dimostrato che i pazienti affetti da LN che hanno avuto una o pi\u00f9 infiammazioni hanno avuto un declino pi\u00f9 rapido della funzione renale e un tasso di mortalit\u00e0 pi\u00f9 elevato. Il relatore consiglia quindi di sospendere gli steroidi solo nei pazienti molto stabili che mostrano una buona risposta alla terapia.  <\/p>\n\n<p class=\"wp-block-paragraph\">Se i pazienti con LN rimessa non presentano pi\u00f9 alcuna anomalia nelle urine, ha comunque senso sottoporli a un&#8217;ulteriore biopsia renale dopo un anno, per verificare l&#8217;andamento dell&#8217;attivit\u00e0 renale. Su questa base si pu\u00f2 determinare l&#8217;ulteriore procedura di trattamento.  <\/p>\n\n<p class=\"wp-block-paragraph\"><em>Congresso: Conferenza annuale DGIM  <\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Letteratura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Odler B, et al.: Diagnostik und Therapie der Lupusnephritis \u2013 2023 [Diagnostic and therapy of lupus nephritis \u2013 2023]. Wien Klin Wochenschr 2023; 135(Suppl 5): 675\u2013687. <\/li>\n\n\n\n<li>\u00abLupusnephritis: Highlights \u2013 Was ist neu f\u00fcr die Praxis\u00bb, Univ.-Prof. Dr. med. Julia Weinmann-Menke, 130. Kongress der Deutschen Gesellschaft f\u00fcr Innere Medizin (DGIM), 13.04.2024.<\/li>\n\n\n\n<li>Reppe Moe SE, et al.: Assessing the relative impact of lupus nephritis on mortality in a population-based systemic lupus erythematosus cohort. Lupus 2019; 28(7): 818\u2013825. <\/li>\n\n\n\n<li>Kidney Disease: Improving Global Outcomes (KDIGO) Lupus Nephritis Work Group. KDIGO 2024 Clinical Practice Guideline for the management of LUPUS NEPHRITIS. Kidney Int 2024; 105(1S): S1\u2013S69. <\/li>\n\n\n\n<li>Rovin BH, et al.: Executive summary of the KDIGO 2024 Clinical Practice Guideline for the Management of Lupus Nephritis. Kidney Int 2024; 105(1): 31\u201334. <\/li>\n\n\n\n<li>Furie R, et al.: Two-year, randomized, controlled trial of belimumab in lupus nephritis. N Engl J Med 2020; 383: 1117\u20131128.<\/li>\n\n\n\n<li>Rovin BH, et al.: Efficacy and safety of voclosporin versus placebo for lupus nephritis (AURORA 1): a double-blind, randomised, multicentre, placebo-controlled, phase 3 trial. Lancet 2021; 397: 2070\u20132080.<\/li>\n\n\n\n<li>Swissmedic : Informazioni sui medicinali,<br\/><a href=\"http:\/\/www.swissmedicinfo.ch\" target=\"_blank\" rel=\"noopener\">www.swissmedicinfo.ch,<\/a>(ultimo recupero 31\/05\/2024) <\/li>\n\n\n\n<li>\u00abBehandlung von PatientInnen mit aktiver Lupusnephritis nach Marktr\u00fccknahme von Voclosporin\u00bb, Deutsche Gesellschaft f\u00fcr Rheumatologie (DGRh), <a href=\"https:\/\/dgrh.de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/dgrh.de<\/a>, (letzter Abruf 31.05.2024)<\/li>\n\n\n\n<li>Pe\u00f1a-Vizcarra \u00d3R, et al.: Effect of antimalarials on clinical outcomes in lupus nephritis. Rheumatology (Oxford). 2023 Nov 1:kead576.<br\/>doi: 10.1093\/rheumatology\/kead576.<\/li>\n\n\n\n<li>Kostopoulou M, et al.: Management of lupus nephritis: a systematic literature review informing the 2019 update of the joint EULAR and European Renal Association-European Dialysis and Transplant Association (EULAR\/ERA-EDTA) recommendations. RMD Open. 2020;6: 2. doi: 10.1136\/rmdopen-2020-001263.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>HAUSARZT PRAXIS 2024; 19(6): 24\u201325 (pubblicato il 26.6.24, prima della stampa)<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#abb7c25c\"><em>Immagine di copertina: micrografia ad altissimo ingrandimento della nefrite lupica proliferativa diffusa, classe IV. Macchia PAS<\/em>. <em>\u00a9Nephron, wikimedia<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;interessamento renale \u00e8 una delle forme pi\u00f9 gravi di lupus e spesso \u00e8 pericoloso per la vita. Per riconoscere la nefrite lupica (LN) in una fase precoce, si raccomanda una&hellip;<\/p>\n","protected":false},"author":7,"featured_media":381805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Lupus nefrite","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11550,11306,11420,11522,11515,11502],"tags":[21472,77115,77113,77116,65621,15831,67348,77112,14067,13434,77114],"powerkit_post_featured":[],"class_list":["post-381795","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-it","category-medicina-interna-generale","category-nefrologia-it","category-rapporti-del-congresso","category-studi","category-urologia-it","tag-belimumab-it","tag-cicofosfamide","tag-coinvolgimento-dei-reni","tag-conferenza-annuale-dgim","tag-kdigo-it","tag-lupus-eritematoso-it","tag-mmf-it","tag-nefrite-lupica-it","tag-sle-it","tag-steroidi","tag-voclosporina","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 20:54:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"it_IT","wpml_translations":{"pt_PT":{"locale":"pt_PT","id":381809,"slug":"o-que-ha-de-novo-na-pratica","post_title":"O que h\u00e1 de novo na pr\u00e1tica?","href":"https:\/\/medizinonline.com\/pt-pt\/o-que-ha-de-novo-na-pratica\/"},"es_ES":{"locale":"es_ES","id":381825,"slug":"que-hay-de-nuevo-en-la-consulta","post_title":"\u00bfQu\u00e9 hay de nuevo en la consulta?","href":"https:\/\/medizinonline.com\/es\/que-hay-de-nuevo-en-la-consulta\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/381795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/comments?post=381795"}],"version-history":[{"count":2,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/381795\/revisions"}],"predecessor-version":[{"id":382697,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts\/381795\/revisions\/382697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media\/381805"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=381795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/category?post=381795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=381795"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/powerkit_post_featured?post=381795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}