{"id":98324,"count":1,"description":"","link":"https:\/\/medizinonline.com\/it\/tag\/riclassificazione-dei-tumori-epatocolangiali-combinati-con-lausilio-dellintelligenza-artificiale\/","name":"Riclassificazione dei tumori epatocolangiali combinati con l'ausilio dell'intelligenza artificiale","slug":"riclassificazione-dei-tumori-epatocolangiali-combinati-con-lausilio-dellintelligenza-artificiale","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags\/98324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/posts?tags=98324"},{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/article_rx?tags=98324"},{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/post_dl?tags=98324"},{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tribe_events?tags=98324"},{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tec_calendar_embed?tags=98324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}