{"id":403320,"date":"2024-09-08T17:23:32","date_gmt":"2024-09-08T15:23:32","guid":{"rendered":"https:\/\/congressagenda.com\/?post_type=tribe_events&amp;p=2207"},"modified":"2024-09-08T17:23:32","modified_gmt":"2024-09-08T15:23:32","slug":"17-nurnberger-herz-tage-2025","status":"publish","type":"tribe_events","link":"https:\/\/medizinonline.com\/it\/event\/17-nurnberger-herz-tage-2025\/","title":{"rendered":"17. N\u00fcrnberger Herz-Tage 2025"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":17389,"featured_media":0,"template":"","meta":{"_acf_changed":false,"pmpro_default_level":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[77250,116],"tribe_events_cat":[87,88,90,110],"class_list":["post-403320","tribe_events","type-tribe_events","status-publish","tag-featured","tag-featured-home","tribe_events_cat-angiologie","tribe_events_cat-cardiology","tribe_events_cat-general-practice","tribe_events_cat-pharmacology","pmpro-has-access","cat_angiologie","cat_cardiology","cat_general-practice","cat_pharmacology"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"de_DE","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tribe_events\/403320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/users\/17389"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tribe_events\/403320\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/media?parent=403320"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tags?post=403320"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/medizinonline.com\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=403320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}