{"id":11481,"count":636,"description":"","link":"https:\/\/medizinonline.com\/pt-pt\/categoria\/psiquiatria-e-psicoterapia\/","name":"Psiquiatria e psicoterapia","slug":"psiquiatria-e-psicoterapia","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category\/11481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts?category=11481"},{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/article_rx?category=11481"},{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/publication?category=11481"},{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/post_dl?category=11481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}