{"id":323953,"date":"2022-12-05T01:00:00","date_gmt":"2022-12-05T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/alinhamento-dos-cuidados-com-o-paciente-2\/"},"modified":"2023-11-01T14:38:08","modified_gmt":"2023-11-01T13:38:08","slug":"alinhamento-dos-cuidados-com-o-paciente-2","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/alinhamento-dos-cuidados-com-o-paciente-2\/","title":{"rendered":"Alinhamento dos cuidados com o paciente"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A medicina centrada no paciente, que respeita e integra prefer\u00eancias, valores ou necessidades individuais, tornou-se cada vez mais importante nos \u00faltimos anos nos cuidados ao paciente. Nos cuidados cl\u00ednicos, \u00e9 portanto importante que permitamos aos nossos pacientes ter uma palavra a dizer nas decis\u00f5es relativas aos seus tratamentos, ou pelo menos envolv\u00ea-los no processo de tomada de decis\u00f5es.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">A medicina centrada no doente respeita e integra prefer\u00eancias, valores e necessidades individuais [1\u20133] e tornou-se cada vez mais importante nos cuidados ao doente nos \u00faltimos anos. Nos cuidados cl\u00ednicos, \u00e9 portanto importante que permitamos aos nossos pacientes tomar decis\u00f5es sobre os seus tratamentos, ou pelo menos envolv\u00ea-los no processo de tomada de decis\u00f5es [3].<\/p>\n\n<p class=\"wp-block-paragraph\">Durante a hospitaliza\u00e7\u00e3o, as rondas di\u00e1rias na enfermaria formam a base da medicina centrada no doente. Numerosos estudos sublinham a import\u00e2ncia das rondas de enfermaria e mostram que podem contribuir para uma melhor qualidade dos cuidados, seguran\u00e7a dos doentes e melhores resultados para os doentes [4\u20136]. Como encontro entre doentes, m\u00e9dicos e enfermeiros, oferecem \u00e0 equipa de tratamento a oportunidade de estabelecer uma rela\u00e7\u00e3o com o doente, de os informar sobre a sua doen\u00e7a, de discutir a terapia em curso ou de avaliar em conjunto outras etapas de diagn\u00f3stico [5,7].<\/p>\n\n<p class=\"wp-block-paragraph\">As decis\u00f5es relativas ao tratamento de um paciente s\u00e3o muitas vezes tomadas durante as visitas do m\u00e9dico chefe. Durante a visita de um m\u00e9dico chefe, os m\u00e9dicos assistentes apresentam geralmente o historial m\u00e9dico dos seus pacientes \u00e0 equipa de tratamento. A apresenta\u00e7\u00e3o pode ter lugar directamente na cabeceira do paciente ou em frente da porta. Ambos os modos s\u00e3o pr\u00e1tica comum nos cuidados cl\u00ednicos.<\/p>\n\n<p class=\"wp-block-paragraph\">A discuss\u00e3o interdisciplinar do historial m\u00e9dico directamente \u00e0 cabeceira do paciente permite ao paciente participar activamente no tratamento. Al\u00e9m disso, o paciente pode obter informa\u00e7\u00f5es sobre a sua hist\u00f3ria m\u00e9dica atrav\u00e9s da discuss\u00e3o do caso. Contudo, estas discuss\u00f5es, pelo menos do lado m\u00e9dico, s\u00e3o geralmente de natureza acad\u00e9mica e cont\u00eam terminologia m\u00e9dica, com a qual os pacientes normalmente n\u00e3o est\u00e3o familiarizados. Isto pode levar a que os pacientes n\u00e3o compreendam as coisas correctamente ou at\u00e9 mesmo a interpret\u00e1-las mal. A complexidade e o volume da informa\u00e7\u00e3o m\u00e9dica, bem como a partilha de informa\u00e7\u00e3o sens\u00edvel \u00e0 cabeceira do leito, podem tamb\u00e9m levar a confus\u00e3o, desconforto e mal-entendidos, e possivelmente afectar os conhecimentos dos doentes [8\u201310]. O conhecimento e a compreens\u00e3o do paciente, por sua vez, s\u00e3o considerados importantes preditores de uma ades\u00e3o ao tratamento bem sucedida [11\u201313].<\/p>\n\n<p class=\"wp-block-paragraph\">Se a apresenta\u00e7\u00e3o do caso e as discuss\u00f5es acad\u00e9micas n\u00e3o se realizarem directamente \u00e0 cabeceira do paciente, pode ser explicado aos pacientes um resumo &#8220;amigo do paciente&#8221; para depois os informar sobre o que foi discutido. No entanto, as potenciais desvantagens deste tipo de visitas s\u00e3o que os doentes podem estar menos envolvidos, a tomada de decis\u00f5es pode ser menos transparente e a equipa de cuidados pode passar menos tempo com o doente.<\/p>\n\n<p class=\"wp-block-paragraph\">At\u00e9 \u00e0 data, poucos estudos investigaram se a apresenta\u00e7\u00e3o do paciente directamente \u00e0 cabeceira do paciente durante as rondas tem um impacto positivo ou negativo nos resultados centrados no paciente, tais como compreens\u00e3o, satisfa\u00e7\u00e3o ou percep\u00e7\u00e3o da qualidade dos cuidados de sa\u00fade.<\/p>\n\n<p class=\"wp-block-paragraph\">Uma meta-an\u00e1lise de 2019, que incluiu cinco ensaios aleatorizados, n\u00e3o conseguiu mostrar uma diferen\u00e7a na satisfa\u00e7\u00e3o ou conhecimento dos doentes [14]. Uma conclus\u00e3o semelhante foi alcan\u00e7ada numa revis\u00e3o sistem\u00e1tica americana que comparou as apresenta\u00e7\u00f5es de cabeceira com outros tipos de apresenta\u00e7\u00f5es de pacientes em medicina interna, cirurgia e unidades de cuidados intensivos e n\u00e3o encontrou qualquer efeito nos resultados centrados no paciente [15].<\/p>\n\n<p class=\"wp-block-paragraph\">No entanto, os estudos inclu\u00eddos em ambos os trabalhos foram de qualidade baixa a moderada, mostraram uma marcada heterogeneidade em termos de resultados relatados e tinham recrutado apenas pequenas popula\u00e7\u00f5es de pacientes. Uma vez que as evid\u00eancias at\u00e9 \u00e0 data n\u00e3o permitiram quaisquer recomenda\u00e7\u00f5es, a quest\u00e3o levantou-se na pr\u00e1tica cl\u00ednica sobre se \u00e9 \u00fatil durante as rondas de enfermaria discutir todas as considera\u00e7\u00f5es diagn\u00f3sticas ou aspectos terap\u00eauticos directamente \u00e0 cabeceira do paciente ou se esta abordagem \u00e9 mais suscept\u00edvel de causar confus\u00e3o ou mesmo desconfian\u00e7a entre os nossos pacientes.<\/p>\n\n<p class=\"wp-block-paragraph\">A falta de provas levou os hospitais a variar a localiza\u00e7\u00e3o da apresenta\u00e7\u00e3o dos doentes durante a visita, de acordo com a prefer\u00eancia das pessoas envolvidas [16\u201318].<\/p>\n\n<h3 id=\"apresentacao-do-caso-a-beira-da-cama-versus-a-porta-um-estudo-multicentrico-randomizado-e-a-sua-relevancia-clinica\" class=\"wp-block-heading\">Apresenta\u00e7\u00e3o do caso \u00e0 beira da cama versus \u00e0 porta &#8211; um estudo multic\u00eantrico randomizado e a sua relev\u00e2ncia cl\u00ednica<\/h3>\n\n<p class=\"wp-block-paragraph\">O ensaio BEDSIDE-OUTTSIDE, um estudo multic\u00eantrico randomizado da Su\u00ed\u00e7a, investigou a influ\u00eancia do tipo de apresenta\u00e7\u00e3o do paciente (\u00e0 cabeceira do leito vs. fora do quarto do paciente) na compreens\u00e3o e percep\u00e7\u00e3o da qualidade dos cuidados de sa\u00fade por parte dos pacientes [19].<\/p>\n\n<p class=\"wp-block-paragraph\">O estudo BEDSIDE-OUTTSIDE foi realizado em tr\u00eas hospitais universit\u00e1rios su\u00ed\u00e7os e os seus resultados foram publicados na revista Annals of Internal Medicine [19]. Para este estudo, foram inclu\u00eddos pacientes consecutivos na admiss\u00e3o hospitalar que tiveram a sua primeira visita de consultor-chefe. Foram exclu\u00eddos pacientes com defici\u00eancia cognitiva, defici\u00eancia auditiva, pacientes que n\u00e3o conseguiam compreender a(s) l\u00edngua(s) local(is), e pacientes que tinham sido previamente inscritos no estudo ou que n\u00e3o deram o consentimento informado. Os pacientes foram ent\u00e3o distribu\u00eddos aleatoriamente ao &#8220;grupo de cabeceira de cama&#8221; (apresenta\u00e7\u00e3o dos pacientes \u00e0 cabeceira de cama) ou ao &#8220;grupo externo&#8221; (apresenta\u00e7\u00e3o dos pacientes fora do quarto do paciente).<\/p>\n\n<p class=\"wp-block-paragraph\">No grupo de cabeceira, as apresenta\u00e7\u00f5es de casos e\/ou discuss\u00f5es acad\u00e9micas tiveram lugar sem discuss\u00e3o pr\u00e9via \u00e0 porta, directamente \u00e0 cabeceira do paciente. No grupo externo, as apresenta\u00e7\u00f5es e discuss\u00f5es de casos de pacientes tiveram lugar principalmente no corredor sem a presen\u00e7a do paciente. A equipa de tratamento entrou ent\u00e3o no quarto e deu aos pacientes um breve resumo da situa\u00e7\u00e3o m\u00e9dica, e conduziu o resto da enfermaria \u00e0 cabeceira do paciente.<\/p>\n\n<p class=\"wp-block-paragraph\">O ensaio BEDSIDE-OUTTSIDE \u00e9 o primeiro grande ensaio multic\u00eantrico randomizado a mostrar que as visitas \u00e0 cabeceira do leito n\u00e3o afectam negativamente o conhecimento dos nossos pacientes. Os pacientes do grupo de beira do leito tinham conhecimentos subjectivos semelhantes aos dos pacientes aleatorizados para o grupo externo (m\u00e9dia, \u00b1 SD) (79,5 \u00b1 21,6 vs. 79,4 \u00b1 19,8, diferen\u00e7a ajustada 0,09 (95% CI -2,58 a 2,76; p=0,95)  <span style=\"font-family: franklin gothic demi;\">(Tab. 1).  <\/span>Os conhecimentos objectivos classificados pela equipa do estudo tamb\u00e9m n\u00e3o diferiram.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s12_1.png\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s12_1.png\" alt=\"\" class=\"wp-image-20212\" width=\"550\" height=\"508\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s12_1.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s12_1-800x738.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s12_1-120x111.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s12_1-90x83.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s12_1-320x295.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/12\/tab1_hp11_s12_1-560x517.png 560w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Em termos de efici\u00eancia temporal, as apresenta\u00e7\u00f5es dos pacientes \u00e0 cabeceira do leito foram consideradas mais eficientes em termos de tempo do que as apresenta\u00e7\u00f5es dos pacientes fora do quarto (m\u00e9dia, \u00b1 SD) (11,9 \u00b1 4,9 vs. 14,1 \u00b1 5,7 minutos, diferen\u00e7a ajustada -2,3 minutos (95% CI -3,0 a -1,6; p&lt;0,001). As visitas de cabeceira foram assim, em m\u00e9dia, 2,3 minutos mais curtas, o que pode muito bem ser relevante para a dura\u00e7\u00e3o total da visita.<\/p>\n\n<p class=\"wp-block-paragraph\">No entanto, o contacto directo m\u00e9dico-paciente foi mais longo no grupo de beira de cama. Al\u00e9m disso, os pacientes do grupo de beira de cama estimaram que os seus m\u00e9dicos gastavam cerca de 15 minutos mais por dia no seu tratamento. Mesmo que a diferen\u00e7a pare\u00e7a pequena \u00e0 primeira vista, este resultado pode ter importantes efeitos socioecon\u00f3micos. Assumindo que uma equipa de tratamento visita 20 pacientes, a diferen\u00e7a de tempo entre as visitas \u00e0 cabeceira da cama e as visitas ao exterior pode chegar a cerca de 45 minutos. A tarefa central do tratamento hospitalar \u00e9 proporcionar o melhor cuidado poss\u00edvel aos pacientes. Mas especialmente em tempos de DRG e pandemias, os recursos s\u00e3o muitas vezes limitados e a carga de trabalho elevada. As visitas de cabeceira parecem ser uma forma de poupar tempo sem afectar negativamente o conhecimento dos nossos pacientes.<\/p>\n\n<p class=\"wp-block-paragraph\">Por outro lado, os doentes aleatorizados para o grupo da cabeceira eram significativamente mais propensos a referir que se sentiam confusos com a terminologia m\u00e9dica (r\u00e1cio de risco ajustado 7,58 (3,67-11,49); p&lt;0,001) ou mesmo confusos com a discuss\u00e3o acad\u00e9mica (r\u00e1cio de risco ajustado 2,89 (0,30-5,49); p=0,029). Estes resultados est\u00e3o em conformidade com os resultados de um estudo americano de 1997, publicados no <em>New England Journal of Medicine<\/em> [20]. Lehmann et al. descobriu que parece haver uma associa\u00e7\u00e3o entre o n\u00edvel de educa\u00e7\u00e3o dos pacientes e a sua confus\u00e3o ou incerteza. Os pacientes com um baixo n\u00edvel de literacia de sa\u00fade, em particular, t\u00eam dificuldade em compreender os termos ou contextos m\u00e9dicos. Um inqu\u00e9rito su\u00ed\u00e7o de 2019-2021 mostrou que cerca de metade da popula\u00e7\u00e3o tem baixa literacia sanit\u00e1ria. As discuss\u00f5es acad\u00e9micas envolvendo o uso de terminologia m\u00e9dica durante as visitas de cabeceira poderiam causar confus\u00e3o e incerteza para estes pacientes em particular. H\u00e1 alguns anos, o British Royal College of General Practitioners apelou aos m\u00e9dicos para que falassem devagar e evitassem o jarg\u00e3o m\u00e9dico [21]. Mesmo termos como &#8220;cr\u00f3nicos&#8221; ou &#8220;resultados positivos&#8221; n\u00e3o s\u00e3o familiares a muitos pacientes e o seu significado n\u00e3o \u00e9, portanto, claro. A falta de compreens\u00e3o da sua pr\u00f3pria doen\u00e7a e do seu tratamento pode, por sua vez, levar a que os pacientes sejam internados mais frequentemente numa emerg\u00eancia ou sofram de problemas de sa\u00fade graves [22]. Portanto, \u00e9 elementar que prestemos aten\u00e7\u00e3o \u00e0 express\u00e3o amiga do paciente e evitemos termos t\u00e9cnicos, especialmente durante as visitas de cabeceira.<\/p>\n\n<p class=\"wp-block-paragraph\">A comunica\u00e7\u00e3o centrada no paciente pode levar a uma melhor compreens\u00e3o da situa\u00e7\u00e3o de sa\u00fade do paciente e assim facilitar o seu envolvimento na tomada de decis\u00f5es durante as rondas da enfermaria.<\/p>\n\n<p class=\"wp-block-paragraph\">Uma an\u00e1lise secund\u00e1ria do ensaio BEDSIDE-OUTTSIDE mostrou que cerca de 80% dos doentes querem estar envolvidos em decis\u00f5es m\u00e9dicas ou mesmo tomar as suas pr\u00f3prias decis\u00f5es [23]. A prefer\u00eancia dos pacientes por estarem ou n\u00e3o envolvidos na tomada de decis\u00f5es foi um preditor importante da percep\u00e7\u00e3o da qualidade dos cuidados de sa\u00fade no estudo. Os pacientes que queriam tomar as suas pr\u00f3prias decis\u00f5es estavam significativamente menos satisfeitos com a sua estadia no hospital e tinham menos confian\u00e7a nos seus m\u00e9dicos e enfermeiros. Portanto, \u00e9 vantajoso aqui &#8211; especialmente para decis\u00f5es importantes &#8211; trabalhar e ter em conta a prefer\u00eancia do paciente.<\/p>\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o ensaio BEDSIDE-OUTTSIDE descobriu que quest\u00f5es sens\u00edveis tais como comorbilidades psiqui\u00e1tricas, falta de ades\u00e3o ao tratamento ou ambiguidades m\u00e9dicas foram significativamente menos abordadas durante as visitas de cabeceira (odds ratio ajustado 0,72 (0,54-0,97); p=0,033). Poder-se-ia supor que durante as visitas de cabeceira, quest\u00f5es sens\u00edveis n\u00e3o foram discutidas em frente de outros colegas doentes por raz\u00f5es de confidencialidade. Contudo, o estudo descobriu que a equipa de tratamento n\u00e3o abordou aspectos sens\u00edveis mesmo durante os interrogat\u00f3rios ap\u00f3s a visita, ignorando-os assim completamente. Estudos mais antigos mostram, contudo, que temas sens\u00edveis como o bem-estar psicol\u00f3gico ou a experi\u00eancia de doen\u00e7a subjectiva s\u00e3o considerados pelos doentes como temas priorit\u00e1rios de uma visita e devem, portanto, ser abordados [24].<\/p>\n\n<p class=\"wp-block-paragraph\">Numa an\u00e1lise secund\u00e1ria posterior do ensaio BEDSIDE-OUTTSIDE, os autores investigaram a comunica\u00e7\u00e3o interprofissional durante as rondas das enfermarias e a prefer\u00eancia de m\u00e9dicos e enfermeiros em rela\u00e7\u00e3o ao tipo de apresenta\u00e7\u00f5es dos pacientes [25]. Descobriu-se que os prestadores de cuidados preferiam visitas de cabeceira porque se sentiam mais integrados e valorizados e tinham a impress\u00e3o de que podiam exprimir melhor as suas pr\u00f3prias preocupa\u00e7\u00f5es. Uma raz\u00e3o poderia ser que as visitas externas s\u00e3o mais orientadas academicamente e t\u00eam um maior enfoque no ensino aos residentes do que nos aspectos pr\u00e1ticos dos cuidados aos doentes. Isto pode resultar num menor envolvimento das enfermeiras aqui, ao mesmo tempo que se envolvem mais em discuss\u00f5es centradas no paciente \u00e0 beira do leito.<\/p>\n\n<p class=\"wp-block-paragraph\">Os m\u00e9dicos, por outro lado, favoreceram as visitas externas porque se sentiram menos desconfort\u00e1veis a discutir quest\u00f5es sens\u00edveis. As t\u00e9cnicas de comunica\u00e7\u00e3o que tornam mais f\u00e1cil levantar quest\u00f5es sens\u00edveis poderiam assim aumentar a confian\u00e7a no tratamento das mesmas e assim a satisfa\u00e7\u00e3o dos m\u00e9dicos com as visitas de cabeceira.<\/p>\n\n<h3 id=\"como-pode-ser-optimizada-a-comunicacao\" class=\"wp-block-heading\">Como pode ser optimizada a comunica\u00e7\u00e3o?<\/h3>\n\n<p class=\"wp-block-paragraph\">No per\u00edodo que antecedeu a confer\u00eancia, foi tamb\u00e9m discutido a n\u00edvel m\u00e9dico-pol\u00edtico que a falta de compet\u00eancias comunicativas por parte dos m\u00e9dicos se devia principalmente a um &#8220;programa de estudos deficiente, demasiado som\u00e1tico, orientado para os factos e para o desempenho&#8221; [26].<\/p>\n\n<p class=\"wp-block-paragraph\">Em numerosos pa\u00edses europeus, o programa de estudo &#8220;Medicina Humana&#8221; foi reformado nos \u00faltimos anos, no \u00e2mbito do Processo de Bolonha. A faculdade de medicina da Universidade de Basileia utilizou a mudan\u00e7a para uma estrutura de Bacharelato\/Mestrado para implementar um curr\u00edculo longitudinal &#8220;compet\u00eancias sociais e de comunica\u00e7\u00e3o&#8221; [27]. Desde o primeiro bacharelato at\u00e9 ao primeiro ano de Mestrado, as compet\u00eancias comunicativas s\u00e3o ensinadas longitudinalmente em conjunto com o conte\u00fado cl\u00ednico. Estas incluem t\u00e9cnicas centradas no paciente (abertura do espa\u00e7o), tais como ESC (esperar, repetir, espelhar, resumir) ou responder \u00e0s emo\u00e7\u00f5es com a ajuda do modelo NURSE (Naming emotion, Understanding, Respecting, Supporting, Exploring), bem como t\u00e9cnicas centradas no m\u00e9dico, tais como estruturar explicitamente a conversa. Al\u00e9m disso, as t\u00e9cnicas de comunica\u00e7\u00e3o &#8220;Shared decision-making&#8221;, &#8220;Motivational Interviewing&#8221; e &#8220;Breaking bad news&#8221; s\u00e3o ensinadas em palestras e workshops pr\u00e1ticos. O objectivo do curr\u00edculo \u00e9 que os pacientes n\u00e3o sejam apenas experimentados como &#8220;casos de doen\u00e7a&#8221; som\u00e1ticos, mas que os estudantes tamb\u00e9m compreendam o significado da doen\u00e7a para o indiv\u00edduo e aprendam a abordar quest\u00f5es e aspectos emocionais. Numerosos estudos na \u00e1rea da educa\u00e7\u00e3o dos estudantes mostram que as compet\u00eancias comunicativas podem ser ensinadas e as compet\u00eancias dos futuros m\u00e9dicos podem ser melhoradas [28].  <\/p>\n\n<p class=\"wp-block-paragraph\">A import\u00e2ncia da comunica\u00e7\u00e3o em medicina foi sublinhada por um relat\u00f3rio de situa\u00e7\u00e3o hist\u00f3rico sobre a comunica\u00e7\u00e3o no sistema de sa\u00fade do Reino Unido apoiado pela Funda\u00e7\u00e3o Marie Curie [29]. O relat\u00f3rio concluiu que a m\u00e1 comunica\u00e7\u00e3o no sector da sa\u00fade tem um impacto negativo na qualidade dos cuidados m\u00e9dicos e nos resultados dos pacientes. Al\u00e9m disso, os autores descobriram que a m\u00e1 capacidade de comunica\u00e7\u00e3o desperdi\u00e7a recursos, cujos danos foram estimados pelos autores em \u00a31 bili\u00e3o\/ano no Reino Unido. Al\u00e9m disso, as compet\u00eancias comunicativas s\u00e3o capazes n\u00e3o s\u00f3 de aumentar a satisfa\u00e7\u00e3o dos nossos pacientes, mas tamb\u00e9m de reduzir a taxa de burnout do pessoal m\u00e9dico.<\/p>\n\n<p class=\"wp-block-paragraph\">As compet\u00eancias comunicativas s\u00e3o consideradas por muitas sociedades profissionais como uma compet\u00eancia m\u00e9dica essencial, o que levou ao facto de o conte\u00fado pedag\u00f3gico sobre compet\u00eancias comunicativas fazer agora parte do cat\u00e1logo obrigat\u00f3rio de disciplinas nas universidades m\u00e9dicas na Su\u00ed\u00e7a. Os m\u00e9dicos em forma\u00e7\u00e3o complementar em hematologia\/oncologia devem completar v\u00e1rios dias de forma\u00e7\u00e3o em comunica\u00e7\u00e3o a fim de obter o t\u00edtulo de especialista, uma vez que a comunica\u00e7\u00e3o e a resposta \u00e0s necessidades psicossociais dos doentes \u00e9 considerada uma componente elementar dos cuidados de alta qualidade para os doentes com cancro [30]. Por outro lado, a forma\u00e7\u00e3o cont\u00ednua de outros empregados no sector da sa\u00fade \u00e9 muitas vezes menos claramente descrita.<\/p>\n\n<p class=\"wp-block-paragraph\">A forma\u00e7\u00e3o regular em comunica\u00e7\u00e3o para todo o pessoal m\u00e9dico, que retoma exemplos t\u00edpicos da vida cl\u00ednica di\u00e1ria (tais como conversas durante uma ronda de enfermaria), poderia dar um contributo importante para reduzir mal-entendidos e aumentar a satisfa\u00e7\u00e3o dos pacientes. S\u00e3o tamb\u00e9m necess\u00e1rias mais provas em \u00e1reas clinicamente relevantes e comunicativamente desafiantes, para que estas possam ser adequadamente incorporadas no ensino e na forma\u00e7\u00e3o cont\u00ednua. No que respeita \u00e0 comunica\u00e7\u00e3o das visitas, deve ser dada especial aten\u00e7\u00e3o \u00e0 comunica\u00e7\u00e3o mais centrada no paciente durante as visitas, a fim de evitar confus\u00e3o e incerteza e de dar aos pacientes espa\u00e7o para falar sobre temas e quest\u00f5es que lhes sejam relevantes. Por parte da equipa de tratamento, \u00e9 tamb\u00e9m importante desenvolver t\u00e9cnicas que facilitem a abordagem profissional de quest\u00f5es sens\u00edveis, sem perturbar ou desprezar os pacientes, especialmente durante as visitas de cabeceira.<\/p>\n\n<h3 id=\"mensagens-para-levar-para-casa\" class=\"wp-block-heading\">Mensagens para levar para casa<\/h3>\n\n<ul class=\"wp-block-list\">\n<li>As rondas s\u00e3o uma base elementar de cuidados centrados no doente.<\/li>\n\n\n\n<li>As apresenta\u00e7\u00f5es de cabeceira s\u00e3o mais eficazes em termos de tempo, mas podem causar mais confus\u00e3o e incerteza.<\/li>\n\n\n\n<li>A forma\u00e7\u00e3o em compet\u00eancias de comunica\u00e7\u00e3o pode contribuir para melhorar os cuidados ao paciente e \u00e9, portanto, uma compet\u00eancia m\u00e9dica essencial que pode ser aprendida.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Daschle T, Domenici P, Frist W, et al.: Prescription for patient-centered care and cost containment. N Engl J Med 2013; 369(5): 471\u2013474; doi: 10.1056\/NEJMsb1306639.<\/li>\n\n\n\n<li>Stewart M: Towards a global definition of patient centred care. BMJ 2001; 322(7284): 444\u2013445; doi: 10.1136\/bmj.322.7284.444.<\/li>\n\n\n\n<li>Bardes CL: Defining \u00abpatient-centered medicine\u00bb. N Engl J Med 2012; 366(9): 782\u2013783; doi: 10.1056\/NEJMp1200070.<\/li>\n\n\n\n<li>Zwarenstein M, Goldman J, Reeves S: Interprofessional collaboration: effects of practice-based interventions on professional practice and healthcare outcomes. Cochrane Database Syst Rev 2009; 3: CD000072; doi: 10.1002\/14651858.CD000072.pub2.<\/li>\n\n\n\n<li>O\u2019Mahony S, Mazur E, Charney P, et al.: Use of multidisciplinary rounds to simultaneously improve quality outcomes, enhance resident education, and shorten length of stay. J Gen Intern Med 2007; 22(8): 1073\u20131079M; doi: 10.1007\/s11606-007-0225-1.<\/li>\n\n\n\n<li>Pucher PH, Aggarwal R, Darzi A: Surgical ward round quality and impact on variable patient outcomes. Ann Surg 2014; 259(2): 222-226; doi: 10.1097\/SLA.0000000000000376.<\/li>\n\n\n\n<li>Royal College of Physicians RCoN. Ward rounds in medicine: principles for best practice. 2015 (London: RCP, 2012.).<\/li>\n\n\n\n<li>Chapple A, Campion P, May C: Clinical terminology: anxiety and confusion amongst families undergoing genetic counseling. Patient education and counseling 1997; 32(1\u20132): 81\u201391.<\/li>\n\n\n\n<li>Hadlow J, Pitts M: The understanding of common health terms by doctors, nurses and patients. Soc Sci Med 1991; 32(2): 193\u2013196.<\/li>\n\n\n\n<li>Chapman K, Abraham C, Jenkins V, et al.: Lay understanding of terms used in cancer consultations. Psycho-oncology 2003; 12(6): 557\u2013566; doi: 10.1002\/pon.673.<\/li>\n\n\n\n<li>DiMatteo MR, Giordani PJ, Lepper HS, et al.: Patient adherence and medical treatment outcomes: a meta-analysis. Med Care 2002; 40(9): 794\u2013811; doi: 10.1097\/00005650-200209000-00009.<\/li>\n\n\n\n<li>Conn VS, Ruppar TM, Enriquez M, et al.: Patient-Centered Outcomes of Medication Adherence Interventions: Systematic Review and Meta-Analysis. Value Health 2016; 19(2): 277\u2013285; doi: 10.1016\/j.jval.2015.12.001.<\/li>\n\n\n\n<li>Clarke C, Friedman SM, Shi K, et al.: Emergency department discharge instructions comprehension and compliance study. CJEM 2005; 7(1): 5\u201311; doi: 10.1017\/s1481803500012860.<\/li>\n\n\n\n<li>Gamp M, Becker C, Tondorf T, et al.: Effect of Bedside vs. Non-bedside Patient Case Presentation During Ward Rounds: a Systematic Review and Meta-analysis. J Gen Intern Med 2019; 34(3): 447\u2013457; doi: 10.1007\/s11606-018-4714-1.<\/li>\n\n\n\n<li>Ratelle JT, Sawatsky AP, Kashiwagi DT, et al.: Implementing bedside rounds to improve patient-centred outcomes: a systematic review. BMJ Qual Saf 2019; 28(4): 317\u2013326; doi: 10.1136\/bmjqs-2017-007778.<\/li>\n\n\n\n<li>Gonzalo JD, Chuang CH, Huang G, et al.: The return of bedside rounds: an educational intervention. J Gen Intern Med 2010; 25(8): 792\u2013798; doi: 10.1007\/s11606-010-1344-7.<\/li>\n\n\n\n<li>Stickrath C, Noble M, Prochazka A, et al.: Attending rounds in the current era: what is and is not happening. JAMA Intern Med 2013; 173(12): 1084\u20131089; doi: 10.1001\/jamainternmed.2013.6041.<\/li>\n\n\n\n<li>Peters M, Ten Cate O: Bedside teaching in medical education: a literature review. Perspect Med Educ 2014; 3(2): 76\u201388; doi: 10.1007\/s40037-013-0083-y.<\/li>\n\n\n\n<li>Becker C, Gamp M, Schuetz P, et al.: Effect of Bedside Compared With Outside the Room Patient Case Presentation on Patients\u2019 Knowledge About Their Medical Care: A Randomized, Controlled, Multicenter Trial. Ann Intern Med 2021; 174(9): 1282\u20131292; doi: 10.7326\/M21-0909.<\/li>\n\n\n\n<li>Lehmann LS, Brancati FL, Chen MC, et al.: The effect of bedside case presentations on patients\u2019 perceptions of their medical care. N Engl J Med 1997; 336(16): 1150\u20131155; doi: 10.1056\/NEJM199704173361606.<\/li>\n\n\n\n<li>Rimmer A: Doctors must avoid jargon when talking to patients, royal college says. BMJ 2014; 348: g4131.<\/li>\n\n\n\n<li>Berkman ND, Sheridan SL, Donahue KE, et al.: Low health literacy and health outcomes: an updated systematic review. Ann Intern Med 2011; 155(2): 97-107; doi: 10.7326\/0003-4819-155-2-201107190-00005.<\/li>\n\n\n\n<li>Becker C, Gross S, Gamp M, et al.: Patients&#8217; Preference for Participation in Medical Decision-Making: Secondary Analysis of the BEDSIDE-OUTSIDE Trial. J Gen Intern Med 2022; doi: 10.1007\/s11606-022-07775-z.<\/li>\n\n\n\n<li>K\u00f6hle K, Raspe H: Das Gespr\u00e4ch w\u00e4hrend der \u00e4rztlichen Visite. M\u00fcnchen-Wien-Baltimore: Urban &amp; Schwarzenberg 1982.<\/li>\n\n\n\n<li>Gross S, Beck K, Becker C, et al.: Perception of physicians and nursing staff members regarding outside versus bedside ward rounds: ancillary analysis of the randomised BEDSIDE-OUTSIDE trial. Swiss Med Wkly 2022; 152: w30112; doi: 10.4414\/smw.2022.w30112.<\/li>\n\n\n\n<li>Geisler L: Kommunikation bei der Patientenvisite &#8211; Ausdruck unsererer ethischen Werthaltung 2003 [Dispon\u00edvel em: www.linus-geisler.de\/vortraege\/0314patientenvisite.html, acedido a 5 de Outubro de 2022].<\/li>\n\n\n\n<li>Kiessling C, Langewitz W: The longitudinal curriculum \u00absocial and communicative competencies\u00bb within Bologna-reformed undergraduate medical education in Basel. GMS Z Med Ausbild 2013; 30(3): Doc31; doi: 10.3205\/zma000874.<\/li>\n\n\n\n<li>Smith S, Hanson JL, Tewksbury LR, et al.: Teaching patient communication skills to medical students: a review of randomized controlled trials. Eval Health Prof 2007; 30(1): 3\u201321; doi: 10.1177\/0163278706297333.<\/li>\n\n\n\n<li>McDonald A: A long and winding road: improving communication with patients in the NHS. London, 2016.<\/li>\n\n\n\n<li>Adler NE, Page AEK, eds. Cancer Care for the Whole Patient: Meeting Psychosocial Health Needs. Washington (DC) 2008.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><em>HAUSARZT PRAXIS 2022; 17(11): 10\u201314<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medicina centrada no paciente, que respeita e integra prefer\u00eancias, valores ou necessidades individuais, tornou-se cada vez mais importante nos \u00faltimos anos nos cuidados ao paciente. Nos cuidados cl\u00ednicos, \u00e9&hellip;<\/p>\n","protected":false},"author":7,"featured_media":126705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Rondas centradas no paciente em medicina","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11521,22618,11524,11305,11474,11551],"tags":[12192,12191,11754,12193],"powerkit_post_featured":[],"class_list":["post-323953","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudos","category-formacao-cme","category-formacao-continua","category-medicina-interna-geral","category-prevencao-e-cuidados-de-saude","category-rx-pt","tag-comunicacao-medico-doente","tag-cuidados-aos-doentes","tag-formacao-cme","tag-rondas-centradas-no-paciente","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:35:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":323968,"slug":"alinear-la-atencion-con-el-paciente-2","post_title":"Alinear la atenci\u00f3n con el paciente","href":"https:\/\/medizinonline.com\/es\/alinear-la-atencion-con-el-paciente-2\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/323953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=323953"}],"version-history":[{"count":2,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/323953\/revisions"}],"predecessor-version":[{"id":368632,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/323953\/revisions\/368632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/126705"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=323953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=323953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=323953"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=323953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}