{"id":324245,"date":"2022-11-09T10:57:02","date_gmt":"2022-11-09T09:57:02","guid":{"rendered":"https:\/\/medizinonline.com\/a-dor-nao-e-igual-a-dor\/"},"modified":"2022-11-09T10:57:02","modified_gmt":"2022-11-09T09:57:02","slug":"a-dor-nao-e-igual-a-dor","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/a-dor-nao-e-igual-a-dor\/","title":{"rendered":"A dor n\u00e3o \u00e9 igual \u00e0 dor"},"content":{"rendered":"<p><strong>Os investigadores do Centro M\u00e9dico da Universidade de Mainz descobriram que a chamada polineuropatia diab\u00e9tica dolorosa n\u00e3o \u00e9 apenas causada por nervos danificados, mas tamb\u00e9m pode ser muscular. Os doentes diab\u00e9ticos de tipo 2 com ambas as causas de dor tinham uma intensidade de dor mais elevada, pior toler\u00e2ncia e defici\u00eancia psicol\u00f3gica. Com base nas novas descobertas que descobriram, a equipa de investiga\u00e7\u00e3o argumenta que o rastreio de rotina deve tamb\u00e9m ter em conta os mecanismos musculares. Isto poderia levar a um melhor diagn\u00f3stico, bem como a uma terapia mais direccionada e, portanto, mais bem sucedida para muitas pessoas afectadas.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>A dor que ocorre no contexto de uma doen\u00e7a diab\u00e9tica pode ter v\u00e1rias causas. Os cientistas do Departamento de Neurologia do Centro M\u00e9dico da Universidade de Mainz demonstraram isto num estudo cl\u00ednico abrangente. Cerca de um quarto dos doentes com a chamada polineuropatia diab\u00e9tica dolorosa tinha dores nos nervos e dores relacionadas com os m\u00fasculos. Outra descoberta importante foi que estes pacientes tinham defici\u00eancias f\u00edsicas e psicol\u00f3gicas significativamente maiores do que aqueles com apenas dores relacionadas com os nervos. Os investigadores defendem, portanto, o rastreio de rotina das dores relacionadas com os m\u00fasculos. Isto poderia melhorar o diagn\u00f3stico e a terapia para muitos pacientes. Os resultados do estudo foram agora publicados na conceituada revista&nbsp;&#8220;Diabetes Care&#8221;&nbsp;.<\/p>\n<p>&#8220;As nossas descobertas sobre as causas da dor na polineuropatia diab\u00e9tica s\u00e3o de grande import\u00e2ncia para as pessoas afectadas. Abrem a possibilidade de op\u00e7\u00f5es terap\u00eauticas causais e personalizadas e de uma utiliza\u00e7\u00e3o mais direccionada de estrat\u00e9gias de tratamento n\u00e3o farmacol\u00f3gico e medicamentoso&#8221;, explica o Dr. Frank Birklein, Director Cl\u00ednico e Chefe da Sec\u00e7\u00e3o de Neurologia Perif\u00e9rica e Dor do Departamento de Neurologia do Centro M\u00e9dico da Universidade de Mainz.<\/p>\n<p>Sob a direc\u00e7\u00e3o do Professor Birklein, o grupo de trabalho&nbsp;&#8220;Pain &#8211; Autonomic Nervous System&#8221;&nbsp;da Cl\u00ednica e Policl\u00ednica de Neurologia do Centro M\u00e9dico da Universidade de Mainz examinou um total de 69 pessoas afectadas com polineuropatia diab\u00e9tica causada por diabetes mellitus tipo 2. Isto foi associado \u00e0 dor em 41 pacientes. A fim de avaliar as defici\u00eancias individuais dos participantes, os investigadores realizaram um exame cl\u00ednico exaustivo, que incluiu testes normalizados, bem como um exame exaustivo do fen\u00f3tipo sens\u00edvel e da modula\u00e7\u00e3o da dor end\u00f3gena. Al\u00e9m disso, foram tamb\u00e9m utilizados question\u00e1rios de auto-avalia\u00e7\u00e3o dos sintomas depressivos, sintomas de ansiedade e defici\u00eancias relacionadas com a polineuropatia para avaliar a dor.<\/p>\n<p>O resultado: Todos os 41 pacientes com polineuropatia diab\u00e9tica dolorosa preenchiam os crit\u00e9rios para dor relacionada com os nervos (neurop\u00e1tica). Em 22 por cento deles, foi tamb\u00e9m encontrada outra forma de dor que tem a sua causa na musculatura: A chamada dor miofascial \u00e9 caracterizada por pontos de desencadeamento muscular activos. Estes endurecimentos no tecido muscular provocam dor quando palpados directamente ou durante o esfor\u00e7o f\u00edsico. Nos pacientes examinados, os dolorosos pontos de desencadeamento muscular localizavam-se nos m\u00fasculos anteriores ou posteriores da barriga da perna e nos pequenos m\u00fasculos da planta do p\u00e9. Em 89 por cento dos participantes, ocorreram de ambos os lados. Na maioria dos casos (78 por cento), eram sim\u00e9tricos.&nbsp;<\/p>\n<p>No que respeita aos efeitos f\u00edsicos e psicol\u00f3gicos da polineuropatia diab\u00e9tica, os doentes com uma componente adicional de dor miofascial diferiram claramente dos afectados com dor exclusivamente neurop\u00e1tica: os participantes com ambas as formas de dor mostraram maior intensidade de dor e menor toler\u00e2ncia \u00e0 dor. Al\u00e9m disso, tinham pontua\u00e7\u00f5es de ansiedade e depress\u00e3o mais elevadas e relatavam maiores defici\u00eancias relacionadas com a polineuropatia em aspectos como o sono, as rela\u00e7\u00f5es sociais ou a capacidade de andar.<\/p>\n<p>A diabetes mellitus \u00e9 a doen\u00e7a metab\u00f3lica mais comum nos pa\u00edses ocidentais. Nos \u00faltimos anos, o n\u00famero de pessoas com diabetes mellitus tipo 2 em particular tem aumentado. Na Alemanha, cerca de 500.000 pessoas contraem este tipo de diabetes todos os anos. Cerca de metade de todos os pacientes com diabetes desenvolvem polineuropatia. Em cerca de metade das pessoas afectadas, h\u00e1 danos no sistema nervoso perif\u00e9rico, a parte do sistema nervoso que fica fora do c\u00e9rebro e da medula espinal. Na polineuropatia, as m\u00e3os e os p\u00e9s s\u00e3o particularmente afectados pelos danos nos nervos. Os sintomas comuns da doen\u00e7a s\u00e3o perturba\u00e7\u00f5es sensoriais tais como formigueiro e dorm\u00eancia. At\u00e9 um ter\u00e7o dos doentes diab\u00e9ticos com polineuropatia tamb\u00e9m sentem dores que interferem com muitas \u00e1reas da vida, tais como o trabalho, actividades sociais ou sono. Em muitos casos, isto \u00e9 acompanhado por um desenvolvimento depressivo.<\/p>\n<p>At\u00e9 \u00e0 data, a dor na polineuropatia diab\u00e9tica tem sido, na sua maioria, de base neurop\u00e1tica. Isto significa que se assume que a causa da dor \u00e9 apenas um dano ao sistema nervoso. A terapia e o desenvolvimento de novas op\u00e7\u00f5es de tratamento da dor em polineuropatia diab\u00e9tica est\u00e3o tamb\u00e9m a ser realizados especificamente para esta forma de dor. Poss\u00edveis outros componentes individuais, tais como causas de dor no tecido, nos ossos ou nos m\u00fasculos, por outro lado, ainda n\u00e3o foram tidos em conta como padr\u00e3o. Isto leva a um sucesso terap\u00eautico muito heterog\u00e9neo e, em muitos casos, apenas moderado.&nbsp;<\/p>\n<p>&#8220;Com base nos resultados do nosso estudo, recomendamos o rastreio de rotina da dor miofascial em doentes com polineuropatia diab\u00e9tica dolorosa, tanto no tratamento individual como nos ensaios de medicamentos. Isto seria f\u00e1cil de implementar na pr\u00e1tica, adaptando o exame cl\u00ednico. Desta forma, poder\u00e3o ser alcan\u00e7ados sucessos terap\u00eauticos significativamente melhorados no futuro&#8221;, salienta o autor correspondente PD Dr. Christian Geber, professor associado na Cl\u00ednica e Policl\u00ednica de Neurologia no Centro M\u00e9dico Universit\u00e1rio Mainz e m\u00e9dico s\u00e9nior no Centro de Dor DRK Mainz.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:&nbsp;<\/p>\n<p>Escolano-Lozano F, et al.: Neuropatia diab\u00e9tica dolorosa &#8211; a dor miofascial faz a diferen\u00e7a. Diabetes Care (2022); DOI: https:\/\/doi.org\/10.2337\/dc22-1023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os investigadores do Centro M\u00e9dico da Universidade de Mainz descobriram que a chamada polineuropatia diab\u00e9tica dolorosa n\u00e3o \u00e9 apenas causada por nervos danificados, mas tamb\u00e9m pode ser muscular. Os doentes&hellip;<\/p>\n","protected":false},"author":16,"featured_media":126670,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Diabetes","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11397,11521,11305,11374,11551],"tags":[],"powerkit_post_featured":[],"class_list":["post-324245","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologia-e-diabetologia-2","category-estudos","category-medicina-interna-geral","category-neurologia-pt-pt","category-rx-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 14:19:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":324252,"slug":"el-dolor-no-es-igual-al-dolor","post_title":"El dolor no es igual al dolor","href":"https:\/\/medizinonline.com\/es\/el-dolor-no-es-igual-al-dolor\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/324245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=324245"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/324245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/126670"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=324245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=324245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=324245"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=324245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}