{"id":325706,"date":"2022-05-25T01:00:00","date_gmt":"2022-05-24T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/mascara-dermatite-dicas-especializadas-para-profilaxia-e-tratamento\/"},"modified":"2022-05-25T01:00:00","modified_gmt":"2022-05-24T23:00:00","slug":"mascara-dermatite-dicas-especializadas-para-profilaxia-e-tratamento","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/mascara-dermatite-dicas-especializadas-para-profilaxia-e-tratamento\/","title":{"rendered":"M\u00e1scara dermatite &#8211; dicas especializadas para profilaxia e tratamento"},"content":{"rendered":"<p><strong>Durante a pandemia da coroa, observou-se um aumento das les\u00f5es cut\u00e2neas faciais devido ao uso de uma protec\u00e7\u00e3o de nariz e boca. O uso de uma m\u00e1scara protectora FFP2 continuar\u00e1 a ser recomendado em muitos locais, especialmente no sector m\u00e9dico, para reduzir o risco de infec\u00e7\u00e3o com o coronav\u00edrus. Para pessoas que t\u00eam de usar uma m\u00e1scara permanentemente, os peritos do DDG aconselham um conceito individualizado de limpeza e cuidado da pele.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>&#8220;Para muitas pessoas, a m\u00e1scara FFP2 continuar\u00e1 a ser um companheiro di\u00e1rio, porque a protec\u00e7\u00e3o de grupos vulner\u00e1veis, por exemplo em lares ou cl\u00ednicas, vem em primeiro lugar&#8221;, diz o Prof. Peter Elsner, MD, Rela\u00e7\u00f5es P\u00fablicas da Sociedade Alem\u00e3 de Dermatologia (DDG) [1]. Estudos emp\u00edricos mostram que o uso intensivo de m\u00e1scaras pode causar altera\u00e7\u00f5es cut\u00e2neas que ou ocorrem pela primeira vez ou pioram as dermatoses j\u00e1 existentes na zona facial [2].<\/p>\n<p>Num estudo recente da Universidade de Osnabr\u00fcck (D), cerca de 80% dos enfermeiros e m\u00e9dicos inquiridos referiram sofrer de sinais de dermatite de m\u00e1scara, e num estudo anterior da China, cerca de 97% do pessoal cl\u00ednico inquirido tinha desenvolvido sintomas de pele relacionados com a m\u00e1scara na ponte do nariz, bochechas e testa [3,4]. Especialmente quando usado durante mais de 6 horas, o risco parece ser aumentado.<\/p>\n<h2 id=\"o-efeito-de-oclusao-da-mascara-prejudica-o-ambiente-cutaneo\">O efeito de oclus\u00e3o da m\u00e1scara prejudica o ambiente cut\u00e2neo<\/h2>\n<p>&#8220;J\u00e1 t\u00ednhamos algum conhecimento antes da pandemia da coroa sobre como a pele facial reage ao uso de uma m\u00e1scara: por vezes fica irritada, reage com inflama\u00e7\u00e3o ou comich\u00e3o&#8221;, diz o Prof. Elsner [1]. Sob a m\u00e1scara, o teor de humidade da camada c\u00f3rnea e a perda de \u00e1gua atrav\u00e9s da pele s\u00e3o aumentados. A barreira cut\u00e2nea \u00e9 afectada. A temperatura da pele, a produ\u00e7\u00e3o de sebo e o aumento do valor de pH. O ambiente cut\u00e2neo \u00e9 perturbado devido ao efeito de oclus\u00e3o da m\u00e1scara. O atrito mec\u00e2nico na pele facial agrava a apar\u00eancia da pele, especialmente no caso de doen\u00e7as de pele j\u00e1 existentes como a acne ou a ros\u00e1cea.<\/p>\n<p>A quest\u00e3o de como o uso de uma protec\u00e7\u00e3o bucal (MNS) afecta a pele facial do pessoal de enfermagem ou terap\u00eautico foi o foco de um estudo emp\u00edrico realizado por uma equipa de investiga\u00e7\u00e3o liderada pelo Prof. Dr. med. Christoph Skudlik do Instituto de Preven\u00e7\u00e3o e Reabilita\u00e7\u00e3o Dermatol\u00f3gica Interdisciplinar (iDerm) da Universidade de Osnabr\u00fcck [3].<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-18920\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/05\/ubersicht1_dp2_s43.png\" style=\"height:394px; width:600px\" width=\"1100\" height=\"723\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"o-estudo-mostra-um-aumento-dramatico-das-lesoes-cutaneas-faciais\">O estudo mostra um aumento dram\u00e1tico das les\u00f5es cut\u00e2neas faciais<\/h2>\n<p>192 trabalhadores da sa\u00fade participaram no estudo de inqu\u00e9rito escrito realizado em Novembro de 2021. O tempo m\u00e9dio di\u00e1rio de uso de um MNS somado at\u00e9 0,6 \u00b1 1,7 horas antes da pandemia e 9,0 \u00b1 1,9 horas durante a pandemia. 10,9% dos 192 participantes declararam que j\u00e1 tinham sofrido altera\u00e7\u00f5es de pele na \u00e1rea facial antes da introdu\u00e7\u00e3o das medidas de higiene associadas ao Covid 19, que foram auto-avaliadas como sendo devidas ao uso de um MNS. Para 80,7% dos 192 participantes, estes efeitos s\u00f3 ocorreram desde a introdu\u00e7\u00e3o do uso obrigat\u00f3rio da m\u00e1scara. O uso da m\u00e1scara do FFP2 foi citado como o gatilho mais comum da mudan\u00e7a de pele. Para os peritos do DDG Prof. Elsner e Prof. Skudlik, as altera\u00e7\u00f5es na pele do rosto causadas pelo uso de uma m\u00e1scara devem ser levadas muito a s\u00e9rio. &#8220;Aconselhamos os empregados a informar sobre a preven\u00e7\u00e3o de altera\u00e7\u00f5es cut\u00e2neas. Os conceitos individualizados de limpeza e cuidados da pele devem ser aplicados na pr\u00e1tica da dermatologia ocupacional&#8221;, sublinha o Prof. Skudlik, que \u00e9 tamb\u00e9m presidente do Grupo de Trabalho de Dermatologia Ocupacional e Ambiental do DDG [1]. Elsner acrescenta: &#8220;Estamos conscientes de que algumas pessoas est\u00e3o preocupadas com a sua pele facial. Contudo, com a profilaxia e tratamento adequados, \u00e9 muito raramente necess\u00e1rio deixar de usar uma m\u00e1scara por completo&#8221; [1].<\/p>\n<p>\n<em>Congresso:&nbsp;Sociedade Alem\u00e3 de Dermatologia<\/em><br \/>\n&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>&#8220;Corona protection vs. skin health: What protecting against mask dermatitis and what helps against it&#8221;, Deutsche Dermatologische Gesellschaft e. V. (DDG), 28.03.2022<\/li>\n<li>Seguro de Acidentes Sociais Alem\u00e3o (DGUV), https:\/\/forum.dguv.de\/ausgabe\/5-2021\/artikel\/schutzmasken-und-hautbeschwerden-ein-haeufiges-berufsdermatologisches-problem-waehrend-der-pandemie, (\u00faltimo acesso 14.04.2022)<\/li>\n<li>Symanzik C, et al.: altera\u00e7\u00f5es da pele devido ao uso de uma protec\u00e7\u00e3o oral-nasal entre os trabalhadores da sa\u00fade durante a conten\u00e7\u00e3o da pandemia COVID-19: um estudo emp\u00edrico num hospital de cuidados m\u00e1ximos na Baixa Sax\u00f3nia. Dermatologia na Ocupa\u00e7\u00e3o e Ambiente, Vol. 70, No. 1\/2022, pp. 3-11.<\/li>\n<li>Lan J, et al: Danos de pele entre os profissionais de sa\u00fade que gerem a doen\u00e7a de coronav\u00edrus -2019. In: J Am Acad Dermatol 2020; 82: 1215-1216.<\/li>\n<li>Kreft B: Preven\u00e7\u00e3o e terapia de dermatoses desencadeadas pela protec\u00e7\u00e3o pessoal da boca e do nariz (protec\u00e7\u00e3o m\u00e9dica da boca e do nariz, filtragem de meias m\u00e1scaras (FFP1\/FFP2\/FFP3). J Dtsch Dermatol Ges 2021; 19(7): 1121-1122.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1TICA DA DERMATOLOGIA 2022; 32(2): 43<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a pandemia da coroa, observou-se um aumento das les\u00f5es cut\u00e2neas faciais devido ao uso de uma protec\u00e7\u00e3o de nariz e boca. O uso de uma m\u00e1scara protectora FFP2 continuar\u00e1&hellip;<\/p>\n","protected":false},"author":7,"featured_media":119962,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Protec\u00e7\u00e3o da corona e sa\u00fade da pele","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11344,11356,11521,11421,11517,11529,11551],"tags":[15739,13213,15747,15743],"powerkit_post_featured":[],"class_list":["post-325706","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alergologia-e-imunologia-clinica","category-dermatologia-e-venereologia-pt-pt","category-estudos","category-infecciologia","category-noticias-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-alergia-de-mascara","tag-corona-pt-pt","tag-dermatite-de-mascara","tag-ffp2-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 02:26:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":325718,"slug":"dermatitis-de-la-mascara-consejos-de-expertos-para-la-profilaxis-y-el-tratamiento","post_title":"Dermatitis de la m\u00e1scara - Consejos de expertos para la profilaxis y el tratamiento","href":"https:\/\/medizinonline.com\/es\/dermatitis-de-la-mascara-consejos-de-expertos-para-la-profilaxis-y-el-tratamiento\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/325706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=325706"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/325706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/119962"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=325706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=325706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=325706"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=325706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}