{"id":327291,"date":"2021-11-30T01:00:00","date_gmt":"2021-11-30T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/gestao-de-infeccoes-de-feridas-pos-operatorias\/"},"modified":"2021-11-30T01:00:00","modified_gmt":"2021-11-30T00:00:00","slug":"gestao-de-infeccoes-de-feridas-pos-operatorias","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/gestao-de-infeccoes-de-feridas-pos-operatorias\/","title":{"rendered":"Gest\u00e3o de infec\u00e7\u00f5es de feridas p\u00f3s-operat\u00f3rias"},"content":{"rendered":"<p><strong>Durante as opera\u00e7\u00f5es, n\u00e3o \u00e9 poss\u00edvel alcan\u00e7ar uma esterilidade absoluta, apesar das medidas de higiene \u00f3ptimas. Assim, as infec\u00e7\u00f5es p\u00f3s-operat\u00f3rias de feridas ainda hoje s\u00e3o um problema cl\u00ednico relevante, apesar das t\u00e9cnicas anti-s\u00e9pticas. Para al\u00e9m das medidas pr\u00e9 e perioperat\u00f3rias, alguns princ\u00edpios devem tamb\u00e9m ser tidos em conta na sequ\u00eancia de uma interven\u00e7\u00e3o cir\u00fargica.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Cerca de 6% dos doentes nos hospitais su\u00ed\u00e7os contraem uma infec\u00e7\u00e3o [1]. Esta taxa est\u00e1 no meio-campo europeu. As infec\u00e7\u00f5es de feridas ap\u00f3s interven\u00e7\u00f5es cir\u00fargicas e a bacteremia associada ao cateter (envenenamento do sangue) s\u00e3o particularmente frequentes e potencialmente graves. No entanto, os pulm\u00f5es e as vias urin\u00e1rias s\u00e3o tamb\u00e9m suscept\u00edveis a infec\u00e7\u00f5es ap\u00f3s um procedimento m\u00e9dico. &#8220;As infec\u00e7\u00f5es de s\u00edtios cir\u00fargicos (SSIs) resultam em estadias hospitalares mais longas, custos mais elevados e, nos piores casos, em mortes. \u00c9 uma complica\u00e7\u00e3o grave e generalizada da cirurgia moderna com consequ\u00eancias negativas para as pessoas afectadas e para o sistema de sa\u00fade. Os factores mais importantes que influenciam o SSI s\u00e3o, por um lado, o estado geral do paciente e, por outro lado, o tipo de cirurgia a ser realizada. As infec\u00e7\u00f5es de feridas nosocomiais p\u00f3s-operat\u00f3rias s\u00e3o principalmente causadas por agentes patog\u00e9nicos bacterianos, raramente combinados com fungos. O espectro dos agentes patog\u00e9nicos varia em fun\u00e7\u00e3o do tipo e da localiza\u00e7\u00e3o da opera\u00e7\u00e3o [3]. Certos agentes patog\u00e9nicos facultativos (por exemplo, estafilococos coagulase negativos, CoNS) s\u00f3 ocorrem em constela\u00e7\u00f5es especiais, por exemplo, em liga\u00e7\u00e3o com implantes.  <span style=\"font-family:franklin gothic demi\">O quadro&nbsp;1<\/span> fornece uma vis\u00e3o geral das esp\u00e9cies patog\u00e9nicas mais importantes determinadas empiricamente [4]. No p\u00f3s-operat\u00f3rio, \u00e9 particularmente importante evitar a coloniza\u00e7\u00e3o secund\u00e1ria de feridas ainda abertas e\/ou drenos inseridos, bem como a contamina\u00e7\u00e3o de outros doentes. No entanto, a tentativa de anti-s\u00e9ptica posterior da ferida ou do ambiente da ferida n\u00e3o tem normalmente qualquer efeito sobre a taxa de infec\u00e7\u00e3o [5].<\/p>\n<h2 id=\"cura-de-feridas-primarias-vs-secundarias\">Cura de feridas prim\u00e1rias vs. secund\u00e1rias<\/h2>\n<p>No decurso da cicatriza\u00e7\u00e3o da ferida prim\u00e1ria, a ferida fecha pela justaposi\u00e7\u00e3o directa, coalesc\u00eancia e cicatriza\u00e7\u00e3o das bordas lisas da ferida [2]. Fundem-se com o m\u00ednimo de forma\u00e7\u00e3o de novos tecidos. A cura n\u00e3o \u00e9 retardada por inflama\u00e7\u00e3o ou secre\u00e7\u00e3o de ferida. A cicatriza\u00e7\u00e3o de feridas secund\u00e1rias refere-se ao encerramento lento e gradual da ferida devido a um dist\u00farbio de cicatriza\u00e7\u00e3o da ferida. Ap\u00f3s a forma\u00e7\u00e3o de tecido de granula\u00e7\u00e3o no leito da ferida e epiteliza\u00e7\u00e3o a partir da margem da ferida, a ferida tende a cicatrizar severamente (contrac\u00e7\u00e3o). Numa ferida cicatrizante prim\u00e1ria, demora 48 horas para que a ferida feche sem drenagem, pelo que n\u00e3o h\u00e1 mais risco de contamina\u00e7\u00e3o. Interven\u00e7\u00f5es terap\u00eauticas de cicatriza\u00e7\u00e3o secund\u00e1ria, feridas agudas e cr\u00f3nicas s\u00e3o um desafio, uma vez que todas as fases da cicatriza\u00e7\u00e3o de feridas s\u00e3o afectadas.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-17665\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/tab1_hp10_s36_0.png\" style=\"height:283px; width:600px\" width=\"1100\" height=\"519\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/tab1_hp10_s36_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/tab1_hp10_s36_0-800x377.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/tab1_hp10_s36_0-120x57.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/tab1_hp10_s36_0-90x42.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/tab1_hp10_s36_0-320x151.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/tab1_hp10_s36_0-560x264.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"mudanca-de-penso-tecnica-non-touch\">Mudan\u00e7a de penso: t\u00e9cnica &#8220;non-touch&#8221;.<\/h2>\n<p>A ferida cir\u00fargica no final do procedimento cir\u00fargico deve ser coberta com um penso esterilizado. A primeira mudan\u00e7a de penso de uma ferida essencialmente fechada \u00e9 aconselh\u00e1vel ap\u00f3s cerca de 48 horas, no m\u00ednimo, a menos que seja necess\u00e1ria uma mudan\u00e7a de penso mais cedo devido a poss\u00edveis complica\u00e7\u00f5es (secre\u00e7\u00e3o, dor, hemorragia no penso) [2,5]. Se a ferida estiver seca e fechada posteriormente, pode ser dispensada uma nova cobertura esterilizada da ferida sob aspectos higi\u00e9nicos [5]. Intervalos de tempo mais curtos aumentam o risco de les\u00f5es na rede de fibrina [2]. Os pensos para feridas que tenham sangrado ou ficado h\u00famidos devem ser mudados imediatamente. A t\u00e9cnica &#8220;non-touch&#8221; \u00e9 recomendada para as trocas de penso, ou seja, luvas descart\u00e1veis s\u00e3o usadas para remover o penso e luvas ou instrumentos esterilizados s\u00e3o usados para vestir a ferida e aplicar a primeira camada de penso [2]. O objectivo \u00e9 evitar tocar na pele, feridas ou artigos esterilizados com as m\u00e3os nuas ou instrumentos n\u00e3o esterilizados.<\/p>\n<h2 id=\"sistema-de-saude-suico-estrategia-noso\">Sistema de sa\u00fade su\u00ed\u00e7o: estrat\u00e9gia NOSO<\/h2>\n<p>A redu\u00e7\u00e3o das infec\u00e7\u00f5es associadas aos cuidados de sa\u00fade \u00e9 uma alta prioridade para o Conselho Federal. Por esta raz\u00e3o, a estrat\u00e9gia NOSO foi declarada uma medida priorit\u00e1ria na revis\u00e3o global da pol\u00edtica de sa\u00fade &#8220;Sa\u00fade 2020&#8221; [1]. NOSO baseia-se no que j\u00e1 foi experimentado e testado, colmata lacunas e tem em conta os diferentes pr\u00e9-requisitos das instala\u00e7\u00f5es de sa\u00fade. Um objectivo estrat\u00e9gico e um conjunto de medidas-chave s\u00e3o definidos para cada uma de cinco \u00e1reas. O projecto foi desenvolvido em estreita coopera\u00e7\u00e3o com a Confer\u00eancia Su\u00ed\u00e7a de Directores de Sa\u00fade Cantonal, H+ Os Hospitais da Su\u00ed\u00e7a, Associa\u00e7\u00e3o de Casas e Institui\u00e7\u00f5es Su\u00ed\u00e7a de Curaviva, o grupo de peritos Swissnoso, bem como com sociedades m\u00e9dicas e outras partes interessadas importantes. \u00c9 coordenado com medidas federais tais como a estrat\u00e9gia de resist\u00eancia aos antibi\u00f3ticos (StAR) e os programas-piloto no \u00e2mbito da estrat\u00e9gia de qualidade, de modo a assegurar uma abordagem conjunta sem duplica\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Gabinete Federal de Sa\u00fade P\u00fablica: Estrat\u00e9gia NOSO,&nbsp; , (\u00faltimo acesso: 29.09.2021)<\/li>\n<li>Mudan\u00e7as de penso para feridas ass\u00e9pticas e s\u00e9pticas, <em>The Practice Guide <\/em>Issue 01.2019, www.die-praxisanleitung.de, (\u00faltimo acesso: 29.09.2021).<\/li>\n<li>Mangram AJ, et al: Guideline for prevention of surgical site infection. Am J Controlo de Infec\u00e7\u00f5es 1999; 27(2): 97-134<\/li>\n<li>Centro Nacional de Refer\u00eancia para a Vigil\u00e2ncia das Infec\u00e7\u00f5es Nosocomiais 2015, www.nrz-hygiene.de\/fileadmin\/nrz\/ module\/op\/reference_data_2010-2014 (\u00faltimo recuperado em 29.09.2021)<\/li>\n<li>Instituto Robert Koch (RKI), www.rki.de\/DE\/Content\/Infekt\/Krankenhaushygiene (\u00faltima vez que se acedeu a 29.09.2021)<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1TICA DO GP 2021; 16(10): 34<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante as opera\u00e7\u00f5es, n\u00e3o \u00e9 poss\u00edvel alcan\u00e7ar uma esterilidade absoluta, apesar das medidas de higiene \u00f3ptimas. Assim, as infec\u00e7\u00f5es p\u00f3s-operat\u00f3rias de feridas ainda hoje s\u00e3o um problema cl\u00ednico relevante, apesar&hellip;<\/p>\n","protected":false},"author":7,"featured_media":113019,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Profilaxia e tratamento de feridas","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11356,11524,11305,11551,11325],"tags":[18435,16319],"powerkit_post_featured":[],"class_list":["post-327291","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dermatologia-e-venereologia-pt-pt","category-formacao-continua","category-medicina-interna-geral","category-rx-pt","category-traumatologia-e-cirurgia-de-trauma","tag-noso-pt-pt","tag-tratamento-de-feridas","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:59:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":327298,"slug":"tratamiento-de-las-infecciones-postoperatorias-de-las-heridas","post_title":"Tratamiento de las infecciones postoperatorias de las heridas","href":"https:\/\/medizinonline.com\/es\/tratamiento-de-las-infecciones-postoperatorias-de-las-heridas\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/327291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=327291"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/327291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/113019"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=327291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=327291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=327291"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=327291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}