{"id":327300,"date":"2021-11-29T01:00:00","date_gmt":"2021-11-29T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/uma-doenca-no-seu-auge\/"},"modified":"2021-11-29T01:00:00","modified_gmt":"2021-11-29T00:00:00","slug":"uma-doenca-no-seu-auge","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/uma-doenca-no-seu-auge\/","title":{"rendered":"Uma doen\u00e7a no seu auge"},"content":{"rendered":"<p><strong>A exposi\u00e7\u00e3o ao amianto at\u00e9 1990 est\u00e1 a ter o seu pre\u00e7o &#8211; entre outras coisas atrav\u00e9s do n\u00famero ainda crescente de mesoteliomas pleurais malignos na Su\u00ed\u00e7a. A esperan\u00e7a de vida das pessoas afectadas \u00e9 extremamente baixa, cerca de doze meses, e n\u00e3o existe um procedimento de rastreio adequado. No entanto, com a recente aprova\u00e7\u00e3o da primeira op\u00e7\u00e3o imunoterap\u00eautica para esta doen\u00e7a, h\u00e1 alguma esperan\u00e7a.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>O principal factor de risco \u00e9 claro: a exposi\u00e7\u00e3o ao amianto. Contudo, embora a importa\u00e7\u00e3o e o processamento de amianto tenham sido proibidos na Su\u00ed\u00e7a desde 1&nbsp;de Mar\u00e7o de 1990, o n\u00famero de casos de mesotelioma pleural maligno continua a aumentar [1,2]. Devido ao per\u00edodo de lat\u00eancia de 20 a 55 anos, n\u00e3o se espera um m\u00e1ximo de novos casos at\u00e9 2030 [1]. Actualmente, cerca de 200 doen\u00e7as s\u00e3o diagnosticadas na Su\u00ed\u00e7a todos os anos. Os homens s\u00e3o afectados em 85% dos casos, na sua maioria com mais de 60 anos de idade [3]. Infelizmente, o progn\u00f3stico \u00e9 extremamente desfavor\u00e1vel com um tempo m\u00e9dio de sobreviv\u00eancia inferior a um ano [4]. Ap\u00f3s d\u00e9cadas de cirurgia e quimioterapia, bem como de radioterapia, se necess\u00e1rio, formando a espinha dorsal da terapia, os medicamentos oncol\u00f3gicos modernos entraram recentemente em ac\u00e7\u00e3o pela primeira vez com a aprova\u00e7\u00e3o da dupla imunoterapia usando ipilimumab\/nivolumab &#8211; esperemos que como um sinal de partida para novas melhorias terap\u00eauticas no futuro.<\/p>\n<h2 id=\"o-amianto-como-culpado\">O amianto como culpado<\/h2>\n<p>Em 70-90% das pessoas afectadas, o mesotelioma pleural maligno \u00e9 atribu\u00eddo \u00e0 exposi\u00e7\u00e3o anterior ao amianto [1]. O amianto entra nos pulm\u00f5es como p\u00f3; as fibras mortais s\u00e3o produzidas atrav\u00e9s do processamento do material. Uma vez inaladas, as fibras de amianto s\u00e3o depositadas nas vias respirat\u00f3rias e, devido \u00e0 sua dimens\u00e3o cr\u00edtica, n\u00e3o podem ser decompostas nem excretadas. A forma de agulha das fibras permite-lhes migrar para a pleura e at\u00e9 atravessar para o espa\u00e7o pleural. O resultado: fibrose e, a longo prazo, cancro, sendo as sequelas neopl\u00e1sicas mais comuns relacionadas com o amianto [5]. Quanto maior for a dose cumulativa, maior \u00e9 o risco de doen\u00e7a [6]. Mas nem todo o amianto \u00e9 o mesmo. Por exemplo, o amianto branco (cris\u00f3tilo) mais utilizado \u00e9 considerado menos prejudicial do que outros tipos de amianto, como o amianto azul (crocidolite). Em geral, o material de constru\u00e7\u00e3o ainda utilizado em grandes partes do mundo &#8211; o amianto s\u00f3 foi proibido at\u00e9 agora em 67 pa\u00edses<span style=\"font-family:franklin gothic demi\"> (Fig.&nbsp;1) <\/span>[2] &#8211; \u00e9 um grupo de minerais inorg\u00e2nicos cristalinos naturais, os chamados silicatos. Com excelente resist\u00eancia ao calor e melhores propriedades isolantes [5].<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-17699\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/abb1-oh5_s32.png\" style=\"height:348px; width:600px\" width=\"1100\" height=\"638\"><\/p>\n<p>&nbsp;<\/p>\n<p>O mesotelioma pleural maligno ap\u00f3s exposi\u00e7\u00e3o profissional ao amianto \u00e9 considerado uma doen\u00e7a profissional e est\u00e1, portanto, coberto por um seguro obrigat\u00f3rio de acidentes na Su\u00ed\u00e7a. No entanto, uma vez que a exposi\u00e7\u00e3o data frequentemente de h\u00e1 v\u00e1rias d\u00e9cadas, nem sempre \u00e9 f\u00e1cil chegar a um acordo com ela. Aqueles que tiveram contacto n\u00e3o profissional com o material est\u00e3o menos seguros financeiramente. Entretanto, os servi\u00e7os de apoio \u00e0s pessoas afectadas est\u00e3o cada vez mais dispon\u00edveis, tais como a Funda\u00e7\u00e3o para o Fundo de Indemniza\u00e7\u00e3o das V\u00edtimas do Amianto (EFA) [7].<\/p>\n<h2 id=\"o-papel-dos-genes\">O papel dos genes<\/h2>\n<p>Para al\u00e9m da exposi\u00e7\u00e3o ao amianto, v\u00e1rias altera\u00e7\u00f5es gen\u00e9ticas foram tamb\u00e9m identificadas nos \u00faltimos anos como factores de risco para o desenvolvimento de mesoteliomas pleurais malignos, sobretudo muta\u00e7\u00f5es BAP1 (prote\u00edna associada a BRCA-1&nbsp;1), tanto ao n\u00edvel da prote\u00edna como do ADN. Estes s\u00e3o frequentemente observados em fam\u00edlias com uma incid\u00eancia superior \u00e0 m\u00e9dia, em doentes jovens e na presen\u00e7a de segundos tumores [6,8]. Globalmente, as muta\u00e7\u00f5es BAP1 est\u00e3o presentes em cerca de dois ter\u00e7os dos mesoteliomas espor\u00e1dicos [9]. Certas regi\u00f5es da Turquia, que est\u00e3o altamente contaminadas com a erionite natural da fibra de amianto, parecem ser particularmente afectadas. Devido a esta ocorr\u00eancia, bem como \u00e0s muta\u00e7\u00f5es heredit\u00e1rias do BAP1, at\u00e9 50% das pessoas morrem de mesotelioma em algumas \u00e1reas [9]. A inactiva\u00e7\u00e3o de muta\u00e7\u00f5es de genes supressores de tumores como CDKN2A, LATS-1 ou NF2 tamb\u00e9m pode promover mesotelioma pleural maligno [9].<\/p>\n<h2 id=\"apresentacao-clinica-e-diagnosticos\">Apresenta\u00e7\u00e3o cl\u00ednica e diagn\u00f3sticos<\/h2>\n<p>Devido a sintomas n\u00e3o espec\u00edficos e na sua maioria tardios, a doen\u00e7a s\u00f3 \u00e9 frequentemente descoberta em fases avan\u00e7adas. Para al\u00e9m da dispneia, tosse e dores tor\u00e1cicas, a perda de peso \u00e9 mais comum. As efus\u00f5es pleurais recorrentes ocorrem em cerca de um ter\u00e7o dos doentes. Mais tarde, hemoptise, disfagia, rouquid\u00e3o e s\u00edndrome de Horners tamb\u00e9m n\u00e3o s\u00e3o incomuns [10]. Especialmente em casos de derrames pleurais unilaterais ou espessamento pleural, a doen\u00e7a do mesotelioma deve ser considerada [11].<\/p>\n<p>Em primeiro lugar e acima de tudo no diagn\u00f3stico est\u00e1 a quest\u00e3o da poss\u00edvel exposi\u00e7\u00e3o ao amianto no passado. A hist\u00f3ria da fam\u00edlia tamb\u00e9m desempenha um papel importante. Se a exposi\u00e7\u00e3o ao amianto permanecer inexplicada, as fibras de amianto podem ser detectadas por microscopia electr\u00f3nica. No entanto, isto n\u00e3o confirma o diagn\u00f3stico de mesotelioma pleural, apenas a exposi\u00e7\u00e3o. O pr\u00e9-requisito \u00e9 uma lavagem broncoalveolar ou uma bi\u00f3psia pulmonar para obter material [4]. O encaminhamento para um centro especializado deve ser feito o mais cedo poss\u00edvel em caso de suspeita de mesotelioma.<\/p>\n<p>Para al\u00e9m dos procedimentos de imagem, o processamento histopatol\u00f3gico de bi\u00f3psias e efus\u00f5es pleurais \u00e9 de particular import\u00e2ncia. Os marcadores tumorais n\u00e3o desempenham actualmente qualquer papel no diagn\u00f3stico e tamb\u00e9m na avalia\u00e7\u00e3o da progress\u00e3o [6]. As imagens utilizando raio-X tor\u00e1cico, ultra-som e\/ou TAC podem confirmar o diagn\u00f3stico suspeito e determinar o local ideal para a bi\u00f3psia. O diagn\u00f3stico final, contudo, s\u00f3 pode ser confirmado pelo exame histopatol\u00f3gico do tecido. Um t\u00f3rax CT com meio de contraste \u00e9 recomendado como diagn\u00f3stico de imagem inicial de escolha, onde o mesotelioma pleural maligno se apresenta caracteristicamente como espessamento pleural difuso ou nodular<span style=\"font-family:franklin gothic demi\"> (tab.&nbsp;1)<\/span>. No decurso da encena\u00e7\u00e3o, s\u00e3o tamb\u00e9m utilizados PET-CT e possivelmente MRI. Em qualquer caso, o estadiamento deve tamb\u00e9m incluir ultra-sons endobraquiais e mediastinoscopia para determinar o estado dos g\u00e2nglios linf\u00e1ticos antes de iniciar a terapia. S\u00e3o tamb\u00e9m utilizados VATS (toracoscopias v\u00eddeo-assistidas) e laparoscopias [6]. A encena\u00e7\u00e3o \u00e9 feita de acordo com a classifica\u00e7\u00e3o internacional TNM.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-17700 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/tab1-oh5_s33.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/423;height:231px; width:600px\" width=\"1100\" height=\"423\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Para confirmar o diagn\u00f3stico, as bi\u00f3psias s\u00e3o retiradas de \u00e1reas pleurais morfologicamente vis\u00edveis e inconsp\u00edcuas, quer por VATS, biopsia com agulha guiada por ultra-sons ou biopsia pleural aberta [6]. O exame puramente citol\u00f3gico do derrame pleural n\u00e3o pode substituir a bi\u00f3psia devido \u00e0 falta de sensibilidade [4]. As an\u00e1lises imunohistoqu\u00edmicas e gen\u00e9ticas moleculares s\u00e3o realizadas como parte do trabalho histopatol\u00f3gico. Estes servem, por um lado, para provar a origem mesotelial e, por outro lado, para a distinguir de outras altera\u00e7\u00f5es malignas. Al\u00e9m disso, os subtipos histol\u00f3gicos est\u00e3o associados a diferentes prote\u00ednas de superf\u00edcie [8]. Em geral, os subtipos epithelioide, bif\u00e1sico e sarcomat\u00f3ide distinguem-se com base nos padr\u00f5es de crescimento histomorfol\u00f3gico, com os mesoteliomas pleurais epitelioide a revelarem-se mais progn\u00f3sticos favor\u00e1veis do que os sarcomat\u00f3ide [12].<\/p>\n<h2 id=\"terapia-o-caminho-para-a-modernidade\">Terapia: O caminho para a modernidade<\/h2>\n<p>At\u00e9 agora, n\u00e3o existem normas uniformes para o tratamento do mesotelioma pleural maligno. Uma coisa \u00e9 clara, por\u00e9m: a monoterapia n\u00e3o parece ser suficiente [13]. O objectivo do tratamento \u00e9 &#8211; se poss\u00edvel &#8211; uma ressec\u00e7\u00e3o macroscopicamente completa num conceito de tratamento multimodal. Neste contexto, a quimioterapia adjuvante ou neoadjuvante usando platina mais pemetrexed tem sido a base do tratamento at\u00e9 \u00e0 data. Gemcitabine provou ser igualmente eficaz com uma tolerabilidade significativamente pior [13]. A adi\u00e7\u00e3o de bevacizumab \u00e9 uma possibilidade, mas n\u00e3o \u00e9 aprovada na Su\u00ed\u00e7a [14]. Actualmente, n\u00e3o \u00e9 recomendada nenhuma terapia de manuten\u00e7\u00e3o, e faltam op\u00e7\u00f5es bem testadas para a terapia de segunda linha [6]. Em princ\u00edpio, os doentes devem ser tratados preferencialmente em centros especializados e ter acesso a ensaios cl\u00ednicos [6].<\/p>\n<p>Para al\u00e9m da cirurgia e quimioterapia, s\u00e3o tamb\u00e9m utilizados procedimentos radioter\u00e1picos. Estes s\u00e3o utilizados, por exemplo, para aliviar a dor e podem ter influ\u00eancia no risco de recorr\u00eancia, que est\u00e1 actualmente a ser investigado em estudos [6]. A irradia\u00e7\u00e3o radical de todo o tumor n\u00e3o \u00e9 geralmente recomendada fora dos estudos devido \u00e0 propaga\u00e7\u00e3o de tumores mais complexos e \u00e0 exposi\u00e7\u00e3o \u00e0 dose resultante. Os s\u00edtios de biopsia n\u00e3o devem ser irradiados profilaticamente para evitar a semeadura de c\u00e9lulas tumorais, ao contr\u00e1rio de suposi\u00e7\u00f5es anteriores [6].<\/p>\n<p>A terapia cir\u00fargica radical \u00e9 geralmente reservada aos doentes sem histologia sarcomat\u00f3ide. Outros pr\u00e9-requisitos s\u00e3o um estado de g\u00e2nglio linf\u00e1tico N&lt;2 e uma fase da UICC &lt;IV. Isto significa que n\u00e3o deve haver met\u00e1stases [6]. O objectivo n\u00e3o \u00e9 operar sem tumor residual, mas sim conseguir uma ressec\u00e7\u00e3o macroscopicamente completa. Dependendo da situa\u00e7\u00e3o, a pneumonectomia extrapleural (EPP), a pleurectomia e decortica\u00e7\u00e3o (P\/D) e a pleurectomia parcial podem ser consideradas como procedimentos [8]. O resultado final \u00e9 que o benef\u00edcio destas opera\u00e7\u00f5es permanece pouco claro, e o ensaio MARS2 est\u00e1 actualmente a investigar o benef\u00edcio da pleurectomia e decortica\u00e7\u00e3o compressiva de lung-preserving em compara\u00e7\u00e3o com um procedimento sem cirurgia. As interven\u00e7\u00f5es cir\u00fargicas s\u00e3o tamb\u00e9m importantes no quadro de um conceito de tratamento paliativo. Por exemplo, a pleurodese com p\u00f3 de talco pode ser realizada para derrames pleurais recorrentes [15].<\/p>\n<p>No campo da terapia sist\u00e9mica, um avan\u00e7o foi recentemente alcan\u00e7ado ap\u00f3s uma longa pausa. Por exemplo, o estudo CheckMate-743 mostrou uma vantagem do tratamento de primeira linha com os dois inibidores de ponto de controlo nivolumab e ipilimumab na situa\u00e7\u00e3o paliativa [16,17]. A dupla imunoterapia j\u00e1 foi aprovada devido aos resultados convincentes em histologia n\u00e3o-epithelioide, bem como em histologia epithelioide e express\u00e3o PD-L1 [14]% \u22651 . No ensaio, resultou numa sobreviv\u00eancia global (SO) mediana de 18,1 meses, em compara\u00e7\u00e3o com 14,1 meses no grupo de quimioterapia (hazard ratio 0,74, p=0,002) [17]. Este primeiro sucesso significativo no campo das modernas terapias oncol\u00f3gicas suscita outras quest\u00f5es. Entre outras coisas, est\u00e1 em discuss\u00e3o a combina\u00e7\u00e3o de quimioterapia e imunoterapia, bem como poss\u00edveis novas op\u00e7\u00f5es na segunda linha. E n\u00e3o s\u00e3o apenas outras novas subst\u00e2ncias activas que poder\u00e3o em breve encontrar o seu caminho para o tratamento do mesotelioma pleural maligno, mas tamb\u00e9m vias alternativas de aplica\u00e7\u00e3o. Como a elevada taxa de recidivas locais \u00e9 um problema relevante, as op\u00e7\u00f5es terap\u00eauticas localizadas, tais como a terapia intracavit\u00e1ria, est\u00e3o cada vez mais em foco. Por exemplo, o ensaio INFLuenCe-Meso fase II est\u00e1 actualmente em curso no Hospital Universit\u00e1rio de Zurique, testando a seguran\u00e7a e efic\u00e1cia da quimioterapia intracavit\u00e1ria ap\u00f3s a ressec\u00e7\u00e3o cir\u00fargica [13].<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Beeler P, et al: Fontes de dados sobre a incid\u00eancia de mesotelioma pleural maligno na Su\u00ed\u00e7a desde 2001. ASU Journal of Medical Prevention. 2021; 09.<\/li>\n<li>Unia: 30 anos de proibi\u00e7\u00e3o do amianto. www.unia.ch\/de\/arbeitswelt\/von-a-z\/asbest\/30-jahre-asbestverbot (\u00faltimo acesso em 30.09.2021).<\/li>\n<li>Krebsliga Schweiz: Cancro na Su\u00ed\u00e7a: figuras importantes. Situa\u00e7\u00e3o em Dezembro de 2020. www.krebsliga.ch\/fileadmin\/downloads\/sheets\/zahlen-krebs-in-der-schweiz.pdf (\u00faltimo acesso em 30.09.2021).<\/li>\n<li>Scherpereel A, et al: Guidelines of the European Respiratory Society and the European Society of Thoracic Surgeons for the management of malignant pleural mesothelioma. Eur Respir J. 2010; 35(3): 479-495.<\/li>\n<li>Duelo T: Guia Oncol\u00f3gico &#8211; Mesotelioma Pleural | Causas, Diagn\u00f3stico e Tratamento.www.oncology-guide.com\/erkrankung\/pleuramesotheliom (\u00faltimo acesso 30.09.2021).<\/li>\n<li>Scherpereel A, et al: ERS\/ESTS\/EACTS\/ESTRO guidelines for the management of malignant pleural mesothelioma. Eur Respir J. 2020; 55(6).<\/li>\n<li>Funda\u00e7\u00e3o EFA. www.stiftung-efa.ch (\u00faltimo acesso em 30.09.2021).<\/li>\n<li>Baas P, et al: Malignant pleural mesothelioma: ESMO Clinical Practice Guidelines for diagnosis, treatment and follow-up. Ann Oncol. 2015; 26 Suppl. 5: v31-9.<\/li>\n<li>Duell T: Terapia sist\u00e9mica do mesotelioma pleural. Terapia com medicamentos. 2017; 35(06).<\/li>\n<li>Mesotelioma pleural maligno &#8211; sintomas, tratamento e busca m\u00e9dica: Deutscher Verlag f\u00fcr Gesundheitsinformation, Heidelberg, Alemanha; www.leading-medicine-guide.ch\/erkrankungen\/tumoren\/mesotheliom#topics (\u00faltimo acesso 30.09.2021).<\/li>\n<li>Gill RR: Imagem de mesotelioma. Resultados recentes Cancer Res. 2011; 189: 27-43.<\/li>\n<li>Husain AN, et al: Guidelines for pathologic diagnosis of malignant mesothelioma: 2012 update of the consensus statement from the International Mesothelioma Interest Group. Arch Pathol Lab Med. 2013; 137(5): 647-667.<\/li>\n<li>Terapia do mesotelioma pleural maligno. www.usz.ch\/fachbereich\/thoraxchirurgie\/angebot\/malignes-pleuramesotheliom (\u00faltimo acesso em 30.09.2021).<\/li>\n<li>Informa\u00e7\u00e3o sobre Medicamentos Swissmedic Medicinal Product Information. www.swissmedicinfo.ch (\u00faltimo acesso em 30.09.2021).<\/li>\n<li>Bielsa S, et al: O tipo tumoral influencia a efic\u00e1cia da pleurodese em efus\u00f5es malignas. Lung. 2011; 189(2): 151-155.<\/li>\n<li>Nowak AK, Jackson A, Sidhu C: Gest\u00e3o de Mesotelioma Pleural Avan\u00e7ado &#8211; Na encruzilhada. Pr\u00e1tica de JCO Oncol. 2021: Op2100426.<\/li>\n<li>Baas P, et al: nivolumab de primeira linha mais ipilimumab em mesotelioma pleural maligno incontest\u00e1vel (CheckMate 743): um ensaio multic\u00eantrico, aleatorizado, com r\u00f3tulo aberto, fase 3. Lanceta. 2021; 397(10272): 375-386.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGy &amp; HEMATOLOGy 2021; 9(5): 32-33<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A exposi\u00e7\u00e3o ao amianto at\u00e9 1990 est\u00e1 a ter o seu pre\u00e7o &#8211; entre outras coisas atrav\u00e9s do n\u00famero ainda crescente de mesoteliomas pleurais malignos na Su\u00ed\u00e7a. A esperan\u00e7a de&hellip;<\/p>\n","protected":false},"author":7,"featured_media":113149,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Um retrato de mesotelioma pleural maligno","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11524,11379,11547,11551],"tags":[15281,13523,18450],"powerkit_post_featured":[],"class_list":["post-327300","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacao-continua","category-oncologia-pt-pt","category-pneumologia-pt-pt","category-rx-pt","tag-amianto","tag-imunoterapia","tag-mesotelioma-pleural-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 19:28:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":327304,"slug":"una-enfermedad-en-su-apogeo","post_title":"Una enfermedad en su apogeo","href":"https:\/\/medizinonline.com\/es\/una-enfermedad-en-su-apogeo\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/327300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=327300"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/327300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/113149"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=327300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=327300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=327300"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=327300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}