{"id":327414,"date":"2021-11-20T01:00:00","date_gmt":"2021-11-20T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/prurigo-cronico-em-doentes-atopicos-tratamento-bem-sucedido-com-dupilumab\/"},"modified":"2021-11-20T01:00:00","modified_gmt":"2021-11-20T00:00:00","slug":"prurigo-cronico-em-doentes-atopicos-tratamento-bem-sucedido-com-dupilumab","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/prurigo-cronico-em-doentes-atopicos-tratamento-bem-sucedido-com-dupilumab\/","title":{"rendered":"Prurigo cr\u00f3nico em doentes at\u00f3picos: tratamento bem sucedido com dupilumab"},"content":{"rendered":"<p><strong>Na revista cient\u00edfica <em>Acta Dermato Venerologica<\/em>, foi publicada uma s\u00e9rie de casos de pacientes com prurigo em que o uso de dupilumab resultou numa melhoria significativa no decurso da doen\u00e7a, acompanhada por um aumento maci\u00e7o da qualidade de vida, ap\u00f3s m\u00faltiplas terapias anteriores sem sucesso. Anamn\u00e9sticamente, atopia estava presente em todos os tr\u00eas casos.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>O prurigo cr\u00f3nico caracteriza-se por prurido persistente, por vezes com les\u00f5es de arranh\u00f5es secund\u00e1rios. Esta forma altamente cr\u00f3nica de prurido desenvolve-se, de acordo com o entendimento actual, atrav\u00e9s da sensibiliza\u00e7\u00e3o neuronal e do desenvolvimento de um ciclo de coceira-arranh\u00e3o. Distinguem-se as quatro formas cl\u00ednicas: papular, nodular, placa ou subtipo de \u00falcera umbilical. Na maioria das vezes, o prurigo cr\u00f3nico \u00e9 muito resistente a v\u00e1rios tratamentos aprovados. Uma das alternativas de tratamento promissoras \u00e9 o Dupilumab biol\u00f3gico, como ilustrado por esta s\u00e9rie de casos [1].<\/p>\n<h2 id=\"caso-1-pontuacao-dlqi-de-25-a-menos-de-5-no-prazo-de-seis-semanas\">Caso 1 &#8211; pontua\u00e7\u00e3o DLQI de 25 a menos de 5 no prazo de seis semanas<\/h2>\n<p>O paciente de 41 anos foi diagnosticado com prurigo cr\u00f3nico do subtipo nodular em 2016. Uma asma al\u00e9rgica e alergias do tipo I, bem como uma IgE total elevada de 14.778 kU\/I foram documentadas anamn\u00e9sticamente. O eczema generalizado estava presente na altura da consulta inicial. Foi diagnosticada uma dermatite at\u00f3pica, que foi bem controlada por fototerapia UVB de espectro estreito (311 nm) e ester\u00f3ides t\u00f3picos. No entanto, o doente sofria de prurigo cr\u00f3nico persistente e muito angustiante, acompanhado pelo desenvolvimento de novos n\u00f3dulos de comich\u00e3o. V\u00e1rias op\u00e7\u00f5es de tratamento n\u00e3o tiveram sucesso e o paciente continuou a queixar-se de prurido grave. Em Dezembro de 2017, a intensidade m\u00e1xima de prurido de 10 foi medida na Escala de Classifica\u00e7\u00e3o Num\u00e9rica (NRS), bem como uma deteriora\u00e7\u00e3o significativa da qualidade de vida com uma pontua\u00e7\u00e3o DLQI de 25 e uma pontua\u00e7\u00e3o ItchyQoL de&nbsp;88. Uma multid\u00e3o de n\u00f3dulos e escalas altamente pruriginosa manifestada. Como o tratamento com ciclosporina n\u00e3o era uma op\u00e7\u00e3o devido a hipertens\u00e3o mal controlada, foi iniciada a terapia com dupilumab. O doente relatou uma melhoria significativa dos sintomas 2&nbsp;semanas ap\u00f3s a dose de carga de 600&nbsp;mg. A sua condi\u00e7\u00e3o melhorou progressivamente, a partir da semana&nbsp;6 ap\u00f3s ter iniciado o tratamento dupilumab, o paciente relatou um al\u00edvio tremendo da comich\u00e3o e um grande melhoramento do controlo prurigo. A qualidade de vida foi apenas ligeiramente reduzida e houve uma lenta mas cont\u00ednua melhoria das les\u00f5es prurigo.<\/p>\n<h2 id=\"caso-2-pontuacao-nrs-de-10-a-0-no-prazo-de-oito-semanas\">Caso 2 &#8211; pontua\u00e7\u00e3o NRS de 10 a 0 no prazo de oito semanas<\/h2>\n<p>O paciente de 45 anos foi diagnosticado com prurigo cr\u00f3nico do subtipo nodular em 2015. Havia m\u00faltiplos n\u00f3dulos cr\u00f3nicos e muito pruriginosos nas pernas, n\u00e1degas e bra\u00e7os. O paciente tinha uma hist\u00f3ria documentada de atopia, incluindo alergias do tipo I, eczema disidr\u00f3tico das m\u00e3os e asma al\u00e9rgica. Apesar de v\u00e1rias tentativas de terapia, o paciente sofreu de prurido persistente com uma intensidade m\u00e1xima de&nbsp;10 no NRS, acompanhado por uma qualidade de vida extremamente prejudicada (pontua\u00e7\u00e3o DLQI de 29). Como uma terapia com ciclosporina teve de ser interrompida duas vezes devido ao aumento da creatinina s\u00e9rica, foi iniciada uma terapia com dupilumab. 8&nbsp;Semanas ap\u00f3s o in\u00edcio do tratamento, o paciente relatou uma diminui\u00e7\u00e3o maci\u00e7a do prurido com uma pontua\u00e7\u00e3o NRS de 0. A qualidade de vida melhorou significativamente e a pontua\u00e7\u00e3o DLQI de&nbsp;10 diminu\u00edram nos tr\u00eas anos seguintes.&nbsp;meses at\u00e9 ao valor de 2.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-17496\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/kasten_dp5_s31_0.png\" style=\"height:242px; width:600px\" width=\"1100\" height=\"443\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/kasten_dp5_s31_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/kasten_dp5_s31_0-800x322.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/kasten_dp5_s31_0-120x48.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/kasten_dp5_s31_0-90x36.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/kasten_dp5_s31_0-320x129.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/11\/kasten_dp5_s31_0-560x226.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"caso-3-itchyqol-pontua-de-91-a-74-no-prazo-de-duas-semanas\">Caso 3: ItchyQol pontua de 91 a 74 no prazo de duas semanas<\/h2>\n<p>O paciente de 52 anos com uma hist\u00f3ria documentada de atopia, incluindo alergias do tipo I e dermatite at\u00f3pica, apresentou-se pela primeira vez em 2017 com m\u00faltiplos n\u00f3dulos gravemente pruriginosos em ambas as pernas. Apesar da terapia com ciclosporina durante tr\u00eas anos e da adi\u00e7\u00e3o de gabapentina, o paciente continuou a sofrer de prurido grave e de um comprometimento maci\u00e7o da qualidade de vida com uma pontua\u00e7\u00e3o DLQI de&nbsp;19, uma pontua\u00e7\u00e3o ItchyQoL de&nbsp;91 e uma intensidade m\u00e1xima de coceira de 10 no NRS. Ap\u00f3s a descontinua\u00e7\u00e3o da ciclosporina e gabapentina, foi iniciada a terapia com dupilumabe. Duas semanas ap\u00f3s o in\u00edcio do tratamento, o DLQI mostrou uma redu\u00e7\u00e3o para&nbsp;14 e a express\u00e3o no ItchyQol reduzida a&nbsp;Tr\u00eas meses mais tarde, o paciente relatou um al\u00edvio significativo do prurido e uma melhoria lenta mas constante nos tr\u00eas meses seguintes, com uma redu\u00e7\u00e3o para um n\u00edvel de&nbsp;4 no NRS. A pontua\u00e7\u00e3o DLQI diminuiu para 12.<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Almustafa ZZ, et al: Dupilumab in Treatment of Chronic Prurigo: A Case Series and Literature Review. Acta Dermato Venerologica 2019; 99(10)<\/li>\n<li>International Institute for Dermatological Allergology, http:\/\/i2deal.net (\u00faltima vez que se acedeu a 19.09.2021)<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1TICA DA DERMATOLOGIA 2021; 31(5): 31<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na revista cient\u00edfica Acta Dermato Venerologica, foi publicada uma s\u00e9rie de casos de pacientes com prurigo em que o uso de dupilumab resultou numa melhoria significativa no decurso da doen\u00e7a,&hellip;<\/p>\n","protected":false},"author":7,"featured_media":112359,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"S\u00e9rie de casos","footnotes":""},"category":[11344,11536,11356,11524,11551],"tags":[18639,12487,18637,13525,16238,18642,14379,18641,18635,18640,18643],"powerkit_post_featured":[],"class_list":["post-327414","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alergologia-e-imunologia-clinica","category-casos-pt-pt","category-dermatologia-e-venereologia-pt-pt","category-formacao-continua","category-rx-pt","tag-atopico-pt-pt-2","tag-comichao","tag-dlqi-pt-pt","tag-dupilumab-pt-pt","tag-dupixent-pt-pt","tag-itchyqol-pt-pt","tag-nrs-pt-pt","tag-prurigo-cronico-pt-pt","tag-pruritus-pt-pt","tag-serie-de-casos","tag-teste-de-controlo-prurigo","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:31:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":327416,"slug":"prurigo-cronico-en-pacientes-atopicos-tratamiento-exitoso-con-dupilumab","post_title":"Prurigo cr\u00f3nico en pacientes at\u00f3picos: tratamiento exitoso con dupilumab","href":"https:\/\/medizinonline.com\/es\/prurigo-cronico-en-pacientes-atopicos-tratamiento-exitoso-con-dupilumab\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/327414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=327414"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/327414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/112359"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=327414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=327414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=327414"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=327414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}