{"id":328146,"date":"2021-09-04T16:47:37","date_gmt":"2021-09-04T14:47:37","guid":{"rendered":"https:\/\/medizinonline.com\/hobit-transforma-celulas-imunes-em-assassinos\/"},"modified":"2021-09-04T16:47:37","modified_gmt":"2021-09-04T14:47:37","slug":"hobit-transforma-celulas-imunes-em-assassinos","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/hobit-transforma-celulas-imunes-em-assassinos\/","title":{"rendered":"Hobit transforma c\u00e9lulas imunes em assassinos"},"content":{"rendered":"<p>Contra infec\u00e7\u00f5es, tumores e inflama\u00e7\u00f5es, as c\u00e9lulas imunit\u00e1rias locais est\u00e3o dispon\u00edveis nos \u00f3rg\u00e3os do corpo como tropas de reac\u00e7\u00e3o r\u00e1pida. No local, eles especializam-se e assumem diferentes tarefas.<\/p>\n<p> <!--more--> <\/p>\n<p>Quando os agentes patog\u00e9nicos invadem o corpo humano, \u00e9 necess\u00e1ria uma resposta r\u00e1pida. As c\u00e9lulas imunit\u00e1rias especiais est\u00e3o na linha da frente da resposta imunit\u00e1ria. Residem em v\u00e1rios tecidos tais como os pulm\u00f5es, f\u00edgado, pele e intestinos, onde assumem a luta contra os invasores numa fase precoce. O seu nome: c\u00e9lulas linf\u00f3ides inatas, ou ILCs, para abreviar.<\/p>\n<p>Uma propriedade especial destas c\u00e9lulas: N\u00e3o precisam de ser alertadas primeiro, como muitas outras c\u00e9lulas imunit\u00e1rias, para depois migrarem para o seu local de ac\u00e7\u00e3o no corpo. Em vez disso, fixam-se nos tecidos e \u00f3rg\u00e3os pouco depois do nascimento e a\u00ed permanecem permanentemente.<\/p>\n<p><strong>mRNA atlas do ILC1 criado ao n\u00edvel de c\u00e9lula \u00fanica<\/strong><\/p>\n<p>Os ILCs podem surgir em tecidos a partir de c\u00e9lulas progenitoras imaturas e amadurecer em c\u00e9lulas imunes operacionais. Isto foi recentemente demonstrado por cientistas do Max Planck Research Group do Institute for Systems Immunology da Universidade Julius Maximilians de W\u00fcrzburg (JMU). At\u00e9 agora, n\u00e3o era claro como \u00e9 que esta matura\u00e7\u00e3o se processava em detalhe. &#8220;Quer\u00edamos compreender como os ILC imaturos se tornam c\u00e9lulas effector que podem, por exemplo, matar c\u00e9lulas tumorais ou combater infec\u00e7\u00f5es com a ajuda de citocinas&#8221;, explica o Professor Georg Gasteiger, presidente e chefe do Max Planck Research Group no Institute for Systems Immunology da JMU. Para este efeito, a equipa de investiga\u00e7\u00e3o de W\u00fcrzburg estudou o grupo de ILC1s que desempenham um papel nas infec\u00e7\u00f5es virais e na defesa contra tumores. A equipa registou todas as mol\u00e9culas de mRNA do ILC1 individual no f\u00edgado e criou um atlas de c\u00e9lulas virtuais a partir destas an\u00e1lises.<\/p>\n<p><strong>Divis\u00e3o de tarefas: fornecimento, ajuda e c\u00e9lulas assassinas<\/strong><\/p>\n<p>Com base nestas &#8220;impress\u00f5es digitais moleculares&#8221;, os investigadores reconheceram que existem c\u00e9lulas especializadas dentro do ILC1 que partilham as suas tarefas: &#8220;Encontr\u00e1mos c\u00e9lulas que se podem multiplicar muito rapidamente e assim assegurar um fornecimento de ILCs. No processo, eles especializam-se nos chamados helper ou killer ILCs&#8221;. A equipa de Gasteiger descobriu que as c\u00e9lulas auxiliares produzem uma vasta gama de subst\u00e2ncias mensageiras que desempenham um papel na fase inicial das infec\u00e7\u00f5es, por exemplo. As c\u00e9lulas assassinas, por outro lado, est\u00e3o armadas com mol\u00e9culas que lhes permitem reconhecer e matar c\u00e9lulas tumorais. &#8220;At\u00e9 agora, pensava-se que estas c\u00e9lulas eram diferentes tipos de SCI&#8221;, explica Christin Friedrich. O postdoc da equipa de Gasteiger \u00e9 o primeiro autor da publica\u00e7\u00e3o, que apareceu na conceituada revista Nature Immunology. &#8220;Mas os nossos dados mostram que estes s\u00e3o diferentes n\u00edveis de especializa\u00e7\u00e3o que podem surgir em cada institui\u00e7\u00e3o a partir das mesmas for\u00e7as de abastecimento&#8221;.<\/p>\n<p><strong>Podem os ILCs assassinos ser terapeuticamente \u00fateis?<\/strong><\/p>\n<p>&#8220;Curiosamente, contudo, os ILCs apenas se desenvolvem em c\u00e9lulas assassinas em alguns tecidos, embora os nossos dados mostrem que t\u00eam potencial para o fazer em todos os tecidos&#8221; explica Gasteiger. &#8220;Temos provas iniciais de que este desenvolvimento \u00e9 activamente reprimido em alguns tecidos, possivelmente para evitar danos ou inflama\u00e7\u00e3o dos tecidos. Queremos agora compreender como podemos activar terap\u00eauticamente as c\u00e9lulas assassinas, por exemplo, para melhorar o controlo imunit\u00e1rio do desenvolvimento de tumores e met\u00e1stases. Tamb\u00e9m queremos investigar que mol\u00e9culas os ILCs podem utilizar para reconhecer tumores e como se comportam nos diferentes tecidos durante as infec\u00e7\u00f5es&#8221;.<\/p>\n<p>Especializa\u00e7\u00e3o do factor de transcri\u00e7\u00e3o Hobit drives<\/p>\n<p>Christin Friedrich acrescenta: &#8220;O nosso trabalho mostra como o factor de transcri\u00e7\u00e3o Hobit impulsiona a especializa\u00e7\u00e3o em c\u00e9lulas efectoras maduras. \u00c9 excitante que Hobit seja tamb\u00e9m expresso em outras c\u00e9lulas assassinas do sistema imunit\u00e1rio humano. Com base nos nossos resultados, a fun\u00e7\u00e3o de Hobit nestas c\u00e9lulas de defesa pode agora ser explorada, como elas amadurecem e como podem ser levadas a combater tumores em diferentes tecidos&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:<\/p>\n<p>A diferencia\u00e7\u00e3o do efeito a jusante do compromisso da linhagem no ILC1 \u00e9 impulsionada pelo Hobit atrav\u00e9s dos tecidos. Christin Friedrich, Renske L. R. E. Taggenbrock, R\u00e9mi Doucet-Ladev\u00e8ze, Gosia Golda, Rebekka Moenius, Panagiota Arampatzi, Natasja A. M. Kragten, Katharina Kreymborg, Mercedes Gomez de Ag\u00fcero, Wolfgang Kastenmueller, Antoine-Emmanuel Saliba, Dominic Gr\u00fcn, Klaas P. J. M. van Gisbergen, Georg Gasteiger. Nature Immunology, 30 de Agosto de 2021, DOI: 10.1038\/s41590-021-01013-0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contra infec\u00e7\u00f5es, tumores e inflama\u00e7\u00f5es, as c\u00e9lulas imunit\u00e1rias locais est\u00e3o dispon\u00edveis nos \u00f3rg\u00e3os do corpo como tropas de reac\u00e7\u00e3o r\u00e1pida. No local, eles especializam-se e assumem diferentes tarefas.<\/p>\n","protected":false},"author":12,"featured_media":111209,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"C\u00e9lulas linf\u00f3ides inatas (ILCs)","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11547,11551],"tags":[],"powerkit_post_featured":[],"class_list":["post-328146","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pneumologia-pt-pt","category-rx-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-10 01:28:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":328155,"slug":"el-hobit-convierte-las-celulas-inmunitarias-en-asesinas","post_title":"El hobit convierte las c\u00e9lulas inmunitarias en asesinas","href":"https:\/\/medizinonline.com\/es\/el-hobit-convierte-las-celulas-inmunitarias-en-asesinas\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/328146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=328146"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/328146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/111209"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=328146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=328146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=328146"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=328146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}