{"id":328314,"date":"2021-08-16T02:00:00","date_gmt":"2021-08-16T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/da-suspeita-a-gestao-adequada\/"},"modified":"2021-08-16T02:00:00","modified_gmt":"2021-08-16T00:00:00","slug":"da-suspeita-a-gestao-adequada","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/da-suspeita-a-gestao-adequada\/","title":{"rendered":"Da suspeita \u00e0 gest\u00e3o adequada"},"content":{"rendered":"<p><strong>A s\u00edndrome de Lynch, tamb\u00e9m conhecida como HNPCC <em>(cancro colorrectal heredit\u00e1rio n\u00e3o-polipose), \u00e9<\/em> a causa heredit\u00e1ria mais comum de cancro colorrectal em todo o mundo. Al\u00e9m da cirurgia preventiva, a aspirina \u00e9 tamb\u00e9m utilizada para a profilaxia do cancro. Quando deve pensar na s\u00edndrome de Lynch e o que deve fazer se suspeitar dela?<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>A s\u00edndrome do linchamento, herdada de forma autoss\u00f3mica dominante, aumenta substancialmente o risco de desenvolvimento de v\u00e1rios tipos de cancro. Para al\u00e9m dos carcinomas endometriais e colorrectais, outras doen\u00e7as malignas tais como tumores ovarianos, pancre\u00e1ticos ou g\u00e1stricos tamb\u00e9m ocorrem frequentemente <span style=\"font-family:franklin gothic demi\">(Tab.&nbsp;1) <\/span>. Embora as muta\u00e7\u00f5es que comp\u00f5em a s\u00edndrome do HNPCC sejam raras na popula\u00e7\u00e3o, com uma preval\u00eancia de 1:270 a 1:440, representam no entanto a predisposi\u00e7\u00e3o heredit\u00e1ria mais frequente do cancro [1]. O diagn\u00f3stico precoce e as medidas preventivas que envolvem toda a fam\u00edlia podem prevenir doen\u00e7as malignas.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-16738\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/tab1-oh3_s37.png\" style=\"height:232px; width:600px\" width=\"1100\" height=\"425\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"reparacao-de-adn-defeituoso\">Repara\u00e7\u00e3o de ADN defeituoso<\/h2>\n<p>Nos indiv\u00edduos afectados, pode ser detectado um defeito gen\u00e9tico na repara\u00e7\u00e3o do ADN, que se reflecte num alongamento de segmentos repetitivos de ADN &#8211; os chamados microssat\u00e9lites. Estes diferem entre tecido tumoral e tecido saud\u00e1vel em pacientes com HNPCC, que \u00e9 chamado de &#8220;instabilidade por microsat\u00e9lite&#8221; (MSI). A presen\u00e7a de tal MSI com suspeita cl\u00ednica simult\u00e2nea \u00e9, portanto, altamente suscept\u00edvel de indicar a s\u00edndrome de Lynch [2]. At\u00e9 agora, s\u00e3o conhecidos quatro genes de repara\u00e7\u00e3o de incompatibilidade de DNA (MMR) cujas muta\u00e7\u00f5es na linha germinal conduzem ao desenvolvimento do HNPCC: MLH1, MSH2, MSH6 e PMS2. Al\u00e9m disso, a elimina\u00e7\u00e3o da linha germinal do gene EPCAM \u00e9 uma causa poss\u00edvel, o que tamb\u00e9m resulta numa perda da prote\u00edna MSH2 no tumor <span style=\"font-family:franklin gothic demi\">(Fig.&nbsp;1) <\/span>. Uma perda de express\u00e3o correspondente nas c\u00e9lulas tumorais pode ser demonstrada pela imuno-histoqu\u00edmica e o diagn\u00f3stico subsequentemente confirmado pela gen\u00e9tica molecular [2]. A identifica\u00e7\u00e3o da muta\u00e7\u00e3o familiar \u00e9 de grande import\u00e2ncia, uma vez que afecta n\u00e3o s\u00f3 o pr\u00f3prio paciente, mas tamb\u00e9m toda a sua fam\u00edlia. Permite testar de forma preditiva os parentes saud\u00e1veis, que \u00e9 o que torna as medidas preventivas poss\u00edveis em primeiro lugar. O risco de contrair a doen\u00e7a difere em fun\u00e7\u00e3o da muta\u00e7\u00e3o e da idade. Isto pode ser calculado individualmente utilizando a base de dados da futura s\u00edndrome de Lynch [3].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-16739 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/abb1-oh3_s37_0.png\" style=\"--smush-placeholder-width: 765px; --smush-placeholder-aspect-ratio: 765\/772;height:404px; width:400px\" width=\"765\" height=\"772\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/abb1-oh3_s37_0.png 765w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/abb1-oh3_s37_0-80x80.png 80w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/abb1-oh3_s37_0-120x120.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/abb1-oh3_s37_0-90x90.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/abb1-oh3_s37_0-320x323.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/abb1-oh3_s37_0-560x565.png 560w\" data-sizes=\"(max-width: 765px) 100vw, 765px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Devido \u00e0 heran\u00e7a autoss\u00f3mica dominante, existe normalmente uma c\u00f3pia defeituosa do gene desencadeador na linha germinal, que \u00e9 transmitida com uma probabilidade de 50%. Se ocorrem muta\u00e7\u00f5es som\u00e1ticas, isto \u00e9, aleat\u00f3rias, na segunda c\u00f3pia gen\u00e9tica &#8211; originalmente funcional -, ocorre o defeito de repara\u00e7\u00e3o do ADN descrito e, portanto, uma degenera\u00e7\u00e3o maligna acelerada. Assim, s\u00e3o necess\u00e1rios acontecimentos desfavor\u00e1veis adicionais para que o cancro se desenvolva. Este mecanismo explica a acumula\u00e7\u00e3o de carcinomas colorrectais em particular, uma vez que a din\u00e2mica da forma\u00e7\u00e3o de adenomas representa provavelmente um factor de risco independente [4].<\/p>\n<h2 id=\"o-lobo-em-pele-de-ovelha\">O lobo em pele de ovelha<\/h2>\n<p>Mas quando \u00e9 que os testes gen\u00e9ticos fazem sentido? Quais s\u00e3o os sinais cl\u00ednicos que sugerem a presen\u00e7a da s\u00edndrome de Lynch? Em contraste com outras s\u00edndromes como a polipose adenomatosa familiar (FAP), n\u00e3o existem caracter\u00edsticas fenot\u00edpicas claras na s\u00edndrome HNPCC que sugiram uma doen\u00e7a heredit\u00e1ria. Existem normalmente apenas adenomas ou carcinomas \u00fanicos, que s\u00e3o clinicamente indistingu\u00edveis de tumores espor\u00e1dicos. S\u00f3 com a ocorr\u00eancia de v\u00e1rias malignidades, devido \u00e0 idade frequentemente jovem das pessoas afectadas ou a uma hist\u00f3ria familiar consp\u00edcua, se pode assim suspeitar da s\u00edndrome de Lynch [5]. Por exemplo, a idade m\u00e9dia no diagn\u00f3stico do cancro colorrectal \u00e9 de 45 anos e em cerca de 30% dos casos \u00e9 adicionado outro tumor t\u00edpico dentro de dez anos [6]. Em geral, os tumores associados ao HNPCC s\u00e3o na sua maioria adenocarcinomas; no intestino, ocorrem preferencialmente no hemic\u00f3lon direito.<\/p>\n<p>Para facilitar a identifica\u00e7\u00e3o dos doentes em risco, foram desenvolvidos v\u00e1rios resultados de diagn\u00f3stico ao longo dos anos, nomeadamente os Crit\u00e9rios de Amesterd\u00e3o e as Directrizes de Bethesda. Al\u00e9m disso, o modelo PREMM existe para o c\u00e1lculo de probabilidades. O elemento central de todos estes sistemas \u00e9 uma hist\u00f3ria familiar detalhada. Para preencher os crit\u00e9rios de Amesterd\u00e3o II, que s\u00e3o suficientes para o diagn\u00f3stico do HNPCC, pelo menos tr\u00eas familiares devem ter cancro associado \u00e0 s\u00edndrome de Lynch, pelo menos duas gera\u00e7\u00f5es consecutivas devem ser afectadas e pelo menos um membro da fam\u00edlia deve ter tido a doen\u00e7a antes dos 50 anos de idade <span style=\"font-family:franklin gothic demi\">(vis\u00e3o geral&nbsp;1)<\/span> [7]. Em casos menos claros, as Directrizes de Bethesda ajudam a identificar indiv\u00edduos potencialmente afectados e a orient\u00e1-los para diagn\u00f3sticos apropriados<span style=\"font-family:franklin gothic demi\">  (Resumo&nbsp;2).  <\/span>Com a crescente disponibilidade da an\u00e1lise de MSI, que hoje em dia j\u00e1 \u00e9 rotineiramente realizada para muitos carcinomas, estas directrizes est\u00e3o a perder o seu significado, mas ainda s\u00e3o importantes na avalia\u00e7\u00e3o cl\u00ednica dos resultados [7]. Isto porque a instabilidade dos microsat\u00e9lites n\u00e3o prova a s\u00edndrome de Lynch, pois ocorre em 10-15% de todos os c\u00f3lon e 15-20% de todos os carcinomas endometriais [5].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-16740 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/08\/ubersicht1-3_oh3_s38.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1274;height:695px; width:600px\" width=\"1100\" height=\"1274\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"instabilidade-por-microssatelite-detectada-e-agora\">Instabilidade por microssat\u00e9lite detectada&#8230; e agora?<\/h2>\n<p>Se for detectada uma instabilidade por microsat\u00e9lite ou uma defici\u00eancia das prote\u00ednas MMR no tumor de um paciente suspeito de ter s\u00edndrome de Lynch, h\u00e1 uma indica\u00e7\u00e3o de testes gen\u00e9ticos para desencadear muta\u00e7\u00f5es. Estes, bem como o aconselhamento gen\u00e9tico, s\u00e3o servi\u00e7os obrigat\u00f3rios prestados pela companhia de seguros de sa\u00fade, desde que as condi\u00e7\u00f5es para o esclarecimento gen\u00e9tico sejam cumpridas [1]. Se for encontrada uma muta\u00e7\u00e3o para a qual tenha sido estabelecida uma liga\u00e7\u00e3o clara com a doen\u00e7a, devem tamb\u00e9m ser recomendados testes direccionados aos membros da fam\u00edlia. Neste contexto, as altera\u00e7\u00f5es gen\u00e9ticas de (ainda) import\u00e2ncia desconhecida s\u00e3o problem\u00e1ticas. Neste caso, a preven\u00e7\u00e3o baseia-se na hist\u00f3ria m\u00e9dica pessoal e na hist\u00f3ria familiar e n\u00e3o no resultado do exame gen\u00e9tico. O procedimento \u00e9, portanto, o mesmo que no caso de um achado discreto; os membros da fam\u00edlia n\u00e3o devem ser testados.<\/p>\n<p>Na aus\u00eancia de terapias espec\u00edficas, o tratamento de tumores malignos baseia-se principalmente nas recomenda\u00e7\u00f5es que tamb\u00e9m se aplicam aos tumores espor\u00e1dicos. Em fases avan\u00e7adas, por\u00e9m, os inibidores de pontos de controlo s\u00e3o cada vez mais utilizados. Por exemplo, o pembrolizumab \u00e9 aprovado como monoterapia para o tratamento de primeira linha do cancro colorrectal metast\u00e1tico com MSI elevado ou repara\u00e7\u00e3o de desajustes de ADN defeituosos [8]. No que diz respeito \u00e0 utiliza\u00e7\u00e3o de mais imunoterap\u00eautica e ao valor da instabilidade dos microssat\u00e9lites como marcador preditivo, podem esperar-se dados interessantes nos pr\u00f3ximos anos.<\/p>\n<h2 id=\"prevencao-e-deteccao-precoce\">Preven\u00e7\u00e3o e detec\u00e7\u00e3o precoce<\/h2>\n<p>As provas gen\u00e9ticas da s\u00edndrome de Lynch resultam numa longa cauda de ratazana de recomenda\u00e7\u00f5es para um maior rastreio do cancro. Estes tamb\u00e9m se aplicam aos familiares portadores da muta\u00e7\u00e3o correspondente. Para al\u00e9m de um estilo de vida saud\u00e1vel e de medidas de detec\u00e7\u00e3o precoce, s\u00e3o tamb\u00e9m utilizadas cirurgias preventivas e medica\u00e7\u00e3o. As colonoscopias regulares e os exames ginecol\u00f3gicos devem prevenir o cancro colorrectal e endometrial. Recomenda-se tamb\u00e9m o rastreio de Helicobacter pylori (Vis\u00e3o Geral 3). N\u00e3o existe actualmente uma detec\u00e7\u00e3o precoce eficaz do carcinoma ovariano, que tamb\u00e9m ocorre frequentemente, ou de tumores uroteliais. Isto torna ainda mais importante a sensibiliza\u00e7\u00e3o das pessoas afectadas aos sintomas correspondentes e, dependendo da doen\u00e7a tumoral na fam\u00edlia, a implementa\u00e7\u00e3o de medidas adicionais de monitoriza\u00e7\u00e3o.<\/p>\n<p>Em alguns casos, uma histerectomia profil\u00e1ctica com ou sem adnexectomia \u00e9 realizada ap\u00f3s o planeamento familiar ter sido conclu\u00eddo. Tamb\u00e9m s\u00e3o por vezes utilizadas ressec\u00e7\u00f5es prolongadas do c\u00f3lon. O resultado final \u00e9 que o benef\u00edcio da cirurgia preventiva da s\u00edndrome de Lynch n\u00e3o \u00e9 claro e deve ser pesado numa base individual [1]. H\u00e1 tamb\u00e9m falta de dados fi\u00e1veis sobre a utiliza\u00e7\u00e3o profil\u00e1ctica da aspirina, especialmente sobre a dosagem e a dura\u00e7\u00e3o da administra\u00e7\u00e3o. De acordo com os resultados a longo prazo do estudo CAPP II, a ingest\u00e3o di\u00e1ria de 600 mg de \u00e1cido acetilsalic\u00edlico reduz significativamente o risco de todas as malignidades associadas ao HNPCC ap\u00f3s um per\u00edodo de lat\u00eancia de cerca de quatro anos. Este efeito parece durar cerca de dez anos ap\u00f3s dois anos de administra\u00e7\u00e3o, mesmo sem mais administra\u00e7\u00e3o [9]. Com o CAPP III, est\u00e1 actualmente em curso um estudo para avaliar doses mais baixas.<\/p>\n<p>Embora muito tenha sido feito no diagn\u00f3stico gen\u00e9tico e na gest\u00e3o de pacientes com s\u00edndrome de Lynch nos \u00faltimos anos, especialmente nos centros, \u00e9 prov\u00e1vel que a s\u00edndrome ainda esteja subdiagnosticada [10]. A fim de contribuir significativamente para um melhor tratamento das pessoas afectadas, podemos fazer uma coisa acima de tudo: Pense sobre isso.<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>SAKK: Guia de Aconselhamento S\u00edndrome de Lynch 2021.&nbsp;www.sakk.ch\/sites\/default\/files\/2020-11\/Leitfaden%20Lynch-Syndrom.pdf. (\u00faltimo acesso 08.05.2021)<\/li>\n<li>UKB, Institute of Human Genetics: HNPCC \/ S\u00edndrome de Lynch. &nbsp; (\u00faltimo acesso 08.05.2021)<\/li>\n<li>Prospective Lynch Syndrome Database (PLSD) &#8211; risco cumulativo de cancro por idade, variante gen\u00e9tica, e sexo em portadores sujeitos a colonoscopia. www.plsd.eu.<\/li>\n<li>Engel C, et al: Efic\u00e1cia da vigil\u00e2ncia colonosc\u00f3pica anual em indiv\u00edduos com cancro colorrectal heredit\u00e1rio n\u00e3o-polipose. Clin Gastroenterol Hepatol. 2010; 8(2): 174-182.<\/li>\n<li>Steinke V, et al: Cancro colorrectal heredit\u00e1rio sem polipose. Dtsch Arztebl Internacional. 2013; 110(3): 32-8.<\/li>\n<li>Lynch HT, et al: Revis\u00e3o da s\u00edndrome de Lynch: hist\u00f3ria, gen\u00e9tica molecular, rastreio, diagn\u00f3stico diferencial, e ramifica\u00e7\u00f5es m\u00e9dico-legais. Clin Genet. 2009; 76(1): 1-18.<\/li>\n<li>Livstone EM: S\u00edndrome de Lynch 2019. Manual MSD. www.msdmanuals.com\/de\/profi\/gastrointestinale-erkrankungen\/tumoren-des-gastrointestinaltrakts\/lynch-syndrom (\u00faltimo acesso 08.05.2021)<\/li>\n<li>Informa\u00e7\u00e3o sobre medicamentos da Swissmedic, a Ag\u00eancia Su\u00ed\u00e7a para Produtos Terap\u00eauticos. www.swissmedicinfo.ch (\u00faltimo acesso 08.05.2021)<\/li>\n<li>Burn J, et al: Preven\u00e7\u00e3o do cancro com aspirina em cancro colorrectal heredit\u00e1rio (s\u00edndrome de Lynch), seguimento de 10 anos e dados de 20 anos baseados em registos no estudo CAPP2: um ensaio duplo-cego, aleatorizado e controlado por placebo. A Lanceta. 2020; 395(10240): 1855-1863.<\/li>\n<li>Morrow A, et al: Understanding implementation success: protocol for an in-depth, mixed-methods process evaluation of a cluster randomised controlled trial testing methods to improve detection of Lynch syndrome in Australian hospitals. BMJ Aberto. 2020; 10(6): e033552.<\/li>\n<li>Vasen HF, et al: Novos crit\u00e9rios cl\u00ednicos para o cancro colorrectal heredit\u00e1rio n\u00e3o-polipose (HNPCC, s\u00edndrome de Lynch) propostos pelo grupo International Collaborative sobre HNPCC. Gastroenterologia. 1999; 116(6): 1453-1456.<\/li>\n<li>Umar A, et al: Directrizes revistas de Bethesda para o cancro colorrectal heredit\u00e1rio n\u00e3o-polipose (s\u00edndrome de Lynch) e instabilidade por micro-sat\u00e9lite. J Natl Cancer Inst. 2004; 96(4): 261-268.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGy &amp; HEMATOLOGy 2021; 9(3): 37-39<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A s\u00edndrome de Lynch, tamb\u00e9m conhecida como HNPCC (cancro colorrectal heredit\u00e1rio n\u00e3o-polipose), \u00e9 a causa heredit\u00e1ria mais comum de cancro colorrectal em todo o mundo. Al\u00e9m da cirurgia preventiva, a&hellip;<\/p>\n","protected":false},"author":7,"featured_media":109259,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"S\u00edndrome de Lynch","footnotes":""},"category":[11524,11407,11419,11379,11474,11551],"tags":[15381],"powerkit_post_featured":[],"class_list":["post-328314","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacao-continua","category-gastroenterologia-e-hepatologia","category-ginecologia-pt-pt","category-oncologia-pt-pt","category-prevencao-e-cuidados-de-saude","category-rx-pt","tag-sindrome-do-linchamento","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:02:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":328322,"slug":"de-la-sospecha-a-la-gestion-adecuada","post_title":"De la sospecha a la gesti\u00f3n adecuada","href":"https:\/\/medizinonline.com\/es\/de-la-sospecha-a-la-gestion-adecuada\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/328314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=328314"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/328314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/109259"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=328314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=328314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=328314"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=328314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}