{"id":328560,"date":"2021-07-15T02:00:00","date_gmt":"2021-07-15T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/traumatologia-na-vanguarda-da-ciencia\/"},"modified":"2023-01-12T14:02:57","modified_gmt":"2023-01-12T13:02:57","slug":"traumatologia-na-vanguarda-da-ciencia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/traumatologia-na-vanguarda-da-ciencia\/","title":{"rendered":"Traumatologia na vanguarda da ci\u00eancia"},"content":{"rendered":"\n<p><strong>Os traumas psicol\u00f3gicos podem ter causas diferentes. No entanto, t\u00eam uma coisa em comum &#8211; causariam profundo desespero em quase todos. As experi\u00eancias traum\u00e1ticas podem ser classificadas de acordo com diferentes aspectos e tratadas individualmente.<\/strong><\/p>\n\n<!--more-->\n\n<p>A seguir, s\u00e3o apresentadas as caracter\u00edsticas do trauma psicol\u00f3gico e as abordagens terap\u00eauticas ao seu tratamento. \u00c9 dada especial aten\u00e7\u00e3o aos sintomas mais importantes e \u00e0s interven\u00e7\u00f5es mais eficazes. O resumo conciso dos resultados da investiga\u00e7\u00e3o actual torna esta contribui\u00e7\u00e3o especialmente adequada para os profissionais. A refer\u00eancia a manuais e estudos terap\u00eauticos oferece tamb\u00e9m a oportunidade de um estudo mais aprofundado.<\/p>\n\n<h2 id=\"eventos-traumaticos\" class=\"wp-block-heading\">Eventos traum\u00e1ticos<\/h2>\n\n<p>O trauma psicol\u00f3gico \u00e9 definido no CID-11 como um evento ou s\u00e9rie de eventos de extraordin\u00e1ria amea\u00e7a ou magnitude catastr\u00f3fica que causaria um sofrimento profundo a quase todos [1]. O sistema US DSM (Diagnostic and Statistical Manual of Mental Disorders) descreve o trauma como eventos que envolvem confronta\u00e7\u00e3o com a morte, ferimentos graves ou viol\u00eancia sexual [2]. Experi\u00eancia directa, testemunho pessoal, ocorr\u00eancia em fam\u00edlia pr\u00f3xima ou com amigos pr\u00f3ximos, e confronto repetido com detalhes aversivos (por exemplo, no contexto do trabalho) s\u00e3o especificados como 4 formas poss\u00edveis.<\/p>\n\n<p>Os eventos traum\u00e1ticos podem ser classificados de acordo com diferentes aspectos. Como esquema orientador, a divis\u00e3o em trauma induzido pelo homem versus trauma acidental e em trauma de curto versus longo prazo (tipo I versus tipo II) provou ser \u00fatil.  <span style=\"font-family: franklin gothic demi;\">(Tab. 1).  <\/span>Os traumas de tipo I s\u00e3o geralmente caracterizados por perigo de vida agudo, repentino e surpresa, traumas de tipo II por s\u00e9ries de diferentes eventos individuais traum\u00e1ticos e por uma baixa previsibilidade dos outros eventos stressantes.<\/p>\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"390\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab1_np1_s7.png\" alt=\"\" class=\"wp-image-15509\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab1_np1_s7.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab1_np1_s7-800x284.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab1_np1_s7-120x43.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab1_np1_s7-90x32.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab1_np1_s7-320x113.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab1_np1_s7-560x199.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/figure>\n\n<p>Em todos os tipos de trauma, existe uma probabilidade condicional de desenvolvimento de transtorno de stress p\u00f3s-traum\u00e1tico (TEPT) de 8-15%. Isto significa que, de cada 100 pessoas traumatizadas, 8-15 t\u00eam um diagn\u00f3stico de TEPT. No entanto, no que diz respeito aos diferentes tipos de trauma, a probabilidade condicional \u00e9 muito diferente:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Cerca de 50-65% ap\u00f3s a experi\u00eancia directa da guerra como civil;<\/li>\n\n\n\n<li>cerca de 50% ap\u00f3s a viola\u00e7\u00e3o e o abuso sexual;<\/li>\n\n\n\n<li>cerca de 25% depois de outros crimes violentos;<\/li>\n\n\n\n<li>cerca de 5% ap\u00f3s graves acidentes de via\u00e7\u00e3o;<\/li>\n\n\n\n<li>&lt;5% ap\u00f3s desastres naturais, inc\u00eandios ou relacionados com inc\u00eandios;<\/li>\n\n\n\n<li>&lt;5% para testemunhas de acidentes e actos violentos.<\/li>\n<\/ul>\n\n<h2 id=\"transtorno-de-stress-pos-traumatico\" class=\"wp-block-heading\">Transtorno de stress p\u00f3s-traum\u00e1tico<\/h2>\n\n<p>&#8220;Desde o ataque tornei-me uma pessoa completamente diferente&#8221;, relata um homem de 60 anos, &#8220;\u00e0 noite deito-me na cama, e depois v\u00eam estes pensamentos e imagens, e depois fico acordado para sempre. (&#8230;). Se eu estiver algures e houver um ru\u00eddo s\u00fabito, hesito. (&#8230;) N\u00e3o se pode deslig\u00e1-lo&#8221;. O homem, v\u00edtima de uma agress\u00e3o, sofre do chamado PTSD. A presen\u00e7a de um trauma grave \u00e9 um pr\u00e9-requisito para o diagn\u00f3stico de TEPT. \u00c9 diagnosticado quando alguns sintomas individuais ocorrem em conjunto durante um per\u00edodo de tempo mais longo. De acordo com a \u00faltima defini\u00e7\u00e3o do CID-11, os sintomas concentram-se na viv\u00eancia viva da situa\u00e7\u00e3o traum\u00e1tica (intrus\u00e3o), na evita\u00e7\u00e3o e num sentimento persistente de amea\u00e7a.<\/p>\n\n<p><strong>Intrus\u00e3o: <\/strong>Os pacientes com TEPT exibem uma liga\u00e7\u00e3o involunt\u00e1ria \u00e0 experi\u00eancia horr\u00edvel. Esta servid\u00e3o manifesta-se em imagens, sons ou outras impress\u00f5es v\u00edvidas do acontecimento traum\u00e1tico que involuntariamente &#8220;invadem&#8221; tanto o estado de vig\u00edlia da consci\u00eancia como o sono. Isto tamb\u00e9m \u00e9 chamado de flashbacks. Muitas vezes existe um estado subjectivamente experimentado de ser inundado por estas imagens interiores.<\/p>\n\n<p><strong>Evitar: <\/strong>Al\u00e9m disso, os afectados tentam muitas vezes com todas as suas for\u00e7as &#8220;desligar&#8221; os pensamentos que os inundam, ou seja, deixar de pensar no que aconteceu. Apesar das tentativas intensivas, esta evas\u00e3o n\u00e3o \u00e9 bem sucedida na maioria dos casos. O comportamento evitador inclui tamb\u00e9m a timidez de fazer actividades, ir a lugares ou conhecer pessoas que recordam o trauma.<\/p>\n\n<p><strong>Persist\u00eancia da sensa\u00e7\u00e3o de amea\u00e7a: <\/strong>o corpo tamb\u00e9m reage ap\u00f3s um trauma, mesmo se as pessoas afectadas muitas vezes n\u00e3o v\u00eaem as consequ\u00eancias f\u00edsicas relacionadas com o trauma. O limiar de excita\u00e7\u00e3o do sistema nervoso aut\u00f3nomo baixa, ou seja, tens\u00f5es subsequentes ainda menores levam a uma excita\u00e7\u00e3o mais forte. Como resultado do trauma, existe um persistente sentimento de amea\u00e7a (hipervigil\u00e2ncia). As situa\u00e7\u00f5es quotidianas s\u00e3o consideradas excessivamente perigosas. Isto diz respeito tanto a situa\u00e7\u00f5es associadas a trauma como a situa\u00e7\u00f5es n\u00e3o associadas a trauma.<\/p>\n\n<p><strong>Epidemiologia e curso do TEPT: <\/strong>Embora estudos epidemiol\u00f3gicos mostrem que a maioria da popula\u00e7\u00e3o experimenta eventos traum\u00e1ticos no decurso das suas vidas, a preval\u00eancia ao longo da vida na Europa situa-se apenas entre 1 e 3 por cento [3]. Isto significa que a maioria das pessoas traumatizadas n\u00e3o desenvolvem TEPT, mas mostram uma recupera\u00e7\u00e3o espont\u00e2nea. O curso do PTSD caracteriza-se tamb\u00e9m pelo facto de, na maioria das v\u00edtimas de trauma, os sintomas se remeterem em poucas semanas. Uma dura\u00e7\u00e3o dos sintomas de mais de tr\u00eas meses \u00e9 prognosticadamente desfavor\u00e1vel, uma vez que os sintomas persistem por mais tempo e se tornam cr\u00f3nicos.<\/p>\n\n<h2 id=\"ptsd-complexo\" class=\"wp-block-heading\">PTSD complexo<\/h2>\n\n<p>Os mesmos sintomas psicol\u00f3gicos t\u00eam sido descritos para todos os traumas. No entanto, foi demonstrado que em muitos casos, os traumas deliberadamente feitos pelo homem e os traumas de tipo II, que duram mais tempo, levam a defici\u00eancias mais extensas do que as outras formas. Portanto, o complexo PTSD (KPTBS) foi introduzido como um novo diagn\u00f3stico no CID-11. O TEPT complexo envolve uma forte reac\u00e7\u00e3o psicol\u00f3gica causada por experi\u00eancias traum\u00e1ticas prolongadas, geralmente envolvendo m\u00faltiplos ou repetidos eventos traum\u00e1ticos (por exemplo, abuso sexual infantil). O diagn\u00f3stico inclui todos os principais sintomas do PTSD cl\u00e1ssico. Al\u00e9m disso, para um diagn\u00f3stico de TEPT <span style=\"font-family: franklin gothic demi;\">(Quadro 2)<\/span>, deve estar presente uma desordem de regula\u00e7\u00e3o do efeito (incluindo uma tend\u00eancia para a dissocia\u00e7\u00e3o), uma autopercep\u00e7\u00e3o negativa e desordens de relacionamento.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"1293\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab2_np1_s8.png\" alt=\"\" class=\"wp-image-15510 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab2_np1_s8.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab2_np1_s8-800x940.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab2_np1_s8-120x141.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab2_np1_s8-90x106.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab2_np1_s8-320x376.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab2_np1_s8-560x658.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1293;\" \/><\/figure>\n\n<h2 id=\"psicoterapia\" class=\"wp-block-heading\">Psicoterapia<\/h2>\n\n<p>Nas \u00faltimas duas d\u00e9cadas, foram desenvolvidos m\u00e9todos bem sucedidos para a terapia de reac\u00e7\u00f5es p\u00f3s-traum\u00e1ticas e sequelas de trauma manifesto. \u00c9 importante lembrar ao tratar o TEPT que muitos pacientes t\u00eam uma s\u00e9rie de outros problemas psicol\u00f3gicos e interpessoais (depress\u00e3o, v\u00edcios, doen\u00e7as f\u00edsicas, dist\u00farbios sociais). No mundo de l\u00edngua alem\u00e3, foram estabelecidas tr\u00eas fases terap\u00eauticas no tratamento do PTSD <span style=\"font-family: franklin gothic demi;\">(Fig. 1)<\/span>.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"385\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/abb1_np1_s8.png\" alt=\"\" class=\"wp-image-15511 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/abb1_np1_s8.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/abb1_np1_s8-800x280.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/abb1_np1_s8-120x42.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/abb1_np1_s8-90x32.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/abb1_np1_s8-320x112.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/abb1_np1_s8-560x196.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/385;\" \/><\/figure>\n\n<p>As abordagens terap\u00eauticas comportamentais (por exemplo, Exposi\u00e7\u00e3o Prolongada) e as terapias cognitivas t\u00eam o maior efeito entre todos os m\u00e9todos de tratamento de TEPT <span style=\"font-family: franklin gothic demi;\">(Tab. 3) <\/span>. A terapia de exposi\u00e7\u00e3o narrativa (NET) e a EMDR (Eye Movement Desensitisation and Reprocessing) s\u00e3o tamb\u00e9m abordagens de tratamento comuns. Os resultados da investiga\u00e7\u00e3o tamb\u00e9m mostram que a psicoterapia \u00e9 mais eficaz que a medica\u00e7\u00e3o (por exemplo, escitalopram) [4].<\/p>\n\n<p>A exposi\u00e7\u00e3o ao evento traum\u00e1tico \u00e9 o foco das psicoterapias avaliadas como bem sucedidas. Na terapia de exposi\u00e7\u00e3o prolongada, os doentes com TEPT s\u00e3o imaginativamente confrontados com eventos traum\u00e1ticos [5]. O trauma \u00e9 revivido e narrado com a ajuda dos pr\u00f3prios sentimentos. Atrav\u00e9s desta exposi\u00e7\u00e3o em sensu (na imagina\u00e7\u00e3o), o evento traum\u00e1tico \u00e9 relatado repetidamente at\u00e9 ocorrer uma habitua\u00e7\u00e3o, ou seja, uma habitua\u00e7\u00e3o com uma reac\u00e7\u00e3o enfraquecida quando confrontada com as mem\u00f3rias do trauma. Em alguns casos, esta abordagem \u00e9 combinada com a exposi\u00e7\u00e3o in vivo a situa\u00e7\u00f5es evitadas.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"708\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab3_np1_s8.png\" alt=\"\" class=\"wp-image-15512 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab3_np1_s8.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab3_np1_s8-800x515.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab3_np1_s8-120x77.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab3_np1_s8-90x58.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab3_np1_s8-320x206.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/02\/tab3_np1_s8-560x360.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/708;\" \/><\/figure>\n\n<p>A terapia de processamento cognitivo \u00e9 outro elemento da terapia de trauma. As pessoas com TEPT s\u00e3o frequentemente caracterizadas por uma avalia\u00e7\u00e3o extremamente negativa dos sintomas p\u00f3s-traum\u00e1ticos [6]. Por exemplo, sintomas persistentes de intrus\u00e3o podem ser interpretados de forma catastr\u00f3fica (por exemplo, &#8220;Se estas mem\u00f3rias s\u00fabitas n\u00e3o pararem em breve, acabarei por enlouquecer!&#8221;). Tamb\u00e9m n\u00e3o \u00e9 invulgar as pessoas terem uma forte convic\u00e7\u00e3o de culpa ap\u00f3s um trauma. As interven\u00e7\u00f5es cognitivas centram-se na modifica\u00e7\u00e3o de avalia\u00e7\u00f5es e cren\u00e7as disfuncionais utilizando t\u00e9cnicas cognitivas cl\u00e1ssicas [7].<\/p>\n\n<p>A Terapia de Exposi\u00e7\u00e3o Narrativa (NET) foi desenvolvida para o tratamento do TEPT ap\u00f3s m\u00faltiplos traumatismos e baseia-se nos princ\u00edpios da terapia cognitiva-comportamental. NET n\u00e3o lida com um trauma de cada vez, mas apresenta e escreve narrativamente todo o per\u00edodo de vida. Colocando cronologicamente um ou mais traumas na sua pr\u00f3pria biografia, realiza-se um processamento de confronto [8]. O m\u00e9todo EMDR (Eye Movement Desensitisation and Reprocessing) de acordo com Shapiro \u00e9 tamb\u00e9m um m\u00e9todo comum na terapia de trauma. Na exposi\u00e7\u00e3o EMDR, as imagens, percep\u00e7\u00f5es, cogni\u00e7\u00f5es ou sentimentos associados ao trauma s\u00e3o processados com estimula\u00e7\u00e3o sensorial bilateral atrav\u00e9s de movimentos oculares (ou estimula\u00e7\u00e3o auditiva ou t\u00e1ctil) at\u00e9 que a ang\u00fastia seja reduzida [9].<\/p>\n\n<p>A terapia de exposi\u00e7\u00e3o, em particular, consegue frequentemente reduzir os sintomas p\u00f3s-traum\u00e1ticos dentro de algumas semanas. Para al\u00e9m da redu\u00e7\u00e3o dos sintomas, lidar com as m\u00faltiplas consequ\u00eancias e integrar o trauma na vida da pessoa traumatizada requer um trabalho terap\u00eautico mais longo. Basicamente, o procedimento de exposi\u00e7\u00e3o (isto \u00e9, visualiza\u00e7\u00e3o do trauma juntamente com o psicoterapeuta) deve ser distinguido da retraumatiza\u00e7\u00e3o, uma vez que o primeiro serve um prop\u00f3sito de apoio e cura e oferece ao paciente possibilidades de reestruturar o seu conte\u00fado de mem\u00f3ria traum\u00e1tica. A retraumatiza\u00e7\u00e3o, por outro lado, \u00e9 definida como um procedimento que apenas coloca um novo stress no paciente ou o sobrecarrega severamente e n\u00e3o proporciona qualquer al\u00edvio intencional (a retraumatiza\u00e7\u00e3o \u00e9, por exemplo, o resultado de interrogat\u00f3rios policiais ou entrevistas com jornalistas sensacionalistas).<\/p>\n\n<p><strong>Procedimento para o TEPT complexo: O TEPT <\/strong>coloca desafios particulares aos psicoterapeutas e h\u00e1 ainda muitas quest\u00f5es por responder relativamente ao procedimento terap\u00eautico, \u00e0 dura\u00e7\u00e3o do tratamento e ao sucesso esperado do tratamento. No entanto, h\u00e1 acordo que a terapia bem sucedida de PTSD requer exposi\u00e7\u00e3o em sensu em combina\u00e7\u00e3o com m\u00e9todos cognitivos. Isto foi demonstrado por Watts et al.  [10]  confirmado numa extensa meta-an\u00e1lise. No entanto, a exposi\u00e7\u00e3o deve ser precedida por uma fase suficientemente longa de estabiliza\u00e7\u00e3o. No entanto, esta fase tamb\u00e9m pode ser muito curta se for fornecido tratamento intensivo, como foi demonstrado utilizando o conceito de 12 semanas de terapia dial\u00e9ctica comportamental (DBT) para PTSD [11]. Ap\u00f3s apenas um m\u00eas de estabiliza\u00e7\u00e3o, o confronto foi realizado com sucesso com pessoas traumatizadas complexas. No entanto, alguns pacientes que s\u00e3o particularmente afectados podem precisar de alternar entre interven\u00e7\u00f5es ambulat\u00f3rias e internas v\u00e1rias vezes at\u00e9 alcan\u00e7arem sucesso terap\u00eautico.<\/p>\n\n<p>Como descrito anteriormente, para al\u00e9m dos sintomas do TEPT, as pessoas com TEPT t\u00eam frequentemente problemas de regula\u00e7\u00e3o das emo\u00e7\u00f5es e problemas interpessoais. Ao implementar estrat\u00e9gias de DBT no processo terap\u00eautico, as emo\u00e7\u00f5es podem ser eficazmente reguladas, raz\u00e3o pela qual esta abordagem \u00e9 particularmente adequada para a KPTBS [12]. Cloitre et al. desenvolveu um programa de terapia em duas fases que integra interven\u00e7\u00f5es eficazes para v\u00e1rias \u00e1reas sintom\u00e1ticas [13]. Na primeira fase do tratamento, o enfoque \u00e9 nas compet\u00eancias para a regula\u00e7\u00e3o das emo\u00e7\u00f5es e o trabalho em esquemas interpessoais disfuncionais (&#8220;treino de compet\u00eancias em mat\u00e9ria de regula\u00e7\u00e3o dos efeitos e das rela\u00e7\u00f5es interpessoais&#8221;, STAIR). Na segunda fase do tratamento, as mem\u00f3rias traum\u00e1ticas s\u00e3o processadas suavemente e em doses, com a ajuda de m\u00e9todos narrativos. Esta abordagem passo a passo provou ser muito eficaz com as v\u00edtimas de abuso sexual e f\u00edsico, por exemplo [14].<\/p>\n\n<h2 id=\"mensagens-take-home\" class=\"wp-block-heading\">Mensagens Take-Home<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>O PTSD ocorre ap\u00f3s eventos de risco de vida\/traum\u00e1ticos e caracteriza-se por intrus\u00f5es (sob a forma de imagens imponentes ou pesadelos), evas\u00e3o e um persistente sentimento de amea\u00e7a.<\/li>\n\n\n\n<li>O TEPT ocorre em particular como resultado de eventos traum\u00e1ticos repetitivos ou prolongados e, para al\u00e9m dos sintomas do TEPT, caracteriza-se adicionalmente por perturba\u00e7\u00f5es de regula\u00e7\u00e3o emocional, auto-percep\u00e7\u00e3o negativa e perturba\u00e7\u00f5es de relacionamento.<\/li>\n\n\n\n<li>V\u00e1rias formas de exposi\u00e7\u00e3o em sensu ao evento traum\u00e1tico s\u00e3o o foco das psicoterapias para o TEPT que foram avaliadas como bem sucedidas.<\/li>\n\n\n\n<li>As abordagens de tratamento bem sucedidas para o PTSD devem incluir a exposi\u00e7\u00e3o em sensu, an\u00e1loga ao PTSD cl\u00e1ssico. Interven\u00e7\u00f5es complementares tais como STAIR ou DBT-PTBS s\u00e3o particularmente promissoras para a KPTBS.<\/li>\n<\/ul>\n\n<p>Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>OMS (Organiza\u00e7\u00e3o Mundial de Sa\u00fade). (2020). ICD-11 beta draft (estat\u00edsticas de mortalidade e morbidade). https:\/\/icd.who.int\/dev11\/l-m\/en. Acedido em 16.12.2020.<\/li>\n\n\n\n<li>APA (Organiza\u00e7\u00e3o Psiqui\u00e1trica Americana). (2013). Manual de diagn\u00f3stico e estat\u00edstica de perturba\u00e7\u00f5es mentais (DSM-V). Washington DC: American Psychiatric Press.<\/li>\n\n\n\n<li>Maercker A, Forstmeier S, Wagner B, et al: (2008). Perturba\u00e7\u00f5es de stress p\u00f3s-traum\u00e1tico na Alemanha. Der Nervenarzt, 79(5), 577.<\/li>\n\n\n\n<li>Shalev AY, Ankri Y, Israel-Shalev Y, et al: (2012). Preven\u00e7\u00e3o do transtorno de stress p\u00f3s-traum\u00e1tico atrav\u00e9s de tratamento precoce: resultados do estudo Jerusalem Trauma Outreach and Prevention. Arquivos de Psiquiatria Geral, 69(2), 166-176.<\/li>\n\n\n\n<li>Foa EB, Hembree EA, Rothbaum BO: (2014). Manual de Exposi\u00e7\u00e3o Prolongada: Conceitos B\u00e1sicos e Aplica\u00e7\u00e3o &#8211; um Guia para Terapeutas. Lichtenau: Probst.<\/li>\n\n\n\n<li>Ehlers A, Clark DM: (2000). Um modelo cognitivo de transtorno de stress p\u00f3s-traum\u00e1tico. Investiga\u00e7\u00e3o e Terapia de Comportamento, 38(4), 319-345.<\/li>\n\n\n\n<li>K\u00f6nig J, Resick PA, Karl R, Rosner R: (2012). Dist\u00farbio de Stress P\u00f3s-Traum\u00e1tico: Um Manual para Terapia de Processamento Cognitivo. G\u00f6ttingen: Hogrefe.<\/li>\n\n\n\n<li>Schauer M, Neuner F, Elbert, T: (2011). Terapia de exposi\u00e7\u00e3o narrativa: Uma interven\u00e7\u00e3o a curto prazo para perturba\u00e7\u00f5es traum\u00e1ticas de stress ap\u00f3s a guerra, terror, ou tortura. G\u00f6ttingen: Hogrefe.<\/li>\n\n\n\n<li>Shapiro F: (2012). EMDR &#8211; Fundamentos e Pr\u00e1tica: Manual para o Tratamento de Pessoas Traumatizadas. Paderborn: Junfermann.<\/li>\n\n\n\n<li>Watts BV, Schnurr PP, Mayo L, et al: (2013). Meta-an\u00e1lise da efic\u00e1cia dos tratamentos para o transtorno de stress p\u00f3s-traum\u00e1tico. Journal of Clinical Psychiatry, 74(6), 541-550.<\/li>\n\n\n\n<li>Bohus M, Dyer AS, Priebe K, et al: (2013). Terapia dial\u00e9ctica comportamental para o transtorno de stress p\u00f3s-traum\u00e1tico ap\u00f3s abuso sexual infantil em doentes com e sem transtorno de personalidade lim\u00edtrofe: Um ensaio aleat\u00f3rio controlado. Psicoterapia e Psicossom\u00e1tica, 82(4), 221-233.<\/li>\n\n\n\n<li>Bohus M, Priebe K: (2019). Terapia dial\u00e9ctico-comportamental para PTSD complexo. Em A. Maercker (ed.). Trauma sequelae disorders (pp. 331-348). Berlim: Springer.<\/li>\n\n\n\n<li>Cloitre M, Koenen KC, Cohen L, et al: (2002). Forma\u00e7\u00e3o de compet\u00eancias em regula\u00e7\u00e3o afectiva e interpessoal seguida de exposi\u00e7\u00e3o: um tratamento baseado em fases para PTSD relacionado com o abuso infantil. Journal of Consulting and Clinical Psychology, 70(5), 1067-1074.<\/li>\n\n\n\n<li>Cloitre M, Cohen LR, Koenen KC: (2014). Abuso sexual e maus-tratos na inf\u00e2ncia: Um programa terap\u00eautico para o tratamento das consequ\u00eancias de traumas complexos. G\u00f6ttingen: Hogrefe.<\/li>\n\n\n\n<li>Maercker A, Augsburger M: (2019). Transtorno de stress p\u00f3s-traum\u00e1tico. Em A. Maercker (ed.). Perturba\u00e7\u00f5es de sequelas de trauma (217-227). Berlim: Springer.<\/li>\n\n\n\n<li>Maercker A: (2019). Sistem\u00e1tica e efic\u00e1cia dos m\u00e9todos terap\u00eauticos. Em A. Maercker (ed.). Trauma sequelae disorders (pp. 217-227). Berlim: Springer.<\/li>\n<\/ol>\n\n<p><em>PR\u00c1TICA DO GP 2021; 16(7): 5-8<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os traumas psicol\u00f3gicos podem ter causas diferentes. No entanto, t\u00eam uma coisa em comum &#8211; causariam profundo desespero em quase todos. As experi\u00eancias traum\u00e1ticas podem ser classificadas de acordo com&hellip;<\/p>\n","protected":false},"author":7,"featured_media":109593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Traumas","footnotes":""},"category":[22618,11524,11305,11481,11551],"tags":[19998,11754,19996,19997],"powerkit_post_featured":[],"class_list":["post-328560","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacao-cme","category-formacao-continua","category-medicina-interna-geral","category-psiquiatria-e-psicoterapia","category-rx-pt","tag-eventos-traumaticos","tag-formacao-cme","tag-trauma-pt-pt","tag-traumatologia","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:35:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":328564,"slug":"la-terapia-del-trauma-a-la-vanguardia-de-la-ciencia","post_title":"La terapia del trauma a la vanguardia de la ciencia","href":"https:\/\/medizinonline.com\/es\/la-terapia-del-trauma-a-la-vanguardia-de-la-ciencia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/328560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=328560"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/328560\/revisions"}],"predecessor-version":[{"id":328563,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/328560\/revisions\/328563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/109593"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=328560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=328560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=328560"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=328560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}