{"id":329102,"date":"2021-05-10T09:33:11","date_gmt":"2021-05-10T07:33:11","guid":{"rendered":"https:\/\/medizinonline.com\/nova-opcao-em-terapia-de-manutencao-de-primeira-linha\/"},"modified":"2021-05-10T09:33:11","modified_gmt":"2021-05-10T07:33:11","slug":"nova-opcao-em-terapia-de-manutencao-de-primeira-linha","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/nova-opcao-em-terapia-de-manutencao-de-primeira-linha\/","title":{"rendered":"Nova op\u00e7\u00e3o em terapia de manuten\u00e7\u00e3o de primeira linha"},"content":{"rendered":"<p>O cancro do ov\u00e1rio \u00e9 ainda o tumor ginecol\u00f3gico mais letal e, especialmente em fases avan\u00e7adas, o risco de progress\u00e3o permanece elevado mesmo com uma terapia \u00f3ptima [1, 2]. Assim, s\u00e3o necess\u00e1rios tratamentos eficazes para reduzir o risco de progress\u00e3o ou morte ap\u00f3s quimioterapia de primeira linha [1]. Para pacientes com defici\u00eancia de recombina\u00e7\u00e3o hom\u00f3loga (DRH), uma nova op\u00e7\u00e3o est\u00e1 dispon\u00edvel desde Abril de 2021 [3].<\/p>\n<p> <!--more--> <\/p>\n<p>O ensaio aleat\u00f3rio, duplo-cego fase III PRIMA demonstrou a efic\u00e1cia da terapia de manuten\u00e7\u00e3o com niraparibe (Zejula) em doentes com cancro ovariano avan\u00e7ado recentemente diagnosticado. Os pacientes tinham anteriormente respondido \u00e0 quimioterapia \u00e0 base de platina e estavam em alto risco de progress\u00e3o. Cerca de metade dos 733 pacientes inclu\u00eddos tinham DRH, dos quais cerca de 60% tinham uma muta\u00e7\u00e3o BRCA e 40% n\u00e3o [1]. Na Su\u00ed\u00e7a, o niraparib \u00e9 aprovado para pacientes com muta\u00e7\u00e3o BRCA ou outro DRH [3].<\/p>\n<p><strong>Vedopplica\u00e7\u00e3o do PFS mediano em doentes com DRH [1].<\/strong><\/p>\n<p>Ap\u00f3s um seguimento mediano de 13,8 meses, foi observada uma sobrevida mediana sem progress\u00e3o (PFS) de mais do dobro do tempo em doentes com DRH a tomar niraparibe que a tomar placebo (21,9 contra 10,4 meses, Figura). Isto corresponde a uma redu\u00e7\u00e3o de 57% no risco de progress\u00e3o ou morte (HR: 0,43; 95% CI: 0,31-0,59; P&lt;0,001) [1]. O benef\u00edcio PFS do niraparib foi observado independentemente do estatuto BRCA. Assim, numa an\u00e1lise explorat\u00f3ria pr\u00e9-definida, foi observada uma redu\u00e7\u00e3o substancial do risco tanto em pacientes com DRH positivo com (HR: 0,40; 95% CI: 0,265-0,618; P&lt;0,0001) como sem muta\u00e7\u00e3o BRCA (HR: 0,50; 95% CI: 0,305-0,831; P=0,0064) [4].<\/p>\n<p><img decoding=\"async\" alt=\"\" data-src=\"https:\/\/assets.medizinonline.com\/sites\/default\/files\/field\/images\/pfs.jpg\" style=\"height:308px; width:566px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/p>\n<p><strong>Figura:<\/strong>&nbsp;Sobreviv\u00eancia sem progress\u00e3o mediana com niraparibe versus placebo em doentes com DRH no ensaio PRIMA fase III aleat\u00f3ria e duplo-cego (adaptado de [1]). As pessoas censuradas s\u00e3o mostradas como c\u00edrculos.<\/p>\n<p><strong>Criada&nbsp;<\/strong><strong>Perfil de Tolerabilidade [3, 4]<\/strong><\/p>\n<p>Os efeitos secund\u00e1rios mais comuns (\u226530%) com niraparibe no ensaio PRIMA foram anemia, n\u00e1usea, trombocitopenia, obstipa\u00e7\u00e3o e fadiga. Anemia, trombocitopenia e neutropenia foram observados como os efeitos secund\u00e1rios mais frequentes (grau \u22653) [1]. Os efeitos adversos foram geridos pela interrup\u00e7\u00e3o do tratamento ou redu\u00e7\u00e3o da dose, e apenas 12% dos doentes da popula\u00e7\u00e3o em geral interromperam o tratamento devido a efeitos secund\u00e1rios [1]. A qualidade geral de vida foi mantida com o niraparib [1].<\/p>\n<p><strong>Conclus\u00e3o<\/strong><\/p>\n<p>Com a expans\u00e3o da indica\u00e7\u00e3o em Abril de 2021, o niraparib oferece uma terapia de manuten\u00e7\u00e3o de primeira linha para o cancro avan\u00e7ado dos ov\u00e1rios que pode ser utilizada em todos os doentes com DRH, independentemente do estado de BRCA [3]. Como mostram os dados do ensaio PRIMA, o niraparib reduz significativamente o risco de progress\u00e3o ou morte em compara\u00e7\u00e3o com o placebo, mantendo a qualidade de vida [1]. Com a sua administra\u00e7\u00e3o oral \u00fanica e di\u00e1ria independente das refei\u00e7\u00f5es, o inibidor PARP \u00e9 uma op\u00e7\u00e3o amiga do paciente que tem um perfil de tolerabilidade control\u00e1vel [1, 3].<\/p>\n<div>\n<table border=\"1\" cellpadding=\"1\" cellspacing=\"1\" style=\"width:647px\">\n<tbody>\n<tr>\n<td style=\"width:637px\">\n<p><strong>Dosagem inicial individualizada&nbsp;[3]<\/strong><\/p>\n<div>Niraparib foi tamb\u00e9m aprovado na primeira linha com uma dose inicial individualizada:<\/div>\n<ul>\n<li>200mg para um peso corporal &lt;77kg ou uma contagem de plaquetas &lt;150 000\/\u03bcl<\/li>\n<li>300mg para um peso corporal \u226577kg e uma contagem de plaquetas \u2265150 000\/\u03bcl<\/li>\n<\/ul>\n<div>Isto pode reduzir quaisquer efeitos secund\u00e1rios que ocorram, mantendo ao mesmo tempo a efic\u00e1cia da terapia [3, 5].<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>A Zejula \u00e9 indicada como terapia de manuten\u00e7\u00e3o em pacientes com carcinoma s\u00e9rico avan\u00e7ado (FIGO fase III a IV) de ov\u00e1rio, tub\u00e1rio ou peritoneal de alta qualidade com elevado risco de recorr\u00eancia e uma muta\u00e7\u00e3o BRCA ou outra defici\u00eancia de recombina\u00e7\u00e3o hom\u00f3loga (DRH) com instabilidade gen\u00f3mica na presen\u00e7a de remiss\u00e3o completa ou parcial ap\u00f3s quimioterapia de primeira linha \u00e0 base de platina. Al\u00e9m disso, Zejula \u00e9 indicado para o tratamento de manuten\u00e7\u00e3o de pacientes adultos com carcinoma epitelial prim\u00e1rio recorrente sens\u00edvel \u00e0 platina de alto grau (altamente desdiferenciado) ovariano, tub\u00e1rio ou peritoneal. O paciente deve ter respondido total ou parcialmente \u00e0 quimioterapia \u00e0 base de platina [3].<\/p>\n<p>Respons\u00e1vel pelo conte\u00fado e financiado pela GlaxoSmithKline AG, Talstr. 3-5,&nbsp;3053 M\u00fcnchenbuchsee.<\/p>\n<p>As marcas comerciais s\u00e3o propriedade dos seus respectivos propriet\u00e1rios. \u00a9 2021 Grupo de empresas GSK ou o seu licenciador.<\/p>\n<p><a href=\"https:\/\/assets.medizinonline.com\/sites\/default\/files\/210201_zejula_kurz-fi_d_0221_ab_april_2021_0.pdf\" target=\"_blank\" rel=\"noopener\">Informa\u00e7\u00e3o sobre temas curtos Zejula<\/a><\/p>\n<p>PM-CH-NRP-ADVR-210023-04\/2021<\/p>\n<p><strong>Literatura<\/strong><\/p>\n<ol>\n<li><span style=\"font-size:12px\">Gonz\u00e1lez-Mart\u00edn, A., et al, Niraparib em Pacientes com Cancro do Ov\u00e1rio Avan\u00e7ado Recentemente Diagnosticado. N Engl J Med, 2019. 381(25): p. 2391-2402.<\/span><\/li>\n<li><span style=\"font-size:12px\">Lorusso, D., et al, The role of secondary surgery in recurrent ovarian cancer. Int J Surg Oncol, 2012. 2012: p. 613980.<\/span><\/li>\n<li><span style=\"font-size:12px\">Informa\u00e7\u00e3o sobre o produto Zejula (niraparib). <a href=\"www.swissmedicinfo.ch\">www.swissmedicinfo.ch<\/a>. \u00daltimo acesso: 01.04.2021.<\/span><\/li>\n<li><span style=\"font-size:12px\">Monk, B.J. e A.G. Martin, Efficacy of niraparib therapy in patients with newly diagnosticed advanced ovarian cancer by BRCA and homologous recombination status: estudo PRIMA\/ENGOT-OV26\/GOG-3012. Oncologia Ginecol\u00f3gica, 2020. 159: p. 18.<\/span><\/li>\n<li><span style=\"font-size:12px\">Mirza, M.R., et al, Evaluation of an individualized start-dose of niraparib in the PRIMA\/ENGOT-OV26\/GOG-3012 study. Journal of Clinical Oncology, 2020. 38(15_suppl): p. 6050-6050.<\/span><\/li>\n<\/ol>\n<div>&nbsp;<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O cancro do ov\u00e1rio \u00e9 ainda o tumor ginecol\u00f3gico mais letal e, especialmente em fases avan\u00e7adas, o risco de progress\u00e3o permanece elevado mesmo com uma terapia \u00f3ptima [1, 2]. Assim,&hellip;<\/p>\n","protected":false},"author":12,"featured_media":106555,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Conte\u00fado patrocinado: HRD-positivo cancro avan\u00e7ado dos ov\u00e1rios","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11419,11379,11551],"tags":[],"powerkit_post_featured":[],"class_list":["post-329102","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ginecologia-pt-pt","category-oncologia-pt-pt","category-rx-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:18:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":329113,"slug":"nueva-opcion-en-la-terapia-de-mantenimiento-de-primera-linea","post_title":"Nueva opci\u00f3n en la terapia de mantenimiento de primera l\u00ednea","href":"https:\/\/medizinonline.com\/es\/nueva-opcion-en-la-terapia-de-mantenimiento-de-primera-linea\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/329102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=329102"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/329102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/106555"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=329102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=329102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=329102"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=329102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}