{"id":333435,"date":"2020-09-16T02:00:00","date_gmt":"2020-09-16T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/o-controlo-precoce-do-ritmo-visa-melhores-resultados\/"},"modified":"2020-09-16T02:00:00","modified_gmt":"2020-09-16T00:00:00","slug":"o-controlo-precoce-do-ritmo-visa-melhores-resultados","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/o-controlo-precoce-do-ritmo-visa-melhores-resultados\/","title":{"rendered":"O controlo precoce do ritmo visa melhores resultados"},"content":{"rendered":"<p><strong>Em pacientes com fibrila\u00e7\u00e3o atrial recentemente diagnosticada, o in\u00edcio precoce do controlo do ritmo pode reduzir os resultados cardiovasculares. A terapia com medicamentos antiarr\u00edtmicos e\/ou abla\u00e7\u00e3o de cateteres reduziu as mortes cardiovasculares, acidentes vasculares cerebrais e hospitaliza\u00e7\u00f5es devido ao agravamento da insufici\u00eancia card\u00edaca ou s\u00edndrome coron\u00e1ria aguda em compara\u00e7\u00e3o com os actuais cuidados padr\u00e3o baseados em evid\u00eancias.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Embora o controlo precoce do ritmo estivesse associado a eventos mais adversos, a seguran\u00e7a global de ambas as estrat\u00e9gias era compar\u00e1vel e n\u00e3o afectava o n\u00famero de noites de hospitaliza\u00e7\u00e3o por ano. Estas foram as conclus\u00f5es do estudo EAST-AFNET 4 [1,2]. A equipa de investiga\u00e7\u00e3o mostrou que mesmo com o actual tratamento baseado em directrizes, cerca de 5% dos pacientes com FA sofrem de s\u00edndrome coron\u00e1ria aguda, insufici\u00eancia card\u00edaca, acidente vascular cerebral ou morte cardiovascular todos os anos. Especialmente no primeiro ano ap\u00f3s o diagn\u00f3stico de fibrila\u00e7\u00e3o atrial, o risco de complica\u00e7\u00f5es cardiovasculares \u00e9 aumentado. Assim, quanto mais cedo come\u00e7ar a terapia de controlo de ritmo, mais depressa pode funcionar.<\/p>\n<p>Inclu\u00edam-se 2789 pacientes com FA e doen\u00e7a cardiovascular precoces que receberam ou o controlo precoce do ritmo ou cuidados padr\u00e3o. O controlo precoce do ritmo inclu\u00eda tratamento com medicamentos antiarr\u00edtmicos ou abla\u00e7\u00e3o de cateteres ap\u00f3s aleatoriza\u00e7\u00e3o. Os cuidados padr\u00e3o limitam o controlo do ritmo ao tratamento dos sintomas relacionados com a fibrila\u00e7\u00e3o atrial. O ponto final prim\u00e1rio foi a morte por causas cardiovasculares, acidente vascular cerebral ou hospitaliza\u00e7\u00e3o com agravamento da insufici\u00eancia card\u00edaca ou s\u00edndrome coron\u00e1ria aguda. Ap\u00f3s um seguimento m\u00e9dio de 5,1 anos, o estudo foi interrompido prematuramente por causa da sua efic\u00e1cia. Verificou-se que a terapia de controlo precoce do ritmo estava associada a um risco mais baixo de resultados cardiovasculares do que os cuidados padr\u00e3o em pacientes com FA e doen\u00e7a cardiovascular precoces.<\/p>\n<p><em>Fonte: Congresso CES 2020 <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Kirchhof P. EAST &#8211; AFNET 4: Efeitos da terapia de controlo precoce do ritmo em pacientes com fibrilha\u00e7\u00e3o atrial. Hot Line 1, Congresso ESC 2020, 29 de Agosto.<\/li>\n<li>Kirchhof P, et al: Pacientes com Fibrila\u00e7\u00e3o Atrial. Novo Engl J Med. 2020, 29 de Agosto. DOI: 10.1056\/NEJMoa2019422.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>CARDIOVASC 2020; 19(3): 36 (publicado 18.9.20, antes da impress\u00e3o).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em pacientes com fibrila\u00e7\u00e3o atrial recentemente diagnosticada, o in\u00edcio precoce do controlo do ritmo pode reduzir os resultados cardiovasculares. A terapia com medicamentos antiarr\u00edtmicos e\/ou abla\u00e7\u00e3o de cateteres reduziu as&hellip;<\/p>\n","protected":false},"author":7,"featured_media":99583,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Fibrila\u00e7\u00e3o atrial","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11367,11521,11529,11551],"tags":[14818],"powerkit_post_featured":[],"class_list":["post-333435","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia-pt-pt","category-estudos","category-relatorios-do-congresso","category-rx-pt","tag-fibrilacao-atrial","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:53:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":333442,"slug":"el-control-precoz-del-ritmo-busca-mejores-resultados","post_title":"El control precoz del ritmo busca mejores resultados","href":"https:\/\/medizinonline.com\/es\/el-control-precoz-del-ritmo-busca-mejores-resultados\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/333435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=333435"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/333435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/99583"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=333435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=333435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=333435"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=333435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}