{"id":334520,"date":"2020-03-30T02:00:00","date_gmt":"2020-03-30T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/contra-atacar-o-medo-da-dor\/"},"modified":"2020-03-30T02:00:00","modified_gmt":"2020-03-30T00:00:00","slug":"contra-atacar-o-medo-da-dor","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/contra-atacar-o-medo-da-dor\/","title":{"rendered":"Contra-atacar o medo da dor"},"content":{"rendered":"<p><strong>A psicoterapia da dor inclui uma abordagem orientada tanto para os sintomas como para os problemas. Os factores psicossociais e relacionados com o trabalho contribuem para a cronifica\u00e7\u00e3o e devem definitivamente ser tidos em conta na terapia. A educa\u00e7\u00e3o \u00e9 uma componente importante na promo\u00e7\u00e3o do coping e da conformidade.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>As dores nas costas s\u00e3o um problema de sa\u00fade significativo nos pa\u00edses industrializados ocidentais. No inqu\u00e9rito de Schmidt et al. [1], 76% dos inquiridos relataram dores nas costas nos \u00faltimos 12 meses. Os seguintes aspectos podem ser observados em todos os estudos [2]: As mulheres s\u00e3o mais frequentemente afectadas do que os homens, as dores nas costas s\u00e3o encontradas em todos os grupos et\u00e1rios e em todas as classes sociais, os jovens adultos j\u00e1 mostram uma elevada preval\u00eancia anual a partir dos 20 anos de idade, a preval\u00eancia de dores cr\u00f3nicas nas costas aumenta com a idade. Uma elevada taxa de recorr\u00eancia combinada com uma tend\u00eancia para a cronifica\u00e7\u00e3o torna as dores nas costas um problema de sa\u00fade e sociopol\u00edtico, uma vez que a cronifica\u00e7\u00e3o das queixas est\u00e1 associada ao aumento das consequ\u00eancias sociom\u00e9dicas, tais como a redu\u00e7\u00e3o da incapacidade para o trabalho e a incapacidade, mas tamb\u00e9m o recurso aos servi\u00e7os m\u00e9dicos.<\/p>\n<h2 id=\"definicao-e-sintomas\">Defini\u00e7\u00e3o e sintomas  &nbsp;<\/h2>\n<p>As causas subjacentes ou patomecanismos das dores lombares incluem um grande n\u00famero de processos de doen\u00e7a. Contudo, doen\u00e7as espec\u00edficas, tais como uma h\u00e9rnia discal ou processos inflamat\u00f3rios, s\u00e3o a base patol\u00f3gica em apenas alguns dos casos. A grande maioria das dores nas costas \u00e9 referida como dores &#8220;n\u00e3o espec\u00edficas&#8221; nas costas. Em 80-90%, a causa exacta permanece pouco clara; para al\u00e9m das altera\u00e7\u00f5es degenerativas, s\u00e3o encontradas perturba\u00e7\u00f5es funcionais que afectam os discos intervertebrais, m\u00fasculos, f\u00e1scias, ligamentos e articula\u00e7\u00f5es do arco vertebral [3]. N\u00e3o espec\u00edfico significa que nenhum ou apenas um achado patol\u00f3gico estrutural irrelevante pode ser encontrado para a sintomatologia da dor.<\/p>\n<h2 id=\"factores-de-cronificacao\">Factores de cronifica\u00e7\u00e3o<\/h2>\n<p>A vis\u00e3o puramente m\u00e9dica e a terapia das dores nas costas atinge repetidamente os seus limites, uma vez que outros importantes factores de influ\u00eancia no processo de cronifica\u00e7\u00e3o s\u00e3o negligenciados. Estes factores de risco s\u00e3o descritos de forma abrangente com as chamadas &#8220;bandeiras&#8221; no <strong>quadro&nbsp;1 <\/strong>[4].<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-13383\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab1_hp3_s5.png\" style=\"height:362px; width:600px\" width=\"1100\" height=\"663\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab1_hp3_s5.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab1_hp3_s5-800x482.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab1_hp3_s5-120x72.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab1_hp3_s5-90x54.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab1_hp3_s5-320x193.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab1_hp3_s5-560x338.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>As caracter\u00edsticas do local de trabalho (&#8220;bandeiras negras&#8221;) tais como trabalho f\u00edsico pesado, tens\u00e3o vibrat\u00f3ria e posi\u00e7\u00f5es corporais constantes prolongadas s\u00e3o descritas como prognosticalmente desfavor\u00e1veis. Contudo, existem d\u00favidas sobre uma liga\u00e7\u00e3o directa entre as condi\u00e7\u00f5es objectivas do local de trabalho e a ocorr\u00eancia de dores lombares: a preval\u00eancia de dores lombares nos pa\u00edses industrializados est\u00e1 a aumentar, embora as condi\u00e7\u00f5es ergon\u00f3micas do local de trabalho estejam a melhorar cada vez mais. No entanto, os factores de risco relevantes para a cronifica\u00e7\u00e3o das queixas s\u00e3o sobretudo caracter\u00edsticas tais como o stress subjectivo experimentado no local de trabalho (&#8220;bandeiras azuis&#8221;) e factores psicossociais (&#8220;bandeiras amarelas&#8221;), estrat\u00e9gias de resposta disfuncional e tamb\u00e9m reac\u00e7\u00f5es emocionais \u00e0s queixas (ansiedade, depress\u00e3o) [5].<\/p>\n<p>A incapacidade subjectiva do paciente e a percep\u00e7\u00e3o do tipo e tratabilidade da doen\u00e7a, as pr\u00f3prias possibilidades de influ\u00eancia do paciente e o comportamento de doen\u00e7a associado (passividade, protec\u00e7\u00e3o, incapacidade de trabalhar, utiliza\u00e7\u00e3o do sistema de cuidados de sa\u00fade) s\u00e3o factores significativos que mant\u00eam as queixas. Se o doente estiver convencido de que o seu desconforto assinala um perigo f\u00edsico e \u00e9 resultado de stress f\u00edsico, evitar\u00e1 o stress no futuro para evitar mais danos f\u00edsicos potenciais e um aumento da dor. Por medo da dor e dos danos, desenvolve-se um chamado comportamento de preven\u00e7\u00e3o do medo. Em termos de teoria da aprendizagem, isto pode ser explicado da seguinte forma: A associa\u00e7\u00e3o cognitivamente mediada entre dor e stress f\u00edsico surge atrav\u00e9s do condicionamento cl\u00e1ssico e \u00e9 operantemente refor\u00e7ada por comportamentos evasivos motivados pelo medo <strong>(Fig.&nbsp;1)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-13384 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/abb1_hp3_s5.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/789;height:430px; width:600px\" width=\"1100\" height=\"789\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/abb1_hp3_s5.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/abb1_hp3_s5-800x574.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/abb1_hp3_s5-120x86.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/abb1_hp3_s5-90x65.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/abb1_hp3_s5-320x230.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/abb1_hp3_s5-560x402.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Com a inactividade crescente, h\u00e1 perda de mobilidade, problemas de coordena\u00e7\u00e3o, descondicionamento, m\u00e1 postura e fraqueza da musculatura (atrofia) [6]. Os movimentos controlados (movimento vigiado) associados ao comportamento de evitar o medo levam a padr\u00f5es de movimento n\u00e3o fisiol\u00f3gicos, aumento da auto-consciencializa\u00e7\u00e3o e aumento da tens\u00e3o muscular. Este comportamento tende a ser refor\u00e7ado pelas escolas cl\u00e1ssicas de costas, nas quais o paciente \u00e9 &#8220;treinado&#8221; para seguir certos padr\u00f5es de movimento. Por exemplo, o paciente aprende a dobrar os joelhos quando s\u00f3 quer pegar em objectos leves. Os pacientes descrevem uma sensa\u00e7\u00e3o de movimento muito r\u00edgido e consciente, como se estivesse num espartilho. Durante a observa\u00e7\u00e3o comportamental, estes padr\u00f5es de movimento s\u00e3o tamb\u00e9m reconhec\u00edveis.<\/p>\n<p>Para al\u00e9m destas cren\u00e7as espec\u00edficas para evitar o medo em pacientes com dores nas costas, outros conhecimentos desfavor\u00e1veis relacionados com a dor podem ser identificados como factores de risco. Atribui\u00e7\u00f5es de controlo externo (&#8220;s\u00f3 uma opera\u00e7\u00e3o me pode ajudar&#8221;), pronunciadas atribui\u00e7\u00f5es causais est\u00e1veis (&#8220;a minha coluna vertebral est\u00e1 em ru\u00ednas, nada pode ser feito&#8221;) e a tend\u00eancia para a cat\u00e1strofe (&#8220;a dor vai piorar cada vez mais e tornar-me-ei um caso de enfermagem&#8221;) s\u00e3o os padr\u00f5es de pensamento maladaptado mais comuns. A experi\u00eancia de impot\u00eancia e desesperan\u00e7a associada a tais pensamentos, por sua vez, encoraja comportamentos protectores e evitadores e estrat\u00e9gias de sobreviv\u00eancia bastante passivas.&nbsp;  A retirada crescente, a incapacidade existente para trabalhar e o desamparo podem intensificar os estados de humor depressivos e os medos. H\u00e1 uma perda do papel social existente (por exemplo, como provedor da fam\u00edlia), conflitos no seio da fam\u00edlia e com o ambiente social. A auto-estima pode mudar, a rotina di\u00e1ria \u00e9 cada vez mais determinada pela &#8220;gest\u00e3o&#8221; da dor.<\/p>\n<p>Outro grupo de pacientes, por outro lado, tende a demonstrar um comportamento de perseveran\u00e7a, apresenta elevadas exig\u00eancias de desempenho e excede repetidamente os limites de desempenho f\u00edsico, o que tamb\u00e9m contribui para a cronifica\u00e7\u00e3o. Muitas vezes h\u00e1 cargas duplas (v\u00e1rios empregos, monoparentalidade, membros da fam\u00edlia para cuidar), o que favorece este tratamento disfuncional. Estes pacientes t\u00eam frequentemente uma m\u00e1 percep\u00e7\u00e3o do stress, alguns banalizam os sintomas e tamb\u00e9m utilizam analg\u00e9sicos para funcionar na vida quotidiana. \u00c9 feita uma distin\u00e7\u00e3o entre as &#8220;depress\u00f5es&#8221;, que frequentemente descrevem um humor depressivo-espelhado, uma vez que as exig\u00eancias di\u00e1rias da dor cr\u00f3nica s\u00e3o quase imposs\u00edveis de lidar, mas &#8220;mordem&#8221;, e as &#8220;depress\u00f5es alegres&#8221;, que utilizam injec\u00e7\u00f5es e medicamentos para funcionar e muitas vezes mostram pouca consci\u00eancia do problema. Por vezes, no entanto, \u00e9 mais um &#8220;rosto de p\u00f3quer&#8221;, a pessoa em quest\u00e3o coloca um rosto feliz porque o contexto profissional ou familiar o exige, mas o humor \u00e9 na realidade claramente afectado. Os pacientes com tal perseveran\u00e7a muitas vezes exageram durante anos at\u00e9 serem cada vez mais for\u00e7ados a descansar devido \u00e0 exaust\u00e3o e, finalmente, ficarem incapacitados para o trabalho a longo prazo. O desempenho f\u00edsico diminui cada vez mais ao longo do tempo porque o corpo n\u00e3o tem tempo suficiente para se regenerar at\u00e9 \u00e0 actividade seguinte.<\/p>\n<p>Para al\u00e9m destes factores psicossociais (bandeiras amarelas), a chamada cronifica\u00e7\u00e3o iatrog\u00e9nica (&#8220;bandeiras cor-de-rosa&#8221;) [7] desempenha um papel essencial. Meios iatrog\u00e9nicos: influ\u00eancias nocivas resultantes de comportamentos terap\u00eauticos e n\u00e3o-comportamentais. O sistema de cuidados m\u00e9dicos apoia as concep\u00e7\u00f5es leigas do doente sobre a doen\u00e7a, a patologia local e as op\u00e7\u00f5es de tratamento puramente m\u00e9dico s\u00e3o sobrevalorizadas, enquanto os factores psicossociais s\u00e3o negligenciados.<\/p>\n<p>Al\u00e9m disso, existem condi\u00e7\u00f5es do mercado de trabalho regional que tornam improv\u00e1vel a reintegra\u00e7\u00e3o na vida activa no caso de m\u00e1s qualifica\u00e7\u00f5es e defici\u00eancia devido a problemas de costas. Com um per\u00edodo de doen\u00e7a mais longo, as considera\u00e7\u00f5es de requerer uma pens\u00e3o tornam-se ent\u00e3o mais prov\u00e1veis.&nbsp;  A interac\u00e7\u00e3o das consequ\u00eancias psico-sociais e som\u00e1ticas das queixas leva, no sentido de um c\u00edrculo vicioso, a uma maior perpetua\u00e7\u00e3o das queixas.<\/p>\n<h2 id=\"terapia\">Terapia<\/h2>\n<p>Na Alemanha, o Barmer Ersatzkasse descreve no seu relat\u00f3rio de 2015 uma compara\u00e7\u00e3o da terapia em 2006 com 2014: Apesar da actualiza\u00e7\u00e3o da National Health Care Guideline for Low Back Pain em 2017, houve um aumento na taxa de terapia da dor interventiva. A terapia multimodal quadruplicou, mas a rela\u00e7\u00e3o entre a terapia interventiva da dor e a terapia interdisciplinar da dor multimodal \u00e9 de 11:1. Em geral, h\u00e1 uma falta, subutiliza\u00e7\u00e3o e sobreutiliza\u00e7\u00e3o de cuidados para as dores cr\u00f3nicas das costas na Alemanha.<\/p>\n<p>A dor cr\u00f3nica \u00e9 um evento multifactorial que pode ser explicado e tornado compreens\u00edvel com uma abordagem biopsicossocial. Consequentemente, as abordagens terap\u00eauticas devem tamb\u00e9m ter um car\u00e1cter multimodal e uma orienta\u00e7\u00e3o interdisciplinar e representam hoje o padr\u00e3o de ouro na terapia da dor. O interc\u00e2mbio regular entre as disciplinas (medicina, psicoterapia, fisioterapia), a linguagem comum e a filosofia s\u00e3o aqui importantes para se poder transmitir um modelo apropriado da doen\u00e7a ao paciente e assim facilitar o tratamento das queixas a longo prazo, o que inclui necessariamente lidar com factores psicossociais que aumentam a dor.<\/p>\n<p>Os objectivos globais da terapia interdisciplinar podem ser encontrados no<strong> quadro&nbsp;2<\/strong> [8].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-13385 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab2_hp3_s6.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/495;height:270px; width:600px\" width=\"1100\" height=\"495\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab2_hp3_s6.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab2_hp3_s6-800x360.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab2_hp3_s6-120x54.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab2_hp3_s6-90x41.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab2_hp3_s6-320x144.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab2_hp3_s6-560x252.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Os objectivos da psicoterapia da dor [9,10] s\u00e3o, para al\u00e9m da educa\u00e7\u00e3o de um modelo de doen\u00e7a, tamb\u00e9m o ensino de estrat\u00e9gias de assimila\u00e7\u00e3o para influenciar o sintoma (por exemplo, confrontando movimentos evitados, melhor equil\u00edbrio entre repouso e actividade, t\u00e9cnicas de relaxamento, estrat\u00e9gias de distrac\u00e7\u00e3o). Com o aumento da cronifica\u00e7\u00e3o, o ensino de estrat\u00e9gias acomodat\u00edcias (por exemplo, uma maior flexibilidade no tratamento das queixas, a aceita\u00e7\u00e3o do sintoma e a limita\u00e7\u00e3o que o acompanha) representa um aspecto importante. Al\u00e9m disso, trata-se de melhorar o tratamento de factores que influenciam a dor, tais como a forma\u00e7\u00e3o em compet\u00eancias de stress, lidar com o stress profissional e familiar e, por \u00faltimo mas n\u00e3o menos importante, lidar com poss\u00edveis traumas biogr\u00e1ficos. Aproximadamente um ter\u00e7o dos pacientes sofre de perturba\u00e7\u00f5es comorbidas afectivas ou de ansiedade, que tamb\u00e9m devem ser tratadas para al\u00e9m da abordagem orientada para os sintomas.<\/p>\n<p>Em seguida, alguns aspectos s\u00e3o explicados com mais detalhe:<\/p>\n<p>Os pacientes com dores nas costas t\u00eam frequentemente um quadro cl\u00ednico muito som\u00e1tico, o objectivo da educa\u00e7\u00e3o \u00e9 transmitir um modelo biopsicossocial da doen\u00e7a, a diferen\u00e7a entre dor aguda e cr\u00f3nica (processamento da dor, processos fisiol\u00f3gicos de sensibiliza\u00e7\u00e3o da dor, factores de manuten\u00e7\u00e3o) e estar bem informado sobre as suas pr\u00f3prias possibilidades de influ\u00eancia e tamb\u00e9m sobre os seus limites.<\/p>\n<p>Com a ajuda do biofeedback, os sinais f\u00edsicos podem ser reportados visualmente ou acusticamente. O biofeedback encontra uma grande aceita\u00e7\u00e3o &#8211; &#8220;a\u00ed podem ver a minha dor&#8221;. No caso de um modelo de dor de orienta\u00e7\u00e3o som\u00e1tica, serve para melhorar a conformidade atrav\u00e9s da transmiss\u00e3o de um modelo biopsicossocial, \u00e9 tamb\u00e9m utilizado para complementar e ilustrar o conte\u00fado da educa\u00e7\u00e3o, e a capacidade de relaxar pode ser melhorada.<\/p>\n<p>T\u00e9cnicas de relaxamento como o relaxamento muscular progressivo ou mesmo imagina\u00e7\u00f5es s\u00e3o parte integrante da psicoterapia da dor e perseguem simultaneamente objectivos muito diferentes: estabiliza\u00e7\u00e3o muscular e vegetativa, distrac\u00e7\u00e3o da dor, melhoria da percep\u00e7\u00e3o corporal e gest\u00e3o do stress. Al\u00e9m disso, as t\u00e9cnicas de relaxamento s\u00e3o adequadas como ajuda para adormecer e permanecer a dormir, e s\u00e3o ensinadas estrat\u00e9gias apropriadas de higiene do sono.<\/p>\n<p>Para reduzir o medo de movimentos, o paciente precisa da tranquilidade de um profissional m\u00e9dico e de uma explica\u00e7\u00e3o das suas descobertas som\u00e1ticas (por exemplo, raio-X, resson\u00e2ncia magn\u00e9tica) a fim de se envolver na activa\u00e7\u00e3o da terapia e exposi\u00e7\u00e3o dos movimentos evitados. O &#8220;medo da dor&#8221; est\u00e1 associado ao medo da dor durante um movimento. O objectivo de enfrentar o temido stress \u00e9 &#8220;reenquadrar&#8221; (mudar a cren\u00e7a de que o stress \u00e9 prejudicial) e construir mais confian\u00e7a no corpo sob stress. O tratamento conjunto por psic\u00f3logos e fisioterapeutas faz aqui muitas vezes sentido. O psic\u00f3logo guia o paciente atrav\u00e9s do movimento indutor de ansiedade, e o fisioterapeuta pode tamb\u00e9m ensinar estrat\u00e9gias \u00fateis como alongamento ou afrouxamento ap\u00f3s o stress.<\/p>\n<p>Os pacientes muito descondicionados com uma generaliza\u00e7\u00e3o do comportamento evitador devem ser activados numa actividade graduada, de acordo com uma abordagem orientada para as quotas. A raz\u00e3o \u00e9 uma medida de stress que regista, por exemplo, o tempo de stress, a frequ\u00eancia do movimento ou mesmo a dist\u00e2ncia percorrida a p\u00e9 at\u00e9 que a dor se intensifique. Desta medida, s\u00e3o subtra\u00eddos 20% para determinar a primeira quota para a forma\u00e7\u00e3o. Se o paciente suportar bem esta carga durante o treino, mesmo num dia mau, aumenta em 20% do valor inicial. A activa\u00e7\u00e3o por quota segue, assim, uma abordagem contingente da dor, de modo a que a dor perca a sua fun\u00e7\u00e3o discriminat\u00f3ria no controlo do comportamento. Sem esta especifica\u00e7\u00e3o de quotas, o paciente interromperia a carga devido \u00e0 dor. As abordagens orientadas para as quotas s\u00e3o adequadas para al\u00e9m de lidarem com exig\u00eancias de alto desempenho e &#8220;condutores internos&#8221; em pacientes com comportamento perseverante e ultrapassando limites f\u00edsicos pessoais. Evitam-se tanto as situa\u00e7\u00f5es de sub e sobre-desafio e elogia-se o paciente de acordo com os princ\u00edpios do condicionamento operante para um comportamento &#8220;saud\u00e1vel&#8221; e funcional (acumulando tens\u00f5es quotidianas que s\u00e3o significativas para ele, por exemplo, o lar, o trabalho, ir \u00e0s compras, praticar desporto).<\/p>\n<p>O objectivo de ensinar estrat\u00e9gias acomodat\u00edcias \u00e9 conseguir uma maior flexibilidade no tratamento das queixas, reduzir a discrep\u00e2ncia entre objectivos e desejos para as circunst\u00e2ncias dadas, por exemplo baixando o n\u00edvel de aspira\u00e7\u00e3o ou estabelecendo objectivos realistas, e possivelmente chegar a uma reavalia\u00e7\u00e3o da pr\u00f3pria situa\u00e7\u00e3o. As t\u00e9cnicas aqui utilizadas s\u00e3o principalmente as da terapia cognitiva comportamental. O papel dos pr\u00f3prios condutores internos e cren\u00e7as b\u00e1sicas disfuncionais s\u00e3o identificados e questionados a fim de se poder construir novas atitudes internas mais apropriadas. O objectivo \u00e9 desenvolver um comportamento mais flex\u00edvel, adaptado e uma forma mais adaptativa de lidar com as exig\u00eancias, independentemente da situa\u00e7\u00e3o.<\/p>\n<p>Com a ajuda da terapia de aceita\u00e7\u00e3o e compromisso, procura-se uma vida orientada para o valor e o desenvolvimento de uma nova perspectiva de vida. Trata-se de construir uma vontade de deixar as coisas como est\u00e3o neste momento e voltar para outras \u00e1reas importantes da vida. No entanto, alguns pacientes p\u00f5em toda a sua energia a &#8220;combater&#8221; o seu sintoma. A aten\u00e7\u00e3o \u00e9 uma compet\u00eancia b\u00e1sica e uma base neste contexto e \u00e9, portanto, praticada tanto em exerc\u00edcios formais (por exemplo, aten\u00e7\u00e3o respirat\u00f3ria, exame do corpo) como em exerc\u00edcios informais na vida quotidiana.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-13386 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab3_hp3_s7.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/459;height:250px; width:600px\" width=\"1100\" height=\"459\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab3_hp3_s7.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab3_hp3_s7-800x334.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab3_hp3_s7-120x50.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab3_hp3_s7-90x38.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab3_hp3_s7-320x134.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/03\/tab3_hp3_s7-560x234.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Outros t\u00f3picos importantes s\u00e3o frequentemente o desenvolvimento de compet\u00eancias assertivas para melhor se distinguir das exig\u00eancias dos colegas ou familiares e tamb\u00e9m como lidar com problemas e conflitos no local de trabalho para permitir um regresso ao trabalho.<\/p>\n<h2 id=\"resumo\">Resumo<\/h2>\n<p>A dor cr\u00f3nica \u00e9 um problema de sa\u00fade significativo. No contexto de uma compreens\u00e3o biopsicossocial da dor cr\u00f3nica, a factores psicol\u00f3gicos e sociais \u00e9 cada vez mais atribu\u00edda import\u00e2ncia, para al\u00e9m dos aspectos f\u00edsicos das queixas. Consequentemente, faz sentido n\u00e3o s\u00f3 oferecer uma terapia unimodal, puramente m\u00e9dica, mas tamb\u00e9m trabalhar de forma interdisciplinar com dores cr\u00f3nicas nas costas e incluir a psicoterapia e a fisioterapia em igual medida.<\/p>\n<h2 id=\"mensagens-take-home\">Mensagens Take-Home<\/h2>\n<ul>\n<li>Os factores psicossociais e de local de trabalho, para al\u00e9m dos aspectos iatrog\u00e9nicos nos cuidados de sa\u00fade, contribuem significativamente para a cronifica\u00e7\u00e3o e devem ser urgentemente considerados na terapia.<\/li>\n<li>A psicoterapia da dor inclui uma abordagem orientada tanto para os sintomas como para os problemas.<\/li>\n<li>A educa\u00e7\u00e3o promove uma maior aceita\u00e7\u00e3o da pr\u00f3pria doen\u00e7a, reduz os medos, apoia a luta contra a doen\u00e7a e, assim, aumenta tamb\u00e9m a ades\u00e3o do paciente a uma terapia activa.<\/li>\n<li>No caso de dores cr\u00f3nicas nas costas, faz sentido uma abordagem interdisciplinar envolvendo os campos da medicina, psicoterapia e fisioterapia.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Schmidt CO, Raspe H, Pfingsten M, et al: Dores de costas na popula\u00e7\u00e3o adulta alem\u00e3: preval\u00eancia, gravidade, e correlatos sociodemogr\u00e1ficos num inqu\u00e9rito multirregional. Coluna vertebral 2007; 32: 2005-2011.<\/li>\n<li>Fahland AR, Kohlmann T, Schmidt CO: De dor aguda a cr\u00f3nica. In: Casser HR, Hasenbring M, Becker A, Baron R. (eds.) Dor nas costas e pesco\u00e7o. 2016; 3-12. Berlim: Springer.<\/li>\n<li>Hildebrandt J, Sch\u00f6ps P: Dor do sistema m\u00fasculo-esquel\u00e9tico \/ dor nas costas. In: Zens M, Jurna I. (eds.) Textbook of Pain Therapy. 2001; 577-609. Stuttgart: Wissenschaftliche Verlagsgesellschaft.<\/li>\n<li>Nicholas MK, Linton SJ, Watson PJ, Main CJ &amp; o Grupo de Trabalho &#8220;D\u00e9cada das Bandeiras&#8221;: Identifica\u00e7\u00e3o precoce e gest\u00e3o dos factores de risco psicol\u00f3gico (&#8220;Bandeiras Amarelas&#8221;) em doentes com dores lombares baixas: Uma reavalia\u00e7\u00e3o. Fisioterapia 2011; 91: 737-753.<\/li>\n<li>Linton SJ: Uma revis\u00e3o dos factores de risco psicol\u00f3gico nas dores nas costas e no pesco\u00e7o. Coluna 2000; 25: 1148-1156.<\/li>\n<li>Hildebrandt J: A musculatura como causa de dores nas costas. Dor 2003; 17: 412-418.<\/li>\n<li>Locher H, Nilges P: Como posso cronificar o meu doente com dor? Pr\u00e1tica Ortop\u00e9dica 2001; 37\/10: 672-677.<\/li>\n<li>Arnold B, Brinkschmidt T, Casser HR: Terapia da dor multimodal no tratamento de s\u00edndromes de dor cr\u00f3nica. Um documento de consenso da comiss\u00e3o ad hoc Multimodal Interdisciplinar de Terapia da Dor da Sociedade Alem\u00e3 da Dor sobre o conte\u00fado do tratamento. Dor 2014; 28: 459-472.<\/li>\n<li>Kr\u00f6ner-Herwig B, Frettl\u00f6h J, Klinger R, Nilges P. (eds.): Schmerzpsychotherapie. 2016; 8\u00aa edi\u00e7\u00e3o. Berlim: Springer.<\/li>\n<li>Nilges P, Diezemann A. Dor cr\u00f3nica. Conceitos, diagn\u00f3sticos e tratamentos. Behaviour Therapy &amp; Behavioural Medicine 2018; 39 (2): 167-186.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1TICA DO GP 2020; 15(3): 4-8<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A psicoterapia da dor inclui uma abordagem orientada tanto para os sintomas como para os problemas. Os factores psicossociais e relacionados com o trabalho contribuem para a cronifica\u00e7\u00e3o e devem&hellip;<\/p>\n","protected":false},"author":7,"featured_media":95087,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Psicoterapia da dor para as dores lombares","footnotes":""},"category":[11524,11463,11305,11445,11481,11551],"tags":[17464,25838],"powerkit_post_featured":[],"class_list":["post-334520","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacao-continua","category-medicina-fisica-e-reabilitacao","category-medicina-interna-geral","category-ortopedia-pt-pt","category-psiquiatria-e-psicoterapia","category-rx-pt","tag-dores-de-costas","tag-dores-nas-costas","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:29:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":334617,"slug":"contrarrestar-el-miedo-al-dolor","post_title":"Contrarrestar el miedo al dolor","href":"https:\/\/medizinonline.com\/es\/contrarrestar-el-miedo-al-dolor\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/334520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=334520"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/334520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/95087"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=334520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=334520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=334520"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=334520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}