{"id":335963,"date":"2019-07-22T09:28:07","date_gmt":"2019-07-22T07:28:07","guid":{"rendered":"https:\/\/medizinonline.com\/diagnosticos-diferenciados-para-resultados-eficazes\/"},"modified":"2019-07-22T09:28:07","modified_gmt":"2019-07-22T07:28:07","slug":"diagnosticos-diferenciados-para-resultados-eficazes","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/diagnosticos-diferenciados-para-resultados-eficazes\/","title":{"rendered":"Diagn\u00f3sticos diferenciados para resultados eficazes"},"content":{"rendered":"<p><strong>As op\u00e7\u00f5es de diagn\u00f3stico diferenciado devem permitir uma terapia individual adaptada \u00e0s necessidades individuais. No caso de neoplasias hematol\u00f3gicas, contudo, as op\u00e7\u00f5es de tratamento estabelecidas tamb\u00e9m s\u00e3o eficazes.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Para o tratamento de linfoma raro indolente, os principais medicamentos utilizados s\u00e3o R-Benda (rituximab e bendamustina), RDC (dexametasona, rituximab e ciclofosfamida) e BDR (bortezomib, dexametasona e rituximab). Estes tr\u00eas regimes foram comparados em termos da sua efic\u00e1cia. Foram inclu\u00eddos pacientes com WM que foram avaliados na Cl\u00ednica Mayo entre 2000 e 2018 e que estavam numa de tr\u00eas terapias prim\u00e1rias.<\/p>\n<p>Havia uma clara vantagem para a combina\u00e7\u00e3o de rituximab e bendamustine (R-Benda). O ORR era de 95%, enquanto que o BDR era de 81% e a RDC de 76%. As remiss\u00f5es completas de 10% s\u00f3 puderam ser demonstradas para o regime de R-Benda. A remiss\u00e3o parcial muito boa (VGPR) foi de 21% e a remiss\u00e3o parcial foi de 62% <strong>(Fig.&nbsp;1)<\/strong>. Contudo, n\u00e3o houve diferen\u00e7as entre as abordagens terap\u00eauticas individuais no que diz respeito \u00e0 sobreviv\u00eancia global.<\/p>\n<p>A coorte retrospectiva demonstrou que a terapia de primeira linha com R-Benda era superior \u00e0 RDC ou BDR em termos de resposta, tempo para a pr\u00f3xima terapia e sobreviv\u00eancia sem progress\u00e3o &#8211; independentemente de uma muta\u00e7\u00e3o MYD88L265P. Em termos do seu perfil de toxicidade, os tr\u00eas regimes eram compar\u00e1veis. Apenas sob BDR ocorreu neurotoxicidade de grau 3 em 13%.<\/p>\n<p>&nbsp;<\/p>\n<p>\nLeitura adicional:<\/p>\n<ul>\n<li>Abeykoon JP, et al: Resultados com rituximab mais bendamustine (R-Benda), dexametasona, rituximab, caclophosfamida (RDC), e bortezomib, dexametasona, rituximab (BDR) como terapia prim\u00e1ria em doentes com macroglobulinemia de Waldenstrom (WM). Reuni\u00e3o Anual da ASCO 2019, Resumo 7509.<\/li>\n<\/ul>\n<p>\n<em>InFo ONCOLOGY &amp; HEMATOLOGY 2019;(2-3): 30 (publicado 17.6.19, antes da impress\u00e3o).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As op\u00e7\u00f5es de diagn\u00f3stico diferenciado devem permitir uma terapia individual adaptada \u00e0s necessidades individuais. No caso de neoplasias hematol\u00f3gicas, contudo, as op\u00e7\u00f5es de tratamento estabelecidas tamb\u00e9m s\u00e3o eficazes.<\/p>\n","protected":false},"author":7,"featured_media":90144,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Neoplasias hematol\u00f3gicas","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11521,11365,11379,11529,11551],"tags":[28379,11955,28383],"powerkit_post_featured":[],"class_list":["post-335963","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudos","category-hematologia-pt-pt","category-oncologia-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-neoplasias-hematologicas-pt-pt","tag-terapia-de-primeira-linha","tag-waldenstroem-macroglobulinemia-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 15:19:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":335928,"slug":"diagnosticos-diferenciados-para-resultados-eficaces","post_title":"Diagn\u00f3sticos diferenciados para resultados eficaces","href":"https:\/\/medizinonline.com\/es\/diagnosticos-diferenciados-para-resultados-eficaces\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/335963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=335963"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/335963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/90144"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=335963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=335963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=335963"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=335963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}