{"id":337772,"date":"2018-07-15T02:00:00","date_gmt":"2018-07-15T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/actualizacao-sobre-a-pneumonia-adquirida-na-comunidade-em-criancas\/"},"modified":"2018-07-15T02:00:00","modified_gmt":"2018-07-15T00:00:00","slug":"actualizacao-sobre-a-pneumonia-adquirida-na-comunidade-em-criancas","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/actualizacao-sobre-a-pneumonia-adquirida-na-comunidade-em-criancas\/","title":{"rendered":"Actualiza\u00e7\u00e3o sobre a pneumonia adquirida na comunidade em crian\u00e7as"},"content":{"rendered":"<p><strong>Actualiza\u00e7\u00e3o sobre a gest\u00e3o da pneumonia comum n\u00e3o adquirida na comunidade na inf\u00e2ncia: s\u00e3o recomendados exames de raio-X tor\u00e1cico e laboratoriais? Quantos dias deve ser dado o tratamento antibi\u00f3tico? Quando e como deve ser tratada a pneumonia por micoplasma? Peritos deram respostas na reuni\u00e3o anual da Sociedade Su\u00ed\u00e7a de Pneumologia (SGP) 2018.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>A pneumonia adquirida na comunidade \u00e9 comum nas crian\u00e7as e leva frequentemente ao uso de antibi\u00f3ticos, \u00e0 hospitaliza\u00e7\u00e3o e a custos elevados. Tendo como pano de fundo o aumento da resist\u00eancia aos antibi\u00f3ticos e os custos crescentes, \u00e9 importante um tratamento baseado em provas com a dura\u00e7\u00e3o mais curta poss\u00edvel da terapia antimicrobiana. Por esta raz\u00e3o, a Sociedade Alem\u00e3 de Infecciologia Pedi\u00e1trica (DGPI) e a Sociedade de Pneumologia Pedi\u00e1trica (GPP) publicaram agora a primeira directriz em l\u00edngua alem\u00e3 sobre a gest\u00e3o de crian\u00e7as e adolescentes com PAC (&#8220;pneumonia adquirida na comunidade&#8221;) [1]. Representantes do Grupo das Doen\u00e7as Infecciosas Pedi\u00e1tricas da Su\u00ed\u00e7a (PIGS) e da Sociedade Su\u00ed\u00e7a de Pneumologia Pedi\u00e1trica (SGPP) tamb\u00e9m contribu\u00edram para a directriz. Na Reuni\u00e3o Anual do SGP de 2018, o Dr Nicolaus Schwerk, M\u00e9dico S\u00e9nior de Pneumologia Pedi\u00e1trica da Escola M\u00e9dica de Hannover, apresentou a nova directriz.<\/p>\n<h2 id=\"gestao-de-criancas-com-pac-nao-seria\">Gest\u00e3o de crian\u00e7as com PAC n\u00e3o s\u00e9ria<\/h2>\n<p>A PAC pedi\u00e1trica \u00e9 uma infec\u00e7\u00e3o causada por bact\u00e9rias ou v\u00edrus com inflama\u00e7\u00e3o na \u00e1rea dos alv\u00e9olos, onde c\u00e9lulas, detritos celulares e fluido rico em prote\u00ednas se acumulam e prejudicam as trocas gasosas. Os sintomas s\u00e3o frequentemente n\u00e3o espec\u00edficos:<\/p>\n<ul>\n<li>sintomas respirat\u00f3rios tais como tosse, dispneia, dores tor\u00e1cicas,<\/li>\n<li>Sintomas gerais tais como febre, recusa de comer, dor abdominal, inactividade, vigil\u00e2ncia alterada (apatia, agita\u00e7\u00e3o).<\/li>\n<\/ul>\n<p>Os sinais cl\u00ednicos que podem indicar PAC pedi\u00e1trica s\u00e3o febre, taquipneia, dispneia\/dispneia, som respirat\u00f3rio atenuado, palpita\u00e7\u00e3o abafada, taquicardia, desidrata\u00e7\u00e3o. A febre e a taquipneia s\u00e3o os sinais cl\u00ednicos mais espec\u00edficos e sens\u00edveis da pneumonia. Tamb\u00e9m pode haver apenas febre sem taquipneia\/dyspnoea. As crian\u00e7as afectadas podem estar livres de febre.<\/p>\n<p>Os pacientes podem ser tratados em regime ambulat\u00f3rio se se suspeitar que a crian\u00e7a tem PAC n\u00e3o s\u00e9ria com base na hist\u00f3ria e exame cl\u00ednico (com respira\u00e7\u00e3o acelerada mas sem sinais de aviso adicionais, tais como estado geral gravemente reduzido, recusa de alimentos, desidrata\u00e7\u00e3o, sonol\u00eancia, inconsci\u00eancia, convuls\u00f5es cerebrais). No que diz respeito ao diagn\u00f3stico, a directriz recomenda a n\u00e3o realiza\u00e7\u00e3o de um raio-X tor\u00e1cico em PAC n\u00e3o s\u00e9ria. Pessoalmente, o orador falou a favor do diagn\u00f3stico radiogr\u00e1fico do t\u00f3rax porque a pneumonia \u00e9 sobrediagnosticada com base em constata\u00e7\u00f5es puramente cl\u00ednicas. Tamb\u00e9m assinalou que o diagn\u00f3stico de pneumonia pode ser confirmado ou descartado de forma fi\u00e1vel por examinadores experientes utilizando ultra-sons pulmonares.<\/p>\n<p>A directriz estabelece que os testes sangu\u00edneos de rotina n\u00e3o devem ser realizados em PAC clinicamente suspeita, n\u00e3o s\u00e9ria porque, por exemplo, a contagem de CRP e leuc\u00f3citos n\u00e3o permite uma diferencia\u00e7\u00e3o fi\u00e1vel entre pneumonia viral e bacteriana. Os exames virol\u00f3gicos (testes r\u00e1pidos de antig\u00e9nios, PCR) e bacteriol\u00f3gicos tamb\u00e9m n\u00e3o devem ser realizados rotineiramente na PAC n\u00e3o s\u00e9ria. Os esfrega\u00e7os na garganta n\u00e3o s\u00e3o adequados para detectar os agentes patog\u00e9nicos mais comuns da pneumonia bacteriana porque os pneumococos, estafilococos e Haemophilus influenzae s\u00e3o frequentemente encontrados na flora da garganta de crian\u00e7as saud\u00e1veis.<\/p>\n<h2 id=\"a-terapia-antiobiotica-de-cinco-dias-e-suficiente\">A terapia antiobi\u00f3tica de cinco dias \u00e9 suficiente<\/h2>\n<p>A directriz recomenda o tratamento de crian\u00e7as e adolescentes com PAC n\u00e3o s\u00e9ria e com febre com antibi\u00f3ticos [1]. Beb\u00e9s e crian\u00e7as pequenas com PAC n\u00e3o grave sem febre ou com sinais de obstru\u00e7\u00e3o br\u00f4nquica n\u00e3o devem ser tratados com antibi\u00f3ticos, principalmente porque \u00e9 provavelmente uma infec\u00e7\u00e3o viral. A dura\u00e7\u00e3o recomendada da terapia antibi\u00f3tica para a PAC n\u00e3o s\u00e9ria \u00e9 agora de apenas cinco dias (n\u00e3o dez dias). A antibioticoterapia intravenosa n\u00e3o \u00e9 superior \u00e0 terapia oral. Para a terapia emp\u00edrica sem detec\u00e7\u00e3o de agentes patog\u00e9nicos, recomenda-se a amoxicilina (50-90&nbsp;mg\/kg\/dia peroral) como o antibi\u00f3tico de primeira escolha. Em crian\u00e7as com intoler\u00e2ncia \u00e0 penicilina, as cefalosporinas (cuidado: reac\u00e7\u00f5es cruzadas), macr\u00f3lidos ou, a partir dos nove anos, as tetraciclinas podem ser escolhidas como alternativas. As macrol\u00eddeas e tetraciclinas tamb\u00e9m s\u00e3o eficazes contra Mycoplasma pneumoniae. Em caso de complica\u00e7\u00f5es, recomenda-se febre persistente ou gripe ou sarampo com suspeita de co-infec\u00e7\u00e3o bacteriana, aminopenicilinas mais inibidores da beta-lactamase ou cepaholosporinas de segunda gera\u00e7\u00e3o (por exemplo, cefuroxima).<\/p>\n<h2 id=\"m-pneumoniae-infeccao-ou-apenas-colonizacao\">M. pneumoniae: infec\u00e7\u00e3o ou apenas coloniza\u00e7\u00e3o?<\/h2>\n<p>A pneumonia &#8220;at\u00edpica&#8221; causada por Mycoplasma pneumoniae \u00e9 mais comum em crian\u00e7as entre os cinco e os quinze anos de idade [2]. N\u00e3o h\u00e1 sintomas ou sinais radiol\u00f3gicos espec\u00edficos para esta infec\u00e7\u00e3o. M. pneumoniae \u00e9 uma bact\u00e9ria sem parede celular com resist\u00eancia natural aos antibi\u00f3ticos beta-lact\u00e2micos. A bact\u00e9ria multiplica-se extracelularmente na superf\u00edcie do epit\u00e9lio respirat\u00f3rio e, como parasita, obt\u00e9m os nutrientes necess\u00e1rios das c\u00e9lulas hospedeiras, informou Patrick Meyer Sauteur, MD, m\u00e9dico s\u00e9nior, infectologista, Hospital Universit\u00e1rio Infantil de Zurique. A IgM espec\u00edfica aparece no soro dentro de uma semana ap\u00f3s a infec\u00e7\u00e3o inicial, cerca de duas semanas antes da IgG [2]. As crian\u00e7as saud\u00e1veis s\u00e3o frequentemente portadoras assintom\u00e1ticas de M. pneumoniae nas vias respirat\u00f3rias. Os m\u00e9todos de teste habituais (PCR do esfrega\u00e7o far\u00edngeo, serologia IgM e IgG) n\u00e3o conseguem distinguir entre infec\u00e7\u00e3o sintom\u00e1tica e estado de portador assintom\u00e1tico. O grupo de investiga\u00e7\u00e3o de Meyer Sauteur conseguiu desenvolver um teste que pode detectar de forma fi\u00e1vel a infec\u00e7\u00e3o por micoplasma em pacientes com PAC. O teste detecta c\u00e9lulas secretoras de IgM espec\u00edficas de M. pneumonia que circulam no sangue apenas alguns dias a seis semanas ap\u00f3s a infec\u00e7\u00e3o prim\u00e1ria, enquanto os anticorpos IgM s\u00e3o encontrados durante meses a anos. No estudo myCAP, foi demonstrado em crian\u00e7as de tr\u00eas a dezoito anos e membros da fam\u00edlia que as c\u00e9lulas secretoras de IgM s\u00f3 eram detect\u00e1veis no Mycoplasma-CAP, mas n\u00e3o em portadores de Mycoplasma saud\u00e1veis e assintom\u00e1ticos com PCR positiva na zaragatoa far\u00edngea.<\/p>\n<h2 id=\"mycoplasma-pneumonia-quando-e-como-tratar\">Mycoplasma pneumonia: Quando e como tratar?<\/h2>\n<p>Na PAC leve a moderada, a terapia antibi\u00f3tica especificamente dirigida contra M. pneumoniae n\u00e3o \u00e9 necess\u00e1ria porque a doen\u00e7a \u00e9 auto-limitada, disse o orador. Provavelmente n\u00e3o s\u00e3o tanto os micoplasmas em si que s\u00e3o respons\u00e1veis pelo quadro cl\u00ednico, mas sim a reac\u00e7\u00e3o imunit\u00e1ria do corpo. Para pneumonia grave, recomendou claritromicina em crian\u00e7as com menos de oito anos de idade ou doxiciclina a partir dos oito anos de idade.<\/p>\n<p><em>Fonte: Apresenta\u00e7\u00f5es &#8220;Diagn\u00f3stico e tratamento da pneumonia adquirida pela comunidade pedi\u00e1trica, nova directriz&#8221; (N. Schwerk) e &#8220;Mycoplasma pneumoniae: infec\u00e7\u00e3o ou coloniza\u00e7\u00e3o inofensiva? (P. Meyer Sauteur) na Sess\u00e3o de Infec\u00e7\u00f5es Respirat\u00f3rias Pedi\u00e1tricas. Reuni\u00e3o Anual Conjunta da Sociedade Su\u00ed\u00e7a de Pneumologia e Sociedades Parceiras, St. Gallen, 25 de Maio de 2018.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Rose M et al.: S2k guideline &#8220;Management of community-acquired pneumonia in children and adolescents (paediatric community-acquired pneumonia, pCAP)&#8221;, 2017, AWMF register no. 048-013.<\/li>\n<li>Meyer Sauteur PM et al: Infec\u00e7\u00e3o e transporte de Mycoplasma pneumoniae em crian\u00e7as. Microbiol frontal 2016; 7: 329.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1TICA DO GP 2018; 13(7): 47-48<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actualiza\u00e7\u00e3o sobre a gest\u00e3o da pneumonia comum n\u00e3o adquirida na comunidade na inf\u00e2ncia: s\u00e3o recomendados exames de raio-X tor\u00e1cico e laboratoriais? Quantos dias deve ser dado o tratamento antibi\u00f3tico? Quando&hellip;<\/p>\n","protected":false},"author":7,"featured_media":80676,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Reuni\u00e3o Anual Conjunta 2018 do SGP, St. Gallen","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11305,11450,11547,11529,11551],"tags":[32881,32884,32885,32882,32880,32883],"powerkit_post_featured":[],"class_list":["post-337772","post","type-post","status-publish","format-standard","has-post-thumbnail","category-medicina-interna-geral","category-pediatria-pt-pt","category-pneumologia-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-directrizes-para-a-pneumonia","tag-pac-pediatrica-pt-pt","tag-pneumonia-adquirida-na-comunidade","tag-pneumonia-por-micoplasma","tag-sgp-pt-pt","tag-sociedade-suica-de-pneumologia","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:01:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":337722,"slug":"actualizacion-sobre-la-neumonia-adquirida-en-la-comunidad-en-ninos","post_title":"Actualizaci\u00f3n sobre la neumon\u00eda adquirida en la comunidad en ni\u00f1os","href":"https:\/\/medizinonline.com\/es\/actualizacion-sobre-la-neumonia-adquirida-en-la-comunidad-en-ninos\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/337772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=337772"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/337772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/80676"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=337772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=337772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=337772"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=337772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}