{"id":338233,"date":"2018-04-13T02:00:00","date_gmt":"2018-04-13T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/video-farmacoterapia-baseada-em-provas-para-disturbios-de-personalidade-limitrofes\/"},"modified":"2018-04-13T02:00:00","modified_gmt":"2018-04-13T00:00:00","slug":"video-farmacoterapia-baseada-em-provas-para-disturbios-de-personalidade-limitrofes","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/video-farmacoterapia-baseada-em-provas-para-disturbios-de-personalidade-limitrofes\/","title":{"rendered":"V\u00eddeo: Farmacoterapia baseada em provas para dist\u00farbios de personalidade lim\u00edtrofes"},"content":{"rendered":"<p><strong>50% dos pacientes com dist\u00farbio de personalidade lim\u00edtrofe tomam tr\u00eas medicamentos&nbsp;ou mais diariamente. Isto \u00e9 surpreendente uma vez que n\u00e3o existem provas emp\u00edricas validadas suficientes para o tratamento do dist\u00farbio de personalidade lim\u00edtrofe com medica\u00e7\u00e3o.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>H\u00e1 v\u00e1rias raz\u00f5es para o fen\u00f3meno da polifarm\u00e1cia&nbsp;em doentes com transtorno de personalidade lim\u00edtrofe, que o orador ir\u00e1 discutir. Apresenta v\u00e1rias directrizes actuais sobre o tema da medica\u00e7\u00e3o e explica as recomenda\u00e7\u00f5es de tratamento do SGPP para o tratamento farmacol\u00f3gico.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe frameborder=\"0\" height=\"360\" data-src=\"https:\/\/player.vimeo.com\/video\/256783101\" width=\"640\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mais v\u00eddeos deste simp\u00f3sio:<\/strong><\/p>\n<p><a href=\"https:\/\/www.medizinonline.com\/artikel\/behandlungs-empfehlungen-und-leitlinien-fuer-die-borderline-persoenlichkeitsstoerung\">Recomenda\u00e7\u00f5es e directrizes de tratamento para a desordem de personalidade lim\u00edtrofe<\/a><\/p>\n<p><a href=\"https:\/\/www.medizinonline.com\/artikel\/allgemeine-interventionsprinzipien-zur-behandlung-der-borderline-persoenlichkeitsstoerung\">Princ\u00edpios gerais de interven\u00e7\u00e3o para o tratamento do dist\u00farbio de personalidade lim\u00edtrofe<\/a><\/p>\n<p><a href=\"https:\/\/www.medizinonline.com\/artikel\/evidenzbasierte-psychotherapeutische-verfahren-zur-behandlung-der-borderline\">M\u00e9todos psicoterap\u00eauticos baseados em provas para o tratamento de dist\u00farbios de personalidade lim\u00edtrofes<\/a><\/p>\n<p>Depois dos v\u00eddeos, clicar em START TEST.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>50% dos pacientes com dist\u00farbio de personalidade lim\u00edtrofe tomam tr\u00eas medicamentos&nbsp;ou mais diariamente. Isto \u00e9 surpreendente uma vez que n\u00e3o existem provas emp\u00edricas validadas suficientes para o tratamento do dist\u00farbio&hellip;<\/p>\n","protected":false},"author":7,"featured_media":75168,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Congresso Anual SGPP 2017, Berna - palestra em v\u00eddeo","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11697,11481,11529,11551],"tags":[],"powerkit_post_featured":[],"class_list":["post-338233","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacao-com-parceiro","category-psiquiatria-e-psicoterapia","category-relatorios-do-congresso","category-rx-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:41:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":338206,"slug":"video-farmacoterapia-basada-en-la-evidencia-para-el-trastorno-limite-de-la-personalidad","post_title":"V\u00eddeo: Farmacoterapia basada en la evidencia para el trastorno l\u00edmite de la personalidad","href":"https:\/\/medizinonline.com\/es\/video-farmacoterapia-basada-en-la-evidencia-para-el-trastorno-limite-de-la-personalidad\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/338233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=338233"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/338233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/75168"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=338233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=338233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=338233"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=338233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}