{"id":338576,"date":"2018-02-25T01:00:00","date_gmt":"2018-02-25T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/estabilizacao-e-terapia-eficaz-da-dor-com-vertebroplastia-percutanea\/"},"modified":"2018-02-25T01:00:00","modified_gmt":"2018-02-25T00:00:00","slug":"estabilizacao-e-terapia-eficaz-da-dor-com-vertebroplastia-percutanea","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/estabilizacao-e-terapia-eficaz-da-dor-com-vertebroplastia-percutanea\/","title":{"rendered":"Estabiliza\u00e7\u00e3o e terapia eficaz da dor com vertebroplastia percut\u00e2nea"},"content":{"rendered":"<p><strong>As fracturas vertebrais osteopor\u00f3ticas em doentes idosos s\u00e3o comuns. Se os sintomas forem ligeiros, s\u00e3o geralmente tratados de forma conservadora. Contudo, em caso de dor pronunciada, a vertebroplastia percut\u00e2nea (PVP) pode ser \u00fatil na fase aguda.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><strong>Introdu\u00e7\u00e3o: <\/strong>As fracturas vertebrais osteopor\u00f3ticas em pacientes idosos s\u00e3o comuns e s\u00e3o geralmente tratadas de forma conservadora quando os sintomas s\u00e3o ligeiros. No entanto, a vertebroplastia percut\u00e2nea (PVP) pode ser \u00fatil na fase aguda se a dor for pronunciada.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9710\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/02\/abb1_np1_s40.jpg\" style=\"height:479px; width:600px\" width=\"1100\" height=\"879\"><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Descri\u00e7\u00e3o do caso:<\/strong> Um paciente de 64 anos com epilepsia conhecida desde a inf\u00e2ncia caiu de costas num degrau de escada durante um ataque epil\u00e9ptico. Subsequentemente, ocorreu uma sintomatologia de dor lombar pronunciada. Uma radiografia convencional mostrou uma impress\u00e3o m\u00ednima da placa de cobertura<strong> (Fig.&nbsp;1) <\/strong>. A RM mostrou sem d\u00favida uma fractura de compress\u00e3o aguda de BWK 12 (tipo A1 de acordo com a classifica\u00e7\u00e3o AO) <strong>(Fig.&nbsp;2A e B), a<\/strong> osteodensitometria mostrou osteopenia. Devido \u00e0 dor imobilizante apesar da medica\u00e7\u00e3o de morfina, foi indicada uma PVP quatro dias ap\u00f3s o trauma. Um bom preenchimento do espa\u00e7o de fractura e do osso adjacente foi conseguido atrav\u00e9s de uma abordagem unilateral e transpedicular <strong>(Fig.&nbsp;2C e D)<\/strong>. Imediatamente ap\u00f3s a PVP, o paciente mostrou uma melhoria nos sintomas da dor, ap\u00f3s dois dias a medica\u00e7\u00e3o para a dor p\u00f4de ser interrompida e ap\u00f3s mais dois dias o paciente p\u00f4de ter alta.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9711 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2018\/02\/abb2_np1_s41.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/924;height:504px; width:600px\" width=\"1100\" height=\"924\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Conclus\u00e3o:<\/strong> Num estudo multic\u00eantrico prospectivo randomizado recentemente publicado, a PVP demonstrou ser significativamente superior a uma interven\u00e7\u00e3o placebo em fracturas vertebrais agudas (menos de seis semanas) em termos de redu\u00e7\u00e3o da dor [1]. Numa an\u00e1lise de subgrupo, isto foi particularmente verdadeiro para fracturas &#8211; como aqui descrito &#8211; na regi\u00e3o toracolombar.<\/p>\n<p>Com o procedimento minimamente invasivo, n\u00e3o s\u00f3 a dor pode ser tratada eficazmente, como em particular os efeitos secund\u00e1rios da terapia conservadora (consequ\u00eancias da imobiliza\u00e7\u00e3o a longo prazo e da medica\u00e7\u00e3o para a dor) podem ser reduzidos. No caso de pacientes que s\u00e3o frequentemente polimorbidos, a indica\u00e7\u00e3o deve ser discutida numa base interdisciplinar.<\/p>\n<p>&nbsp;<\/p>\n<p>\nLiteratura:<\/p>\n<ol>\n<li>Clark W, et al: Seguran\u00e7a e efic\u00e1cia da vertebroplastia para fracturas osteopor\u00f3ticas agudas dolorosas (VAPOUR): um ensaio multic\u00eantrico, aleat\u00f3rio, duplo-cego, controlado por placebo. Lancet 2016; 388: 1408-1416.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo NEUROLOGIA &amp; PSYCHIATRY 2018; 16(1): 40-41.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As fracturas vertebrais osteopor\u00f3ticas em doentes idosos s\u00e3o comuns. Se os sintomas forem ligeiros, s\u00e3o geralmente tratados de forma conservadora. Contudo, em caso de dor pronunciada, a vertebroplastia percut\u00e2nea (PVP)&hellip;<\/p>\n","protected":false},"author":7,"featured_media":74324,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Fractura traum\u00e1tica do corpo vertebral ap\u00f3s convuls\u00e3o epil\u00e9ptica","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11536,11390,11374,11551],"tags":[14958,34873,34880,34878,34879],"powerkit_post_featured":[],"class_list":["post-338576","post","type-post","status-publish","format-standard","has-post-thumbnail","category-casos-pt-pt","category-cirurgia","category-neurologia-pt-pt","category-rx-pt","tag-dor-pt-pt-2","tag-fracturas-vertebrais-osteoporoticas","tag-pvp-pt-pt","tag-tratamento-conservador","tag-vertebroplastia-percutanea","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:20:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":338579,"slug":"estabilizacion-y-terapia-eficaz-del-dolor-con-vertebroplastia-percutanea","post_title":"Estabilizaci\u00f3n y terapia eficaz del dolor con vertebroplastia percut\u00e1nea","href":"https:\/\/medizinonline.com\/es\/estabilizacion-y-terapia-eficaz-del-dolor-con-vertebroplastia-percutanea\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/338576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=338576"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/338576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/74324"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=338576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=338576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=338576"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=338576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}