{"id":338850,"date":"2017-12-28T01:00:00","date_gmt":"2017-12-28T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/diagnosticos-modernos-em-tempos-de-aumento-de-doencas-sexualmente-transmissiveis\/"},"modified":"2017-12-28T01:00:00","modified_gmt":"2017-12-28T00:00:00","slug":"diagnosticos-modernos-em-tempos-de-aumento-de-doencas-sexualmente-transmissiveis","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/diagnosticos-modernos-em-tempos-de-aumento-de-doencas-sexualmente-transmissiveis\/","title":{"rendered":"Diagn\u00f3sticos modernos em tempos de aumento de doen\u00e7as sexualmente transmiss\u00edveis"},"content":{"rendered":"<p><strong>Uma r\u00e1pida clarifica\u00e7\u00e3o microbiol\u00f3gica com diagn\u00f3sticos sens\u00edveis e espec\u00edficos \u00e9 importante devido ao aumento da resist\u00eancia aos antibi\u00f3ticos, especialmente com os gonococos. Este artigo de revis\u00e3o fornece conhecimentos sobre aspectos epidemiol\u00f3gicos e de diagn\u00f3stico de infec\u00e7\u00f5es com Chlamydia trachomatis e Neisseria gonorrhoeae.<\/strong><\/p>\n<div id=\"SL_balloon_obj\" style=\"display: block;\">\n<div class=\"SL_ImTranslatorLogo\" id=\"SL_button\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/imtranslator-s.png\") repeat scroll 0% 0%; display: none; opacity: 0; left: -8px; top: -25px; transition: visibility 2s ease 0s, opacity 2s linear 0s;\">&nbsp;<\/div>\n<div id=\"SL_shadow_translation_result2\" style=\"display: none;\">&nbsp;<\/div>\n<div id=\"SL_shadow_translator\" style=\"display: none;\">\n<div id=\"SL_planshet\">\n<div id=\"SL_arrow_up\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/up.png\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<div id=\"SL_Bproviders\">\n<div class=\"SL_BL_LABLE_ON\" id=\"SL_P0\" title=\"Google\"><strong>G<\/strong><\/div>\n<div class=\"SL_BL_LABLE_ON\" id=\"SL_P1\" title=\"Microsoft\"><strong>M<\/strong><\/div>\n<div class=\"SL_BL_LABLE_ON\" id=\"SL_P2\" title=\"Tradutora\"><strong>T<\/strong><\/div>\n<\/div>\n<div id=\"SL_alert_bbl\" style=\"display: none;\">\n<div id=\"SLHKclose\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/delete.png\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<div id=\"SL_alert_cont\">&nbsp;<\/div>\n<\/div>\n<div id=\"SL_TB\">\n<table cellspacing=\"1\" id=\"SL_tables\">\n<tbody>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"display: block;\">\n<div style=\"display: none;\">\n<div>\n<div>\n<table cellspacing=\"1\">\n<tbody>\n<tr>\n<td><strong>Reconhecer a l\u00ednguaAfricanaAlban\u00easArabeAzerbaijanoBascoBengaliB\u00f3snianB\u00falgaroBurm\u00easCebuanoChichewaChin\u00eas (ver)Chin\u00easDinamarqu\u00easAlem\u00e3oEsperantoEst\u00f3nioFinland\u00easFranc\u00easGalegoGregoGujaratiHaitiano (trad)D\u00e4nischDeutschEnglischEsperantoEstnischFinnischFranz\u00f6sischGalizischGeorgischGriechischGujaratiHaitianischHausaHebr\u00e4ischHindiHmongIgboIndonesischIrischIsl\u00e4ndischItalienischJapanischJavanesischJiddischKannadaKasachischKatalanischKhmerKoreanischKroatischLaoLateinishLettischLitauischMalabarischMalagasyMalaysischMaltesischMaoriMarathischMazedonischMongolischNepalesischNiederl\u00e4ndischNorwegischPersischPolnischPortugiesischPunjabiRum\u00e4nischRussischSchwedischSerbischSesothoSinghalesischSlowakischSlowenischSomaliSpanischSuaheliSundanesischTadschikischTagalogTamilTeluguThail\u00e4ndischTschechischT\u00fcrkischUkrainischUngarischUrduUzbekischVietnamesischWalisischWei\u00dfrussischYorubaZulu<\/strong><\/td>\n<td>\n<div id=\"SL_switch_b\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/switchb.png\") repeat scroll 0% 0%;\" title=\"Troca de idiomas\">&nbsp;<\/div>\n<\/td>\n<td>\n<div style=\"display: block;\">\n<div style=\"display: none;\">\n<div>\n<div>\n<table cellspacing=\"1\">\n<tbody>\n<tr>\n<td><strong><strong>AfrikaansAlban\u00easArabeArm\u00e9nioAzerbaijanoBascoBengaliBosnianoB\u00falgaroBurm\u00easCebuanoChichewaChin\u00eas (ver)Chin\u00easDinamarqu\u00easIngl\u00easEst\u00f3nioFinland\u00easFinland\u00easGalegoGregoGujaratiHaitiano (trad)D\u00e4nischDeutschEnglischEsperantoEstnischFinnischFranz\u00f6sischGalizischGeorgischGriechischGujaratiHaitianischHausaHebr\u00e4ischHindiHmongIgboIndonesischIrischIsl\u00e4ndischItalienischJapanischJavanesischJiddischKannadaKasachischKatalanischKhmerKoreanischKroatischLaoLateinishLettischLitauischMalabarischMalagasyMalaysischMaltesischMaoriMarathischMazedonischMongolischNepalesischNiederl\u00e4ndischNorwegischPersischPolnischPortugiesischPunjabiRum\u00e4nischRussischSchwedischSerbischSesothoSinghalesischSlowakischSlowenischSomaliSpanischSuaheliSundanesischTadschikischTagalogTamilTeluguThail\u00e4ndischTschechischT\u00fcrkischUkrainischUngarischUrduUzbekischVietnamesischWalisischWei\u00dfrussischYorubaZulu<\/strong><\/strong><\/td>\n<td>\n<div id=\"SL_TTS_voice\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/ttsvoice.png\") repeat scroll 0% 0%;\" title=\"Oi\u00e7a\">&nbsp;<\/div>\n<\/td>\n<td>\n<div class=\"SL_copy\" id=\"SL_copy\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/copy.png\") repeat scroll 0% 0%;\" title=\"C\u00f3pia\">&nbsp;<\/div>\n<\/td>\n<td>\n<div id=\"SL_bbl_font_patch\">&nbsp;<\/div>\n<div class=\"SL_bbl_font\" id=\"SL_bbl_font\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/font.png\") repeat scroll 0% 0%;\" title=\"Tamanho de letra\">&nbsp;<\/div>\n<\/td>\n<td>\n<div id=\"SL_bbl_help\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bhelp.png\") repeat scroll 0% 0%;\" title=\"Ajuda\">&nbsp;<\/div>\n<\/td>\n<td>\n<div class=\"SL_pin_off\" id=\"SL_pin\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/pin-on.png\") repeat scroll 0% 0%;\" title=\"Tradutor de pregos pop-up\">&nbsp;<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<div id=\"SL_shadow_translation_result\" style=\"visibility: visible;\">&nbsp;<\/div>\n<div class=\"SL_loading\" id=\"SL_loading\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/loading.gif\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<div id=\"SL_player2\">&nbsp;<\/div>\n<div id=\"SL_alert100\"><strong><strong><strong>A fun\u00e7\u00e3o do som \u00e9 limitada a 200 caracteres<\/strong><\/strong><\/strong><\/div>\n<div id=\"SL_Balloon_options\" style=\"background: rgb(255, 255, 255) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bg3.png\") repeat scroll 0% 0%;\">\n<div id=\"SL_arrow_down\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/down.png\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<table id=\"SL_tbl_opt\" style=\"width:100%\">\n<tbody>\n<tr>\n<td>&nbsp;<\/td>\n<td>\n<div id=\"SL_BBL_IMG\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bbl-logo.png\") repeat scroll 0% 0%;\" title=\"Mostrar bot\u00e3o inTranslator 3 segundos\">&nbsp;<\/div>\n<\/td>\n<td><strong><strong><strong><a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?bbl\" target=\"_blank\" title=\"Mostrar op\u00e7\u00f5es\" rel=\"noopener\">Op\u00e7\u00f5es<\/a>: <a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?hist\" target=\"_blank\" title=\"Hist\u00f3ria da tradu\u00e7\u00e3o\" rel=\"noopener\">Hist\u00f3rico<\/a>: <a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?feed\" target=\"_blank\" title=\"Feedback\" rel=\"noopener\">Feedback<\/a>: <a class=\"SL_options\" href=\"https:\/\/www.paypal.com\/cgi-bin\/webscr?cmd=_s-xclick&amp;hosted_button_id=GD9D8CPW8HFA2\" target=\"_blank\" title=\"Contribua\" rel=\"noopener\">Doa\u00e7\u00e3o<\/a><\/strong><\/strong><\/strong><\/td>\n<td><strong><strong><strong>Fechar<\/strong><\/strong><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p> <!--more--> <\/p>\n<p>Na Su\u00ed\u00e7a e noutros pa\u00edses europeus, tem havido um r\u00e1pido aumento das doen\u00e7as sexualmente transmiss\u00edveis nos \u00faltimos anos. Uma r\u00e1pida clarifica\u00e7\u00e3o microbiol\u00f3gica com diagn\u00f3sticos sens\u00edveis e espec\u00edficos \u00e9 importante devido ao aumento da resist\u00eancia aos antibi\u00f3ticos, especialmente com os gonococos. Este artigo de revis\u00e3o visa fornecer conhecimentos sobre aspectos epidemiol\u00f3gicos e de diagn\u00f3stico de infec\u00e7\u00f5es com Chlamydia trachomatis e Neisseria gonorrhoeae.<\/p>\n<h2 id=\"epidemiologia\">Epidemiologia<\/h2>\n<p>Os n\u00fameros de infec\u00e7\u00f5es por Chlamydia trachomatis, Neisseria gonorrhoeae e Treponema pallidum aumentaram significativamente em termos absolutos e relativos na Su\u00ed\u00e7a e em muitos pa\u00edses europeus nos \u00faltimos anos [1,2]. Na Su\u00ed\u00e7a, estes tr\u00eas agentes patog\u00e9nicos bacterianos e v\u00edrus de transmiss\u00e3o sexual, tais como o VIH e o v\u00edrus da hepatite B, devem ser notificados pelo laborat\u00f3rio de diagn\u00f3stico por lei. A notifica\u00e7\u00e3o obrigat\u00f3ria destas doen\u00e7as permite a vigil\u00e2ncia epidemiol\u00f3gica (www.bag.admin.ch) e a identifica\u00e7\u00e3o de factores e popula\u00e7\u00f5es de risco.<\/p>\n<p>Nos cant\u00f5es de Basileia-Stadt, Zurique, Genebra e Vaud, o aumento das doen\u00e7as sexualmente transmiss\u00edveis \u00e9 significativo, enquanto que foram documentados n\u00fameros mais baixos nas zonas rurais [1]. Embora seja prov\u00e1vel que o grande desenvolvimento no diagn\u00f3stico molecular nos \u00faltimos anos e a maior cobertura diagn\u00f3stica nos centros urbanos expliquem parte deste aumento, \u00e9 tamb\u00e9m muito prov\u00e1vel que o comportamento sexual descuidado seja parcialmente respons\u00e1vel, embora estudos bem fundamentados sobre este t\u00f3pico sejam raros. Pode postular-se que a possibilidade de profilaxia pr\u00e9-exposi\u00e7\u00e3o espec\u00edfica do VIH reduziu significativamente o medo de infec\u00e7\u00e3o pelo VIH. Isto aceita um risco sexualmente mais elevado para outras infec\u00e7\u00f5es. Para certas popula\u00e7\u00f5es de risco com infec\u00e7\u00f5es bacterianas recorrentes, a profilaxia contra a clam\u00eddia e os gonococos est\u00e1, portanto, a ser discutida [3,4]. No entanto, at\u00e9 agora faltam estudos randomizados nesta \u00e1rea, tamb\u00e9m no contexto da resist\u00eancia aos antibi\u00f3ticos.<\/p>\n<p><strong>Neisseria gonorrhoeae: <\/strong>Em 2015, 1895 foram relatadas na Su\u00ed\u00e7a infec\u00e7\u00f5es confirmadas de N. gonorrhoeae, o que \u00e9 aproximadamente 23% mais do que no ano anterior com 1545 relat\u00f3rios <strong>(Fig.&nbsp;<\/strong>1A, ). A maioria dos casos afectou os homens (cerca de 80%). No entanto, tem havido um aumento significativo em ambos os sexos desde 2000. A incid\u00eancia na Su\u00ed\u00e7a em 2015 foi de 9 por 100.000 habitantes para as mulheres e 37 por 100.000 habitantes para os homens [5]. A maioria dos casos ocorre em centros urbanos. A maior propor\u00e7\u00e3o de mulheres foi encontrada na faixa et\u00e1ria 15-24, e entre os homens, a faixa et\u00e1ria 25-34 \u00e9 particularmente afectada. Observou-se um aumento particularmente forte no grupo de homens que t\u00eam contacto sexual com outros homens (HSH). Estima-se que apenas 3% da popula\u00e7\u00e3o sexualmente activa s\u00e3o HSH, mas de acordo com estudos da FOPH mostram uma m\u00e9dia de 38% de infec\u00e7\u00f5es de gonorreia [5].<\/p>\n<p><strong>Chlamydia trachomatis:<\/strong> Em 2015, foram relatadas 10.157 infec\u00e7\u00f5es confirmadas de C. trachomatis na Su\u00ed\u00e7a, o que \u00e9 aproximadamente 5% mais do que no ano anterior com 9677 relat\u00f3rios <strong>(Fig.&nbsp;<\/strong> 1B, ). Globalmente, o n\u00famero de casos mais do que duplicou nos \u00faltimos dez anos. A incid\u00eancia na Su\u00ed\u00e7a em 2015 foi de 161 por 100.000 habitantes para as mulheres e 80 por 100.000 habitantes para os homens [6]. Isto pode ser parcialmente um pseudo-aumento, uma vez que a percentagem de testes positivos em todos os testes realizados se manteve relativamente est\u00e1vel [7]. Certamente, est\u00e3o tamb\u00e9m a ser diagnosticadas mais infec\u00e7\u00f5es assintom\u00e1ticas, o que tem a ver com a disponibilidade de diagn\u00f3sticos moleculares sens\u00edveis e de rastreios mais frequentes. Aproximadamente 70% das infec\u00e7\u00f5es ocorrem em mulheres, metade das quais com idades compreendidas entre os 15-24 anos. Em 70-90% das mulheres, a infec\u00e7\u00e3o \u00e9 assintom\u00e1tica.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9474\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/12\/abb1_dp6_s24.png\" style=\"height:208px; width:600px\" width=\"1100\" height=\"382\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"diagnostico-de-n-gonorrhoeae-colheita-de-especimes\">Diagn\u00f3stico de N. gonorrhoeae &#8211; Colheita de esp\u00e9cimes<\/h2>\n<p>A recolha correcta de esp\u00e9cimes \u00e9 fundamental para a detec\u00e7\u00e3o cultural de N. gonorreia. Os gonococos tendem \u00e0 aut\u00f3lise e s\u00e3o sens\u00edveis \u00e0 desseca\u00e7\u00e3o e a subst\u00e2ncias t\u00f3xicas de alguns lubrificantes [8].<\/p>\n<p>Actualmente, os meios de transporte universais l\u00edquidos s\u00e3o utilizados como meios de recolha e transporte de escolha, que permitem a realiza\u00e7\u00e3o de culturas bacterianas e an\u00e1lises de diagn\u00f3stico molecular (PCR) (por exemplo, eSwab de Copan). Estes meios de transporte cont\u00eam novos esfrega\u00e7os com fibras de nylon do bando que aumentam o rendimento da colheita de amostras em compara\u00e7\u00e3o com os esfrega\u00e7os convencionais [9\u201311]. Contudo, como tamb\u00e9m existem laborat\u00f3rios de diagn\u00f3stico que requerem diferentes recipientes de transporte para PCR e cultura gonoc\u00f3cica, recomendamos que se consulte o respectivo laborat\u00f3rio de exame antes de colher a amostra.<\/p>\n<p>O s\u00edtio de recolha deve ser escolhido de acordo com a hist\u00f3ria sexual [12]. Nos homens, os esfrega\u00e7os uretrais e a urina de primeiro jacto s\u00e3o considerados o material de exame de elei\u00e7\u00e3o. Ambas as amostras devem ser colhidas pelo menos uma hora ap\u00f3s a \u00faltima micturi\u00e7\u00e3o. Um esfrega\u00e7o cervical deve ser tomado como o material de exame de elei\u00e7\u00e3o nas mulheres. As amostras de urina das mulheres n\u00e3o devem normalmente ser utilizadas, uma vez que s\u00e3o menos sens\u00edveis do que os esfrega\u00e7os cervicais [13]. Em raparigas pr\u00e9-puberais, as infec\u00e7\u00f5es com gonococos devem ser procuradas vaginalmente e n\u00e3o cervicalmente [14]. Nesta faixa et\u00e1ria, raparigas e rapazes devem, naturalmente, consultar um pediatra.<\/p>\n<p>Os esfrega\u00e7os rectais devem ser obtidos com um rectosc\u00f3pio. A utiliza\u00e7\u00e3o de lubrificantes deve ser evitada, uma vez que estes por vezes cont\u00eam subst\u00e2ncias t\u00f3xicas para a N. gonorreia e reduzem a sensibilidade da detec\u00e7\u00e3o cultural. A t\u00e9cnica de recolha deve cobrir uma \u00e1rea de esfrega\u00e7o t\u00e3o grande quanto poss\u00edvel [15]. Um estudo mostrou que, no caso da infec\u00e7\u00e3o orofar\u00edngea, a maior \u00e1rea poss\u00edvel com press\u00e3o adicional durante o esfrega\u00e7o quase duplicou a taxa de detec\u00e7\u00e3o [15]. Para uma orienta\u00e7\u00e3o detalhada sobre a colheita \u00f3ptima de esp\u00e9cimes para o diagn\u00f3stico da gonorreia, consulte as recomenda\u00e7\u00f5es da Comiss\u00e3o Federal de Sa\u00fade Sexual e da Sociedade Su\u00ed\u00e7a de Infecciologia [13]. Se for desejada uma cultura gonoc\u00f3cica, a amostra deve ser colhida antes da administra\u00e7\u00e3o de antibi\u00f3ticos. O transporte das amostras para o laborat\u00f3rio deve ser o mais r\u00e1pido poss\u00edvel e o cultivo cultural deve, de prefer\u00eancia, ter lugar no prazo de vinte e quatro horas [16]. A amostra pode ser enviada no meio de transporte \u00e0 temperatura ambiente.<\/p>\n<h2 id=\"microscopia\">Microscopia<\/h2>\n<p>Em homens sintom\u00e1ticos, a detec\u00e7\u00e3o \u00e9 poss\u00edvel com uma prepara\u00e7\u00e3o de Gram a partir de uma zaragatoa uretral. A detec\u00e7\u00e3o de Gram-negativos, diplococos em forma de s\u00e9men a caf\u00e9 em leuc\u00f3citos polinucleares \u00e9 seminal para a gonorreia [17]. A sensibilidade e especificidade deste exame \u00e9 &gt;90% [14]. Nas mulheres, a sensibilidade da an\u00e1lise microsc\u00f3pica de um esfrega\u00e7o cervical \u00e9 inferior a 50-70%, mas a especificidade \u00e9 &gt;90% [14]. Naturalmente, a fiabilidade da microscopia depende da qualidade da amostra e da experi\u00eancia do examinador [14]. A microscopia n\u00e3o \u00e9 \u00fatil para diagnosticar uma infec\u00e7\u00e3o orofar\u00edngea porque a Neisseria spp. apatog\u00e9nica como componente da flora oral n\u00e3o permite uma diferencia\u00e7\u00e3o fi\u00e1vel da N. gonorrhoeae patog\u00e9nica.<\/p>\n<h2 id=\"metodos-biologicos-moleculares\">M\u00e9todos biol\u00f3gicos moleculares<\/h2>\n<p>Actualmente, est\u00e3o dispon\u00edveis v\u00e1rios sistemas comerciais que permitem a detec\u00e7\u00e3o de N. gonorreia e C. trachomatis a partir da mesma amostra atrav\u00e9s da amplifica\u00e7\u00e3o do ADN (PCR) &#8211; os chamados PCRs duplex. A sensibilidade e especificidade destes sistemas s\u00e3o excelentes, cada um em &gt;95% [18\u201321], e s\u00e3o portanto agora padr\u00e3o para a detec\u00e7\u00e3o de infec\u00e7\u00f5es por N. gonorreiae e C. trachomatis [22].<\/p>\n<p>Recentemente, existem tamb\u00e9m PCRs multiplex que permitem uma clarifica\u00e7\u00e3o mais ampla com outros agentes patog\u00e9nicos como o Mycoplasma hominis, M. genitalium, Ureaplasma urealyticum, e U. parvum [23,24]. Os testes moleculares com sistemas (semi)automatizados s\u00e3o menos dispendiosos do que os m\u00e9todos de cultura e permitem um elevado rendimento de amostras cl\u00ednicas, especialmente para um rastreio r\u00e1pido. O tempo desde a recep\u00e7\u00e3o da amostra no laborat\u00f3rio at\u00e9 ao resultado (o chamado turn-around time) \u00e9 normalmente de apenas algumas horas, e os resultados est\u00e3o frequentemente dispon\u00edveis no mesmo dia, dependendo da hora de recep\u00e7\u00e3o da amostra. Os m\u00e9todos PCR n\u00e3o devem ser utilizados para documentar o sucesso do tratamento a curto prazo, uma vez que o ADN de N. gonorreiae ainda pode ser determinado v\u00e1rias semanas ap\u00f3s o tratamento bem sucedido utilizando m\u00e9todos de detec\u00e7\u00e3o sens\u00edveis [14]. As reinfec\u00e7\u00f5es ou isolados resistentes podem tamb\u00e9m ser respons\u00e1veis [25]. Neste caso, o historial m\u00e9dico deve ser retomado e deve seguir-se uma detec\u00e7\u00e3o cultural com testes de resist\u00eancia aos antibi\u00f3ticos.<\/p>\n<h2 id=\"outros-metodos-de-deteccao\">Outros m\u00e9todos de detec\u00e7\u00e3o<\/h2>\n<p>Os testes de ponto de tratamento (POC) para a detec\u00e7\u00e3o de esterase leucocit\u00e1ria e os testes imunocromatogr\u00e1ficos mostram baixa sensibilidade nas infec\u00e7\u00f5es por N. gonorrohoeae, com apenas 23-85% e 60-94%, respectivamente [26]. Neste momento, os m\u00e9todos baseados em PCR s\u00e3o, portanto, claramente superiores.<\/p>\n<h2 id=\"cultura-bacteriana\">Cultura bacteriana<\/h2>\n<p>A detec\u00e7\u00e3o cultural de gonococos vi\u00e1veis \u00e9 necess\u00e1ria para detectar poss\u00edveis falhas de tratamento e para recolher dados fi\u00e1veis sobre a situa\u00e7\u00e3o e a evolu\u00e7\u00e3o da resist\u00eancia. Os gonococos s\u00e3o geralmente cultivados em meios selectivos. Os meios de comunica\u00e7\u00e3o cont\u00eam antibi\u00f3ticos e antif\u00fangicos para inibir a flora bacteriana e f\u00fangica que os acompanha. Um meio t\u00edpico, que tamb\u00e9m \u00e9 utilizado no nosso laborat\u00f3rio, \u00e9 o \u00e1gar Martin-Lewis \u00e0 base de \u00e1gar sangue de cozinha. As placas inoculadas s\u00e3o verificadas diariamente quanto ao crescimento e incubadas durante 48 horas a 36\u00b0C numa atmosfera de 5% de CO2. Os gonococos crescem como col\u00f3nias pequenas, suaves e cinzentas no primeiro ou segundo dia. Assim, uma detec\u00e7\u00e3o cultural de bact\u00e9rias vivas demora geralmente entre dois a tr\u00eas dias, em contraste com uma PCR, mas oferece mais possibilidades de diagn\u00f3stico.<\/p>\n<p>A identifica\u00e7\u00e3o exacta das col\u00f3nias suspeitas na placa de cultura costumava ser feita atrav\u00e9s de testes a v\u00e1rias reac\u00e7\u00f5es bioqu\u00edmicas, que levavam v\u00e1rias horas a estabelecer um perfil bioqu\u00edmico. Actualmente, a identifica\u00e7\u00e3o de um isolado bacteriano \u00e9 realizada em poucos minutos utilizando a espectrometria de massa Matrix Assisted Laser Desorption Ionisation &#8211; Time of Flight (MALDI-TOF). A espectrometria de massa MALDI-TOF tornou-se agora o padr\u00e3o de identifica\u00e7\u00e3o de uma grande variedade de bact\u00e9rias e fungos em laborat\u00f3rios de microbiologia [27]. No entanto, o factor de limita\u00e7\u00e3o temporal continua a ser o cultivo das bact\u00e9rias numa placa de \u00e1gar.<\/p>\n<h2 id=\"posicao-de-resistencia\">Posi\u00e7\u00e3o de resist\u00eancia<\/h2>\n<p>A Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) compilou recentemente uma lista de germes resistentes para os quais deveriam ser desenvolvidos urgentemente novos antibi\u00f3ticos eficazes &#8211; entre eles est\u00e3o os resistentes \u00e0 cefalosporina e \u00e0 fluoroquinolona N. gonorrhoeae (www.who.int). O teste de resist\u00eancia ap\u00f3s a detec\u00e7\u00e3o cultural de N. gonorreiae \u00e9 importante [13,28]. Apesar da urg\u00eancia, a vigil\u00e2ncia da resist\u00eancia antimicrobiana n\u00e3o est\u00e1 estandardizada ou suficientemente estabelecida em muitos pa\u00edses [29]. Os seguintes antibi\u00f3ticos s\u00e3o normalmente testados para N. gonorreia: Cefixime, ceftriaxona, fluoroquinolonas (por exemplo ciprofloxacina) e azitromicina. Os testes de resist\u00eancia requerem um per\u00edodo adicional de dois dias ap\u00f3s a identifica\u00e7\u00e3o.<\/p>\n<p>O tratamento da N. gonorreia \u00e9 complicado pelo desenvolvimento da resist\u00eancia aos antibi\u00f3ticos. Embora a penicilina ainda fosse considerada o tratamento de elei\u00e7\u00e3o nos anos 70, o aumento das penicilinases mediadas por plasm\u00eddeos (enzimas que libertam penicilina) e da resist\u00eancia cromoss\u00f3mica \u00e0 penicilina p\u00f4s fim \u00e0 terapia de penicilina [30]. Do mesmo modo, o desenvolvimento da resist\u00eancia plasm\u00eddica e cromoss\u00f3mica \u00e0 tetraciclina levou \u00e0 utiliza\u00e7\u00e3o de cefalosporinas de largo espectro nos anos 80 e, mais tarde, \u00e0 utiliza\u00e7\u00e3o de fluoroquinolonas [30]. Nos anos 90 assistiu-se a um aumento dos isolados resistentes \u00e0 fluoroquinolona, inicialmente no Sudeste Asi\u00e1tico, seguido de uma r\u00e1pida propaga\u00e7\u00e3o a muitos pa\u00edses. O aumento global de isolados resistentes a cefixime est\u00e1 a progredir e \u00e9 motivo de preocupa\u00e7\u00e3o porque este antibi\u00f3tico \u00e9 actualmente recomendado como uma dose oral \u00fanica para tratamento [30]. Outro problema \u00e9 o aumento da resist\u00eancia \u00e0 ceftriaxona. Devido ao aumento da N. gonorreia multi-resistente, certas orienta\u00e7\u00f5es j\u00e1 recomendam agora uma combina\u00e7\u00e3o de ceftriaxona intramuscular e azitromicina oral como primeira escolha de tratamento [30].<\/p>\n<p>Para detalhes actuais sobre a terapia da gonorreia, consulte as actuais &#8220;Recomenda\u00e7\u00f5es da Comiss\u00e3o Federal de Sa\u00fade Sexual e da Sociedade Su\u00ed\u00e7a de Infecciologia&#8221; [13].<\/p>\n<h2 id=\"diagnostico-de-c-trachomatis-colheita-de-especimes\">Diagn\u00f3stico de C. trachomatis &#8211; Colheita de esp\u00e9cimes<\/h2>\n<p>As clam\u00eddias s\u00e3o bact\u00e9rias intracelulares obrigat\u00f3rias, por isso \u00e9 importante que a amostra contenha o maior n\u00famero de c\u00e9lulas poss\u00edvel. Isto \u00e9 conseguido esfregando a zaragatoa ao recolher a amostra [31].<\/p>\n<p>Os locais habituais para recolha de esp\u00e9cimes em infec\u00e7\u00f5es genitais sintom\u00e1ticas com C. trachomatis s\u00e3o o endoc\u00e9rvix nas mulheres e a uretra nos homens. Amostras menos invasivas, tais como uma zaragatoa vaginal nas mulheres e uma zaragatoa do meio do jacto de urina ou do meato uretral nos homens, s\u00e3o tamb\u00e9m poss\u00edveis hoje em dia, aumentando assim a aceita\u00e7\u00e3o dos testes pelas pacientes. A sensibilidade e especificidade da detec\u00e7\u00e3o de C. tracomatis por PCR em amostras recolhidas de forma n\u00e3o invasiva s\u00e3o compar\u00e1veis \u00e0s amostras recolhidas directamente do colo do \u00fatero ou uretra [32]. As amostras de urina de mulheres s\u00e3o normalmente menos adequadas para a detec\u00e7\u00e3o de C. tracomatis por PCR, uma vez que mostram uma sensibilidade sub\u00f3ptima [29]. Os esfrega\u00e7os vaginais autocolhidos s\u00e3o descritos nas recomenda\u00e7\u00f5es laboratoriais do CDC como esp\u00e9cimes exactos e aceit\u00e1veis [33]. Para a detec\u00e7\u00e3o de clam\u00eddia com PCR, o material deve ser processado ap\u00f3s 48 horas, o mais tardar [31]. A amostra pode ser transportada \u00e0 temperatura ambiente. Para uma orienta\u00e7\u00e3o detalhada sobre a melhor recolha de esp\u00e9cimes, consulte &#8220;Recommendations of the Federal Commission for Sexual Health and the Swiss Society for Infectiology&#8221; [28].<\/p>\n<p>A infec\u00e7\u00e3o com os ser\u00f3tipos C. trachomatis L1, L2 e L3 est\u00e1 associada ao aumento da patogenicidade e leva ao quadro cl\u00ednico conhecido como linfogranuloma ven\u00e9reo (LGV). As infec\u00e7\u00f5es por LGV ocorrem principalmente em popula\u00e7\u00f5es de risco, como os HSH. A detec\u00e7\u00e3o tem lugar em esfrega\u00e7os rectais ou uretrais, pus ou material de pun\u00e7\u00e3o dos g\u00e2nglios linf\u00e1ticos afectados.<\/p>\n<h2 id=\"metodos-biologicos-moleculares-2\">M\u00e9todos biol\u00f3gicos moleculares<\/h2>\n<p>Como m\u00e9todo de escolha, a clam\u00eddia \u00e9 hoje em dia detectada com m\u00e9todos de amplifica\u00e7\u00e3o de ADN (PCR). A detec\u00e7\u00e3o pode ser efectuada simultaneamente para C. tracomatis e N. gonorreia com excelente sensibilidade e especificidade (ver acima). A import\u00e2ncia de um diagn\u00f3stico fi\u00e1vel e de uma vigil\u00e2ncia epidemiol\u00f3gica \u00e9 ilustrada pelo seguinte exemplo: C. trachomatis tem 4-8 c\u00f3pias de um plasm\u00eddeo longo de 7500 nucle\u00f3tidos. Este plasm\u00eddeo \u00e9 portanto um alvo muito atractivo para um m\u00e9todo de detec\u00e7\u00e3o por PCR, uma vez que o aumento da sensibilidade de diagn\u00f3stico \u00e9 conseguido atrav\u00e9s de m\u00faltiplas c\u00f3pias. Entre Novembro de 2005 e Agosto de 2006, registou-se uma queda inesperada na incid\u00eancia de C. trachomatis numa determinada regi\u00e3o da Su\u00e9cia [34]. A redu\u00e7\u00e3o de 25% nos casos diagnosticados foi inicialmente interpretada como o sucesso das medidas de preven\u00e7\u00e3o. No entanto, este foi na realidade o resultado de uma altera\u00e7\u00e3o gen\u00e9tica com uma elimina\u00e7\u00e3o de 377 pares de bases no referido plasm\u00eddeo [34]. Como resultado, os testes PCR comerciais frequentemente utilizados j\u00e1 n\u00e3o detectam a clam\u00eddia no material da amostra. Esta variante chamada &#8220;sueca&#8221; ou &#8220;escandinava&#8221; de C. trachomatis \u00e9 predominante na Su\u00e9cia e agora tamb\u00e9m pode ser encontrada noutros pa\u00edses escandinavos [35]. At\u00e9 agora, s\u00f3 foram comunicados casos individuais noutros pa\u00edses. Os fabricantes de diagn\u00f3sticos de PCR reagiram rapidamente e adaptaram e melhoraram os m\u00e9todos de detec\u00e7\u00e3o em conformidade. A clam\u00eddia associada ao LGV pode ser determinada por PCR para a detec\u00e7\u00e3o dos ser\u00f3tipos espec\u00edficos de LGV [36,37]. Num curso mais grave da doen\u00e7a, por exemplo, com g\u00e2nglios linf\u00e1ticos aumentados, o LGV deve ser procurado &#8211; especialmente em HSH &#8211; e tratado em conformidade [38]. Tal como no caso do N. gonorhoeae, o ADN de bact\u00e9rias n\u00e3o vi\u00e1veis pode permanecer detect\u00e1vel durante muito tempo em caso de infec\u00e7\u00e3o com C. trachomatis &#8211; a PCR n\u00e3o deve, portanto, ser repetida no prazo de tr\u00eas semanas [39].<\/p>\n<h2 id=\"outros-metodos-de-deteccao-2\">Outros m\u00e9todos de detec\u00e7\u00e3o<\/h2>\n<p>A detec\u00e7\u00e3o serol\u00f3gica de anticorpos ou um ELISA de antig\u00e9nio de Chlamydia com uma reac\u00e7\u00e3o de imunofluoresc\u00eancia quase nunca s\u00e3o usados em rotina.<\/p>\n<h2 id=\"posicao-de-resistencia-2\">Posi\u00e7\u00e3o de resist\u00eancia<\/h2>\n<p>Dado que a clam\u00eddia s\u00f3 pode ser cultivada em culturas celulares complexas e isto s\u00f3 \u00e9 feito em laborat\u00f3rios especializados, n\u00e3o \u00e9 normalmente efectuado qualquer teste de resist\u00eancia. O tratamento de escolha s\u00e3o antibi\u00f3ticos com actividade intracelular como a doxiciclina e a azitromicina. O desenvolvimento da resist\u00eancia em C. trachomatis ainda n\u00e3o foi demonstrado [28]. Para as directrizes de tratamento da infec\u00e7\u00e3o por C. trachomatis, remetemos para as &#8220;Recommendations of the Federal Commission for Sexual Health and the Swiss Society for Infectiology&#8221; [28].<\/p>\n<h2 id=\"resumo\">Resumo<\/h2>\n<p>Doen\u00e7as sexualmente transmiss\u00edveis como a N. gonorreia e a C. tracomatis est\u00e3o actualmente a viver um renascimento &#8211; em parte explicado pela disponibilidade e sensibilidade dos diagn\u00f3sticos moleculares modernos &#8211; mas n\u00e3o exclusivamente. Especialmente em tempos de aumento da resist\u00eancia aos antibi\u00f3ticos na N. gonorreia e particularmente na clam\u00eddia virulenta (linfogranuloma ven\u00e9reo), deve ser feito um diagn\u00f3stico r\u00e1pido e fi\u00e1vel. Para al\u00e9m da detec\u00e7\u00e3o de diagn\u00f3stico molecular, tamb\u00e9m \u00e9 recomendado o teste de resist\u00eancia a antibi\u00f3ticos baseado em cultura para a N. gonorreia.<\/p>\n<h2 id=\"mensagens-take-home\">Mensagens Take-Home<\/h2>\n<ul>\n<li>Doen\u00e7as sexualmente transmiss\u00edveis como a N. gonorreia e a C. tracomatis est\u00e3o actualmente a experimentar um renascimento. Este aumento n\u00e3o pode ser explicado exclusivamente pela disponibilidade e sensibilidade dos diagn\u00f3sticos moleculares modernos.<\/li>\n<li>A crescente resist\u00eancia aos antibi\u00f3ticos em N. gonorreiae e a detec\u00e7\u00e3o de clam\u00eddias particularmente virulentas (linfogranuloma ven\u00e9reo) requerem diagn\u00f3sticos r\u00e1pidos e fi\u00e1veis.<\/li>\n<li>Para al\u00e9m da detec\u00e7\u00e3o de diagn\u00f3stico molecular, \u00e9 tamb\u00e9m recomendado o teste de resist\u00eancia a antibi\u00f3ticos baseado em cultura para a N. gonorreia.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Gabinete Federal de Sa\u00fade P\u00fablica D\u00d6G. HIV, s\u00edfilis, gonorreia e clamidiose na Su\u00ed\u00e7a em 2015: uma panor\u00e2mica epidemiol\u00f3gica. Boletim FOPH 2016; 46: 12-13.<\/li>\n<li>(ECDC) ECfDPaC. Infec\u00e7\u00f5es sexualmente transmiss\u00edveis na Europa 2013. Relat\u00f3rio de vigil\u00e2ncia do ECDC 2015: 1-124.<\/li>\n<li>Dubourg G, Raoult D: Os desafios da profilaxia pr\u00e9-exposi\u00e7\u00e3o de infec\u00e7\u00f5es de transmiss\u00e3o sexual bacteriana. Microbiologia cl\u00ednica e infec\u00e7\u00e3o: a publica\u00e7\u00e3o oficial da Sociedade Europeia de Microbiologia Cl\u00ednica e Doen\u00e7as Infecciosas 2016; 22 (9): 753-756.<\/li>\n<li>Unemo M, Bradshaw CS, et al: Infec\u00e7\u00f5es sexualmente transmiss\u00edveis: desafios \u00e0 frente. Lancet Infect Dis 2017; 17 (8): e235-e279.<\/li>\n<li>Gabinete Federal de Sa\u00fade P\u00fablica D\u00d6G: Gonorreia na Su\u00ed\u00e7a em 2015. Boletim FOPH 2016; 46: 27-30.<\/li>\n<li>Gabinete Federal de Sa\u00fade P\u00fablica D\u00d6G: Clamidiose na Su\u00ed\u00e7a em 2015. Boletim FOPH 2016; 46: 32-33.<\/li>\n<li>Schmutz C, Burki D, et al.: Testing for Chlamydia trachomatis: time trends in positivity rates in the canton of Basel-Stadt, Switzerland. Epidemiol Infect 2013; 141 (9): 1953-1964.<\/li>\n<li>Vogel U, Forsch M: Cocos aer\u00f3bicos e anaer\u00f3bicos facultativos gran negativos. Em: Neumeister M, Geiss HK et al. (ed.) Diagn\u00f3sticos microbiol\u00f3gicos. Stuttgart, Nova Iorque: Thieme; 2009.<\/li>\n<li>Coorevits L, Vanscheeuwijck C, et al: Evaluation of Copan FLOQSwab for the molecular detection of Chlamydia trachomatis by Abbott RealTime CT PCR. Acta clinica<\/li>\n<li>Belgica 2015; 70 (6): 398-402.<\/li>\n<li>Jun JK, Lim MC, et al. Compara\u00e7\u00e3o de esfrega\u00e7os vaginais DRY e WET com esp\u00e9cimes cervicais em Roche Cobas 4800 HPV e Abbott RealTime testes HPV de alto risco. J Clin Virol 2016; 79: 80-84.<\/li>\n<li>Tan TY, Ng LS, et al.: Avalia\u00e7\u00e3o da recupera\u00e7\u00e3o bacteriana e viabilidade a partir de tr\u00eas sistemas diferentes de transporte de zaragatoa. Patologia 2014; 46 (3): 230-233.<\/li>\n<li>den Heijer CDJ, Hoebe C, et al: Uma vis\u00e3o abrangente dos testes e diagn\u00f3sticos de gonorreias urogenitais, anorretais e orofar\u00edngeas da Neisseria entre diferentes prestadores de cuidados de DST: um estudo transversal. BMC Infect Dis 2017; 17 (1): 290.<\/li>\n<li>Toutous Trellu L, Oertle D, et al: Gonorrhoea: novas recomenda\u00e7\u00f5es sobre diagn\u00f3stico e tratamento. F\u00f3rum m\u00e9dico su\u00ed\u00e7o 2014; 14 (20): 407-409.<\/li>\n<li>Ng LK, Martin IE: O diagn\u00f3stico laboratorial da Neisseria gonorrhoeae. The Canadian journal of infectious diseases &amp; medical microbiology = Journal canadien des maladies infectieuses et de la microbiologie medicale \/ AMMI Canada 2005; 16 (1): 15-25.<\/li>\n<li>Mitchell M, Rane V, et al: A t\u00e9cnica de amostragem \u00e9 importante para um isolamento \u00f3ptimo da gonorreia far\u00edngea. Sex Transmect Infect 2013; 89 (7): 557-560.<\/li>\n<li>Wind CM, de Vries HJ, et al.:&nbsp; Combina\u00e7\u00e3o bem sucedida de Diagn\u00f3stico de Teste de Amplifica\u00e7\u00e3o de \u00c1cido Nucleico e Cultura de Neisseria gonorrhoeae Diferida Alvo. Journal of clinical microbiology 2015; 53 (6): 1884-1890.<\/li>\n<li>Spence JM, Wright L, Clark VL: Manuten\u00e7\u00e3o laboratorial da Neisseria gonorrhoeae. Protocolos actuais em microbiologia 2008; Cap\u00edtulo 4: Unidade 4A 1.<\/li>\n<li>Perry MD, Jones RN, Corden SA: \u00c9 necess\u00e1rio um teste de confirma\u00e7\u00e3o do teste Roche cobas 4800 CT\/NG Neisseria gonorrhoeae amostras positivas? Compara\u00e7\u00e3o do teste Roche cobas 4800 CT\/NG com um ensaio opa\/pap duplex para a detec\u00e7\u00e3o de N gonorreia. Infecto de transmiss\u00e3o sexual 2014; 90 (4): 303-308.<\/li>\n<li>Ursi D, Crucitti T, Smet H, Ieven M: Avalia\u00e7\u00e3o do ensaio Bio-Rad Dx CT\/NG\/MG(R) para a detec\u00e7\u00e3o simult\u00e2nea de Chlamydia trachomatis, Neisseria gonorrhoeae e Mycoplasma genitalium na urina. Revista europeia de microbiologia cl\u00ednica e doen\u00e7as infecciosas: publica\u00e7\u00e3o oficial da Sociedade Europeia de Microbiologia Cl\u00ednica 2016; 35 (7): 1159-1163.<\/li>\n<li>Wong KC, Ho BS, et al: Sistema Duplex PCR para detec\u00e7\u00e3o simult\u00e2nea de Neisseria gonorrhoeae e Chlamydia trachomatis em esp\u00e9cimes cl\u00ednicos. Journal of clinical patology 1995; 48 (2): 101-104.<\/li>\n<li>Meyer T, Klos C et al.: Avalia\u00e7\u00e3o do desempenho do<\/li>\n<li>Kit de teste PelvoCheck CT\/NG para a detec\u00e7\u00e3o de Chlamydia trachomatis e Neisseria gonorrhoeae. BMJ aberto em 2016; 6 (1): e009894.<\/li>\n<li>Low N, Unemo M, et al.: Molecular diagnostics for gonorrhoea: implications for antimicrobial resistance and the threat of untreatable gonorrhoea. PLoS medicina 2014; 11 (2): e1001598.<\/li>\n<li>Del Prete R, Ronga L et al: Detec\u00e7\u00e3o e identifica\u00e7\u00e3o simult\u00e2nea de agentes patog\u00e9nicos de DST por PCR multiplex em tempo real em amostras do tracto genital numa \u00e1rea seleccionada da Ap\u00falia, uma regi\u00e3o do sul de It\u00e1lia. Infec\u00e7\u00e3o 2017; 45 (4): 469-477.<\/li>\n<li>Fernandez G, Martro E, et al.: Utilidade de um novo ensaio de PCR multiplex em tempo real para o diagn\u00f3stico de infec\u00e7\u00f5es sexualmente transmiss\u00edveis. Enferm Infecc Microbiol Clin 2016; 34(8): 471-476.<\/li>\n<li>Bissessor M, Whiley DM et al: Persist\u00eancia do ADN da Neisseria gonorreia ap\u00f3s tratamento da gonorreia far\u00edngea e rectal \u00e9 influenciada pela susceptibilidade aos antibi\u00f3ticos e reinfec\u00e7\u00e3o. Clin Infect Dis 2015; 60 (4): 557-563.<\/li>\n<li>Watchirs Smith LA, Hillman R et al: Testes no local de tratamento para o diagn\u00f3stico da infec\u00e7\u00e3o por gonorreia de Neisseria: uma revis\u00e3o sistem\u00e1tica das caracter\u00edsticas operacionais e de desempenho. Sex Transmect Infect 2013; 89 (4): 320-326.<\/li>\n<li>Dierig A, Frei R, Egli A: A via r\u00e1pida para a identifica\u00e7\u00e3o microbiana: dessor\u00e7\u00e3o laser assistida por matriz\/tempo de ioniza\u00e7\u00e3o da espectrometria de massa de voo (MALDI-TOF MS). Pediatr Infect Dis J 2015; 34 (1): 97-99.<\/li>\n<li>Tarr P: Infec\u00e7\u00f5es sexualmente transmiss\u00edveis com Chlamydia trachomatis: Recomenda\u00e7\u00f5es da Comiss\u00e3o Federal para a Sa\u00fade Sexual (FCSH) e da Sociedade Su\u00ed\u00e7a de Infecciologia (SSI). Boletim FOPH 2017; 35: 8-14.<\/li>\n<li>Unemo M, Shipitsyna E, Domeika M: S da Europa de Leste, Reproductive Health Network Antimicrobial Resistance G. Vigil\u00e2ncia da gonorreia, diagn\u00f3stico laboratorial e testes de susceptibilidade antimicrobiana da Neisseria gonorrhoeae em 11 pa\u00edses da parte oriental da regi\u00e3o europeia da OMS. APMIS: acta pathologica, microbiologica, et immunologica Scandinavica 2011; 119 (9): 643-649.<\/li>\n<li>Elias J, Frosch M, Vogel U: Neisseria. In: Jorgensen JH, ed. Manual de microbiologia cl\u00ednica. 11\u00aa ed. Washington, DC: ASM Press; 2015: 635-651.<\/li>\n<li>Jacobs E: Mycoplasma e bact\u00e9rias intracelulares obrigat\u00f3rias. In: Neumeister B, Geiss HK, BRaun RW, Kimmig P, eds. Diagn\u00f3sticos microbiol\u00f3gicos. Stuttgart, Nova Iorque: Thieme; 2009.<\/li>\n<li>Gaydos CA, Essig A, Vogel U: Chlamydaceae. In: Jorgensen JH, ed. Manual de Mircobiologia Cl\u00ednica. 11\u00aa ed. Washington: ASM Press; 2015: 1106-1121.<\/li>\n<li>Hobbs MM, van der Pol B et al. Do NIH: procedimentos de um workshop sobre a import\u00e2ncia dos esp\u00e9cimes vaginais autoobtidos para a detec\u00e7\u00e3o de infec\u00e7\u00f5es sexualmente transmiss\u00edveis. Doen\u00e7as sexualmente transmiss\u00edveis 2008; 35 (1): 8-13.<\/li>\n<li>Ripa T, Nilsson P: Uma variante de Chlamydia trachomatis com elimina\u00e7\u00e3o em plasm\u00eddeo cr\u00edptico: implica\u00e7\u00f5es para a utiliza\u00e7\u00e3o de testes de diagn\u00f3stico por PCR. Euro vigil\u00e2ncia: boletim Europeen sur les maladies transmissibles = European communicable disease bulletin 2006; 11 (11): E061109 2.<\/li>\n<li>Unemo M, Clarke IN: A nova variante sueca de Chlamydia trachomatis. Curr Opinion Infect Dis 2011; 24(1): 62-9.<\/li>\n<li>de Roche M, Sawatzki M et al: Lymphogranuloma venereum. Uma doen\u00e7a antiga com um vestido novo. Der Internist 2011; 52 (5): 584-589.<\/li>\n<li>Goldenberger D, Dutly F, Gebhardt M: An\u00e1lise de 721 esp\u00e9cimes de Chlamydia trachomatis-positivos urogenitais de homens e mulheres usando o ensaio de PCR em tempo real espec\u00edfico para linfogranuloma ven\u00e9reo L2. Euro vigil\u00e2ncia: boletim Europeen sur les maladies transmissibles = European communicable disease bulletin 2006; 11 (10): E061018 4.<\/li>\n<li>Stoner BP, Cohen SE: Lymphogranuloma venereum 2015: Apresenta\u00e7\u00e3o cl\u00ednica, diagn\u00f3stico, e tratamento. Clin Infect Dis 2015; 61 (8): S865-873.<\/li>\n<li>Gaydos CA, Crotchfelt KA, et al: Ensaios de amplifica\u00e7\u00e3o molecular para detectar infec\u00e7\u00f5es por clam\u00eddia em amostras de urina de estudantes do ensino secund\u00e1rio e para monitorizar a persist\u00eancia do ADN clamidial ap\u00f3s a terapia. J Infect Dis 1998; 177 (2): 417-424.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1TICA DE DERMATOLOGIA 2017; 27(6): 22-28<\/em><\/p>\n<div id=\"SL_balloon_obj\" style=\"display: block;\">\n<div class=\"SL_ImTranslatorLogo\" id=\"SL_button\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/imtranslator-s.png\") repeat scroll 0% 0%; display: none; opacity: 1; left: -8px; top: -25px;\">&nbsp;<\/div>\n<div id=\"SL_shadow_translation_result2\" style=\"display: none;\">&nbsp;<\/div>\n<div id=\"SL_shadow_translator\" style=\"display: none;\">\n<div id=\"SL_planshet\">\n<div id=\"SL_arrow_up\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/up.png\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<div id=\"SL_Bproviders\">\n<div class=\"SL_BL_LABLE_ON\" id=\"SL_P0\" title=\"Google\">G<\/div>\n<div class=\"SL_BL_LABLE_ON\" id=\"SL_P1\" title=\"Microsoft\">M<\/div>\n<div class=\"SL_BL_LABLE_ON\" id=\"SL_P2\" title=\"Tradutora\">T<\/div>\n<\/div>\n<div id=\"SL_alert_bbl\" style=\"display: none;\">\n<div id=\"SLHKclose\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/delete.png\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<div id=\"SL_alert_cont\">&nbsp;<\/div>\n<\/div>\n<div id=\"SL_TB\">\n<table cellspacing=\"1\" id=\"SL_tables\">\n<tbody>\n<tr>\n<td>&nbsp;<\/td>\n<td>Reconhecer a l\u00ednguaAfricanaAlban\u00easArabeAzerbaijanoBascoBengaliB\u00f3snianB\u00falgaroBurm\u00easCebuanoChichewaChin\u00eas (ver)Chin\u00easDinamarqu\u00easAlem\u00e3oEsperantoEst\u00f3nioFinland\u00easFranc\u00easGalegoGregoGujaratiHaitiano (trad)D\u00e4nischDeutschEnglischEsperantoEstnischFinnischFranz\u00f6sischGalizischGeorgischGriechischGujaratiHaitianischHausaHebr\u00e4ischHindiHmongIgboIndonesischIrischIsl\u00e4ndischItalienischJapanischJavanesischJiddischKannadaKasachischKatalanischKhmerKoreanischKroatischLaoLateinishLettischLitauischMalabarischMalagasyMalaysischMaltesischMaoriMarathischMazedonischMongolischNepalesischNiederl\u00e4ndischNorwegischPersischPolnischPortugiesischPunjabiRum\u00e4nischRussischSchwedischSerbischSesothoSinghalesischSlowakischSlowenischSomaliSpanischSuaheliSundanesischTadschikischTagalogTamilTeluguThail\u00e4ndischTschechischT\u00fcrkischUkrainischUngarischUrduUzbekischVietnamesischWalisischWei\u00dfrussischYorubaZulu<\/td>\n<td>\n<div id=\"SL_switch_b\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/switchb.png\") repeat scroll 0% 0%;\" title=\"Troca de idiomas\">&nbsp;<\/div>\n<\/td>\n<td>AfrikaansAlban\u00easArabeArm\u00e9nioAzerbaijanoBascoBengaliBosnianoB\u00falgaroBurm\u00easCebuanoChichewaChin\u00eas (ver)Chin\u00easDinamarqu\u00easIngl\u00easEst\u00f3nioFinland\u00easFinland\u00easGalegoGregoGujaratiHaitiano (trad)D\u00e4nischDeutschEnglischEsperantoEstnischFinnischFranz\u00f6sischGalizischGeorgischGriechischGujaratiHaitianischHausaHebr\u00e4ischHindiHmongIgboIndonesischIrischIsl\u00e4ndischItalienischJapanischJavanesischJiddischKannadaKasachischKatalanischKhmerKoreanischKroatischLaoLateinishLettischLitauischMalabarischMalagasyMalaysischMaltesischMaoriMarathischMazedonischMongolischNepalesischNiederl\u00e4ndischNorwegischPersischPolnischPortugiesischPunjabiRum\u00e4nischRussischSchwedischSerbischSesothoSinghalesischSlowakischSlowenischSomaliSpanischSuaheliSundanesischTadschikischTagalogTamilTeluguThail\u00e4ndischTschechischT\u00fcrkischUkrainischUngarischUrduUzbekischVietnamesischWalisischWei\u00dfrussischYorubaZulu<\/td>\n<td>\n<div id=\"SL_TTS_voice\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/ttsvoice.png\") repeat scroll 0% 0%;\" title=\"Oi\u00e7a\">&nbsp;<\/div>\n<\/td>\n<td>\n<div class=\"SL_copy\" id=\"SL_copy\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/copy.png\") repeat scroll 0% 0%;\" title=\"C\u00f3pia\">&nbsp;<\/div>\n<\/td>\n<td>\n<div id=\"SL_bbl_font_patch\">&nbsp;<\/div>\n<div class=\"SL_bbl_font\" id=\"SL_bbl_font\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/font.png\") repeat scroll 0% 0%;\" title=\"Tamanho de letra\">&nbsp;<\/div>\n<\/td>\n<td>\n<div id=\"SL_bbl_help\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bhelp.png\") repeat scroll 0% 0%;\" title=\"Ajuda\">&nbsp;<\/div>\n<\/td>\n<td>\n<div class=\"SL_pin_off\" id=\"SL_pin\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/pin-on.png\") repeat scroll 0% 0%;\" title=\"Tradutor de pregos pop-up\">&nbsp;<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<div id=\"SL_shadow_translation_result\" style=\"visibility: visible;\">&nbsp;<\/div>\n<div class=\"SL_loading\" id=\"SL_loading\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/loading.gif\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<div id=\"SL_player2\">&nbsp;<\/div>\n<div id=\"SL_alert100\">A fun\u00e7\u00e3o do som \u00e9 limitada a 200 caracteres<\/div>\n<div id=\"SL_Balloon_options\" style=\"background: rgb(255, 255, 255) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bg3.png\") repeat scroll 0% 0%;\">\n<div id=\"SL_arrow_down\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/down.png\") repeat scroll 0% 0%;\">&nbsp;<\/div>\n<table id=\"SL_tbl_opt\" style=\"width:100%\">\n<tbody>\n<tr>\n<td>&nbsp;<\/td>\n<td>\n<div id=\"SL_BBL_IMG\" style=\"background: rgba(0, 0, 0, 0) url(\"moz-extension:\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/img\/util\/bbl-logo.png\") repeat scroll 0% 0%;\" title=\"Mostrar bot\u00e3o inTranslator 3 segundos\">&nbsp;<\/div>\n<\/td>\n<td><a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?bbl\" target=\"_blank\" title=\"Mostrar op\u00e7\u00f5es\" rel=\"noopener\">Op\u00e7\u00f5es<\/a>: <a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?hist\" target=\"_blank\" title=\"Hist\u00f3ria da tradu\u00e7\u00e3o\" rel=\"noopener\">Hist\u00f3rico<\/a>: <a class=\"SL_options\" href=\"\/\/27c8b66b-4e69-a543-b12c-ee19d038addf\/content\/html\/options\/options.html?feed\" target=\"_blank\" title=\"Feedback\" rel=\"noopener\">Feedback<\/a>: <a class=\"SL_options\" href=\"https:\/\/www.paypal.com\/cgi-bin\/webscr?cmd=_s-xclick&amp;hosted_button_id=GD9D8CPW8HFA2\" target=\"_blank\" title=\"Contribua\" rel=\"noopener\">Doa\u00e7\u00e3o<\/a><\/td>\n<td>Fechar<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma r\u00e1pida clarifica\u00e7\u00e3o microbiol\u00f3gica com diagn\u00f3sticos sens\u00edveis e espec\u00edficos \u00e9 importante devido ao aumento da resist\u00eancia aos antibi\u00f3ticos, especialmente com os gonococos. Este artigo de revis\u00e3o fornece conhecimentos sobre aspectos&hellip;<\/p>\n","protected":false},"author":7,"featured_media":72648,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Microbiologia em dermatologia","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11356,11524,11421,11551],"tags":[],"powerkit_post_featured":[],"class_list":["post-338850","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dermatologia-e-venereologia-pt-pt","category-formacao-continua","category-infecciologia","category-rx-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:16:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":338854,"slug":"diagnosticos-modernos-en-tiempos-de-aumento-de-las-enfermedades-de-transmision-sexual","post_title":"Diagn\u00f3sticos modernos en tiempos de aumento de las enfermedades de transmisi\u00f3n sexual","href":"https:\/\/medizinonline.com\/es\/diagnosticos-modernos-en-tiempos-de-aumento-de-las-enfermedades-de-transmision-sexual\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/338850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=338850"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/338850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/72648"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=338850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=338850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=338850"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=338850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}