{"id":340687,"date":"2016-11-02T01:00:00","date_gmt":"2016-11-02T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/uma-rara-anastomose-carotideo-basilar\/"},"modified":"2016-11-02T01:00:00","modified_gmt":"2016-11-02T00:00:00","slug":"uma-rara-anastomose-carotideo-basilar","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/uma-rara-anastomose-carotideo-basilar\/","title":{"rendered":"Uma rara anastomose carot\u00eddeo-basilar"},"content":{"rendered":"<p><strong>As varia\u00e7\u00f5es nas art\u00e9rias cerebrais s\u00e3o geralmente atribu\u00eddas \u00e0 persist\u00eancia ou involu\u00e7\u00e3o excessiva de vasos anastom\u00f3ticos que s\u00e3o fisiol\u00f3gicos para o embri\u00e3o. Na maioria dos casos, estas anastomoses embrion\u00e1rias persistentes permanecem assintom\u00e1ticas e s\u00f3 s\u00e3o detectadas por angiografia ou na aut\u00f3psia. Ocasionalmente podem transportar um aneurisma ou comprimir um nervo craniano. O caso raro de uma art\u00e9ria hipoglossal primitiva persistente \u00e9 documentado abaixo.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><strong>Descri\u00e7\u00e3o do caso:<\/strong> Numa paciente do sexo feminino de 65 anos, foi realizada uma angiografia de RM guiada por KM das art\u00e9rias de alimenta\u00e7\u00e3o cerebral como parte do trabalho para uma estenose do ramo direito da art\u00e9ria car\u00f3tida interna (ACI). Isto mostrou uma grave hipoplasia de ambas as art\u00e9rias vertebrais cervicais. Ao n\u00edvel do HWK1\/2, uma art\u00e9ria de calibre resultante da circunfer\u00eancia dorsal do ACI distal esquerdo era detect\u00e1vel. Este primeiro correu ventralmente de HWK1 at\u00e9 ao craniano e depois atrav\u00e9s de um canal alargado hipoglossi \u00e0 esquerda para o intracraniano para finalmente tomar o curso da art\u00e9ria basilar.&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-7795\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/11\/abb1_np5_s39_0.jpg\" style=\"height:714px; width:800px\" width=\"1100\" height=\"982\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/11\/abb1_np5_s39_0.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/11\/abb1_np5_s39_0-800x714.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/11\/abb1_np5_s39_0-120x107.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/11\/abb1_np5_s39_0-90x80.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/11\/abb1_np5_s39_0-320x286.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/11\/abb1_np5_s39_0-560x500.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Discuss\u00e3o: <\/strong>A causa das anastomoses carot\u00eddeo-basilares \u00e9 a falta de oblitera\u00e7\u00e3o das liga\u00e7\u00f5es vasculares embrion\u00e1rias entre as car\u00f3tidas e as art\u00e9rias neurais emparelhadas a partir das quais as art\u00e9rias vertebro-b\u00e1silares se desenvolvem mais tarde. A art\u00e9ria trig\u00e9mea \u00e9 a anastomose carot\u00eddeo-basilar mais comum, com uma incid\u00eancia de 0,1-1%. As outras anastomoses, a A. acustica primitiva, a A. proatlantica e a A. hypoglossica primitiva aqui mostradas s\u00e3o claramente mais raras. Com excep\u00e7\u00e3o da letra A. proatlantica, a designa\u00e7\u00e3o das anastomoses segue os nervos que elas seguem. O conhecimento destas varia\u00e7\u00f5es anat\u00f3micas \u00e9 de enorme import\u00e2ncia para um correcto trabalho neurovascular.<\/p>\n<p>&nbsp;<\/p>\n<p><em>InFo NEUROLOGIA &amp; PSYCHIATRY 2016; 14(5): 39<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As varia\u00e7\u00f5es nas art\u00e9rias cerebrais s\u00e3o geralmente atribu\u00eddas \u00e0 persist\u00eancia ou involu\u00e7\u00e3o excessiva de vasos anastom\u00f3ticos que s\u00e3o fisiol\u00f3gicos para o embri\u00e3o. Na maioria dos casos, estas anastomoses embrion\u00e1rias persistentes&hellip;<\/p>\n","protected":false},"author":7,"featured_media":60231,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Art\u00e9ria hipoglossal primitiva  ","footnotes":""},"category":[11350,11536,11374,11551],"tags":[32700],"powerkit_post_featured":[],"class_list":["post-340687","post","type-post","status-publish","format-standard","has-post-thumbnail","category-angiologia-pt-pt","category-casos-pt-pt","category-neurologia-pt-pt","category-rx-pt","tag-anastomose-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:42:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":340692,"slug":"una-rara-anastomosis-carotidobasilar","post_title":"Una rara anastomosis carotidobasilar","href":"https:\/\/medizinonline.com\/es\/una-rara-anastomosis-carotidobasilar\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/340687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=340687"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/340687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/60231"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=340687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=340687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=340687"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=340687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}