{"id":341101,"date":"2016-08-09T02:00:00","date_gmt":"2016-08-09T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/estado-da-arte-da-resseccao-endoscopica\/"},"modified":"2016-08-09T02:00:00","modified_gmt":"2016-08-09T00:00:00","slug":"estado-da-arte-da-resseccao-endoscopica","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/estado-da-arte-da-resseccao-endoscopica\/","title":{"rendered":"Estado da arte da ressec\u00e7\u00e3o endosc\u00f3pica"},"content":{"rendered":"<p><strong>Altera\u00e7\u00f5es malignas ou pr\u00e9-malignas da mucosa do tracto gastrointestinal podem geralmente ser removidas endoscopicamente de forma curativa. As ressec\u00e7\u00f5es endosc\u00f3picas s\u00e3o baseadas em muitas inova\u00e7\u00f5es t\u00e9cnicas; as ressec\u00e7\u00f5es s\u00e3o seguras e permitem um diagn\u00f3stico e progn\u00f3stico definitivos. Um grande n\u00famero de interven\u00e7\u00f5es cir\u00fargicas pode ser evitado atrav\u00e9s de ressec\u00e7\u00f5es endosc\u00f3picas. Ao mesmo tempo, a ressec\u00e7\u00e3o endosc\u00f3pica permite uma selec\u00e7\u00e3o muito boa de pacientes que precisam realmente de cirurgia. As ressec\u00e7\u00f5es endosc\u00f3picas s\u00e3o procedimentos raros, pertencem \u00e0 &#8220;medicina altamente especializada&#8221; e devem ser limitadas a poucos especialistas.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Os tumores do tracto gastrointestinal tubular representam uma propor\u00e7\u00e3o substancial de doen\u00e7as malignas. Estes tumores surgem de displasia da superf\u00edcie mucosa em todas as sec\u00e7\u00f5es do tracto digestivo, come\u00e7ando na boca e estendendo-se at\u00e9 ao \u00e2nus. Algumas das displasias s\u00f3 podem ser detectadas histologicamente, mas em muitos casos s\u00e3o tamb\u00e9m vis\u00edveis endoscopicamente, especialmente quando s\u00e3o utilizados equipamentos modernos e m\u00e9todos de colora\u00e7\u00e3o. A abordagem endosc\u00f3pica permite a detec\u00e7\u00e3o precoce e o tratamento local de altera\u00e7\u00f5es malignas e pr\u00e9-malignas. Esta grande vantagem sobre os \u00f3rg\u00e3os s\u00f3lidos pode e deve ser utilizada.<\/p>\n<p>A endoscopia do tracto gastrointestinal mudou de um instrumento de diagn\u00f3stico para um m\u00e9todo com possibilidades terap\u00eauticas muito eficazes. A base para tal foi, por um lado, as tremendas melhorias nas qualidades \u00f3pticas, que foram o pr\u00e9-requisito para a detec\u00e7\u00e3o e demarca\u00e7\u00e3o de les\u00f5es, e, por outro lado, muitos dispositivos adicionais que permitem uma ressec\u00e7\u00e3o segura.<\/p>\n<h2 id=\"as-tecnicas-endoscopicas-de-resseccao\">As t\u00e9cnicas endosc\u00f3picas de ressec\u00e7\u00e3o<\/h2>\n<p>A ressec\u00e7\u00e3o endosc\u00f3pica consiste essencialmente na remo\u00e7\u00e3o de altera\u00e7\u00f5es na mucosa, separando-a na camada submucosa sem causar perfura\u00e7\u00f5es. Isto \u00e9 poss\u00edvel porque o tecido conjuntivo da submucosa permite uma f\u00e1cil separa\u00e7\u00e3o da mucosa da camada muscular, a muscularis propria. D\u00e9cadas atr\u00e1s, as pessoas come\u00e7aram a usar um la\u00e7o el\u00e9ctrico para remover p\u00f3lipos que est\u00e3o confinados \u00e0 mucosa do c\u00f3lon. A t\u00e9cnica foi inicialmente limitada a pequenos p\u00f3lipos, mas agora \u00e1reas de dez ou mais cent\u00edmetros podem ser removidas do es\u00f3fago, est\u00f4mago, c\u00f3lon e recto. A ressec\u00e7\u00e3o da mucosa endosc\u00f3pica foi prolongada pelos chamados procedimentos de ressec\u00e7\u00e3o da mucosa endosc\u00f3pica: ressec\u00e7\u00e3o da mucosa endosc\u00f3pica (EMR) e dissec\u00e7\u00e3o submucosa endosc\u00f3pica (ESD). As ressec\u00e7\u00f5es endosc\u00f3picas de parede completa representam um desenvolvimento adicional.<\/p>\n<p>Em vez de ressec\u00e7\u00e3o, a mucosa alterada pode tamb\u00e9m ser removida por procedimentos ablativos. A mucosa \u00e9 destru\u00edda por meio de energia t\u00e9rmica. Isto pode ser aplicado como energia fotodin\u00e2mica, radiofrequ\u00eancia ou crioterapia. A principal desvantagem \u00e9 que uma histologia completa do tecido n\u00e3o pode ent\u00e3o ser realizada.<\/p>\n<h2 id=\"o-que-pode-e-deve-ser-ressecado-endoscopicamente\">O que pode e deve ser ressecado endoscopicamente?<\/h2>\n<p>A ressec\u00e7\u00e3o endosc\u00f3pica deve ser oferecida para o tratamento de todas as les\u00f5es displ\u00e1sicas da mucosa em todo o tracto gastrointestinal tubular, independentemente de se tratar de displasias de baixo ou alto grau. Os carcinomas pr\u00e9-existentes podem ser ressecados endoscopicamente se estiverem confinados \u00e0 mucosa. Dependendo do \u00f3rg\u00e3o e do tipo de carcinoma, aqueles com invas\u00e3o na submucosa tamb\u00e9m podem ser correctamente removidos oncologicamente por endoscopia <strong>(tab.&nbsp;1)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-7514\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/08\/tab1_oh4_s27.png\" style=\"height:922px; width:800px\" width=\"1100\" height=\"1268\"><\/p>\n<p>\nOs carcinomas penetrantes mais profundos requerem normalmente uma ressec\u00e7\u00e3o cir\u00fargica oncologicamente correcta com remo\u00e7\u00e3o dos g\u00e2nglios linf\u00e1ticos regionais, uma vez que o seu envolvimento aumenta em frequ\u00eancia proporcionalmente com a profundidade de penetra\u00e7\u00e3o. Com a nova ressec\u00e7\u00e3o de parede completa dispon\u00edvel, mesmo os carcinomas de grau mais elevado poderiam ser completamente removidos. Contudo, devido \u00e0 falta de remo\u00e7\u00e3o de g\u00e2nglios linf\u00e1ticos, esta \u00e9 apenas uma op\u00e7\u00e3o para os pacientes em que uma ressec\u00e7\u00e3o cir\u00fargica correcta \u00e9 demasiado arriscada. Nestes pacientes, contudo, o m\u00e9todo \u00e9 uma t\u00e9cnica minimamente invasiva muito atractiva.<\/p>\n<p>As t\u00e9cnicas de ressec\u00e7\u00e3o da mucosa foram desenvolvidas para carcinomas precoces que se estendem apenas ligeiramente para al\u00e9m da superf\u00edcie da mucosa em termos de espessura. No entanto, especialmente no c\u00f3lon, os primeiros carcinomas podem ser escondidos em p\u00f3lipos por vezes muito volumosos. A ressec\u00e7\u00e3o endosc\u00f3pica destes p\u00f3lipos era anteriormente limitada pelo seu tamanho. Em particular, os riscos de hemorragia e perfura\u00e7\u00e3o limitaram a ressec\u00e7\u00e3o endosc\u00f3pica. T\u00e9cnicas mais recentes permitem agora a preven\u00e7\u00e3o da perfura\u00e7\u00e3o e hemorragia, de modo a que mesmo p\u00f3lipos col\u00f3nicos muito grandes possam ser ressecados em seguran\u00e7a.<\/p>\n<p>Exemplos de ressec\u00e7\u00f5es em diferentes sec\u00e7\u00f5es do tracto gastrointestinal s\u00e3o mostrados nas <strong>Figuras 1 e 2<\/strong>.<br \/>\n&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-7515 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/08\/abb1_oh4_s27.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/366;height:266px; width:800px\" width=\"1100\" height=\"366\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<h2 id=\"\"><img decoding=\"async\" class=\"size-full wp-image-7516 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/08\/abb2_oh4_s28.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/365;height:265px; width:800px\" width=\"1100\" height=\"365\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-2\">&nbsp;<\/h2>\n<h2 id=\"vantagens-e-riscos-da-resseccao-endoscopica-de-tumores\">Vantagens e riscos da ressec\u00e7\u00e3o endosc\u00f3pica de tumores<\/h2>\n<p>A vantagem mais importante da ressec\u00e7\u00e3o endosc\u00f3pica \u00e9, evidentemente, que evita uma terapia cir\u00fargica muito mais invasiva e dispendiosa. No entanto, a fase exacta da displasia ou do suposto carcinoma precoce n\u00e3o \u00e9 normalmente conhecida antes do procedimento. Apenas uma ressec\u00e7\u00e3o endosc\u00f3pica completa de uma patologia luminal permite a classifica\u00e7\u00e3o histol\u00f3gica correcta. Assim, al\u00e9m de uma poss\u00edvel cura completa, a ressec\u00e7\u00e3o endosc\u00f3pica permite acima de tudo um diagn\u00f3stico preciso. Em muitos casos, isto rev\u00ea o diagn\u00f3stico bi\u00f3ptico anterior, geralmente para cima. Por exemplo, sabe-se pelas ressec\u00e7\u00f5es endosc\u00f3picas de displasia de alto grau do es\u00f3fago de Barrett, que s\u00e3o agora realizadas rotineiramente, que ap\u00f3s uma ressec\u00e7\u00e3o endosc\u00f3pica em at\u00e9 30% dos casos j\u00e1 existia de facto um carcinoma anteriormente desconhecido. O estadiamento histol\u00f3gico correcto ap\u00f3s ressec\u00e7\u00e3o endosc\u00f3pica permite assim decidir se j\u00e1 foi dado tratamento oncol\u00f3gico suficiente ou se \u00e9 necess\u00e1ria uma terapia cir\u00fargica, quimioterapia ou radioterapia adicional.<\/p>\n<p>O principal risco de ressec\u00e7\u00e3o endosc\u00f3pica \u00e9 a perfura\u00e7\u00e3o durante ou ap\u00f3s o procedimento. Uma perfura\u00e7\u00e3o converte, pelo menos formalmente, um carcinoma anteriormente confinado ao l\u00famen num carcinoma T4. Em alguns casos, isto leva a um acompanhamento terap\u00eautico desnecessariamente agressivo. No entanto, deve dizer-se que h\u00e1 muito poucos dados para provar uma deteriora\u00e7\u00e3o relevante no progn\u00f3stico nestes casos. Teoricamente, tamb\u00e9m se poderia supor que a manipula\u00e7\u00e3o mec\u00e2nica de um carcinoma &#8211; algo que os cirurgi\u00f5es evitam a todo o custo &#8211; leva a met\u00e1stases mais elevadas. De acordo com&nbsp; a grande quantidade de dados de p\u00f3lipos de c\u00f3lon ressecados endoscopicamente, no entanto, este n\u00e3o parece ser o caso. No entanto, a preven\u00e7\u00e3o da perfura\u00e7\u00e3o deve ser um objectivo muito importante do gastroenterologista endoscopicamente activo. Caso ocorra uma perfura\u00e7\u00e3o, ele deve ser capaz de a gerir endoscopicamente.<\/p>\n<h2 id=\"quem-deve-realizar-resseccoes-endoscopicas\">Quem deve realizar ressec\u00e7\u00f5es endosc\u00f3picas?<\/h2>\n<p>As ressec\u00e7\u00f5es endosc\u00f3picas da mucosa s\u00e3o procedimentos raros. Dizem respeito a tumores como o carcinoma de es\u00f3fago, cujo tratamento pelos cirurgi\u00f5es est\u00e1 agora felizmente limitado pelos regulamentos da medicina altamente especializada a alguns centros com n\u00fameros de casos suficientemente elevados. O curr\u00edculo do gastroenterologista n\u00e3o inclui forma\u00e7\u00e3o em t\u00e9cnicas de ressec\u00e7\u00e3o endosc\u00f3pica. No entanto, est\u00e1 a ser desenvolvido um regulamento de forma\u00e7\u00e3o para gastroenterologistas intervencionistas. \u00c0 semelhan\u00e7a das interven\u00e7\u00f5es cir\u00fargicas, o sucesso na endoscopia \u00e9 tamb\u00e9m definido pelo n\u00famero de casos. Enquanto n\u00e3o existir uma regulamenta\u00e7\u00e3o oficial, \u00e9 da responsabilidade dos m\u00e9dicos encaminhadores apoiar uma limita\u00e7\u00e3o a alguns centros.<\/p>\n<h2 id=\"resultados-a-longo-prazo-da-resseccao-endoscopica-de-tumores\">Resultados a longo prazo da ressec\u00e7\u00e3o endosc\u00f3pica de tumores<\/h2>\n<p>Para nenhum dos primeiros carcinomas intestinais existem estudos aleat\u00f3rios que comparem a terapia cir\u00fargica com a endosc\u00f3pica. Fazendo compara\u00e7\u00f5es hist\u00f3ricas, a sobreviv\u00eancia sem tumores parece ser equivalente com ambos os m\u00e9todos. A vantagem da endoscopia \u00e9 a mortalidade e morbilidade p\u00f3s-operat\u00f3ria significativamente mais baixa. Tamb\u00e9m n\u00e3o \u00e9 prov\u00e1vel que no futuro sejam realizados estudos aleat\u00f3rios, uma vez que os m\u00e9todos endosc\u00f3picos est\u00e3o a tornar-se cada vez mais populares. Al\u00e9m disso, existe uma grande disparidade entre cirurgia e endoscopia em termos do grau de invasividade; pode ser dif\u00edcil aleatorizar os pacientes. A ressec\u00e7\u00e3o endosc\u00f3pica tamb\u00e9m deve ser vista como o primeiro passo antes da cirurgia, se necess\u00e1rio. Por conseguinte, uma coopera\u00e7\u00e3o estreita e harmoniosa entre as duas disciplinas altamente especializadas \u00e9 desej\u00e1vel para o melhor cuidado destes pacientes.<\/p>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGy &amp; HEMATOLOGy 2016; 4(4): 26-28<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Altera\u00e7\u00f5es malignas ou pr\u00e9-malignas da mucosa do tracto gastrointestinal podem geralmente ser removidas endoscopicamente de forma curativa. As ressec\u00e7\u00f5es endosc\u00f3picas s\u00e3o baseadas em muitas inova\u00e7\u00f5es t\u00e9cnicas; as ressec\u00e7\u00f5es s\u00e3o seguras&hellip;<\/p>\n","protected":false},"author":7,"featured_media":58150,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Tumores gastrintestinais","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11390,11524,11407,11379,11551],"tags":[31981,41444,41456,15826,41449,39376,41440,26645],"powerkit_post_featured":[],"class_list":["post-341101","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cirurgia","category-formacao-continua","category-gastroenterologia-e-hepatologia","category-oncologia-pt-pt","category-rx-pt","tag-adenoma-pt-pt","tag-colon-pt-pt","tag-emr-displasias","tag-endoscopia-pt-pt","tag-esd-pt-pt","tag-net-pt-pt","tag-rectum","tag-resseccao","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:28:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":341162,"slug":"estado-del-arte-de-la-reseccion-endoscopica","post_title":"Estado del arte de la resecci\u00f3n endosc\u00f3pica","href":"https:\/\/medizinonline.com\/es\/estado-del-arte-de-la-reseccion-endoscopica\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/341101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=341101"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/341101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/58150"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=341101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=341101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=341101"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=341101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}