{"id":342691,"date":"2015-09-29T02:00:00","date_gmt":"2015-09-29T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/o-apoio-central-de-uma-pessoa-de-referencia-e-util\/"},"modified":"2015-09-29T02:00:00","modified_gmt":"2015-09-29T00:00:00","slug":"o-apoio-central-de-uma-pessoa-de-referencia-e-util","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/o-apoio-central-de-uma-pessoa-de-referencia-e-util\/","title":{"rendered":"O apoio central de uma pessoa de refer\u00eancia \u00e9 \u00fatil"},"content":{"rendered":"<p><strong>No tratamento de toxicodependentes com doen\u00e7as som\u00e1ticas, a quest\u00e3o \u00e9 muitas vezes qual o profissional m\u00e9dico que deve assumir que tarefas. Em princ\u00edpio, a resposta \u00e9: cada um faz o que pode. No entanto, o cl\u00ednico geral tem um papel muito central, uma vez que os pacientes muitas vezes n\u00e3o mant\u00eam consultas com especialistas e os procedimentos programados n\u00e3o podem ser realizados como resultado. Se poss\u00edvel, deve haver uma pessoa central de refer\u00eancia que se encarregue de tudo. O curso cl\u00ednico \u00e9 muitas vezes mais importante do que o pr\u00f3prio diagn\u00f3stico. O reconhecimento das &#8220;bandeiras vermelhas&#8221; e de uma estrat\u00e9gia prudente de vigil\u00e2ncia s\u00e3o de import\u00e2ncia central neste caso. Cuidado e conten\u00e7\u00e3o na retirada do opi\u00e1ceo: a falta de toler\u00e2ncia e o sono conduzem rapidamente \u00e0 morte em caso de reca\u00edda.  <\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>A toxicodepend\u00eancia \u00e9 frequentemente acompanhada por doen\u00e7as som\u00e1ticas<strong> (Quadro 1) <\/strong>. A maioria dos quadros cl\u00ednicos tamb\u00e9m nos s\u00e3o conhecidos de pacientes n\u00e3o-drogados. Contudo, a doen\u00e7a da depend\u00eancia e muitas vezes tamb\u00e9m comorbidades psicol\u00f3gicas colocam desafios especiais, e muitas vezes \u00e9 preciso desviar-se do caminho diagn\u00f3stico-terap\u00eautico habitual para se ser bem sucedido.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-6138\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/tab1_np5_s5.png\" style=\"height:441px; width:400px\" width=\"1100\" height=\"1214\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/tab1_np5_s5.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/tab1_np5_s5-800x883.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/tab1_np5_s5-120x132.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/tab1_np5_s5-90x99.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/tab1_np5_s5-320x353.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/tab1_np5_s5-560x618.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>O mais importante \u00e9 certamente que um paciente com um problema som\u00e1tico grave venha a receber ajuda m\u00e9dica. N\u00e3o \u00e9 raro que os pacientes drogados se afastem do consult\u00f3rio e prefiram apresentar-nos os resultados ou sintomas j\u00e1 \u00e0 porta. Uma triagem inicial com o objectivo de identificar &#8220;bandeiras vermelhas&#8221; deve, portanto, ser efectuada o mais rapidamente poss\u00edvel e com limiares baixos. Quando se refere ao procedimento normal com uma consulta, os diagn\u00f3sticos importantes s\u00e3o muitas vezes perdidos ou feitos demasiado tarde (por exemplo, espondilodiscite) porque os doentes n\u00e3o v\u00eam.<\/p>\n<h2 id=\"padroes-de-doencas-quando-e-que-faz-sentido-envolver-especialistas\">Padr\u00f5es de doen\u00e7as &#8211; Quando \u00e9 que faz sentido envolver especialistas?<\/h2>\n<p>Os quadros cl\u00ednicos s\u00e3o muito diversos e a multimorbilidade \u00e9 a regra. A quest\u00e3o &#8220;Quem faz o qu\u00ea?&#8221; \u00e9 particularmente premente aqui. O envolvimento de especialistas leva frequentemente a experi\u00eancias frustrantes de todos os lados, uma vez que os prazos e o procedimento proposto n\u00e3o podem ser cumpridos. Na pr\u00e1tica, \u00e9 melhor se o paciente tiver uma pessoa de refer\u00eancia que se encarregue de todos os problemas.<\/p>\n<p>Nesta situa\u00e7\u00e3o \u00e9 particularmente importante que o pr\u00f3prio m\u00e9dico de cl\u00ednica geral se torne &#8220;especialista&#8221; nos quadros cl\u00ednicos apresentados pelo paciente o mais rapidamente poss\u00edvel e tente desenvolver um procedimento adaptado \u00e0s necessidades e possibilidades. As compet\u00eancias de trabalho social e a sua aplica\u00e7\u00e3o s\u00e3o tamb\u00e9m importantes.<\/p>\n<p>A pergunta &#8220;Quem faz o qu\u00ea?&#8221; pode, portanto, ser respondida com &#8220;Todos fazem o que podem&#8221;. \u00c9 importante que a quest\u00e3o da &#8220;capacidade&#8221; n\u00e3o seja respondida por um certificado de capacidade, mas sim pela pergunta. Por exemplo, o exame por ultra-sons requer muita per\u00edcia na quest\u00e3o das malforma\u00e7\u00f5es fetais. Numa mulher com doen\u00e7a hep\u00e1tica que se queixa de uma barriga gorda s\u00fabita, o diagn\u00f3stico diferencial de ascite, gravidez, barriga gorda tamb\u00e9m pode ser decidido com um aparelho antigo e por algu\u00e9m com pouca experi\u00eancia. Tamb\u00e9m n\u00e3o \u00e9 necess\u00e1rio um cardiologista para medir o tempo QTc num doente com metadona com s\u00edncope question\u00e1vel.<\/p>\n<p>Ao contr\u00e1rio de uma clarifica\u00e7\u00e3o policl\u00ednica, muitas vezes n\u00e3o temos de fazer um diagn\u00f3stico, mas simplesmente n\u00e3o podemos perder nada de grave. Com uma estrat\u00e9gia de espera vigilante, podemos esperar pelo curso espont\u00e2neo mais favor\u00e1vel dos acontecimentos. Desta forma, pode poupar-se a muitos exames. \u00c9 importante conhecer bem o paciente e ter uma rela\u00e7\u00e3o de confian\u00e7a. A dist\u00e2ncia apropriada na rela\u00e7\u00e3o \u00e9 igualmente central. Mesmo que normalmente seja melhor manter o &#8220;voc\u00ea&#8221;, pode desenvolver-se uma boa rela\u00e7\u00e3o de respeito.<\/p>\n<p>Especialmente em Espera Vigilante, a acessibilidade \u00e9 central. As fotografias enviadas por smartphone tamb\u00e9m ajudam frequentemente. Se um paciente tiver aterrado numa cl\u00ednica como emerg\u00eancia, chamadas telef\u00f3nicas curtas com o m\u00e9dico da cl\u00ednica s\u00e3o muito \u00fateis, especialmente para problemas complexos. Na minha experi\u00eancia, a rendi\u00e7\u00e3o do n\u00famero de telem\u00f3vel privado quase nunca \u00e9 mal utilizada.<\/p>\n<p>Embora as perturba\u00e7\u00f5es viciantes sejam efectivamente classificadas como doen\u00e7as mentais, os doentes toxicodependentes s\u00f3 s\u00e3o tratados de forma limitada por psiquiatras que trabalham em regime ambulat\u00f3rio e s\u00e3o na sua maioria tratados por cl\u00ednicos gerais ou, nas cidades, por centros especializados. Pequenas conversas regulares &#8211; por exemplo, por ocasi\u00e3o da distribui\u00e7\u00e3o pessoal de medicamentos de substitui\u00e7\u00e3o &#8211; s\u00e3o \u00fateis e os problemas psicol\u00f3gicos ou som\u00e1ticos podem ser detectados numa fase precoce.<\/p>\n<h2 id=\"vih-e-hepatite\">VIH e hepatite<\/h2>\n<p>O tratamento do VIH e da hepatite fez enormes progressos nas \u00faltimas d\u00e9cadas e tornou-se muito mais f\u00e1cil. Em particular, a continua\u00e7\u00e3o de uma terapia de VIH estabelecida pode ser bem gerida por um cl\u00ednico geral experiente. O mais importante \u00e9 que o paciente tenha acesso \u00e0 terapia em primeiro lugar e a tome.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6139 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb1-2_np5_s5.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/401;height:219px; width:600px\" width=\"1100\" height=\"401\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb1-2_np5_s5.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb1-2_np5_s5-800x292.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb1-2_np5_s5-120x44.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb1-2_np5_s5-90x33.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb1-2_np5_s5-320x117.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb1-2_np5_s5-560x204.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>Devido aos elevados custos, o tratamento da infec\u00e7\u00e3o pelo HCV \u00e9 actualmente mais um problema de pol\u00edtica de sa\u00fade do que um problema m\u00e9dico. Uma vez que os custos dos medicamentos &#8211; semelhantes aos do software &#8211; s\u00e3o em grande parte relacionados com o desenvolvimento e n\u00e3o com a produ\u00e7\u00e3o, as abordagens de tratamento de todos os HCV RNA-positivos versus apenas os que correm o risco de cirrose seriam teoricamente igualmente dispendiosos. O tratamento de todos os indiv\u00edduos positivos ao HCV-RNA teria benef\u00edcios epidemiol\u00f3gicos. Os novos medicamentos s\u00e3o t\u00e3o eficazes, convenientes de tomar e t\u00eam poucos efeitos secund\u00e1rios que o tratamento quase n\u00e3o necessita de conhecimentos especiais em compara\u00e7\u00e3o com as anteriores terapias baseadas no interfer\u00e3o.<\/p>\n<h2 id=\"abcesso-de-seringas\">Abcesso de seringas<\/h2>\n<p>No caso de abscesso de seringa <strong>(Fig. 2) <\/strong>, o momento correcto da incis\u00e3o da pun\u00e7\u00e3o \u00e9 muito importante. A flutua\u00e7\u00e3o j\u00e1 deve ser palp\u00e1vel, mas a pele sobre ela ainda n\u00e3o deve ser t\u00e3o dilu\u00edda que mais tarde se desenvolva at\u00e9 se tornar uma \u00falcera. Uma pequena incis\u00e3o com inser\u00e7\u00e3o de uma m\u00e8che ap\u00f3s a aplica\u00e7\u00e3o de spray frio \u00e9 normalmente suficiente. A administra\u00e7\u00e3o pr\u00e9via de antibi\u00f3ticos (geralmente co-amoxicilina 2\u00d7 1 g) deve ser considerada especialmente em casos de febre e processos difusos de catarro.<\/p>\n<h2 id=\"endocardite\">Endocardite<\/h2>\n<p>A endocardite do cora\u00e7\u00e3o direito deve ser considerada especialmente no abuso da coca\u00edna por via intravenosa. A redu\u00e7\u00e3o do estado geral, febre s\u00e9ptica, CRP\/leucose elevada e poss\u00edveis novos sopros card\u00edacos s\u00e3o indicativos. Contudo, n\u00e3o \u00e9 raro que a endocardite seja descoberta apenas pelo aparecimento de met\u00e1stases s\u00e9pticas na radiografia do t\u00f3rax. O risco de reca\u00edda de endocardite \u00e9 muito elevado no caso de endocardite anamn\u00e9stica. A dificuldade \u00e9 muitas vezes o tratamento adequado \u00e0 resist\u00eancia ao longo do tempo sugerido pelos infectologistas. As interac\u00e7\u00f5es com a substitui\u00e7\u00e3o (por exemplo, <sup>Rimactan\u00ae<\/sup> &#8211; metadona) devem ser vigiadas e a dose ajustada.<\/p>\n<h2 id=\"osteomielite\">Osteomielite<\/h2>\n<p>A gonartrite s\u00e9ptica purulenta geralmente n\u00e3o oferece dificuldades de diagn\u00f3stico devido \u00e0 tr\u00edade cl\u00e1ssica do rubor-calor-calor. A coxite j\u00e1 \u00e9 mais discreta e a dor na virilha \u00e9 por vezes enganadora. T\u00edpica \u00e9 a dor do choque axial quando se bate na sola do p\u00e9.<\/p>\n<p>A espondilodiscite <strong>(Fig. 3)<\/strong> permanece frequentemente oligossintom\u00e1tica durante muito tempo e \u00e9 por vezes dif\u00edcil de distinguir de lumbago. O desejo cr\u00f3nico de analg\u00e9sicos, a dol\u00eancia local de press\u00e3o e o CRP elevado s\u00e3o indicativos.<\/p>\n<h2 id=\"pneumonia\">Pneumonia<\/h2>\n<p>Pneumonia \u00e9 bastante comum (bronquite cr\u00f3nica, vestu\u00e1rio n\u00e3o sazonal, intoxicado por a\u00ed). Febre superior a 38 graus, bem como dores no peito e mau estado geral conduzem ao diagn\u00f3stico. Muitas vezes a pneumonia pode ser tratada em regime ambulat\u00f3rio ou o tratamento hospitalar \u00e9 recusado &#8211; por exemplo, por causa de animais de estima\u00e7\u00e3o. Um raio-X pode, evidentemente, ser \u00fatil, mas por v\u00e1rias raz\u00f5es nem sempre \u00e9 vi\u00e1vel. Durante a terapia antibi\u00f3tica &#8211; especialmente com azitromicina &#8211; deve prestar-se aten\u00e7\u00e3o ao tempo de QTc, pois este j\u00e1 \u00e9 muitas vezes muito aumentado antes do in\u00edcio da terapia (por exemplo, com metadona mais <sup>Quetiapina\u00ae<\/sup>).<\/p>\n<h2 id=\"doencas-da-civilizacao\">Doen\u00e7as da civiliza\u00e7\u00e3o<\/h2>\n<p>Com a idade m\u00e9dia dos doentes com f\u00e1rmacos que felizmente aumentaram fortemente nas \u00faltimas d\u00e9cadas, a preval\u00eancia de &#8220;doen\u00e7as da civiliza\u00e7\u00e3o&#8221; comuns tamb\u00e9m aumentou fortemente.<\/p>\n<p>O ganho de peso com s\u00edndrome metab\u00f3lica \u00e9 comum. As causas contributivas s\u00e3o as drogas psicotr\u00f3picas e a falta de exerc\u00edcio. Devido ao &#8211; quase obrigat\u00f3rio &#8211; uso de tabaco a longo prazo, COPD e, especialmente em mulheres dependentes de hero\u00edna devido \u00e0 amenorreia induzida pela hero\u00edna, a osteoporose \u00e9 frequentemente adicionada. \u00c9 praticamente imposs\u00edvel seguir todas as recomenda\u00e7\u00f5es m\u00e9dicas e outras recomenda\u00e7\u00f5es das sociedades profissionais, mesmo para pacientes psicologicamente robustos.<\/p>\n<p>O principal perigo \u00e9 a polipragmasia da droga, quando uma nova droga \u00e9 acrescentada para cada novo sintoma que ocorre (muitas vezes efeitos secund\u00e1rios da droga!). Por conseguinte, \u00e9 importante identificar e abordar os principais factores de risco e verificar se o paciente tamb\u00e9m \u00e9 capaz de tomar todos os medicamentos. Muitas vezes, um &#8220;reset de drogas&#8221; com &#8220;f\u00e9rias da droga&#8221; tamb\u00e9m \u00e9 \u00fatil em situa\u00e7\u00f5es confusas.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6140 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb3-4_np5_s6.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/441;height:241px; width:600px\" width=\"1100\" height=\"441\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb3-4_np5_s6.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb3-4_np5_s6-800x321.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb3-4_np5_s6-120x48.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb3-4_np5_s6-90x36.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb3-4_np5_s6-320x128.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/09\/abb3-4_np5_s6-560x225.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<h2 id=\"intoxicacoes\">Intoxica\u00e7\u00f5es<\/h2>\n<p>Felizmente, o n\u00famero de &#8220;mortes por drogas&#8221; cl\u00e1ssicas devido a intoxica\u00e7\u00f5es agudas por opi\u00e1ceos diminuiu consideravelmente nas \u00faltimas d\u00e9cadas com o uso generalizado de terapias de substitui\u00e7\u00e3o. No entanto, a intoxica\u00e7\u00e3o opi\u00e1cea aguda \u00e9 ainda a intoxica\u00e7\u00e3o fatal mais comum. O tempo ap\u00f3s a retirada do opi\u00e1ceo \u00e9 muito cr\u00edtico na aus\u00eancia de toler\u00e2ncia, raz\u00e3o pela qual s\u00f3 se recomenda a sua retirada muito lentamente, se \u00e9 que \u00e9 de todo. A morte de uma reca\u00edda opi\u00e1cea ocorre frequentemente de forma insidiosa durante o sono.<\/p>\n<h2 id=\"violencia\">Viol\u00eancia<\/h2>\n<p>A viol\u00eancia \u00e9 infelizmente um fen\u00f3meno de acompanhamento frequente com situa\u00e7\u00f5es complexas de v\u00edtima-perpetrador. A acusa\u00e7\u00e3o \u00e9 frequentemente complicada por problemas socioculturais e amn\u00e9sticos, por exemplo, no caso de abuso de midazolam <strong>(fig. 4)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><em>InFo NEUROLOGIA &amp; PSYCHIATRY 2015, 13(5): 4-7<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No tratamento de toxicodependentes com doen\u00e7as som\u00e1ticas, a quest\u00e3o \u00e9 muitas vezes qual o profissional m\u00e9dico que deve assumir que tarefas. Em princ\u00edpio, a resposta \u00e9: cada um faz o&hellip;<\/p>\n","protected":false},"author":7,"featured_media":52583,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Doen\u00e7as som\u00e1ticas na toxicodepend\u00eancia","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11524,11305,11474,11481,11551],"tags":[45008,45018,16441,45030,15818,40072,31487,15101,30198,19075,45033,45004,45025,22539,18456,16979],"powerkit_post_featured":[],"class_list":["post-342691","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacao-continua","category-medicina-interna-geral","category-prevencao-e-cuidados-de-saude","category-psiquiatria-e-psicoterapia","category-rx-pt","tag-cocaina","tag-drogas","tag-endocardite-pt-pt","tag-farejar","tag-hepatite-pt-pt","tag-opiate-pt-pt","tag-piolhos","tag-pneumonia-pt-pt","tag-pulgas","tag-sarna-pt-pt","tag-seringas","tag-somatic","tag-traumatismos-recentes","tag-vicio","tag-vih-pt-pt","tag-violencia","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:59:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":342706,"slug":"el-apoyo-central-de-una-persona-de-referencia-es-util","post_title":"El apoyo central de una persona de referencia es \u00fatil","href":"https:\/\/medizinonline.com\/es\/el-apoyo-central-de-una-persona-de-referencia-es-util\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/342691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=342691"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/342691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/52583"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=342691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=342691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=342691"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=342691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}