{"id":343477,"date":"2015-04-17T02:00:00","date_gmt":"2015-04-17T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/combater-a-epidemia-com-novos-conhecimentos\/"},"modified":"2015-04-17T02:00:00","modified_gmt":"2015-04-17T00:00:00","slug":"combater-a-epidemia-com-novos-conhecimentos","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/combater-a-epidemia-com-novos-conhecimentos\/","title":{"rendered":"Combater a epidemia com novos conhecimentos"},"content":{"rendered":"<p><strong>Morrem mais pessoas devido \u00e0s consequ\u00eancias da hepatite C do que devido ao VIH. Metade das pessoas afectadas pela hepatite C n\u00e3o t\u00eam conhecimento da sua infec\u00e7\u00e3o. As pessoas nascidas na d\u00e9cada de 1960 t\u00eam um risco acrescido de hepatite C. A hepatite C pode ser curada em mais de 90% dos casos com combina\u00e7\u00f5es modernas de tratamento sem interfer\u00e3o, mas existem profundas preocupa\u00e7\u00f5es m\u00e9dicas e \u00e9ticas devido ao pre\u00e7o e \u00e0s limita\u00e7\u00f5es de utiliza\u00e7\u00e3o.  <\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Na Su\u00ed\u00e7a, estima-se que 60.000-80.000 pessoas tenham hepatite C cr\u00f3nica, das quais apenas metade foi testada, e menos de 10% foram tratadas at\u00e9 \u00e0 data [1,2]. A infec\u00e7\u00e3o ocorre atrav\u00e9s do contacto de sangue com o sangue. Transfus\u00f5es de sangue, procedimentos m\u00e9dicos invasivos, hemodi\u00e1lise e uso de drogas i.v. s\u00e3o as principais vias de transmiss\u00e3o, embora as tr\u00eas primeiras se tenham tornado raras gra\u00e7as \u00e0 an\u00e1lise de rotina de produtos sangu\u00edneos e aos elevados padr\u00f5es de higiene m\u00e9dica actuais. As tatuagens e piercings em condi\u00e7\u00f5es de higiene inadequadas, bem como a partilha de tubos quando se cheira drogas, s\u00e3o outras vias poss\u00edveis de infec\u00e7\u00e3o. 70-80% das infec\u00e7\u00f5es s\u00e3o cr\u00f3nicas, e cerca de um ter\u00e7o das infec\u00e7\u00f5es cr\u00f3nicas desenvolvem-se em cirrose ou cancro do f\u00edgado ao longo dos anos [3]. A hepatite C (HCV) \u00e9 uma doen\u00e7a infecciosa sist\u00e9mica, todos os \u00f3rg\u00e3os podem ser afectados. Manifesta\u00e7\u00f5es extra-hep\u00e1ticas n\u00e3o-espec\u00edficas como fadiga, dist\u00farbios de concentra\u00e7\u00e3o e apatia s\u00e3o comuns e n\u00e3o s\u00e3o raramente identificadas pelos pacientes como associadas ao HCV apenas depois de curadas.<\/p>\n<p>A hepatite C \u00e9 chamada &#8220;doen\u00e7a silenciosa&#8221; n\u00e3o s\u00f3 devido \u00e0 frequente aus\u00eancia de sintomas espec\u00edficos, mas tamb\u00e9m devido \u00e0 falta de consci\u00eancia e conhecimento tanto a n\u00edvel m\u00e9dico e de pol\u00edtica de sa\u00fade como a n\u00edvel da popula\u00e7\u00e3o em geral. Isto apesar de as infec\u00e7\u00f5es cr\u00f3nicas por hepatite C serem um problema de sa\u00fade p\u00fablica relevante. Actualmente, morrem mais pessoas na Su\u00ed\u00e7a devido \u00e0s consequ\u00eancias da hepatite viral do que devido ao VIH. A hepatite C \u00e9 a principal causa de transplante hep\u00e1tico. As an\u00e1lises do modelo matem\u00e1tico prev\u00eaem um aumento das doen\u00e7as hep\u00e1ticas secund\u00e1rias induzidas pela hepatite C com as correspondentes consequ\u00eancias individuais, sociais e econ\u00f3micas se os n\u00fameros de incid\u00eancia do HCV permanecerem constantes ou diminu\u00edrem [4].<\/p>\n<h2 id=\"transaminases-insuficientes-para-o-rastreio-do-hcv\">Transaminases insuficientes para o rastreio do HCV<\/h2>\n<p>O teste de despistagem da hepatite C \u00e9 feito com a detec\u00e7\u00e3o de anticorpos contra o HCV. No caso de um resultado positivo, uma replica\u00e7\u00e3o viral activa como express\u00e3o da hepatite C cr\u00f3nica, bem como o gen\u00f3tipo, s\u00e3o determinados por meio da determina\u00e7\u00e3o do ARN do VHC. A determina\u00e7\u00e3o da transaminase como marcador da hepatite C n\u00e3o \u00e9 recomendada. At\u00e9 um ter\u00e7o dos doentes com hepatite C com transaminases normais apresentam fibrose hep\u00e1tica relevante ou mesmo cirrose [5,6].<\/p>\n<h2 id=\"teste-vintage-como-um-novo-factor-de-risco\">Teste: Vintage como um &#8220;novo factor de risco<\/h2>\n<p>A fim de contrariar o elevado n\u00famero de infec\u00e7\u00f5es de HCV n\u00e3o detectadas, s\u00e3o necess\u00e1rios testes de risco estratificados mais consistentes [7]. Novas descobertas relativas a factores de risco adicionais podem ser \u00fateis aqui.<\/p>\n<p>As pessoas nascidas entre 1955 e 1974 constituem 60% da popula\u00e7\u00e3o su\u00ed\u00e7a com hepatite C, mas apenas 30% da popula\u00e7\u00e3o total [8]. As pessoas nascidas em meados da d\u00e9cada de 1960 t\u00eam uma probabilidade triplicada de serem infectadas com hepatite C. Por conseguinte, deve ser dada especial aten\u00e7\u00e3o a estas colheitas.<\/p>\n<p>Os imigrantes de pa\u00edses de alta preval\u00eancia formam uma propor\u00e7\u00e3o relevante da popula\u00e7\u00e3o com hepatite C na Su\u00ed\u00e7a. No sul de It\u00e1lia, por exemplo, a preval\u00eancia de anticorpos contra o HCV \u00e9 de at\u00e9 30% entre as pessoas com mais de 60 anos de idade. Isto deve-se a seringas de vidro reutilizadas e procedimentos dent\u00e1rios nos anos 70 [9].<\/p>\n<p>Estes resultados devem ser tidos em conta na pr\u00e1tica ao considerar um teste de hepatite C.<\/p>\n<h2 id=\"novas-terapias\">Novas terapias<\/h2>\n<p>A terapia para a hepatite C est\u00e1 actualmente a sofrer uma revolu\u00e7\u00e3o. A terapia do HCV baseada em interfer\u00f5es \u00e9, em grande parte, uma coisa do passado. Estes s\u00e3o substitu\u00eddos por terapias combinadas com antivirais de ac\u00e7\u00e3o directa (DAA) com ou sem a adi\u00e7\u00e3o de ribavirina, que \u00e9 conhecida das terapias baseadas em Interfon. Com estes novos medicamentos para a hepatite C, foi dado um salto qu\u00e2ntico neste campo da medicina num espa\u00e7o de tempo muito curto. Com as novas combina\u00e7\u00f5es DAA, n\u00e3o s\u00f3 ser\u00e1 alcan\u00e7ada uma efici\u00eancia sem precedentes na terapia do HCV, mas ao mesmo tempo a seguran\u00e7a e tolerabilidade da terapia ser\u00e1 significativamente aumentada, o modo de administra\u00e7\u00e3o simplificado e a dura\u00e7\u00e3o da terapia reduzida.<\/p>\n<p>A soma dos desenvolvimentos e melhorias na medica\u00e7\u00e3o significa que as novas terapias de HCV ter\u00e3o um impacto relevante n\u00e3o s\u00f3 sobre o indiv\u00edduo afectado, mas tamb\u00e9m sobre a sa\u00fade p\u00fablica. No futuro, dificilmente haver\u00e1 doentes que tenham de ser exclu\u00eddos de uma terapia devido aos potenciais efeitos secund\u00e1rios da medica\u00e7\u00e3o e das circunst\u00e2ncias que a acompanham. A aceita\u00e7\u00e3o da terapia pelos pacientes aumentar\u00e1 fortemente, bem como a procura de testes adequados, esclarecimentos e tratamento subsequente.<\/p>\n<p>Actualmente, as recomenda\u00e7\u00f5es de tratamento para a hepatite C est\u00e3o a mudar t\u00e3o rapidamente que as vers\u00f5es impressas j\u00e1 n\u00e3o s\u00e3o produzidas [10]. Existem actualmente cinco DAA ou DAA da Associa\u00e7\u00e3o Nacional Su\u00ed\u00e7a na Su\u00ed\u00e7a. combina\u00e7\u00f5es fixas DAA aprovadas, ou est\u00e3o em vias de serem aprovadas. Os DAAs podem ser divididos aproximadamente em tr\u00eas classes, de acordo com o seu modo de ac\u00e7\u00e3o: Inibidores da protease, inibidores da polimerase NS5B e inibidores da NS5A. Todos eles inibem a replica\u00e7\u00e3o do v\u00edrus directamente na c\u00e9lula hospedeira. O sofosbuvir <sup>(Sovaldi\u00ae<\/sup>), um inibidor da polimerase NS5B, \u00e9 a \u00fanica subst\u00e2ncia que foi aprovada para utiliza\u00e7\u00e3o por companhias de seguros de sa\u00fade. As combina\u00e7\u00f5es fixas de ombitasvir (inibidor NS5A), paritaprevir (inibidor de protease) e ritonavir <sup>(Viekirax\u00ae<\/sup>) mais dasabuvir <sup>(Exviera\u00ae<\/sup>), um inibidor de polimerase, bem como de sofosbuvir e o inibidor de NS5A ledipasvir <sup>(Harvoni\u00ae<\/sup>) foram aprovadas pelo Swissmedic, mas a aprova\u00e7\u00e3o pelos fundos de seguro de sa\u00fade est\u00e1 ainda pendente (a partir de 15.01.2015). O inibidor da protease Simeprevir <sup>(Olysio\u00ae<\/sup>) e o inibidor NS5A Daclatasvir <sup>(Daklinza\u00ae<\/sup>) ainda est\u00e3o em processo de aprova\u00e7\u00e3o.<\/p>\n<h2 id=\"os-precos-dos-medicamentos-limitam-a-oferta\">Os pre\u00e7os dos medicamentos limitam a oferta<\/h2>\n<p>Os novos medicamentos contra o HCV, que podem ser combinados sem interfer\u00e3o, t\u00eam potencial para curar a grande maioria dos pacientes com hepatite cr\u00f3nica C gra\u00e7as \u00e0 sua elevada efici\u00eancia, boa tolerabilidade e aplica\u00e7\u00e3o simples e comparativamente curta. A utiliza\u00e7\u00e3o de tratamentos baseados em interfer\u00e3o era auto-limitada devido ao potencial de efeitos secund\u00e1rios, ansiedade associada e as complexidades de utiliza\u00e7\u00e3o e cuidados durante a terapia. Este elevado obst\u00e1culo relacionado com a droga no acesso \u00e0 terapia poderia ser ultrapassado com o DAA. No entanto, os pre\u00e7os actuais e as restri\u00e7\u00f5es de utiliza\u00e7\u00e3o posteriormente introduzidas pelas autoridades sanit\u00e1rias reduzem consideravelmente este potencial. As combina\u00e7\u00f5es de tratamento baseadas em DAA custam cerca de 100.000 euros para um curso de tratamento de doze semanas na Alemanha, onde s\u00e3o obrigat\u00f3rias h\u00e1 j\u00e1 algum tempo. Se a terapia tiver de ser prolongada at\u00e9 24 semanas devido a preditores negativos, \u00e9 superior a 200.000 euros.<\/p>\n<h2 id=\"a-limitacao-medicamente-e-eticamente-questionavel\">A limita\u00e7\u00e3o medicamente e eticamente question\u00e1vel<\/h2>\n<p>O elevado pre\u00e7o do Sovaldi\u00ae, que custa mais de 600 francos su\u00ed\u00e7os por comprimido na Su\u00ed\u00e7a, levou a FOPH a restringir a prescri\u00e7\u00e3o a doentes com fibrose hep\u00e1tica j\u00e1 grave ou cancro do f\u00edgado. cirrose, independentemente do risco acrescido de insufici\u00eancia hep\u00e1tica e cancro do f\u00edgado, mesmo com uma terapia de HCV bem sucedida. Os doentes que esperaram anos por op\u00e7\u00f5es de tratamento sem interfer\u00f5es devem agora ser adiados porque os seus f\u00edgados ainda n\u00e3o sofreram danos suficientes. De um ponto de vista m\u00e9dico e \u00e9tico, esta \u00e9 uma situa\u00e7\u00e3o insustent\u00e1vel, cuja origem se encontra nos pre\u00e7os muito elevados dos novos medicamentos contra a hepatite C.<\/p>\n<h2 id=\"terapia-do-hcv-olhando-para-o-futuro\">Terapia do HCV: olhando para o futuro<\/h2>\n<p>A diversidade dos DAAs ir\u00e1 aumentar nos pr\u00f3ximos anos. Assim, a combina\u00e7\u00e3o e as op\u00e7\u00f5es de tratamento tornar-se-\u00e3o ainda maiores. Uma vez que os DAAs dispon\u00edveis actualmente t\u00eam taxas de cura superiores a 90%, j\u00e1 n\u00e3o h\u00e1 muito potencial de desenvolvimento na \u00e1rea da efici\u00eancia. As \u00fanicas excep\u00e7\u00f5es s\u00e3o pequenos subgrupos, tais como pacientes do gen\u00f3tipo 3 com cirrose hep\u00e1tica e terapias anteriores sem sucesso. Uma melhoria adicional na terapia da hepatite C pode ser esperada com a dura\u00e7\u00e3o da terapia. Existem boas perspectivas de que a dura\u00e7\u00e3o actual da terapia de 12-24 semanas possa ser encurtada ainda mais, possivelmente at\u00e9 para algumas semanas em grupos de doentes bem tratados. Com uma gama mais vasta de drogas, o uso de ribavirina, que ainda \u00e9 respons\u00e1vel por alguns efeitos secund\u00e1rios, tamb\u00e9m continuar\u00e1 a diminuir no futuro.<\/p>\n<h2 id=\"estrategia-para-a-hepatite-suica\">Estrat\u00e9gia para a Hepatite Su\u00ed\u00e7a<\/h2>\n<p>Os novos medicamentos contra a hepatite C t\u00eam o potencial para eliminar esta epidemia. Devido \u00e0 situa\u00e7\u00e3o inadequada de abastecimento e pre\u00e7os proibitivos, este objectivo est\u00e1 tamb\u00e9m muito longe na Su\u00ed\u00e7a. A revolu\u00e7\u00e3o do tratamento da hepatite C n\u00e3o resolveu o problema do tratamento da hepatite C. Para al\u00e9m das taxas de tratamento, as taxas de teste e esclarecimento, bem como de sensibiliza\u00e7\u00e3o e conhecimento, s\u00e3o ainda insuficientes.<\/p>\n<p>Uma estrat\u00e9gia su\u00ed\u00e7a contra a hepatite est\u00e1 actualmente a ser desenvolvida na Su\u00ed\u00e7a por uma ampla rede de m\u00e9dicos, organiza\u00e7\u00f5es de pessoas afectadas, ind\u00fastria e ag\u00eancias de financiamento. A rede \u00e9 apoiada pela SEVHep (Peritos Su\u00ed\u00e7os em Hepatite Viral), a Associa\u00e7\u00e3o de Hepatologistas (SASL), a Sociedade Su\u00ed\u00e7a de Gastroenterologia (SGGSSG), a Sociedade Su\u00ed\u00e7a de Doen\u00e7as Infecciosas (SGINF) e o Programa Global de Sa\u00fade do Instituto de P\u00f3s-Gradua\u00e7\u00e3o.<\/p>\n<p>Est\u00e1 a ser desenvolvido um plano de ac\u00e7\u00e3o coordenado que inclui os campos de ac\u00e7\u00e3o &#8220;educa\u00e7\u00e3o e preven\u00e7\u00e3o&#8221;, &#8220;testes e monitoriza\u00e7\u00e3o&#8221;, &#8220;terapia&#8221;, &#8220;grupos de risco&#8221;, &#8220;financiamento e pre\u00e7os&#8221; e &#8220;pol\u00edtica&#8221;. O objectivo da estrat\u00e9gia \u00e9 limitar as consequ\u00eancias individuais, m\u00e9dicas e socioecon\u00f3micas da epidemia de hepatite na Su\u00ed\u00e7a com medidas orientadas para o doente, rent\u00e1veis e implement\u00e1veis.<\/p>\n<p>\nLiteratura:<\/p>\n<ol>\n<li>Bruggmann P, et al: Epidemiologia hist\u00f3rica do v\u00edrus da hepatite C (HCV) em pa\u00edses seleccionados. J Hepat Viral 2014 Maio; 21 Suppl 1: 5-33.<\/li>\n<li>Lettmeier B, et al: A adop\u00e7\u00e3o no mercado de novos medicamentos antivirais para o tratamento da hepatite C. J Hepatol 2008 Oct; 49(4): 528-536.<\/li>\n<li>Lavanchy D: Epidemiologia evolutiva do v\u00edrus da hepatite C. Clin Microbiol Infect 2011 Fev; 17(2): 107-115.<\/li>\n<li>Razavi H, et al: O peso actual e futuro da infec\u00e7\u00e3o pelo v\u00edrus da hepatite C (HCV) com o actual paradigma de tratamento. J Viral Hepat 2014 Maio; 21 Suppl 1: 34-59.<\/li>\n<li>Shiffman ML, et al: Hepatite C cr\u00f3nica em doentes com n\u00edveis persistentemente normais de transaminase de alanina. Clin Gastroenterol Hepatol 2006 Maio; 4(5): 645-652.<\/li>\n<li>Puoti C: V\u00edrus da Hepatite C com n\u00edveis normais de transaminase. Dig Dis 2007; 25(3): 277-278.<\/li>\n<li>Fretz R, et al.: Hepatite B e C na Su\u00ed\u00e7a &#8211; o prestador de cuidados de sa\u00fade iniciou os testes de infec\u00e7\u00e3o cr\u00f3nica por hepatite B e C. Swiss Med Wkly 2013; 143: w13793.<\/li>\n<li>Bruggmann P, Richard JL: Distribui\u00e7\u00e3o do ano de nascimento em casos reportados de hepatite C na Su\u00ed\u00e7a. Eur J Sa\u00fade P\u00fablica 2014 Jul 23.<\/li>\n<li>Lavanchy D, McMahon BJ: Preval\u00eancia mundial e preven\u00e7\u00e3o da hepatite C. Hepatite C. San Diego: Academic Press 2000; 185-202.<\/li>\n<li>SASL SSI Expert Opinion Statement: Treatment of Chronic Hepatitis C &#8211; September 2014 Update https:\/\/sasl.unibas.ch\/guidelines\/SASL-SSI_HepC_EOS_Sept2014.pdf. 2014.<\/li>\n<\/ol>\n<p><em>PR\u00c1TICA DO GP 2015; 10(2): 10-12<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morrem mais pessoas devido \u00e0s consequ\u00eancias da hepatite C do que devido ao VIH. Metade das pessoas afectadas pela hepatite C n\u00e3o t\u00eam conhecimento da sua infec\u00e7\u00e3o. As pessoas nascidas&hellip;<\/p>\n","protected":false},"author":7,"featured_media":49479,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Hepatite C","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11524,11421,11305,11551],"tags":[35964,35020,14214,18461,18456],"powerkit_post_featured":[],"class_list":["post-343477","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacao-continua","category-infecciologia","category-medicina-interna-geral","category-rx-pt","tag-daa-pt-pt","tag-hcv-pt-pt","tag-hepatite-c-pt-pt","tag-sida-pt-pt","tag-vih-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:44:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":343448,"slug":"combatir-la-epidemia-con-nuevos-conocimientos","post_title":"Combatir la epidemia con nuevos conocimientos","href":"https:\/\/medizinonline.com\/es\/combatir-la-epidemia-con-nuevos-conocimientos\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/343477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=343477"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/343477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/49479"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=343477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=343477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=343477"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=343477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}