{"id":344928,"date":"2014-07-04T00:00:00","date_gmt":"2014-07-03T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/noticias-de-um-campo-que-se-esta-a-desenvolver-rapidamente\/"},"modified":"2014-07-04T00:00:00","modified_gmt":"2014-07-03T22:00:00","slug":"noticias-de-um-campo-que-se-esta-a-desenvolver-rapidamente","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/noticias-de-um-campo-que-se-esta-a-desenvolver-rapidamente\/","title":{"rendered":"Not\u00edcias de um campo que se est\u00e1 a desenvolver rapidamente"},"content":{"rendered":"<p><strong>As neoplasias mieloproliferativas cl\u00e1ssicas (NMP) incluem policitemia vera, trombocit\u00e9mia essencial e mielofibrose prim\u00e1ria. V\u00e1rias sess\u00f5es no Congresso da EHA em meados de Junho abordaram a revis\u00e3o das directrizes, not\u00edcias sobre a inibi\u00e7\u00e3o JAK e o impacto progn\u00f3stico das muta\u00e7\u00f5es do condutor.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><em>(ag)<\/em>  Ruben Mesa, MD, Arizona, falou sobre o actual diagn\u00f3stico de policitemia vera (PV): &#8220;Esta \u00e9 uma doen\u00e7a heterog\u00e9nea de c\u00e9lulas estaminais principalmente associada a um aumento dos gl\u00f3bulos vermelhos. Como resultado, podem ocorrer eventos tromboemb\u00f3licos. H\u00e1 um risco de transi\u00e7\u00e3o para mielofibrose ou leucemia aguda. A revis\u00e3o dos crit\u00e9rios de diagn\u00f3stico da OMS proposta este ano [1] inclui tr\u00eas crit\u00e9rios ditos maiores e um menor. Para um diagn\u00f3stico de PV, devem ser cumpridos os tr\u00eas ou os dois primeiros crit\u00e9rios principais mais um crit\u00e9rio menor&#8221;. <\/p>\n<p>Os principais crit\u00e9rios incluem<\/p>\n<ol>\n<li>Valores de hemoglobina de &gt;16,5 g\/dl (homens) e&gt;16 g\/dl (mulheres) ou um hemat\u00f3crito de &gt;49% (homens) e &gt;48% (mulheres)<\/li>\n<li>Descobertas de medula \u00f3ssea compat\u00edveis com os crit\u00e9rios da OMS com megacari\u00f3citos pleom\u00f3rficos.<\/li>\n<li>Presen\u00e7a de uma muta\u00e7\u00e3o JAK2.<\/li>\n<\/ol>\n<p>O crit\u00e9rio menor listado na revis\u00e3o \u00e9 o n\u00edvel subnormal do soro eritropoietina. &#8220;Assim, os crit\u00e9rios de diagn\u00f3stico da PV est\u00e3o em desenvolvimento. Prop\u00f5e-se baixar o limiar de hemoglobina e acrescentar hemat\u00f3crito como crit\u00e9rio principal. Em \u00faltima an\u00e1lise, isto conduzir\u00e1 a uma simplifica\u00e7\u00e3o. No entanto, \u00e9 necess\u00e1ria uma biopsia \u00e0 medula \u00f3ssea&#8221;, concluiu Mesa.<\/p>\n<h2 id=\"pv-mascarado\">&#8220;PV &#8220;mascarado<\/h2>\n<p>A influ\u00eancia da morfologia da medula \u00f3ssea como instrumento de diagn\u00f3stico \u00e9 tamb\u00e9m discutida na revis\u00e3o das directrizes da OMS para a chamada PV &#8220;mascarada&#8221;, pois permite uma elevada reprodutibilidade do diagn\u00f3stico mesmo em casos que n\u00e3o atingem os limiares anteriores de hemoglobina e hemat\u00f3crito. Isto \u00e9 significativo porque a sobreviv\u00eancia global em pacientes com PV &#8220;mascarada&#8221; parece ser pior do que a de pacientes com PV expl\u00edcita (se os factores de risco independentes da idade &gt;65 anos e contagem de leuc\u00f3citos &gt;15\u00d7 109 \/ l forem inclu\u00eddos). Sem estes dois factores de risco, as taxas de sobreviv\u00eancia dos dois grupos s\u00e3o compar\u00e1veis, o que, segundo os autores, indica que alguns dos doentes que ficam abaixo dos limiares anteriormente exigidos pelas directrizes da OMS devem ser considerados como doentes com PV aparente [2,3].<\/p>\n<h2 id=\"prognostico-e-sobrevivencia-em-mpn\">Progn\u00f3stico e sobreviv\u00eancia em MPN<\/h2>\n<p>Que muta\u00e7\u00f5es existem na mielofibrose prim\u00e1ria (PMF) e na PV? Esta pergunta foi colocada pelo Prof. Dr. med. Alessandro Vannucchi, Floren\u00e7a. Em PV, cerca de 95% das muta\u00e7\u00f5es fenot\u00edpicas do condutor pertencem ao tipo JAK2-V617F e 4% ao tipo JAK2-Exon12. Em PMF, existem aproximadamente 60% JAK2-V617F, 20% CALR, 8% MPL-W515 e 10% as chamadas muta\u00e7\u00f5es &#8220;triplo-negativas&#8221;.<\/p>\n<p>Segundo o Prof. Vannucchi, o progn\u00f3stico em PMF \u00e9 influenciado por estas muta\u00e7\u00f5es fenot\u00edpicas do condutor na medida em que as muta\u00e7\u00f5es CALR mostram um melhor resultado de sobreviv\u00eancia do que as muta\u00e7\u00f5es JAK2, MPL e &#8220;triple negative&#8221;.<\/p>\n<p>Haifa Kathrin Al-Ali, MD, Leipzig, entrou em mais pormenores sobre progn\u00f3stico e sobreviv\u00eancia em casos de NMP: &#8220;\u00c9 evidente que a mielofibrose traz consigo a pior sobreviv\u00eancia de todas as NMP: Enquanto de acordo com um estudo sueco [4] os doentes com trombocitemia essencial (ET) mostram uma sobrevida de 10 anos reduzida em 17% em compara\u00e7\u00e3o com a popula\u00e7\u00e3o normal, os doentes afectados por PV mostram uma sobrevida de 28% e os doentes com PMF um total de 81% pioraram a sobrevida. Para avaliar o risco de morte e trombose na MPN, est\u00e3o dispon\u00edveis v\u00e1rios instrumentos de progn\u00f3stico, tais como as chamadas escalas Lille, IPSS, DIPSS e DIPSS Plus&#8221;.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0 mielofibrose, existe apenas uma op\u00e7\u00e3o terap\u00eautica curativa: o transplante alog\u00e9nico de c\u00e9lulas estaminais hematopoi\u00e9ticas. No entanto, o resultado ap\u00f3s o transplante depende da classifica\u00e7\u00e3o inicial na escala DIPSS [5].<\/p>\n<p>Os dois ensaios COMFORT tamb\u00e9m mostraram que o ruxolitinib melhorou a sobreviv\u00eancia a longo prazo em doentes MF (em compara\u00e7\u00e3o com placebo [6] e a melhor terapia dispon\u00edvel [7,8]). De acordo com estudos explorat\u00f3rios, a utiliza\u00e7\u00e3o deste agente durante cinco anos poderia atrasar ou mesmo inverter a fibrose da medula \u00f3ssea (isto novamente em compara\u00e7\u00e3o com a melhor terapia dispon\u00edvel) [9]. &#8220;\u00c9 poss\u00edvel, ent\u00e3o, que a inibi\u00e7\u00e3o sustentada de JAK1&amp;2 modifique a doen\u00e7a&#8221;, sugeriu o Dr. Al-Ali.<\/p>\n<p>No campo da PV, os pacientes resistentes \u00e0 hidroxiureia s\u00e3o particularmente afectados por uma elevada mortalidade. Estudos falam de um risco de morte 5,6 vezes maior em compara\u00e7\u00e3o com a popula\u00e7\u00e3o n\u00e3o-resistente. Segundo o Dr. Al-Ali, s\u00e3o urgentemente necess\u00e1rias novas op\u00e7\u00f5es terap\u00eauticas aqui: &#8220;O papel do ruxolitinib foi testado no ensaio RESPONSE. Os resultados s\u00e3o encorajadores em termos do par\u00e2metro prim\u00e1rio (controlo do n\u00famero de gl\u00f3bulos vermelhos e redu\u00e7\u00e3o do volume do ba\u00e7o) e tamb\u00e9m em termos de menor carga de sintomas em compara\u00e7\u00e3o com a melhor terapia dispon\u00edvel [10]&#8221; .<\/p>\n<h2 id=\"o-que-se-segue\">O que se segue?<\/h2>\n<p>Claire Harrison, MD, Londres, descreveu o diagn\u00f3stico exacto como a pedra angular das terapias actualmente poss\u00edveis para NMP: &#8220;Em princ\u00edpio, a aspirina de dose baixa s\u00f3 mostra boas provas na \u00e1rea da PV, mas n\u00e3o para PMF e ET. No entanto, \u00e9 tamb\u00e9m utilizado como padr\u00e3o na ET (excepto em doentes de alto risco). A consolida\u00e7\u00e3o da situa\u00e7\u00e3o do estudo \u00e9 urgentemente necess\u00e1ria aqui&#8221;. Al\u00e9m disso, todos os factores de risco vascular revers\u00edvel precisam de ser tratados de forma agressiva. Deixar de fumar \u00e9 fundamental.<\/p>\n<p>&#8220;Os inibidores JAK est\u00e3o actualmente a mudar fundamentalmente o panorama terap\u00eautico do MF. Est\u00e1 a surgir uma vantagem de sobreviv\u00eancia a longo prazo sobre a melhor terapia dispon\u00edvel (actualiza\u00e7\u00e3o de 3,5 anos no Congresso da EHA de 2014 [8]). No entanto, \u00e9 necess\u00e1rio primeiro examinar cuidadosamente se tamb\u00e9m podem ser considerados como agentes terap\u00eauticos em pacientes com risco mais baixo no futuro <strong>(Fig. 1)<\/strong>&#8220;.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-4312\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/07\/Abb1_OH6_s29.jpg_2399.jpg\" width=\"1100\" height=\"820\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/07\/Abb1_OH6_s29.jpg_2399.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/07\/Abb1_OH6_s29.jpg_2399-800x596.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/07\/Abb1_OH6_s29.jpg_2399-320x240.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/07\/Abb1_OH6_s29.jpg_2399-300x225.jpg 300w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/07\/Abb1_OH6_s29.jpg_2399-120x90.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/07\/Abb1_OH6_s29.jpg_2399-90x68.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/07\/Abb1_OH6_s29.jpg_2399-560x417.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>O Dr. Harrison tamb\u00e9m abordou a possibilidade de modifica\u00e7\u00e3o da doen\u00e7a atrav\u00e9s da utiliza\u00e7\u00e3o de ruxolitinibe: &#8220;Entre outras coisas, um relat\u00f3rio de caso [11] levantou sobrancelhas, no qual foi observada uma resolu\u00e7\u00e3o completa da fibrose da medula \u00f3ssea num doente MF (p\u00f3s-PV) ap\u00f3s tr\u00eas anos de inibi\u00e7\u00e3o JAK1&amp;2&#8221;.<\/p>\n<p><em>Fonte: Congresso da EHA 2014, 12-15 de Junho de 2014, Mil\u00e3o<\/em><\/p>\n<h3 id=\"literatura\">Literatura:<\/h3>\n<ol>\n<li>Barbui T, et al: Repensar os crit\u00e9rios de diagn\u00f3stico da policitemia vera. Leucemia 2014 Jun; 28(6): 1191-1195.<\/li>\n<li>Barbui T, et al: Policitemia vera mascarada diagnosticada de acordo com a classifica\u00e7\u00e3o da OMS e BCSH. Am J Hematol 2014 Fev; 89(2): 199-202.<\/li>\n<li>Barbui T, et al: Mascarada policitemia vera (mPV): resultados de um estudo internacional. Am J Hematol 2014 Jan; 89(1): 52-54.<\/li>\n<li>Hultcrantz M, et al: Patterns of survival among patients with myeloproliferative neoplasms diagnosed in Sweden from 1973 to 2008: um estudo baseado na popula\u00e7\u00e3o. J Clin Oncol 2012 Ago 20; 30(24): 2995-3001.<\/li>\n<li>Scott BL, et al: The Dynamic International Prognostic Scoring System for myelofibrosis prediz resultados ap\u00f3s transplante de c\u00e9lulas hematopoi\u00e9ticas. Sangue 2012 Mar 15; 119(11): 2657-2664.<\/li>\n<li>Verstovsek S, et al: Long-Term Outcomes Of Ruxolitinib Therapy In Patients With Myelofibrosis: 3-Year Update From COMFORT-I. Sangue 2013; 122(21): 396.<\/li>\n<li>Cervantes F, et al: Resultados de tr\u00eas anos de efic\u00e1cia, seguran\u00e7a e sobreviv\u00eancia de COMFORT-II, um estudo de fase 3 comparando o ruxolitinibe com a melhor terapia dispon\u00edvel para a mielofibrose. Sangue 2013 Dez 12; 122(25): 4047-4053.<\/li>\n<li>Harrison C, et al: Resultados de uma actualiza\u00e7\u00e3o de 3,5 anos do COMFORT-II, um estudo de fase 3 comparando ruxolitinibe (rux) com a melhor terapia dispon\u00edvel (morcego) para o tratamento da mielofibrose. EHA 2014 #Abstract P403.<\/li>\n<li>Kvasnicka HM, et al: Effects Of Five-Years Of Ruxolitinib Therapy On Bone Marrow Morphology In Patients With Myelofibrosis And Comparison With Best Available Therapy. Sangue 2013; 122(21): 4055.<\/li>\n<li>Vannucchi A: Ruxolitinibe revela-se superior \u00e0 melhor terapia dispon\u00edvel num estudo prospectivo, aleat\u00f3rio, fase 3 (resposta) em doentes com policitemia vera resistente ou intolerante \u00e0 hidroxiureia. EHA 2014 #Abstract LB2436.<\/li>\n<li>Wilkins BS, et al: Resolu\u00e7\u00e3o da fibrose da medula \u00f3ssea num doente que recebe tratamento inibidor de JAK1\/JAK2 com ruxolitinibe. Haematologica 2013 Dez; 98(12): 1872-1876.<\/li>\n<\/ol>\n<p><em>InFo Oncologia &amp; Hematologia 2014; 2(6): 28-30<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As neoplasias mieloproliferativas cl\u00e1ssicas (NMP) incluem policitemia vera, trombocit\u00e9mia essencial e mielofibrose prim\u00e1ria. V\u00e1rias sess\u00f5es no Congresso da EHA em meados de Junho abordaram a revis\u00e3o das directrizes, not\u00edcias sobre&hellip;<\/p>\n","protected":false},"author":4,"featured_media":45757,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Neoplasias mieloproliferativas","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11365,11379,11529,11551],"tags":[21108,40295,51751,50999,51743,21660,50993,40213,28492,50987,51737],"powerkit_post_featured":[],"class_list":["post-344928","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hematologia-pt-pt","category-oncologia-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-celulas-estaminais","tag-et-pt-pt","tag-fibrose-da-medula-ossea","tag-inibicao-jak","tag-jak2-pt-pt","tag-mielofibrose","tag-mpn-pt-pt","tag-neoplasia-pt-pt-2","tag-policitemia-vera-pt-pt-2","tag-pv-pt-pt","tag-resposta","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:52:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":344935,"slug":"noticias-de-un-campo-que-se-desarrolla-rapidamente","post_title":"Noticias de un campo que se desarrolla r\u00e1pidamente","href":"https:\/\/medizinonline.com\/es\/noticias-de-un-campo-que-se-desarrolla-rapidamente\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/344928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=344928"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/344928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/45757"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=344928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=344928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=344928"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=344928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}