{"id":345030,"date":"2014-06-26T00:00:00","date_gmt":"2014-06-25T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/uma-mudanca-bronquica-que-acompanha-muitas-doencas\/"},"modified":"2014-06-26T00:00:00","modified_gmt":"2014-06-25T22:00:00","slug":"uma-mudanca-bronquica-que-acompanha-muitas-doencas","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/uma-mudanca-bronquica-que-acompanha-muitas-doencas\/","title":{"rendered":"Uma mudan\u00e7a br\u00f4nquica que acompanha muitas doen\u00e7as"},"content":{"rendered":"<p><strong>Bronquiectasia, dilata\u00e7\u00e3o irrevers\u00edvel dos tubos bronquiais, \u00e9 uma caracter\u00edstica de muitas doen\u00e7as, mas tamb\u00e9m pode ser cong\u00e9nita. Se se quiser abordar terap\u00eauticamente todo o quadro cl\u00ednico com todos os seus sintomas (bronquiectasia), confrontamo-nos com numerosos estudos que investigam diferentes op\u00e7\u00f5es terap\u00eauticas. Matthias Salath\u00e9, MD, Miami, deu uma vis\u00e3o geral na reuni\u00e3o anual da Sociedade Su\u00ed\u00e7a de Pneumologia.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>De acordo com Matthias Salath\u00e9, MD, Miami, v\u00e1rias doen\u00e7as podem causar bronquiectasias. Acima de tudo \u00e9 a fibrose c\u00edstica (FC). Bronquiectasia em que a CF foi descartada, uma vez que a causa se chama bronquiectasia n\u00e3o-CF. A bronquiectasia n\u00e3o-CF afecta aproximadamente 4,2 pessoas por cada 100.000 com idades compreendidas entre os 18 e os 34 anos. Entre os jovens &gt;de 75 anos, cerca de 272 por cada 100.000 sofrem com isso. As doen\u00e7as que podem estar associadas \u00e0 bronquiectasia incluem:<\/p>\n<ul>\n<li>Discinesia ciliar prim\u00e1ria<\/li>\n<li>\u03b1-1-antitripsina deficiente<\/li>\n<li>Estado p\u00f3s-infeccioso ap\u00f3s tuberculose\/micobact\u00e9rias e infec\u00e7\u00f5es infantis, aspergilose broncopulmonar al\u00e9rgica (ABPA)<\/li>\n<li>Defeitos imunol\u00f3gicos<\/li>\n<li>Artrite reumat\u00f3ide<\/li>\n<li>Aspira\u00e7\u00e3o, doen\u00e7a do refluxo gastro-esof\u00e1gico (DRGE)<\/li>\n<li>Doen\u00e7as inflamat\u00f3rias cr\u00f3nicas intestinais<\/li>\n<li>Defeitos cong\u00e9nitos.<\/li>\n<\/ul>\n<p>Os factores independentes associados a um decl\u00ednio mais r\u00e1pido da fun\u00e7\u00e3o pulmonar na bronquiectasia n\u00e3o-CF foram principalmente a coloniza\u00e7\u00e3o cr\u00f3nica com Pseudomonas aeruginosa (p=0,005), exacerba\u00e7\u00f5es graves mais frequentes (p=0,014) e inflama\u00e7\u00e3o sist\u00e9mica (p=0,023), de acordo com um estudo de 2007 [1].<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-4192\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Salathe_HP7_s47.png_2322.png\" width=\"859\" height=\"804\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Salathe_HP7_s47.png_2322.png 859w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Salathe_HP7_s47.png_2322-800x749.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Salathe_HP7_s47.png_2322-120x112.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Salathe_HP7_s47.png_2322-90x84.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Salathe_HP7_s47.png_2322-320x300.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Salathe_HP7_s47.png_2322-560x524.png 560w\" sizes=\"(max-width: 859px) 100vw, 859px\" \/><\/p>\n<h4 id=\"como-pode-a-terapia-ser-melhorada\">Como pode a terapia ser melhorada?<\/h4>\n<p>Segundo Salath\u00e9, v\u00e1rios estudos sobre a bronquiectasia n\u00e3o-CF mostram um ligeiro benef\u00edcio da tobramicina inalada devido \u00e0 coloniza\u00e7\u00e3o com Pseudomonas aeruginosa. Embora a droga ajude em certa medida contra as exacerba\u00e7\u00f5es, tamb\u00e9m traz consigo muitos efeitos secund\u00e1rios. A gentamicina tamb\u00e9m parece ser eficaz de acordo com um estudo recente [2], mas apenas com uma utiliza\u00e7\u00e3o cont\u00ednua e a longo prazo (em compara\u00e7\u00e3o com a salina, resultou numa maior resili\u00eancia, menos exacerba\u00e7\u00f5es com um maior tempo para a primeira exacerba\u00e7\u00e3o, e tamb\u00e9m n\u00e3o desencadeou o desenvolvimento de resist\u00eancia). Resultados semelhantes foram encontrados num estudo de fase II mais pequeno [3] para a ciprofloxacina lipossomal inalada.<\/p>\n<p>Um estudo recente [4] concluiu tamb\u00e9m que a colistina inalada \u00e9 um tratamento seguro e eficaz para doentes com bronquiectasia e coloniza\u00e7\u00e3o cr\u00f3nica com Pseudomonas aeruginosa. O ponto final prim\u00e1rio (tempo significativamente mais curto para a exacerba\u00e7\u00e3o em compara\u00e7\u00e3o com o placebo) n\u00e3o p\u00f4de ser alcan\u00e7ado. No entanto, quando a ades\u00e3o dos doentes foi inclu\u00edda como factor (par\u00e2metro secund\u00e1rio), ainda puderam ser observados valores significativos.<\/p>\n<p>Os macrol\u00eddeos (antibi\u00f3ticos) s\u00e3o tamb\u00e9m cada vez mais prescritos para a bronquiectasia est\u00e1vel. No entanto, uma meta-an\u00e1lise [5] sobre a utiliza\u00e7\u00e3o a longo prazo de macrol\u00eddeos salienta o problema exacerbado da resist\u00eancia e a ocorr\u00eancia de eventos gastrointestinais nesta \u00e1rea. Os autores concluem que, devido aos resultados globalmente positivos (por exemplo, redu\u00e7\u00e3o do risco de exacerba\u00e7\u00f5es, menor n\u00famero m\u00e9dio de exacerba\u00e7\u00f5es por pessoa), o aumento da actividade de investiga\u00e7\u00e3o para utiliza\u00e7\u00e3o neste grupo de doentes \u00e9 certamente justificado.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-4193 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_HP7_s48.jpg_2321.jpg\" width=\"1100\" height=\"444\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_HP7_s48.jpg_2321.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_HP7_s48.jpg_2321-800x323.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_HP7_s48.jpg_2321-120x48.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_HP7_s48.jpg_2321-90x36.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_HP7_s48.jpg_2321-320x129.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_HP7_s48.jpg_2321-560x226.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/444;\" \/><\/p>\n<p>Al\u00e9m disso, 7% de soro hipert\u00f3nico pode melhorar a fun\u00e7\u00e3o pulmonar e a qualidade de vida em doentes com bronquiectasias n\u00e3o-CF [6].<br \/>\n&#8220;Um dos pilares mais importantes da terapia, contudo, \u00e9 o treino f\u00edsico&#8221;, salientou Salath\u00e9 em conclus\u00e3o. &#8220;A efic\u00e1cia da reabilita\u00e7\u00e3o pulmonar (RP) na bronquiectasia \u00e9 apoiada por v\u00e1rios estudos [7,8].&#8221;. <strong>O Quadro 1<\/strong> d\u00e1 uma vis\u00e3o geral das poss\u00edveis op\u00e7\u00f5es terap\u00eauticas.<\/p>\n<p><em>Fonte: Reuni\u00e3o anual conjunta da Sociedade Su\u00ed\u00e7a de Pneumologia (SGP), da Sociedade Su\u00ed\u00e7a de Pneumologia Pedi\u00e1trica (SGPP), da Sociedade Su\u00ed\u00e7a de Cirurgia Tor\u00e1cica (SGT) e da Associa\u00e7\u00e3o Su\u00ed\u00e7a de Pessoal de Endoscopia (SVEP), 8-9 de Maio de 2014, Interlaken<\/em><\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Mart\u00ednez-Garc\u00eda MA, et al.: Factores associados ao decl\u00ednio da fun\u00e7\u00e3o pulmonar em doentes adultos com fibrose bronquiectasia n\u00e3o c\u00edstica est\u00e1vel. Peito 2007 Nov; 132(5): 1565-1572.<\/li>\n<li>Murray MP, et al: Um ensaio aleat\u00f3rio controlado de gentamicina nebulizada em fibrose bronquiectasia n\u00e3o c\u00edstica. Am J Respir Crit Care Med 2011 Fev 15; 183(4): 491-499.<\/li>\n<li>Serisier DJ, et al: ciprofloxacina liposs\u00f3mica de liberta\u00e7\u00e3o dupla inalada em fibrose bronquiectasia n\u00e3o c\u00edstica (ORBIT-2): um ensaio aleat\u00f3rio, duplo-cego, controlado por placebo. T\u00f3rax 2013 Set; 68(9): 812-817.<\/li>\n<li>Haworth CS, et al: Colistina inalada em doentes com bronquiectasia e infec\u00e7\u00e3o cr\u00f3nica por Pseudomonas aeruginosa. Am J Respir Crit Care Med 2014 Abr 15; 189(8): 975-982.<\/li>\n<li>Wu Q, et al: Macr\u00f3lidos a longo prazo para a bronquiectasia fibrosa n\u00e3o c\u00edstica: uma revis\u00e3o sistem\u00e1tica e uma meta-an\u00e1lise. Respirologia 2014 Abril; 19(3): 321-329.<\/li>\n<li>Kellett F, Robert NM: Salina hipert\u00f3nica nebulizada a 7% melhora a fun\u00e7\u00e3o pulmonar e a qualidade de vida na bronquiectasia. Respir Med 2011 Dez; 105(12): 1831-1835.<\/li>\n<li>Ong HK, et al: Effects of pulmonary rehabilitation in bronchiectasis: A retrospective study. Chron Respir Dis 2011; 8(1): 21-30.<\/li>\n<li>Newall C, Stockley RA, Hill SL: Exerc\u00edcio de treino e treino muscular inspirat\u00f3rio em doentes com bronquiectasia. T\u00f3rax 2005 Nov; 60(11): 943-948.<\/li>\n<\/ol>\n<p><em>PR\u00c1TICA DO GP 2014; 9(7): 47-48<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bronquiectasia, dilata\u00e7\u00e3o irrevers\u00edvel dos tubos bronquiais, \u00e9 uma caracter\u00edstica de muitas doen\u00e7as, mas tamb\u00e9m pode ser cong\u00e9nita. Se se quiser abordar terap\u00eauticamente todo o quadro cl\u00ednico com todos os seus&hellip;<\/p>\n","protected":false},"author":4,"featured_media":45247,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Bronquiectasis","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11407,11421,11547,11529,11551],"tags":[24150,14307,25097,52134,15514,52141,11807,21489,52130,13070],"powerkit_post_featured":[],"class_list":["post-345030","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gastroenterologia-e-hepatologia","category-infecciologia","category-pneumologia-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-abpa-pt-pt","tag-artrite-reumatoide-pt-pt","tag-aspiracao","tag-bronquiectasis-pt-pt","tag-cf-pt-pt","tag-discinesia-pt-pt-2","tag-doenca-intestinal","tag-fibrose-cistica-pt-pt-2","tag-mudanca-bronquica","tag-tuberculose","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:46:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":345038,"slug":"un-cambio-bronquial-que-acompana-a-muchas-enfermedades","post_title":"Un cambio bronquial que acompa\u00f1a a muchas enfermedades","href":"https:\/\/medizinonline.com\/es\/un-cambio-bronquial-que-acompana-a-muchas-enfermedades\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/345030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=345030"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/345030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/45247"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=345030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=345030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=345030"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=345030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}