{"id":345240,"date":"2014-06-06T00:00:00","date_gmt":"2014-06-05T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/pratica-de-consulta-de-medicina-de-viagem\/"},"modified":"2014-06-06T00:00:00","modified_gmt":"2014-06-05T22:00:00","slug":"pratica-de-consulta-de-medicina-de-viagem","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/pratica-de-consulta-de-medicina-de-viagem\/","title":{"rendered":"Pr\u00e1tica de consulta de medicina de viagem"},"content":{"rendered":"<p><strong>As viagens est\u00e3o a aumentar constantemente em todo o mundo: enquanto em 1970 havia 150 milh\u00f5es de chegadas tur\u00edsticas, este n\u00famero aumentou para mais de 940 milh\u00f5es em 2010 [1]. Em m\u00e9dia, cada su\u00ed\u00e7o fez 2,8 viagens em 2012; foram feitas 20,3 milh\u00f5es de viagens no total, das quais 12,9 milh\u00f5es foram ao estrangeiro. As caracter\u00edsticas do viajante mudaram nos \u00faltimos anos. A percentagem de viagens tur\u00edsticas cl\u00e1ssicas est\u00e1 a diminuir; cada vez mais, as viagens s\u00e3o feitas por pessoas que visitam amigos e familiares nos seus antigos pa\u00edses de origem (VFR &#8220;visitando amigos e familiares&#8221;) [1]. Este artigo destina-se a fornecer uma vis\u00e3o geral dos t\u00f3picos cl\u00e1ssicos da medicina de viagem, mas tamb\u00e9m a apontar a evolu\u00e7\u00e3o da epidemiologia entre os viajantes e a promover na pr\u00e1tica um aconselhamento orientado para o risco.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Na Su\u00ed\u00e7a, os &#8220;amigos e familiares visitantes&#8221; (VFR) representam 17% de todos os viajantes [2]; no Reino Unido, os VFR j\u00e1 representam cerca de 50% de todos os viajantes quando viajam para \u00c1frica ou para o subcontinente indiano. Cada vez mais, os idosos com comorbidades est\u00e3o tamb\u00e9m a realizar viagens a \u00e1reas subtropicais ou tropicais. Estes dois grupos de viajantes, em particular, t\u00eam algumas caracter\u00edsticas especiais e requerem conselhos especiais.<\/p>\n<p>Al\u00e9m disso, os conselhos de viagem podem e devem ser tomados como uma oportunidade para avaliar a exaustividade das vacinas b\u00e1sicas (especialmente MMR) e quaisquer vacinas recomendadas em grupos de risco (por exemplo, vacina pneumoc\u00f3cica conjugada em doentes com comorbilidades cr\u00f3nicas, de acordo com o calend\u00e1rio de vacina\u00e7\u00e3o su\u00ed\u00e7o [3]).  <strong>O quadro&nbsp;1 <\/strong>fornece uma vis\u00e3o geral disto mesmo.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-3907\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_s14_HP6.jpg_2163.jpg\" width=\"1100\" height=\"809\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_s14_HP6.jpg_2163.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_s14_HP6.jpg_2163-800x588.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_s14_HP6.jpg_2163-120x88.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_s14_HP6.jpg_2163-90x66.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_s14_HP6.jpg_2163-320x235.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab1_s14_HP6.jpg_2163-560x412.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>Para um aconselhamento individual significativo, o estado de sa\u00fade dos viajantes (idade, doen\u00e7as, gravidez, alergias, medicamentos, etc.) deve ser conhecido. Precisamos de saber o destino e quanto tempo permanecem em \u00e1reas de risco espec\u00edficas e como viajam (turismo de grupo vs. turismo individual, modo de viagem e op\u00e7\u00f5es de alojamento). Um question\u00e1rio devidamente concebido pode ser preenchido pelos viajantes antes da consulta; isto pode facilitar muito a consulta e poupar tempo de uma forma significativa.<\/p>\n<h2 id=\"riscos-ao-viajar\">Riscos ao viajar<\/h2>\n<p>Em todas as publica\u00e7\u00f5es sobre doen\u00e7as associadas a viagens, a principal queixa \u00e9 a diarreia dos viajantes &#8211; com uma taxa de incid\u00eancia impressionante de at\u00e9 60% j\u00e1 nas primeiras duas semanas. A diarreia dos viajantes \u00e9 geralmente inofensiva e dura alguns dias; metade da diarreia associada \u00e0 viagem cicatriza espontaneamente ap\u00f3s 48 horas. Os grupos de risco especial para a diarreia dos viajantes s\u00e3o as crian\u00e7as e os jovens adultos (&lt;30 anos), as pessoas em tratamento anti\u00e1cido e as pessoas com doen\u00e7as gastrointestinais ou imunodefici\u00eancia pr\u00e9-existentes. No &#8220;eixo do risco&#8221; por Steffen et al. [4] enumera os riscos por m\u00eas de viagem: Ap\u00f3s a diarreia dos viajantes, com uma incid\u00eancia de 3% por m\u00eas, surge o risco de contrair mal\u00e1ria quando se viaja para a \u00c1frica Ocidental sem profilaxia de mal\u00e1ria, seguido da gripe e do risco de sofrer uma mordida de c\u00e3o com risco de raiva <strong>(Fig. 1)<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3908 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb1_HP6_s13.jpg_2160.jpg\" width=\"1100\" height=\"1273\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb1_HP6_s13.jpg_2160.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb1_HP6_s13.jpg_2160-800x926.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb1_HP6_s13.jpg_2160-120x139.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb1_HP6_s13.jpg_2160-90x104.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb1_HP6_s13.jpg_2160-320x370.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb1_HP6_s13.jpg_2160-560x648.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1273;\" \/><\/p>\n<p>A mortalidade em viagem depende essencialmente da idade e, para os viajantes mais jovens, das suas actividades. Numa an\u00e1lise de 89 521 viajantes doentes tratados em cl\u00ednicas GeoSentinel, cl\u00ednicas especializadas em medicina de viagem em todos os continentes do mundo, 8,4% dos viajantes tinham mais de 60 anos de idade [5]. Em compara\u00e7\u00e3o com a popula\u00e7\u00e3o de 18-45 anos de idade, este grupo de viajantes tinha um risco significativamente maior de ser tratado de pneumonia\/bronquite ou insufici\u00eancia card\u00edaca. As raz\u00f5es mais comuns para o tratamento m\u00e9dico entre os viajantes mais jovens, por outro lado, foram a mal\u00e1ria e as infec\u00e7\u00f5es por dengue. A mortalidade foi de 45\/100.000 na popula\u00e7\u00e3o mais jovem e de 199\/100.000 na popula\u00e7\u00e3o mais velha, com risco crescente a cada d\u00e9cada ao longo de 60 anos.<\/p>\n<p>Numa an\u00e1lise [6] das causas de morte na cidade de Chiang Mai, Tail\u00e2ndia, 7,9% de todas as mortes foram de estrangeiros, com uma m\u00e9dia de seis mortes de estrangeiros por m\u00eas. A idade m\u00e9dia dos estrangeiros \u00e0 morte foi de 64 anos, correspondendo as doen\u00e7as cardiovasculares \u00e0s principais causas de morte, seguidas das neoplasias e finalmente das doen\u00e7as infecciosas. 10% de todas as causas de morte foram traum\u00e1ticas (acidentes, suic\u00eddios, overdose de drogas e afogamento). A taxa de mortalidade normalizada n\u00e3o difere da dos pa\u00edses de origem dos viajantes &#8211; por isso, aquilo de que se morre mais frequentemente no pa\u00eds de origem, morre-se do estrangeiro. Dois estudos de mortes de cidad\u00e3os escoceses e canadianos em viagem, respectivamente, mostraram conclus\u00f5es principais semelhantes: tr\u00eas quartos de todas as mortes tiveram uma causa natural. No entanto, nestes dois estudos, as mortes traum\u00e1ticas, principalmente acidentes de tr\u00e2nsito e suic\u00eddio e homic\u00eddio, foram mais elevadas, em cerca de 20%. Estas foram as principais causas de morte entre os viajantes mais jovens.<\/p>\n<h2 id=\"viajantes-especiais\">Viajantes especiais<\/h2>\n<p>\u00c9, portanto, de grande import\u00e2ncia que os conselhos de viagem sejam orientados para a idade e o perfil de risco do viajante. O risco de causas traum\u00e1ticas de morte e a sua preven\u00e7\u00e3o s\u00e3o frequentemente negligenciados nos conselhos de viagem.&nbsp;<\/p>\n<p> <strong>O Quadro 2<\/strong> lista alguns grupos espec\u00edficos de viajantes com os seus riscos particulares. VFR e especialmente os seus filhos s\u00e3o o grupo de viagem com maior morbidez em muitos estudos [7]. Os VFR representam agora 21-68% de todos os casos de mal\u00e1ria importados [8] e, de longe, o principal grupo de casos de hepatite A e febre tif\u00f3ide importados. Ao aconselhar viajantes mais velhos com comorbilidades e comedica\u00e7\u00f5es, as interac\u00e7\u00f5es com a profilaxia de viagem (por exemplo, risco de prolongamento de QTc de alguma profilaxia de mal\u00e1ria) devem ser consideradas. Em caso de diarreia e redu\u00e7\u00e3o da ingest\u00e3o de alimentos, as pessoas em terapia anti-hipertensiva ou antidiab\u00e9tica oral devem ser instru\u00eddas para ajustar esta terapia durante o per\u00edodo de dura\u00e7\u00e3o dos sintomas, pois de outra forma pode ser provocada hipotens\u00e3o ou hipoglic\u00e9mia perigosa. Devido ao risco particular de paludismo grave, as mulheres gr\u00e1vidas devem ser aconselhadas a n\u00e3o viajar para zonas end\u00e9micas de paludismo, se poss\u00edvel.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3909 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab2_HP6_s16.jpg_2162.jpg\" width=\"1100\" height=\"739\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab2_HP6_s16.jpg_2162.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab2_HP6_s16.jpg_2162-800x537.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab2_HP6_s16.jpg_2162-120x81.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab2_HP6_s16.jpg_2162-90x60.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab2_HP6_s16.jpg_2162-320x215.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Tab2_HP6_s16.jpg_2162-560x376.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/739;\" \/><\/p>\n<h2 id=\"ajudas-uteis-em-conselhos-de-viagem\">Ajudas \u00fateis em conselhos de viagem<\/h2>\n<p>H\u00e1 geralmente pouco tempo dispon\u00edvel para aconselhamento adaptado aos riscos individuais dos viajantes, raz\u00e3o pela qual o aconselhamento em viagem \u00e9 frequentemente reduzido a pura vacina\u00e7\u00e3o e aconselhamento sobre paludismo. \u00c9 \u00fatil recomendar medidas preventivas como pacotes espec\u00edficos de exposi\u00e7\u00e3o <strong>(Fig.&nbsp;2)<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3910 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb2_HP6_s13.jpg_2161.jpg\" width=\"1100\" height=\"865\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb2_HP6_s13.jpg_2161.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb2_HP6_s13.jpg_2161-800x629.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb2_HP6_s13.jpg_2161-120x94.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb2_HP6_s13.jpg_2161-90x71.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb2_HP6_s13.jpg_2161-320x252.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/06\/Abb2_HP6_s13.jpg_2161-560x440.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/865;\" \/><\/p>\n<p>Estas incluem naturalmente as recomenda\u00e7\u00f5es de vacina\u00e7\u00e3o e as medidas para prevenir a morbilidade da mal\u00e1ria, mas v\u00e3o muito al\u00e9m destas. Para que estes pacotes relacionados com a exposi\u00e7\u00e3o sejam oferecidos aos viajantes de uma forma razo\u00e1vel e eficiente, \u00e9 essencial um amplo conhecimento b\u00e1sico e uma actualiza\u00e7\u00e3o cont\u00ednua das epidemias que ocorrem em todo o mundo. Em primeiro lugar, \u00e9 \u00fatil ter uma base de dados actualizada das situa\u00e7\u00f5es epidemiol\u00f3gicas, regulamentos e recomenda\u00e7\u00f5es em fun\u00e7\u00e3o do destino e da hora da viagem. <sup>Tropimed\u00ae<\/sup>, outras bases de dados como Safetravel\u00ae ou as recomenda\u00e7\u00f5es emitidas pelo Gabinete Federal de Sa\u00fade P\u00fablica ou pelas respectivas autoridades estatais s\u00e3o recomendadas. O website ProMED mail (www.promedmail.org) fornece informa\u00e7\u00e3o geograficamente mais detalhada sobre epidemias locais. Mais material informativo pode ser fornecido ao viajante sob a forma de folhas de resumo por doen\u00e7a\/risco, devido ao tempo limitado. Al\u00e9m disso, escrevemos um pequeno folheto &#8220;Viagem Segura&#8221; (ISBN 978-3-905708-84-4), que tamb\u00e9m pode ser entregue aos viajantes. Uma lista com informa\u00e7\u00f5es pr\u00e1ticas sobre as vacinas recomendadas em medicina de viagem \u00e9 tamb\u00e9m muito \u00fatil para uma r\u00e1pida vis\u00e3o geral <strong>(Tab. 1)<\/strong>.<\/p>\n<h2 id=\"procedimento-de-betao\">Procedimento de bet\u00e3o<\/h2>\n<p>Recomendamos o aconselhamento<strong> (Fig. 2), <\/strong>que tem em conta as seguintes quatro exposi\u00e7\u00f5es principais de acordo com os riscos espec\u00edficos dos viajantes e o destino da viagem: Mordidas de artr\u00f3podes; Comida, bebida e diarreia; Contacto pessoal incl. Sexo; acidentes, mordeduras de animais e riscos especiais.<br \/>\nQuando este esquema for conclu\u00eddo, o aconselhamento estar\u00e1 completo. O foco do aconselhamento \u00e9 definido individualmente de acordo com o destino da viagem.<\/p>\n<p><strong>Mordidas de artr\u00f3podes: <\/strong>Uma protec\u00e7\u00e3o eficaz contra mosquitos, ou seja, a utiliza\u00e7\u00e3o correcta de redes mosquiteiras impregnadas, vestu\u00e1rio, bem como repelentes \u00e9 fortemente aconselhada. Para al\u00e9m da mal\u00e1ria, esta protec\u00e7\u00e3o cobre uma variedade de doen\u00e7as tais como meningoencefalite do in\u00edcio do Ver\u00e3o, febre rickettsial, dengue e febre chikungunya, febre amarela, encefalite japonesa, &#8220;Rio Ross&#8221; e outras febres maioritariamente virais. Al\u00e9m disso, \u00e9 fornecida informa\u00e7\u00e3o sobre as actividades diurnas dos artr\u00f3podes (Anopheles vs. Aedes, carra\u00e7as).<\/p>\n<p><strong>Comer\/beber e diarreia:<\/strong> Como mencionado anteriormente, a diarreia \u00e9 a queixa de sa\u00fade mais frequentemente relatada pelos viajantes. Poucos viajantes seguem o conselho cl\u00e1ssico de &#8220;cozinhar, ferver, descascar ou esquecer&#8221;, o que explica a elevada incid\u00eancia de at\u00e9 60% de diarreia dos viajantes acima mencionada. No entanto, devem ser ensinadas dicas b\u00e1sicas de higiene em qualquer caso. A antibioticoterapia de emerg\u00eancia pode ser administrada a viajantes idosos e viajantes de qualquer idade com doen\u00e7a gastrointestinal ou imunossupress\u00e3o subjacente pr\u00e9-existente. Actualmente, as quinolonas para a \u00c1frica e a azitromicina para a \u00c1sia e Am\u00e9rica Latina s\u00e3o esses medicamentos, embora o r\u00e1pido aumento da resist\u00eancia das bact\u00e9rias patog\u00e9nicas intestinais a n\u00edvel mundial esteja a p\u00f4r em causa a efic\u00e1cia da terapia antibi\u00f3tica de emerg\u00eancia. Nesta altura, a indica\u00e7\u00e3o para a vacina\u00e7\u00e3o contra a hepatite A e a febre tif\u00f3ide pode ser discutida.<\/p>\n<p><strong>Contacto pessoa-a-pessoa, sexo: <\/strong>A vacina\u00e7\u00e3o combinada para a hepatite A e B facilita a transi\u00e7\u00e3o para o tema das doen\u00e7as sexualmente transmiss\u00edveis: &#8220;Fal\u00e1mos agora da hepatite infecciosa de icter\u00edcia A, que \u00e9 transmitida atrav\u00e9s da alimenta\u00e7\u00e3o e da bebida. Outra icter\u00edcia ainda mais perigosa, a hepatite B, \u00e9 principalmente transmitida sexualmente&#8221;.<\/p>\n<p>O risco de doen\u00e7as sexualmente transmiss\u00edveis \u00e9 elevado entre os viajantes. 20% dos viajantes relatam novos contactos sexuais nas suas viagens, dos quais 49% n\u00e3o utilizaram preservativos [9]. Vale tamb\u00e9m a pena mencionar que 34% de todos os novos diagn\u00f3sticos de VIH entre heterossexuais su\u00ed\u00e7os e 19% dos mesmos entre homossexuais s\u00e3o adquiridos no estrangeiro [10].<\/p>\n<p>Outras doen\u00e7as tamb\u00e9m podem ser transmitidas de pessoa para pessoa fora do contacto sexual. A indica\u00e7\u00e3o de vacinas apropriadas tais como sarampo, caxumba, varicela, tosse convulsa, meningite meningoc\u00f3cica, gripe e pneumococo pode ser discutida neste contexto. A oportunidade de recuperar ou completar a vacina\u00e7\u00e3o b\u00e1sica com MMR pode ser utilizada aqui com particular \u00eanfase &#8211; especialmente tendo em conta que a Su\u00ed\u00e7a \u00e9 um importante pa\u00eds exportador de sarampo. Esta &#8220;actividade de exporta\u00e7\u00e3o&#8221;, especialmente para pa\u00edses mais pobres, \u00e9 vergonhosa, uma vez que o sarampo conduz frequentemente a cursos particularmente severos na popula\u00e7\u00e3o local.<\/p>\n<p><strong>Acidentes, mordeduras de animais e riscos especiais: <\/strong>Acidentes, queimaduras solares e doen\u00e7as de altitude s\u00e3o causas comuns de morbidez durante a viagem. Como mencionado acima, os acidentes s\u00e3o tamb\u00e9m a principal causa de morte durante as viagens tropicais entre os viajantes mais jovens. Os viajantes s\u00e3o aqui encorajados a escolher a op\u00e7\u00e3o de viagem mais segura em caso de d\u00favida e a interromper a viagem se necess\u00e1rio, se o condutor mostrar um estilo de condu\u00e7\u00e3o arriscado.<\/p>\n<p>A exposi\u00e7\u00e3o potencial \u00e0 raiva atrav\u00e9s de picadas de animais n\u00e3o \u00e9 incomum e a imuniza\u00e7\u00e3o contra a raiva pr\u00e9-exposi\u00e7\u00e3o \u00e9 indicada para viagens prolongadas a \u00e1reas de alta endemia de raiva. Nesta parte do aconselhamento, \u00e9 tamb\u00e9m avaliada a cobertura da vacina\u00e7\u00e3o contra o t\u00e9tano e a difteria.<\/p>\n<h2 id=\"resumo\">Resumo<\/h2>\n<p>O aconselhamento de viagens com base na exposi\u00e7\u00e3o \u00e9 eficiente e permite uma consulta individualizada e compreens\u00edvel. Um esquema gr\u00e1fico simples garante a integralidade e uniformidade do aconselhamento e revela-se especialmente \u00fatil nas pr\u00e1ticas em que mais de uma pessoa est\u00e1 envolvida no aconselhamento de viagens.<\/p>\n<p><em><strong>Cornelia Staehelin, MD<\/strong><\/em><\/p>\n<h4 id=\"conclusao-para-a-pratica\">CONCLUS\u00c3O PARA A PR\u00c1TICA<\/h4>\n<ul>\n<li>Os viajantes para os seus pa\u00edses de origem (&#8220;visitar amigos e familiares&#8221;) s\u00e3o menos propensos a procurar aconselhamento antes da viagem, mas s\u00e3o mais propensos a contrair mal\u00e1ria, febre tif\u00f3ide ou hepatite A.<\/li>\n<li>Para al\u00e9m dos conselhos habituais de viagem, os viajantes idosos devem receber conselhos especiais sobre medidas de comportamento em caso de poss\u00edveis complica\u00e7\u00f5es das suas doen\u00e7as subjacentes durante a viagem.<\/li>\n<li>Os viajantes mais jovens est\u00e3o particularmente em risco de complica\u00e7\u00f5es relacionadas com acidentes.<\/li>\n<li>Sexo em viagem: as regras de sexo seguro s\u00e3o frequentemente deixadas em casa durante a viagem &#8211; 20% dos viajantes t\u00eam um novo parceiro sexual durante a viagem; os preservativos n\u00e3o s\u00e3o utilizados em metade destes contactos.<\/li>\n<\/ul>\n<h4 id=\"um-retenir\"><em>UM RETENIR<\/em><\/h4>\n<ul>\n<li><em>Les voyageurs qui se d\u00e9placent vers leurs pays d&#8217;origine (&#8221; visitar amigos e familiares &#8220;) sont ceux qui consultent le moins souvent avant le voyage, but souffrent le plus fr\u00e9quemment de mal\u00e1ria, de typhus ou d&#8217;h\u00e9patite A.<\/em><\/li>\n<li><em>Les voyageurs plus \u00e2g\u00e9s doivent b\u00e9n\u00e9ficier d&#8217;un conseil particulier en plus de la consultation de voyage classique en raison des conduites \u00e0 tenir en cas d&#8217;\u00e9ventuelles complications de leurs maladies pr\u00e9existantes en voyage.<\/em><\/li>\n<li><em>Les jeunes voyageurs sont particuli\u00e8rement \u00e0 risque de souffrir de complications li\u00e9es \u00e0 un accident.<\/em><\/li>\n<li><em>Sexualidade na estrada: as regras de prud\u00eancia sobre sexualidade s\u00e3o frequentemente ignoradas em casa durante uma viagem &#8211; 20% dos viajantes encontram um novo parceiro sexual na estrada; metade destes contactos t\u00eam lugar sem protec\u00e7\u00e3o.<\/em><\/li>\n<\/ul>\n<h4 id=\"literatura\">Literatura:<\/h4>\n<ol>\n<li>Leder K, et al: Travel-associated illness trends and clusters, 2000-2010. Emerg Emerg Infect Dis 2013; 19(7): 1049-1073.<\/li>\n<li>Instituto Estat\u00edstico Federal Su\u00ed\u00e7o: Viagens da popula\u00e7\u00e3o su\u00ed\u00e7a residente&nbsp; 2012.<\/li>\n<li>Gabinete Federal de Sa\u00fade P\u00fablica: Schweizerischer Impfplan 2014.<\/li>\n<li>Steffen R, Amitirigala I, Mutsch M: Riscos para a sa\u00fade entre os viajantes &#8211; necessidade de actualiza\u00e7\u00f5es regulares. J Travel Med 2008; 15(3): 145-146.<\/li>\n<li>Gautret P, et al.: Doen\u00e7a associada \u00e0 viagem em adultos mais velhos (&gt;60 y). J Travel Med 2012; 19(3): 169-177.<\/li>\n<li>Pawun V, et al: Mortality among foreign nationals in Chiang Mai City, Thailand, 2010 to 2011. J Travel Med 2012; 19(6): 334-351.<\/li>\n<li>Behrens R, Barnett ED: Visiting Friends and Relatives. In: Keystone J (ed.): Medicina de Viagens.<sup>2\u00aa<\/sup> ed. Mosby Elsevier 2008; 292-298.<\/li>\n<li>Pavli A, Maltezou HC: Mal\u00e1ria e viajantes que visitam amigos e familiares. Travel Med Infect Dis 2010; 8(3): 161-168.<\/li>\n<li>Vivancos R, Abubakar I, Hunter PR: viagens ao estrangeiro, sexo casual, e infec\u00e7\u00f5es sexualmente transmiss\u00edveis: revis\u00e3o sistem\u00e1tica e meta-an\u00e1lise. Int J Infect Dis 2010; 14(10): e842-e851.<\/li>\n<li>Departamento Federal de Sa\u00fade P\u00fablica Sec\u00e7\u00e3o VIH e SIDA: Estat\u00edsticas e an\u00e1lises do VIH e das IST 2012. 27-5-2013.<\/li>\n<\/ol>\n<p><em>PR\u00c1TICA DO GP 2014; 9(6): 12-18<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As viagens est\u00e3o a aumentar constantemente em todo o mundo: enquanto em 1970 havia 150 milh\u00f5es de chegadas tur\u00edsticas, este n\u00famero aumentou para mais de 940 milh\u00f5es em 2010 [1].&hellip;<\/p>\n","protected":false},"author":4,"featured_media":44057,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Medicina de viagem","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11344,11453,11524,11421,11501,11551],"tags":[50941,52929,15818,13516,46808,52948,19241,52939,16879,52934,18461,52943,52925,18456],"powerkit_post_featured":[],"class_list":["post-345240","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alergologia-e-imunologia-clinica","category-farmacologia-e-toxicologia","category-formacao-continua","category-infecciologia","category-medicina-tropical-e-de-viagem","category-rx-pt","tag-dengue-pt-pt","tag-diarreia-do-viajante-pt-pt","tag-hepatite-pt-pt","tag-influenza-pt-pt","tag-medicina-de-viagem","tag-mordedura-de-animais","tag-paludismo","tag-picada-de-artropodes","tag-raiva","tag-risco-de-raiva","tag-sida-pt-pt","tag-tifo-pt-pt","tag-vacinacao-basica","tag-vih-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:05:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":345243,"slug":"practica-de-la-consulta-de-medicina-del-viajero","post_title":"Pr\u00e1ctica de la consulta de medicina del viajero","href":"https:\/\/medizinonline.com\/es\/practica-de-la-consulta-de-medicina-del-viajero\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/345240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=345240"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/345240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/44057"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=345240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=345240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=345240"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=345240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}