{"id":347217,"date":"2013-09-19T00:00:00","date_gmt":"2013-09-18T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/o-stress-responsavel-pelas-perturbacoes-uni-e-bipolares\/"},"modified":"2013-09-19T00:00:00","modified_gmt":"2013-09-18T22:00:00","slug":"o-stress-responsavel-pelas-perturbacoes-uni-e-bipolares","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/o-stress-responsavel-pelas-perturbacoes-uni-e-bipolares\/","title":{"rendered":"O stress respons\u00e1vel pelas perturba\u00e7\u00f5es uni e bipolares"},"content":{"rendered":"<p><strong>Nos \u00faltimos 20-30 anos, novos conhecimentos t\u00eam sido continuamente adquiridos sobre mecanismos que podem levar a uma desordem afectiva. O foco est\u00e1 nos mecanismos neurobiol\u00f3gicos nos quais o stress cr\u00f3nico desempenha um papel central. No congresso deste ano da Federa\u00e7\u00e3o Su\u00ed\u00e7a das Neurociedades Cl\u00ednicas (SFCNS), peritos da investiga\u00e7\u00e3o b\u00e1sica e cl\u00ednica relataram as \u00faltimas descobertas relativas ao desenvolvimento da depress\u00e3o e da desordem bipolar. No campo da EM, os testes cl\u00ednicos de v\u00e1rias subst\u00e2ncias novas j\u00e1 est\u00e3o bem avan\u00e7ados. Isto tamb\u00e9m foi discutido em Montreux.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>tress leva a uma activa\u00e7\u00e3o do eixo HPA (hipot\u00e1lamo-hip\u00f3fise-adrenal) e \u00e0 liberta\u00e7\u00e3o de hormonas de stress. O eixo HPA \u00e9 normalmente desacelerado novamente atrav\u00e9s de um mecanismo de feedback negativo e a liberta\u00e7\u00e3o de hormonas \u00e9 estrangulada. Em indiv\u00edduos predispostos, este mecanismo de feedback falha e o eixo HPA permanece permanentemente activado.<\/p>\n<h2 id=\"depressao-a-hipotese-da-rede\">Depress\u00e3o &#8211; a hip\u00f3tese da rede<\/h2>\n<p>Em contraste com teorias anteriores, segundo as quais a depress\u00e3o \u00e9 supostamente causada por um desequil\u00edbrio neuroqu\u00edmico, assume-se agora que a depress\u00e3o se baseia em perturba\u00e7\u00f5es dos processos de informa\u00e7\u00e3o em certas redes neuronais (hip\u00f3tese de rede de depress\u00e3o) [1]. &#8220;Se expomos os animais ao stress cr\u00f3nico, eles desenvolvem dist\u00farbios cognitivos, padr\u00f5es de comportamento semelhantes \u00e0 depress\u00e3o e ansiedade&#8221;, diz a Professora Carmen Sandi, MD, Lausanne. A n\u00edvel molecular, as Mol\u00e9culas de Ades\u00e3o de C\u00e9lulas Neurais (NCAM) parecem ser importantes mediadores dos efeitos do stress sobre o c\u00e9rebro. Em experi\u00eancias em animais com roedores expostos a stress cr\u00f3nico, Sandi e colegas encontraram atrofia do hipocampo e altera\u00e7\u00f5es estruturais no c\u00f3rtex pr\u00e9-frontal e am\u00edgdala com as correspondentes altera\u00e7\u00f5es funcionais. Ao mesmo tempo, encontraram padr\u00f5es alterados de express\u00e3o do NCAM, sugerindo que estas mol\u00e9culas desempenham um papel fundamental no desenvolvimento de danos neuronais induzidos pelo stress e na neuroprotec\u00e7\u00e3o [2\u20134]. As NCAMs poderiam assim tornar-se o alvo de uma nova abordagem ao tratamento da depress\u00e3o. &#8220;Al\u00e9m disso, uma estrutura de personalidade caracterizada por forte ansiedade, bem como experi\u00eancias stressantes antes da puberdade parecem aumentar a vulnerabilidade a situa\u00e7\u00f5es stressantes e assim predispor para o desenvolvimento da depress\u00e3o. A preven\u00e7\u00e3o seria, portanto, muito importante aqui&#8221;, diz o Prof. Sandi [5].<\/p>\n<h2 id=\"imagens-em-disturbios-de-depressao-e-ansiedade\">Imagens em dist\u00farbios de depress\u00e3o e ansiedade<\/h2>\n<p>Embora se saiba agora muito sobre os mecanismos que levam \u00e0 depress\u00e3o, n\u00e3o se pode estabelecer qualquer liga\u00e7\u00e3o entre o fen\u00f3tipo cl\u00ednico da doen\u00e7a e o gen\u00f3tipo. Com a ajuda de t\u00e9cnicas de imagem (por exemplo, tomografia por emiss\u00e3o de positr\u00f5es, espectroscopia de resson\u00e2ncia magn\u00e9tica, resson\u00e2ncia magn\u00e9tica funcional), espera-se que diferentes endofen\u00f3tipos possam ser utilizados para melhor definir fen\u00f3tipos cl\u00ednicos e desenvolver novos tratamentos \u00e0 medida [6]. &#8220;A imagem \u00e9 importante para poder fazer uma liga\u00e7\u00e3o entre os genes, os processos bioqu\u00edmicos, os sistemas funcionais, o endofen\u00f3tipo e o fen\u00f3tipo cl\u00ednico. Precisamos de imagens para podermos traduzir os alvos identificados nos seres humanos em modelos animais ou, inversamente, os comportamentos disfuncionais nos animais em investiga\u00e7\u00e3o cl\u00ednica&#8221;, explicou o Prof. Erich Seifritz, MD, Zurique. Os primeiros a trabalhar com imagens foram Drevets et al. que foram capazes de mostrar com a ajuda de PET que os pacientes com depress\u00e3o mostraram altera\u00e7\u00f5es metab\u00f3licas significativas e circunscritas e altera\u00e7\u00f5es espec\u00edficas que estavam ausentes em pessoas sem depress\u00e3o [7]. Alguns anos mais tarde, Pezawas et al. descobriram mudan\u00e7as estruturais em pessoas sem depress\u00e3o mas com uma constela\u00e7\u00e3o de risco gen\u00e9tico e um polimorfismo funcional do gene transportador de serotonina que n\u00e3o foram encontradas em pessoas que n\u00e3o eram portadoras deste polimorfismo [8]. Esta \u00e9 a primeira vez que se identifica um endofen\u00f3tipo que est\u00e1 associado a um risco acrescido de doen\u00e7a, mas sem manifesta\u00e7\u00f5es cl\u00ednicas. Outro exemplo \u00e9 o trabalho de Sheline et al. que utilizaram a RM funcional para mostrar que os pacientes com grande depress\u00e3o t\u00eam uma conectividade muito mais densa do nexo dorsal com \u00e1reas cerebrais diferentes dos indiv\u00edduos saud\u00e1veis [9]. &#8220;Com base nestes resultados, descobrimos no nosso pr\u00f3prio estudo com volunt\u00e1rios saud\u00e1veis que a cetamina, um forte antidepressivo, reduz significativamente a conectividade no nexo dorsal&#8221;, diz o Prof. Seifritz.  [10].<br \/>\nOutro artigo interessante \u00e9 o de Rubeis et al. que encontraram altera\u00e7\u00f5es id\u00eanticas na actividade e inactividade em certas \u00e1reas do c\u00e9rebro em pacientes tratados com sucesso com depress\u00e3o, independentemente de ter sido feita farmacoterapia ou terapia cognitiva comportamental [11]. &#8220;Esperamos que os conhecimentos que obtivermos da investiga\u00e7\u00e3o com t\u00e9cnicas de imagem abram possibilidades de tratar a doen\u00e7a muito heterog\u00e9nea da depress\u00e3o, mais especificamente no futuro&#8221;, concluiu o Prof. Seifritz.<\/p>\n<h2 id=\"perturbacao-bipolar-uma-perturbacao-multissistemica\">Perturba\u00e7\u00e3o bipolar:&nbsp;uma perturba\u00e7\u00e3o multissist\u00e9mica?<\/h2>\n<p>As perturba\u00e7\u00f5es bipolares s\u00e3o relativamente comuns com uma preval\u00eancia de 2-3% e normalmente come\u00e7am na adolesc\u00eancia ou na idade adulta jovem. Recentemente, tem sido defendido que a doen\u00e7a bipolar deve ser vista como parte de uma doen\u00e7a multi-sist\u00e9mica [12]. De acordo com esta teoria, v\u00e1rios mecanismos levam \u00e0 imuno-inflama\u00e7\u00e3o cerebral e perif\u00e9rica, o que por sua vez pode desencadear dist\u00farbios bipolares, mas tamb\u00e9m diabetes, obesidade, hipertens\u00e3o e doen\u00e7as cerebro-vasculares<strong>(Fig. 1<\/strong>). &#8220;Um dos mecanismos centrais que conduzem a esta inflama\u00e7\u00e3o imunol\u00f3gica \u00e9 o stress&#8221;, diz o Prof. Jean-Michel Aubry, MD, Genebra. Sabe-se que o stress \u00e9 um factor ambiental que desencadeia tanto epis\u00f3dios depressivos como man\u00edacos, e que os eventos com elevados n\u00edveis de stress s\u00e3o os mais fortes preditores de reca\u00edda.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-1986\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as1.png-bbd66b_711.png\" width=\"1100\" height=\"711\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as1.png-bbd66b_711.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as1.png-bbd66b_711-800x517.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as1.png-bbd66b_711-120x78.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as1.png-bbd66b_711-90x58.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as1.png-bbd66b_711-320x207.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as1.png-bbd66b_711-560x362.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>A vulnerabilidade ao stress varia muito de indiv\u00edduo para indiv\u00edduo e depende de factores cognitivos, familiares e gen\u00e9ticos. Curiosamente, com o aumento da idade, o stress aumenta cada vez menos o risco de desenvolvimento da desordem bipolar, raz\u00e3o pela qual se assume que existe uma janela temporal cr\u00edtica em que o stress leva a altera\u00e7\u00f5es cerebrais que podem resultar em desordem bipolar [13, 14]. Tal como na depress\u00e3o unipolar, o eixo HPA tamb\u00e9m \u00e9 sobreactivado nas desordens bipolares. A desregula\u00e7\u00e3o permanente do eixo HPA em pacientes em remiss\u00e3o indica um risco mais elevado de reca\u00edda.<\/p>\n<p>Estudos epidemiol\u00f3gicos mostram que os descendentes de pais com perturba\u00e7\u00f5es afectivas t\u00eam um risco acrescido de desenvolver eles pr\u00f3prios uma perturba\u00e7\u00e3o afectiva ou de ansiedade [15]. Nessas crian\u00e7as e adolescentes, os n\u00edveis elevados de cortisol indicam perturba\u00e7\u00f5es ligeiras do eixo HPA, que podem aumentar a susceptibilidade \u00e0 desordem bipolar [16].<br \/>\nEm doentes com doen\u00e7a bipolar, s\u00e3o encontrados n\u00edveis elevados de IL-6 e TNF-\u03b1 em fases iniciais da doen\u00e7a e durante epis\u00f3dios depressivos e man\u00edacos [17, 18]. O sistema imunit\u00e1rio pode mesmo ser activado antes do in\u00edcio da doen\u00e7a. Se estas anomalias imunol\u00f3gicas em indiv\u00edduos em risco coincidem com perturba\u00e7\u00f5es do eixo HPA ainda n\u00e3o \u00e9 conhecido. &#8220;Em resumo, tanto os factores gen\u00e9ticos como ambientais (stress psicol\u00f3gico) contribuem para a neuroend\u00f3crina e a vulnerabilidade imunol\u00f3gica, o que aumenta o risco de desordem bipolar, mas tamb\u00e9m de doen\u00e7as inflamat\u00f3rias&#8221;, diz o Prof. Aubry [18].<\/p>\n<h2 id=\"novas-substancias-para-esclerose-multipla\">Novas subst\u00e2ncias para esclerose m\u00faltipla<\/h2>\n<p>A esclerose m\u00faltipla (EM) \u00e9 um dos t\u00f3picos que n\u00e3o pode faltar em nenhum evento de orienta\u00e7\u00e3o neurol\u00f3gica, e Montreux n\u00e3o \u00e9 excep\u00e7\u00e3o. Nos \u00faltimos anos, a investiga\u00e7\u00e3o intensiva neste campo levou, entre outras coisas, a que novas op\u00e7\u00f5es terap\u00eauticas se tornassem dispon\u00edveis. Os ensaios cl\u00ednicos de dois outros medicamentos, teriflunomida e alemtuzumab, j\u00e1 est\u00e3o bem avan\u00e7ados. Teriflunomida, dispon\u00edvel em forma oral, \u00e9 um metabolito activo da leflunomida [19]. A Leflunomida mostrou efeitos anti-inflamat\u00f3rios em v\u00e1rios modelos animais de doen\u00e7as auto-imunes, incluindo encefalomielite auto-imune experimental (EAE). A teriflunomida causa uma inibi\u00e7\u00e3o da dihidroorotate desidrogenase (DHODH), uma enzima importante na neoss\u00edntese da pirimidina. Reduz assim a expans\u00e3o clonal dos linf\u00f3citos activados e a actividade inflamat\u00f3ria na EM.<\/p>\n<h2 id=\"temso-e-tower\">TEMSO e TOWER<\/h2>\n<p>O ensaio TEMSO fase III comparou duas doses diferentes de teriflunomida (7 ou 14 mg) com placebo em 1088 doentes com EM recorrente (RRMS) [20]. Isto mostrou uma redu\u00e7\u00e3o da taxa de reca\u00edda de 31,2 e 31,5% respectivamente (p&lt;0,001) e uma redu\u00e7\u00e3o significativa do risco de progress\u00e3o da incapacidade de 29,8% para a dose de 14 mg (p=0,03). Os efeitos secund\u00e1rios mais comuns registados foram a diarreia e n\u00e1useas, um desbaste tempor\u00e1rio do cabelo e um ligeiro aumento nos valores hep\u00e1ticos. No entanto, os efeitos secund\u00e1rios raramente levaram \u00e0 interrup\u00e7\u00e3o da terapia. A fase de extens\u00e3o dose-blinded do TEMSO, com 68% da popula\u00e7\u00e3o original do estudo, mostrou um efeito sustentado do tratamento teriflunom\u00eddico nos par\u00e2metros cl\u00ednicos e de resson\u00e2ncia magn\u00e9tica durante um per\u00edodo de cinco anos ap\u00f3s a aleatoriza\u00e7\u00e3o inicial [21].<\/p>\n<p>TOWER tamb\u00e9m comparou duas doses de monoterapia teriflunomida com placebo [22]. A dose de 14 mg reduziu a taxa anual de recidivas (ARR) versus placebo em 36,6% (p&lt;0,001) e a progress\u00e3o da incapacidade confirmada ao longo de pelo menos 12 semanas em 31,5% (p=0,044).<\/p>\n<h2 id=\"destruicao-selectiva-de-celulas-b-e-t\">Destrui\u00e7\u00e3o selectiva de c\u00e9lulas B e T<\/h2>\n<p>O anticorpo monoclonal selectivo anti-CD52 alemtuzumab leva \u00e0 destrui\u00e7\u00e3o selectiva de linf\u00f3citos T e B atrav\u00e9s de citotoxicidade anti-corpo dependente e lise celular completa [23]. Nos dois estudos CARE-MS I e II, alemtuzumab provou ser superior ao interferon beta-1a s.c. [24, 25]. O tratamento resultou numa redu\u00e7\u00e3o da actividade cl\u00ednica da doen\u00e7a (redu\u00e7\u00e3o do risco de reca\u00edda de 54,9% na CARE-MS I e 49,4% na CARE-MS II), mas tamb\u00e9m levou a uma taxa consider\u00e1vel de doen\u00e7a auto-imune secund\u00e1ria (16-19% de tiroidite auto-imune, 1% de trombocitopenia imune). As doen\u00e7as da tir\u00f3ide eram, na maioria dos casos, trat\u00e1veis por medica\u00e7\u00e3o oral convencional. A trombocitopenia imune tamb\u00e9m respondeu r\u00e1pida e persistentemente ao tratamento de primeira linha.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1987 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as3.png-eb1405_713.png\" width=\"1100\" height=\"1844\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as3.png-eb1405_713.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as3.png-eb1405_713-800x1341.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as3.png-eb1405_713-120x201.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as3.png-eb1405_713-90x151.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as3.png-eb1405_713-320x536.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2013\/09\/as3.png-eb1405_713-560x939.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1844;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><em>Fonte:<sup>2\u00ba<\/sup> Congresso SFCNS &#8211; Federa\u00e7\u00e3o Su\u00ed\u00e7a de Neuroci\u00eancias Cl\u00ednicas, 5-7 de Junho de 2013, Montreux<\/em><br \/>\n&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Castr\u00e9n E: Nat Rev Neurosci 2005; 6: 241-246.<\/li>\n<li>Sandi C: Nat Rev Neurosci 2004; 5: 917-930.<\/li>\n<li>Sandi C, Bisaz R: Neuroendocrinologia 2007; 85: 158-176.<\/li>\n<li>Bisaz R, Sandi C: Genes Brain Behav 2010; 9: 353-364.<\/li>\n<li>Sandi C, Richter-Levin G: Trends Neurosci 2009; 32: 312-320.<\/li>\n<li>Hasler G, Northoff G: Mol Psychiatry 2011; 16: 604-619.<\/li>\n<li>Drevets WC, et al: Science 1992; 256: 1696.<\/li>\n<li>Pezawas L, et al: Nat Neurosci 2005; 8: 828-834.<\/li>\n<li>Sheline YI, et al: Proc Natl Acad Sci 2010; 107: 11020-11025.<\/li>\n<li>Scheidegger M, et al: PLoS One 2012; 7: e44799.<\/li>\n<li>De Rubeis RJ, et al: Nat Rev Neurosci 2008; 9: 788-796.<\/li>\n<li>Leboyer M, et al: J Affect Disord 2012; 141: 1-10.<\/li>\n<li>Lupien SJ, et al: Nat Rev Neurosci 2009; 10: 434-445.<\/li>\n<li>Hillegers MH, et al: Br J Psychiatry 2004; 185: 97-101.<\/li>\n<li>Vandeleur C, et al: Bipolar Disord 2012; 14: 641-653.<\/li>\n<li>Ellenbogen MA, et al: Bipolar Disord 2010; 12: 77-86.<\/li>\n<li>Kauer-Sant&#8217;Anna M, et al: Int J Neuropsychopharmacol 2009; 12: 447-458.<\/li>\n<li>Duffy A, et al: Early Interv Psychiatry 2012; 6: 128-137.<\/li>\n<li>Papadopoulou A, et al: Expert Rev Clin Pharmacol 2012; 5: 617-628.<\/li>\n<li>O&#8217;Connor PW, et al: N Engl J Med 2011; 365: 1293-1303.<\/li>\n<li>O&#8217;Connor P, et al: Mult Scler 2011; 17, P924.<\/li>\n<li>Miller A, et al: Neurology 2013; 80(Annual Meeting Abstracts). S01.004.<\/li>\n<li>Wiendl H, Kieseier B: Nat Rev Neurol 2013; 9: 125-126.<\/li>\n<li>Cohen JA, et al: Lancet 2012; 380: 1819-1828.<\/li>\n<li>Coles AJ, et al: Lancet 2012; 380: 1829-1839.<\/li>\n<li>Pryce CR, Seifritz E: Psychoneuroendocrinology 2011; 36: 308-329.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Nos \u00faltimos 20-30 anos, novos conhecimentos t\u00eam sido continuamente adquiridos sobre mecanismos que podem levar a uma desordem afectiva. O foco est\u00e1 nos mecanismos neurobiol\u00f3gicos nos quais o stress cr\u00f3nico&hellip;<\/p>\n","protected":false},"author":4,"featured_media":35046,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Congresso SFCNS em Montreux","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11374,11529,11551],"tags":[34308,14717,61549,12313,61569,15572,12325,13349,61546,61577,61593,61583,61561,27354,12441,34204,16990,17258,61588,13906,27847,17107],"powerkit_post_featured":[],"class_list":["post-347217","post","type-post","status-publish","format-standard","has-post-thumbnail","category-neurologia-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-alemtuzumab-pt-pt","tag-depressao","tag-desordem-uni-bipolar","tag-diabetes-mellitus-pt-pt","tag-eixo-hpa","tag-em","tag-esclerose-multipla","tag-hipertensao-arterial","tag-hormim","tag-hypothalamus-pituitary-adrenal","tag-il-6-alfa","tag-imuno-inflamacao-cerebral-e-periferica","tag-mecanismo-neurobiologico","tag-mri-pt-pt-2","tag-obesidade","tag-pet-pt-pt","tag-risco","tag-stress-pt-pt","tag-stress-oxidativo","tag-teriflunomida-pt-pt","tag-tnf-alpha-pt-pt","tag-transtorno-de-ansiedade","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 02:26:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":347233,"slug":"el-estres-responsable-de-los-trastornos-uni-y-bipolares","post_title":"El estr\u00e9s, responsable de los trastornos uni y bipolares","href":"https:\/\/medizinonline.com\/es\/el-estres-responsable-de-los-trastornos-uni-y-bipolares\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/347217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=347217"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/347217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/35046"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=347217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=347217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=347217"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=347217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}