{"id":350678,"date":"2023-02-06T01:00:00","date_gmt":"2023-02-06T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/dicas-e-truques-no-treino-do-gp\/"},"modified":"2024-09-19T10:55:35","modified_gmt":"2024-09-19T08:55:35","slug":"dicas-e-truques-no-treino-do-gp","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/dicas-e-truques-no-treino-do-gp\/","title":{"rendered":"Dicas e truques no treino do GP"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A insufici\u00eancia card\u00edaca \u00e9 um problema crescente na Su\u00ed\u00e7a, tal como no resto do mundo industrializado, porque a incid\u00eancia de insufici\u00eancia card\u00edaca aumenta com a idade e h\u00e1 cada vez mais pessoas idosas. Por outro lado, as op\u00e7\u00f5es de tratamento t\u00eam aumentado significativamente nos \u00faltimos 20 anos. Que dicas e truques podem tornar o tratamento mais f\u00e1cil?<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n\n\n<p class=\"wp-block-paragraph\">A insufici\u00eancia card\u00edaca \u00e9 um problema crescente na Su\u00ed\u00e7a, tal como no resto do mundo industrializado, porque a incid\u00eancia de insufici\u00eancia card\u00edaca aumenta com a idade e h\u00e1 cada vez mais pessoas idosas. Por outro lado, as op\u00e7\u00f5es de tratamento t\u00eam aumentado significativamente nos \u00faltimos 20 anos. Foram introduzidas mais de cinco classes de medicamentos que reduzem significativamente a mortalidade e as hospitaliza\u00e7\u00f5es. Existem tamb\u00e9m novas t\u00e9cnicas de tratamento baseadas em cateteres para doen\u00e7as card\u00edacas valvulares e avan\u00e7os no tratamento invasivo das arritmias card\u00edacas, bem como novos desenvolvimentos em dispositivos de assist\u00eancia ventricular. A perspectiva de um doente quando diagnosticado pela primeira vez com insufici\u00eancia card\u00edaca \u00e9 muito melhor hoje do que h\u00e1 alguns anos atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste artigo, n\u00e3o \u00e9 nosso objectivo repetir as orienta\u00e7\u00f5es do CES sobre este tema [1]. Em vez disso, queremos entrar em dicas e truques que podem facilitar o tratamento de pacientes com insufici\u00eancia card\u00edaca no consult\u00f3rio do m\u00e9dico de fam\u00edlia.<\/p>\n\n\n\n<h3 id=\"definicao-e-diagnostico\" class=\"wp-block-heading\"><strong>Defini\u00e7\u00e3o e diagn\u00f3stico<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A insufici\u00eancia card\u00edaca \u00e9 definida como um desajuste entre a fun\u00e7\u00e3o do cora\u00e7\u00e3o e as exig\u00eancias que lhe s\u00e3o impostas. Nos \u00faltimos anos, surgiram muitas abreviaturas que tornaram bastante dif\u00edcil a compreens\u00e3o das listas de diagn\u00f3sticos. Na realidade, a insufici\u00eancia card\u00edaca pode ser dividida em duas grandes categorias. Primeiro, insufici\u00eancia card\u00edaca com fun\u00e7\u00e3o sist\u00f3lica ventricular <em> preservada <\/em>(a <em> frac\u00e7\u00e3o de <\/em>ejec\u00e7\u00e3o <em>) (HFpEF <\/em>) e, segundo, insufici\u00eancia card\u00edaca com fun\u00e7\u00e3o sist\u00f3lica reduzida <em>(HFrEF<\/em> ). Esta distin\u00e7\u00e3o \u00e9 muito importante, pois os conceitos terap\u00eauticos em ambos os grupos s\u00e3o fundamentalmente diferentes e t\u00eam sido pesquisados separadamente [1]. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m a mencionar aqui s\u00e3o a insufici\u00eancia card\u00edaca com Fra\u00e7\u00e3o de Eje\u00e7\u00e3o moderadamente reduzida (HFmrEF), esta demarca\u00e7\u00e3o adicional existe principalmente para fins de investiga\u00e7\u00e3o, e a insufici\u00eancia card\u00edaca com Fra\u00e7\u00e3o de Eje\u00e7\u00e3o recuperada (HFrecEF) [2] para pacientes com uma normaliza\u00e7\u00e3o da fun\u00e7\u00e3o ventricular sist\u00f3lica ap\u00f3s uma restri\u00e7\u00e3o inicial (Tab. 1).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2158\" height=\"728\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13.png\" alt=\"\" class=\"wp-image-349143\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13.png 2158w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-800x270.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-1160x391.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-2048x691.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-120x40.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-90x30.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-320x108.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-560x189.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-1920x648.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-240x81.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-180x61.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-640x216.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-1120x378.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab1_HP1_s13-1600x540.png 1600w\" sizes=\"(max-width: 2158px) 100vw, 2158px\" \/><\/a><\/figure>\n\n\n\n<h3 id=\"etologia-da-insuficiencia-cardiaca\" class=\"wp-block-heading\">Etologia da insufici\u00eancia card\u00edaca<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Uma vez feito o diagn\u00f3stico de insufici\u00eancia card\u00edaca, a etiologia deve ser identificada. Embora o tratamento b\u00e1sico das v\u00e1rias causas de insufici\u00eancia card\u00edaca n\u00e3o seja, na sua maioria, diferente, s\u00e3o propostos diferentes tratamentos (por exemplo, a revasculariza\u00e7\u00e3o das doen\u00e7as card\u00edacas isqu\u00e9micas), medidas preventivas ou rastreio familiar espec\u00edfico, dependendo da etiologia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13.png\"><img decoding=\"async\" width=\"2145\" height=\"1637\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13.png\" alt=\"\" class=\"wp-image-349144 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13.png 2145w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-800x611.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-1160x885.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-2048x1563.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-120x92.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-90x68.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-320x244.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-560x427.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-1920x1465.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-240x183.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-180x136.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-640x488.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-1120x855.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab2_HP1_s13-1600x1221.png 1600w\" data-sizes=\"(max-width: 2145px) 100vw, 2145px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2145px; --smush-placeholder-aspect-ratio: 2145\/1637;\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">As directrizes do CES [1] fornecem uma lista abrangente de etiologias e as investiga\u00e7\u00f5es adicionais necess\u00e1rias para as diagnosticar. Compilando 18 estudos-chave sobre este t\u00f3pico (Tab. 2), cerca de 70% dos pacientes sofrem de cardiopatias isqu\u00e9micas, 20% de cardiopatias dilatadas de origem indeterminada e os restantes 10% de cardiopatias p\u00f3s-miocardite, alco\u00f3licas, valvulares, diab\u00e9ticas, t\u00f3xicas (principalmente relacionadas com a quimioterapia) ou cardiopatias p\u00f3s-parto. A ecocardiografia transtor\u00e1cica seguida de angiografia coron\u00e1ria, complementada por resson\u00e2ncia magn\u00e9tica, se negativa, em conjunto com uma hist\u00f3ria detalhada e laborat\u00f3rio, conduz normalmente \u00e0 causa da insufici\u00eancia card\u00edaca (Tab. 3). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14.png\"><img decoding=\"async\" width=\"2188\" height=\"1443\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14.png\" alt=\"\" class=\"wp-image-349145 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14.png 2188w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-800x528.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-1160x765.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-2048x1351.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-120x79.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-90x59.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-320x211.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-560x369.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-1920x1266.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-240x158.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-180x119.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-640x422.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-1120x739.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab3_HP1_s14-1600x1055.png 1600w\" data-sizes=\"(max-width: 2188px) 100vw, 2188px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2188px; --smush-placeholder-aspect-ratio: 2188\/1443;\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Uma causa de HFpEF foi ignorada durante anos porque n\u00e3o houve uma terapia eficaz durante muito tempo: amiloidose card\u00edaca do tipo ATTR. Em caso de suspeita (hipertrofia ventricular acentuada, fibrila\u00e7\u00e3o atrial persistente gravemente sintom\u00e1tica, necessidade diur\u00e9tica inesperadamente elevada com FEVE preservada), deve procurar-se activamente amiloidose ATTR. Actualmente, existe uma terapia espec\u00edfica para melhorar o progn\u00f3stico, embora intensiva em termos de custos, com tafamidis. A cintilografia DPD \u00e9 o instrumento de diagn\u00f3stico de elei\u00e7\u00e3o aqui.<\/p>\n\n\n\n<h3 id=\"terapia\" class=\"wp-block-heading\">Terapia<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Temos de imaginar os diferentes n\u00edveis terap\u00eauticos na insufici\u00eancia card\u00edaca como uma pir\u00e2mide. Deve-se expandir e completar os n\u00edveis inferiores da pir\u00e2mide tanto quanto poss\u00edvel antes de passar para o n\u00edvel superior seguinte. Quanto maior for o n\u00edvel, mais complexo \u00e9 o tratamento e os efeitos secund\u00e1rios <strong>(Fig. 1)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14.png\"><img decoding=\"async\" width=\"2207\" height=\"1462\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14.png\" alt=\"\" class=\"wp-image-349146 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14.png 2207w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-800x530.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-1160x768.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-2048x1357.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-120x79.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-90x60.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-320x212.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-560x371.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-1920x1272.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-240x159.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-180x119.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-640x424.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-1120x742.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1_Hp1_s14-1600x1060.png 1600w\" data-sizes=\"(max-width: 2207px) 100vw, 2207px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2207px; --smush-placeholder-aspect-ratio: 2207\/1462;\" \/><\/a><\/figure>\n\n\n\n<h3 id=\"terapia-nao-especifica-sem-drogas-e-medicamentos\" class=\"wp-block-heading\">Terapia n\u00e3o espec\u00edfica sem drogas e medicamentos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A base da pir\u00e2mide \u00e9 constitu\u00edda por terapias n\u00e3o farmacol\u00f3gicas, incluindo medidas de preven\u00e7\u00e3o cardiovascular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No contexto do GP, a s\u00edndrome da apneia obstrutiva do sono, que \u00e9 particularmente prejudicial ao cora\u00e7\u00e3o, e a defici\u00eancia de ferro podem ser facilmente detectadas (ver <strong>Quadro 4 <\/strong>para indica\u00e7\u00f5es <strong>) <\/strong>. Os doentes com doen\u00e7a card\u00edaca isqu\u00e9mica e uma fun\u00e7\u00e3o ventricular de &lt;40% beneficiam mais da suplementa\u00e7\u00e3o com ferro intravenoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14.png\"><img decoding=\"async\" width=\"1073\" height=\"394\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14.png\" alt=\"\" class=\"wp-image-349147 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14.png 1073w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14-800x294.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14-120x44.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14-90x33.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14-320x118.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14-560x206.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14-240x88.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14-180x66.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab4_HP1_s14-640x235.png 640w\" data-sizes=\"(max-width: 1073px) 100vw, 1073px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1073px; --smush-placeholder-aspect-ratio: 1073\/394;\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Uma quest\u00e3o sens\u00edvel em doentes com insufici\u00eancia card\u00edaca \u00e9 o aconselhamento sobre o consumo de \u00e1lcool. Embora se assuma que o consumo de \u00e1lcool de mais de tr\u00eas unidades por dia \u00e9 prejudicial, o consumo de duas unidades de \u00e1lcool por dia ou menos n\u00e3o parece ser prejudicial [3]. Se o consumo de \u00e1lcool for a causa da pr\u00f3pria insufici\u00eancia card\u00edaca, recomendamos naturalmente a abstin\u00eancia absoluta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medi\u00e7\u00e3o simples e regular do peso e o ajustamento do peso dos diur\u00e9ticos \u00e9 uma das medidas mais eficazes para evitar a hospitaliza\u00e7\u00e3o para a descompensa\u00e7\u00e3o card\u00edaca aguda. Recomendamos que o paciente e o m\u00e9dico determinem a quantidade de diur\u00e9tico de acordo com um hor\u00e1rio individual. O programa cont\u00e9m a quantidade de diur\u00e9tico de acordo com o peso, um peso alvo e um peso de alarme. Se o peso do alarme for excedido, o paciente deve procurar aconselhamento m\u00e9dico. Para manter um peso est\u00e1vel, a adi\u00e7\u00e3o tempor\u00e1ria de metolazone \u00e0 torasemida (por exemplo, metolazone 5 mg durante 3-5 dias) pode melhorar significativamente a diurese em resist\u00eancia diur\u00e9tica em la\u00e7o [4]. A Metolazone deve ser tomada cerca de uma hora antes do torasemide. Deve ser dada maior aten\u00e7\u00e3o aos dist\u00farbios electrol\u00edticos, especialmente em combina\u00e7\u00e3o com v\u00e1rios diur\u00e9ticos. A disselectrolytaemia relevante pode levar a arritmias malignas nos doentes em stress card\u00edaco.<\/p>\n\n\n\n<h3 id=\"terapia-medicamentosa-especifica-os-4-pilares\" class=\"wp-block-heading\">Terapia medicamentosa espec\u00edfica: os 4 pilares<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O segundo passo na pir\u00e2mide do tratamento moderno da insufici\u00eancia card\u00edaca \u00e9 a combina\u00e7\u00e3o de Entresto\/ARNI, bloqueador de receptores de aldosterona, beta-bloqueador e a \u00faltima adi\u00e7\u00e3o, o inibidor de co-transporte de s\u00f3dio-glucose (SGLT2i). Alguns &#8220;truques&#8221; podem ser \u00fateis na introdu\u00e7\u00e3o e posterior titula\u00e7\u00e3o destas terapias:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na Su\u00ed\u00e7a, o Forxiga ou Jardiance deve ser iniciado ANTES do tratamento com Entresto. Isto n\u00e3o se baseia nem em recomenda\u00e7\u00f5es do CES nem em dados cl\u00ednicos. Mas \u00e9 um crit\u00e9rio obrigat\u00f3rio na lista de especialidades e \u00e9, portanto, um crit\u00e9rio de cobertura de custos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 do conhecimento geral que Entresto, sartans e inibidores da ECA n\u00e3o devem ser dados em paralelo. H\u00e1 tamb\u00e9m um efeito de sobreposi\u00e7\u00e3o entre os inibidores de Entresto e ECA ao passar de um inibidor da ECA para Entresto. Se o tratamento tiver de ser alterado de um inibidor da ECA para Entresto, deve ser observado um intervalo de pelo menos 72 horas em rela\u00e7\u00e3o ao inibidor da ECA. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entresto baixa a tens\u00e3o arterial sist\u00f3lica em cerca de 20%. Recomenda-se a titula\u00e7\u00e3o durante 6 semanas, especialmente em doentes com tens\u00e3o arterial de base de cerca de 100-110 mmHg sist\u00f3lica [5]. O Entresto n\u00e3o deve ser formalmente iniciado abaixo de uma s\u00edstole de 90 mmHg. No entanto, a nossa experi\u00eancia mostra que com um in\u00edcio de terapia em doses baixas e um aumento cauteloso, mesmo os pacientes com tens\u00e3o arterial de base baixa podem beneficiar do Entresto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante notar que o efeito das terapias medicamentosas foi provado em estudos com a dose m\u00e1xima tolerada e n\u00e3o com a dose m\u00e1xima poss\u00edvel. Felizmente, na pr\u00e1tica, o efeito positivo de uma dose m\u00e1xima recomendada e m\u00e1xima tolerada \u00e9 muito semelhante [6].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medica\u00e7\u00e3o para insufici\u00eancia card\u00edaca tem um efeito negativo sobre a sexualidade masculina. Pode suspeitar-se de um efeito secund\u00e1rio na sexualidade feminina, mas infelizmente n\u00e3o h\u00e1 estudos sobre isto. A espironolactona (Aldactone) tem, entre outras coisas, um efeito negativo na libido, provoca o aumento da mama nos homens e leva \u00e0 disfun\u00e7\u00e3o er\u00e9ctil. Eplerenona, a alternativa \u00e0 Aldactone, tamb\u00e9m recomendada para o tratamento da insufici\u00eancia card\u00edaca, n\u00e3o tem estes efeitos secund\u00e1rios. Contudo, as companhias de seguros de sa\u00fade s\u00f3 reembolsam a eplerenona se a ginecomastia ocorrer enquanto se toma aldosterona. Os beta-bloqueadores s\u00e3o tamb\u00e9m conhecidos pelo seu efeito negativo na fun\u00e7\u00e3o er\u00e9ctil. Bisoprololol e nebivololol t\u00eam um efeito menos pronunciado nesta \u00e1rea. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ajuda na prescri\u00e7\u00e3o de medicamentos para insufici\u00eancia card\u00edaca, ver as tabelas no ap\u00eandice das directrizes do CES (https:\/\/academic.oup.com\/eurheartj\/article\/42\/36\/3599\/6358045#supplementary-data).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, \u00e9 importante neste ponto abordar o &#8220;problema&#8221; dos pacientes com HFrecEF. Como devem ser tratados os pacientes cuja fun\u00e7\u00e3o ventricular tenha melhorado? Na maioria dos casos, a medica\u00e7\u00e3o deve ser continuada. Se o paciente sofrer severamente de efeitos secund\u00e1rios, a terapia pode ser continuada com uma dose reduzida. O risco de recidiva de insufici\u00eancia card\u00edaca grave ap\u00f3s a interrup\u00e7\u00e3o da medica\u00e7\u00e3o \u00e9 de cerca de 40% [7]. <\/p>\n\n\n\n<h3 id=\"terapia-intermedia\" class=\"wp-block-heading\">Terapia interm\u00e9dia<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O terceiro n\u00edvel da pir\u00e2mide s\u00e3o as terapias interm\u00e9dias. Estas incluem terapias mas n\u00e3o envolvem directamente apoio mec\u00e2nico ou substitui\u00e7\u00e3o ventricular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fazemos uma breve revis\u00e3o dos m\u00e9todos de tratamento estabelecidos: O desfibrilador \u00e9 implantado na preven\u00e7\u00e3o prim\u00e1ria e secund\u00e1ria de arritmias potencialmente fatais. Na profilaxia prim\u00e1ria, h\u00e1 uma indica\u00e7\u00e3o para a LVEF \u226435%, especialmente nas doen\u00e7as card\u00edacas isqu\u00e9micas. As mulheres com doen\u00e7a card\u00edaca n\u00e3o isqu\u00e9mica e com um amplo (&gt;150 ms) bloco de ramo esquerdo beneficiam mais de um pacemaker de ressincroniza\u00e7\u00e3o em que um bloco de ramo esquerdo \u00e9 ligado a um bloco de ramo. Em contraste com o desfibrilador, os pacientes normalmente tamb\u00e9m beneficiam aqui na vida di\u00e1ria com uma melhoria no desempenho. Uma combina\u00e7\u00e3o de desfibrilador e de pacemaker de ressincroniza\u00e7\u00e3o \u00e9 frequentemente implantada porque a indica\u00e7\u00e3o para ambas as fun\u00e7\u00f5es do dispositivo se sobrep\u00f5e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As terapias de repara\u00e7\u00e3o ou substitui\u00e7\u00e3o de v\u00e1lvulas tais como TAVI ou TEER (por exemplo, Mitra Clip) s\u00e3o contribui\u00e7\u00f5es importantes para a preserva\u00e7\u00e3o da fun\u00e7\u00e3o card\u00edaca em casos de estenose a\u00f3rtica ou regurgita\u00e7\u00e3o mitral grave. Em particular, a regurgita\u00e7\u00e3o mitral secund\u00e1ria grave \u00e9 a via final comum de muitas cardiopatias dilatadas e acelera a progress\u00e3o da doen\u00e7a e dos seus sintomas. O clip Mitra \u00e9 um m\u00e9todo de interven\u00e7\u00e3o relativamente novo com um baixo risco periintervencional e uma redu\u00e7\u00e3o significativa da insufici\u00eancia em anatomia adequada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, h\u00e1 outras novas interven\u00e7\u00f5es invasivas, ainda menos estabelecidas, na v\u00e1lvula tric\u00faspide em doentes com regurgita\u00e7\u00e3o tric\u00faspide grave sintom\u00e1tica ou estimula\u00e7\u00e3o carot\u00eddea para reduzir o impulso simp\u00e1tico (&#8220;bloqueadores beta el\u00e9ctricos&#8221;). Todas estas s\u00e3o op\u00e7\u00f5es que tamb\u00e9m est\u00e3o dispon\u00edveis para pacientes que n\u00e3o s\u00e3o candidatos a implanta\u00e7\u00e3o ou transplante de LVAD.<\/p>\n\n\n\n<h3 id=\"terapias-avancadas\" class=\"wp-block-heading\">Terapias avan\u00e7adas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O topo da pir\u00e2mide \u00e9 terapias avan\u00e7adas com transplante card\u00edaco (HTX) e o<em> dispositivo <\/em>mec\u00e2nico<em> de assist\u00eancia <\/em>ventricular esquerda<em> ( <\/em>LVAD).  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao determinar a indica\u00e7\u00e3o, \u00e9 \u00fatil conhecer a escala INTERMAC, que descreve o grau de sintomas. Quanto mais baixo for o valor INTERMAC, pior ser\u00e1 a situa\u00e7\u00e3o do paciente. Os pacientes INTERMAC 1-3 est\u00e3o em cuidados intensivos, os pacientes INTERMAC-4 s\u00e3o frequentemente hospitalizados, os pacientes INTERMAC-5-7 s\u00e3o ambulat\u00f3rios mas sofrem de graves problemas respirat\u00f3rios <strong>(Fig. 2)<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15.png\"><img decoding=\"async\" width=\"2007\" height=\"1395\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15.png\" alt=\"\" class=\"wp-image-349148 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15.png 2007w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-800x556.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-1160x806.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-120x83.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-90x63.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-320x222.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-560x389.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-1920x1335.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-240x167.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-180x125.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-640x445.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-1120x778.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb2_HP1_s15-1600x1112.png 1600w\" data-sizes=\"(max-width: 2007px) 100vw, 2007px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2007px; --smush-placeholder-aspect-ratio: 2007\/1395;\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se um paciente \u00e9 listado para transplante ou recebe um LVAD permanentemente (Terapia de Destino, DT) ou temporariamente at\u00e9 que o transplante (Ponte para o Transplante, BTT) seja decidido com base em muitos factores. Os factores mais importantes na decis\u00e3o para a implanta\u00e7\u00e3o do LVAD s\u00e3o a qualidade de vida (em doentes INTERMAC 5-7) [8] e a sobreviv\u00eancia (em doentes INTERMAC 4-1). As comorbidades e a idade biol\u00f3gica, bem como a conformidade, podem limitar a escalada do tratamento. As indica\u00e7\u00f5es para transplante card\u00edaco s\u00e3o muito mais diversas, variando desde insufici\u00eancia card\u00edaca sist\u00f3lica grave (na grande maioria dos casos) a insufici\u00eancia diast\u00f3lica sintom\u00e1tica grave (rara) a arritmias repetidas, apesar dos tratamentos m\u00faltiplos (raros).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16.png\"><img decoding=\"async\" width=\"2155\" height=\"1203\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16.png\" alt=\"\" class=\"wp-image-349149 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16.png 2155w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-800x447.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-1160x648.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-2048x1143.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-120x67.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-90x50.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-320x179.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-560x313.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-1920x1072.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-240x134.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-180x100.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-640x357.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-1120x625.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/tab5_HP1_s16-1600x893.png 1600w\" data-sizes=\"(max-width: 2155px) 100vw, 2155px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2155px; --smush-placeholder-aspect-ratio: 2155\/1203;\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O contributo do GP \u00e9 central para a equipa de cardiologia e para o paciente tomar a decis\u00e3o correcta sobre transplante ou LVAD. A ades\u00e3o aos medicamentos \u00e9 um problema mesmo antes de um poss\u00edvel transplante? Estar\u00e1 ele socialmente isolado? Ou est\u00e1 ele, pelo contr\u00e1rio, em excelente estado geral, apesar da sua idade e apenas a sofrer dos sintomas da sua insufici\u00eancia card\u00edaca? A estreita coopera\u00e7\u00e3o com o cardiologista e o conhecimento das indica\u00e7\u00f5es, limites e contra-indica\u00e7\u00f5es das v\u00e1rias terapias s\u00e3o \u00fateis. Estes est\u00e3o resumidos no Quadro 5.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mensagens Take-Home<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O cl\u00ednico geral desempenha um papel central no tratamento da insufici\u00eancia card\u00edaca. Primeiro na detec\u00e7\u00e3o precoce em doentes com sintomas tais como falta de ar ou redu\u00e7\u00e3o da resili\u00eancia.<\/li>\n\n\n\n<li>Na expans\u00e3o da terapia da insufici\u00eancia card\u00edaca, o m\u00e9dico de cl\u00ednica geral est\u00e1 subsequentemente na vanguarda. Aproximar-se da dose m\u00e1xima tolerada pode ser um grande desafio e pode perder o paciente como parceiro nos esfor\u00e7os de expans\u00e3o.  <\/li>\n\n\n\n<li>O m\u00e9dico de fam\u00edlia \u00e9 tamb\u00e9m um parceiro importante na discuss\u00e3o sobre o passo em direc\u00e7\u00e3o ao transplante card\u00edaco e ao implante do LVAD. V\u00ea dificuldades a surgir com anteced\u00eancia e, por outro lado, conhece os recursos do paciente. Finalmente, uma boa rede de cuidados prim\u00e1rios \u00e9 essencial para o acompanhamento ap\u00f3s transplante card\u00edaco ou implante de LVAD.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>McDonagh TA, Metra M, Adamo M, et al: 2021 ESC Guidelines for the diagnosis and treatment of acute and chronic heart failure: Developed by the Task Force for the diagnosis and treatment of acute and chronic heart failure of the European Society of Cardiology (ESC) With the special contribution of the Heart Failure Association (HFA) of the ESC. European Heart Journal 2021; 42: 3599-3726.<\/li>\n\n\n\n<li>Wilcox JE, Fang JC, Margulies KB, Mann DL: Insufici\u00eancia Card\u00edaca com Ejec\u00e7\u00e3o Ventricular Esquerda Recuperada: Painel de Peritos Cient\u00edficos do JACC. Journal of the American College of Cardiology 2020; 76: 719-734.<\/li>\n\n\n\n<li>Larsson SC, Orsini N, Wolk A: Consumo de \u00e1lcool e risco de insufici\u00eancia card\u00edaca: uma meta-an\u00e1lise dose-resposta de estudos prospectivos. European Journal of Heart Failure 2015; 17: 367-373.<\/li>\n\n\n\n<li>Grosskopf I, Rabinovitz M, Rosenfeld JB: Combina\u00e7\u00e3o de furosemida e metolazona no tratamento de insufici\u00eancia card\u00edaca congestiva grave. Isr J Med Sci 1986; 22: 787-790.<\/li>\n\n\n\n<li>Senni M, McMurray JJV, Wachter R, et al: Iniciando o sacubitril\/valsartan (LCZ696) na insufici\u00eancia card\u00edaca: resultados de TITRA\u00c7\u00c3O, uma compara\u00e7\u00e3o duplo-cega e aleat\u00f3ria de dois regimes de uptitration. European Journal of Heart Failure 2016; 18: 1193-1202.<\/li>\n\n\n\n<li>Corrado E, Dattilo G, Coppola G, et al: Efeitos ARNI de baixa vs alta dose no estado cl\u00ednico, desempenho do exerc\u00edcio e fun\u00e7\u00e3o card\u00edaca em pacientes com HFrEF na vida real. Eur J Clin Pharmacol 2022; 78: 19-25.<\/li>\n\n\n\n<li>Wilcox JE, Fang JC, Margulies KB, Mann DL: Insufici\u00eancia Card\u00edaca com Ejec\u00e7\u00e3o Ventricular Esquerda Recuperada: Painel de Peritos Cient\u00edficos do JACC. Journal of the American College of Cardiology 2020; 76: 719-734.<\/li>\n\n\n\n<li>Shah KB, Starling RC, Rogers JG, et al: Dispositivos de assist\u00eancia ventricular esquerda versus gest\u00e3o m\u00e9dica em pacientes com insufici\u00eancia card\u00edaca ambulatorial: Uma an\u00e1lise dos Perfis 4 e 5 a 7 da INTERMACS do estudo ROADMAP. The Journal of Heart and Lung Transplantation 2018; 37: 706-714.<\/li>\n\n\n\n<li>Cook JL, Colvin M, Francis GS, et al: Recommendations for the Use of Mechanical Circulatory Support: Ambulatory and Community Patient Care: A Scientific Statement. The American Heart Association Circulation 2017; 135: e1145-e1158.<\/li>\n\n\n\n<li>Mehra MR, Canter CE, Hannan MM, et al: The 2016 International Society for Heart Lung Transplantation listing criteria for heart transplantation: A 10-year update. The Journal of Heart and Lung Transplantation 2016; 35: 1-23.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em><em>HAUSARZT PRAXIS 2023; 18(1): 12\u201317<\/em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A insufici\u00eancia card\u00edaca \u00e9 um problema crescente na Su\u00ed\u00e7a, tal como no resto do mundo industrializado, porque a incid\u00eancia de insufici\u00eancia card\u00edaca aumenta com a idade e h\u00e1 cada vez&hellip;<\/p>\n","protected":false},"author":7,"featured_media":127025,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Insufici\u00eancia card\u00edaca","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11367,11390,22618,11305,11551],"tags":[12185,12187,12186],"powerkit_post_featured":[],"class_list":["post-350678","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia-pt-pt","category-cirurgia","category-formacao-cme","category-medicina-interna-geral","category-rx-pt","tag-insuficiencia-cardiaca","tag-lvad-pt-pt","tag-transplante-de-coracao","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:36:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":350680,"slug":"consejos-y-trucos-en-la-consulta-del-medico-de-cabecera","post_title":"Consejos y trucos en la consulta del m\u00e9dico de cabecera","href":"https:\/\/medizinonline.com\/es\/consejos-y-trucos-en-la-consulta-del-medico-de-cabecera\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/350678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=350678"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/350678\/revisions"}],"predecessor-version":[{"id":386682,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/350678\/revisions\/386682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/127025"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=350678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=350678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=350678"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=350678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}