{"id":352216,"date":"2023-02-08T01:00:00","date_gmt":"2023-02-08T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/a-terapia-moderna-pode-retardar-a-progressao-da-nefropatia-diabetica\/"},"modified":"2023-02-23T14:47:23","modified_gmt":"2023-02-23T13:47:23","slug":"a-terapia-moderna-pode-retardar-a-progressao-da-nefropatia-diabetica","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/a-terapia-moderna-pode-retardar-a-progressao-da-nefropatia-diabetica\/","title":{"rendered":"A terapia moderna pode retardar a progress\u00e3o da nefropatia diab\u00e9tica"},"content":{"rendered":"\n<p><strong>A diabetes \u00e9 a causa mais comum de doen\u00e7a renal cr\u00f3nica (CKD).<br\/>A organiza\u00e7\u00e3o internacional Kidney Disease: Improving Global Outcomes (KDIGO) publicou recentemente novas directrizes sobre a gest\u00e3o da diabetes tipo 2 em pessoas com CKD. Propaga-se uma abordagem de tratamento que se baseia em v\u00e1rios pilares. Uma das mensagens chave: a progress\u00e3o da doen\u00e7a renal pode ser retardada com novos medicamentos, para que muitas pessoas possam ser poupadas \u00e0 di\u00e1lise por um longo per\u00edodo de tempo.  <\/strong><\/p>\n\n<!--more-->\n\n<p>Embora no passado houvesse apenas algumas op\u00e7\u00f5es de tratamento dispon\u00edveis que podiam parar a progress\u00e3o do CKD associado \u00e0 diabetes, existem actualmente v\u00e1rias classes modernas de medicamentos que podem retardar significativamente a perda da fun\u00e7\u00e3o renal se forem utilizados a tempo. \u00c9 portanto importante que as pessoas afectadas recebam cuidados atempados de um nefrologista [1]. &#8220;Os crit\u00e9rios para apresentar a pessoa com diabetes mellitus ao nefrologista s\u00e3o, por exemplo: gota eGFR nova ou significativa, eGFR \u226460 ml\/min\/1,73 m\u00b2, eritrocit\u00faria ou uma albumin\u00faria de grau 2 ou 3&#8221;, explicou a Prof.\u00aa Dra. Julia Weinmann-Menke, Mainz, assessora de imprensa da Sociedade Alem\u00e3 de Nefrologia [1,3].  <\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1469\" height=\"1326\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21.png\" alt=\"\" class=\"wp-image-349452\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21.png 1469w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-800x722.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-1160x1047.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-120x108.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-90x81.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-320x289.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-560x505.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-240x217.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-180x162.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-640x578.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/abb1-HP1_s21-1120x1011.png 1120w\" sizes=\"(max-width: 1469px) 100vw, 1469px\" \/><\/a><\/figure>\n\n<p>O facto de as directrizes do KDIGO emitidas em 2020 j\u00e1 estarem dispon\u00edveis numa vers\u00e3o revista em 2022 reflecte o r\u00e1pido progresso no campo do tratamento da nefropatia associada \u00e0 diabetes [4]. O KDIGO propaga uma abordagem de terapia multimodal <strong>(Fig. 1)<\/strong>. <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Todos os pacientes devem prestar aten\u00e7\u00e3o aos factores do estilo de vida como o exerc\u00edcio, a dieta e a cessa\u00e7\u00e3o do tabagismo. As terapias medicamentosas de primeira linha devem ser seleccionadas de acordo com as caracter\u00edsticas cl\u00ednicas individuais.  <\/li>\n\n\n\n<li>O controlo da glicemia na diabetes tipo 2 (T2D) \u00e9 baseado numa combina\u00e7\u00e3o de metformina e cotransportador de s\u00f3dio-glucose 2 inibidores (SGLT-2-i). Para pacientes em que SGLT-2-i e metformina n\u00e3o s\u00e3o eficazes para atingir os objectivos de glicose no sangue, os agonistas do receptor do pept\u00eddeo 1 tipo glucagon (GLP-1 RA) s\u00e3o o medicamento preferido para a diminui\u00e7\u00e3o do glucose-baixo.<\/li>\n\n\n\n<li>Em doentes com albumin\u00faria e hipertens\u00e3o (HTN), aconselha-se a inibi\u00e7\u00e3o do sistema renina-angiotensina (RAS). A estatina \u00e9 recomendada para todos os doentes com T1D ou T2D e CKD.  <\/li>\n\n\n\n<li>Um antagonista n\u00e3o ester\u00f3ide dos receptores de mineralocortic\u00f3ides (ns-MRA) pode ser acrescentado \u00e0 terapia de primeira linha em pacientes com T2D e um elevado risco residual de progress\u00e3o de CKD e eventos cardiovasculares**.  <\/li>\n\n\n\n<li>A aspirina \u00e9 geralmente utilizada para a preven\u00e7\u00e3o secund\u00e1ria ao longo da vida em pacientes com doen\u00e7as cardiovasculares estabelecidas, a menos que existam contra-indica\u00e7\u00f5es, e pode ser considerada para a preven\u00e7\u00e3o prim\u00e1ria em pacientes de alto risco de doen\u00e7a cardiovascular ateroscler\u00f3tica (ASCVD).<\/li>\n<\/ul>\n\n<p class=\"has-medium-font-size\"><br\/><em>** Indicador de risco residual elevado para a progress\u00e3o de CKD e eventos cardiovasculares: albumin\u00faria persistente (&gt;30 mg\/g [&gt;3 mg\/mmol])<\/em><\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20.png\"><img decoding=\"async\" width=\"771\" height=\"520\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20.png\" alt=\"\" class=\"wp-image-349453 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20.png 771w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20-120x81.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20-90x61.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20-320x216.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20-560x378.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20-240x162.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20-180x121.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten1_HP1_s20-640x432.png 640w\" data-sizes=\"(max-width: 771px) 100vw, 771px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 771px; --smush-placeholder-aspect-ratio: 771\/520;\" \/><\/a><\/figure>\n\n<h3 id=\"sglt-2-i-o-limiar-egfr-foi-reduzido\" class=\"wp-block-heading\">SGLT-2-i: o limiar eGFR foi reduzido  <\/h3>\n\n<p>Os pacientes com T2D, CKD e um eGFR \u226520 ml\/min por 1,73 m\u00b2 foram agora extensamente estudados em TCR no SGLT-2-i. Com base nestes estudos, reitera-se a forte recomenda\u00e7\u00e3o de tratar pacientes com T2D e CKD com um SGLT-2-i, independentemente da albumin\u00faria. Uma mudan\u00e7a importante \u00e9 o limiar eGFR mais baixo em que o SGLT-2-i deve ser iniciado. A directriz de 2022 recomenda a introdu\u00e7\u00e3o de um SGLT-2-i para pacientes com T2D e CKD que tenham um eGFR \u226520 ml\/min por 1,73 m\u00b2, em oposi\u00e7\u00e3o a \u226530 ml\/min por 1,73 m\u00b2 na directriz de 2020 [4].  <\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20.png\"><img decoding=\"async\" width=\"1467\" height=\"342\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20.png\" alt=\"\" class=\"wp-image-349455 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20.png 1467w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-800x187.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-1160x270.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-120x28.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-90x21.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-320x75.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-560x131.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-240x56.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-180x42.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-640x149.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten2_HP1_s20-1120x261.png 1120w\" data-sizes=\"(max-width: 1467px) 100vw, 1467px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1467px; --smush-placeholder-aspect-ratio: 1467\/342;\" \/><\/a><\/figure>\n\n<p>Os estudos  <em>Dapagliflozina e Preven\u00e7\u00e3o de Resultados Adversos na Doen\u00e7a Cr\u00f3nica dos Rins<\/em>  (DAPA-CKD) e  <em>Efeito da Sotagliflozina em Eventos Cardiovasculares e Renais em Pacientes com Diabetes Tipo 2 e Defici\u00eancia Renal Moderada que Est\u00e3o em Risco Cardiovascular<\/em>  (SCORED) inclu\u00eda doentes com CKD com um eGFR de at\u00e9 25 ml\/min por 1,73 m\u00b2.  [5,6].<\/p>\n\n<p>O <em>Estudo de Protec\u00e7\u00e3o do Cora\u00e7\u00e3o e Rim com Empagliflozina<\/em> (EMPA-KIDNEY), realizado exclusivamente com popula\u00e7\u00f5es de CKD e parado precocemente devido ao benef\u00edcio, incluiu tamb\u00e9m participantes com um eGFR \u226520 ml\/min por 1,73 m\u00b2 [7]. An\u00e1lises de subgrupos de estudos individuais e meta-an\u00e1lises demonstraram benef\u00edcios renais e cardiovasculares em todas as categorias de eGFR, incluindo participantes com eGFR &lt;30 ml\/min por 1,73 m\u00b2 e aqueles sem albumin\u00faria [8,9].  <\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1450\" height=\"790\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21.png\" alt=\"\" class=\"wp-image-349454 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21.png 1450w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-800x436.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-1160x632.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-120x65.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-90x49.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-320x174.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-560x305.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-240x131.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-180x98.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-640x349.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/01\/Kasten3_HP1_s21-1120x610.png 1120w\" data-sizes=\"(max-width: 1450px) 100vw, 1450px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1450px; --smush-placeholder-aspect-ratio: 1450\/790;\" \/><\/figure>\n\n<h3 id=\"agonistas-de-receptores-glp-1-novos-conhecimentos\" class=\"wp-block-heading\">Agonistas de receptores GLP-1: novos conhecimentos  <\/h3>\n\n<p>Em 2021, foram publicados os resultados de um novo grande estudo sobre efpeglenatide, que foram incorporados nas novas directrizes do KDIGO. O estudo AMPLITUDE-O <em>(Effect of Efpeglenatide on Cardiovascular Outcomes)<\/em> apoiou a evid\u00eancia dos benef\u00edcios cardiovasculares da AR GLP-1 e refor\u00e7ou a hip\u00f3tese de que a AR GLP-1 tamb\u00e9m pode melhorar os resultados renais [2]. Consequentemente, a GLP-1 RA continua a ser a terapia de segunda linha recomendada para a redu\u00e7\u00e3o dos n\u00edveis de glicose no sangue em T2D e CKD. O benef\u00edcio cardiovascular comprovado da AR da GLP-1 foi demonstrado para todas as categorias de eGFR e serviu como a principal raz\u00e3o para recomendar a AR da GLP-1 como o medicamento de escolha para baixar a glicemia em pacientes com T2D e CKD que n\u00e3o alcan\u00e7aram os seus objectivos de glicemia apesar da utiliza\u00e7\u00e3o de SGLT-2-i e metformina (ou nos quais SGLT-2-i e\/ou metformina n\u00e3o puderam ser utilizados).  <\/p>\n\n<h3 id=\"finerenone-antagonista-nao-esteroide-de-mineralocorticoides-como-o-mais-recente-jogador\" class=\"wp-block-heading\">Finerenone &#8211; antagonista n\u00e3o ester\u00f3ide de mineralocortic\u00f3ides como o mais recente jogador<\/h3>\n\n<p>Tamb\u00e9m eficaz na preven\u00e7\u00e3o da progress\u00e3o da doen\u00e7a renal diab\u00e9tica \u00e9 o novo antagonista selectivo, n\u00e3o ester\u00f3ide, dos receptores mineralocortic\u00f3ides finerenona [1]. Isto foi demonstrado pelos dois grandes ensaios cl\u00ednicos FIDELIO-DKD <em>(Finerenone in Reducing Kidney Failure and Disease Progression in Diabetic Kidney Disease)<\/em> [10] e FIGARO-DKD <em>(Finerenone in Reducing Cardiovascular Mortality and Morbidity in Diabetic Kidney Disease)<\/em> [11] bem como pela an\u00e1lise combinada FIDELITY [12] baseada neles. Os resultados mais importantes num relance:  <\/p>\n\n<p>No ensaio FIDELIO-DKD, a finerenona reduziu significativamente a incid\u00eancia tanto do resultado renal composto prim\u00e1rio (insufici\u00eancia renal, decl\u00ednio sustentado no eGFR pelo \u226540% ou morte devido a doen\u00e7a renal; raz\u00e3o de perigo  [HR](morte por causas cardiovasculares, enfarte do mioc\u00e1rdio n\u00e3o fatal, acidente vascular cerebral n\u00e3o fatal ou hospitaliza\u00e7\u00e3o por insufici\u00eancia card\u00edaca; FC: 0,86; IC 95%: 0,75-0,99) e o resultado cardiovascular composto secund\u00e1rio (morte por causas cardiovasculares, enfarte do mioc\u00e1rdio n\u00e3o fatal, acidente vascular cerebral n\u00e3o fatal ou hospitaliza\u00e7\u00e3o por insufici\u00eancia card\u00edaca; FC: 0,86; IC 95%: 0,75-0,99).  [10].  <\/p>\n\n<p>No FIGARO-DKD, a finerenona reduziu significativamente o ponto final cardiovascular combinado (HR: 0,87; 95% CI: 0,76-0,98) [11].  <\/p>\n\n<p>No ensaio FIDELITY, os resultados cardiovasculares globais foram reduzidos em doentes tratados com finerenona (HR: 0,86; 95% CI: 0,78-0,95), sem heterogeneidade significativa nas caracter\u00edsticas dos doentes na linha de base [12].  <\/p>\n\n<p>Os doentes tratados com finerenona tamb\u00e9m tinham menos probabilidades de experimentar insufici\u00eancia renal, um decr\u00e9scimo da taxa de filtra\u00e7\u00e3o glomerular (TFGE) superior a 57% ou morte renal (FC: 0,77; IC 95%: 0,67-0,88), e menos probabilidades de experimentar insufici\u00eancia renal definida como in\u00edcio de di\u00e1lise cr\u00f3nica ou transplante renal (FC: 0,80; IC 95%: 0,64-0,99).  <\/p>\n\n<p><\/p>\n\n<p>Literatura: <\/p>\n\n<ol class=\"wp-block-list\">\n<li>&#8220;Dia Mundial da Diabetes: A di\u00e1lise n\u00e3o \u00e9 um destino inevit\u00e1vel para as pessoas com diabetes mellitus&#8221;, Sociedade Alem\u00e3 de Nefrologia, 11.11.2022  <\/li>\n\n\n\n<li>Gerstein HC, et al: N Engl J Med 2021; 385: 896-907.  <\/li>\n\n\n\n<li>Documento de posi\u00e7\u00e3o Coopera\u00e7\u00e3o Diabetologia\/Nefrologia. Sociedade Alem\u00e3 de Diabetes\/Sociedade Alem\u00e3 de Nefrologia\/Associa\u00e7\u00e3o de Nefrologistas de Hospital S\u00e9nior 2018. <a href=\"http:\/\/www.ddg.info\" target=\"_blank\" rel=\"noreferrer noopener\">www.ddg.info,<\/a>(\u00faltimo acesso 10.01.2023)  <\/li>\n\n\n\n<li>Rossing P, et al: Executive summary of the KDIGO 2022 Clinical Practice Guideline for Diabetes Management in Chronic Kidney Disease: an update based on rapidly emerging new evidence. Kidney Int 2022; 102(5): 990-999.<\/li>\n\n\n\n<li>Bhatt DL, et al: N Engl J Med 2021; 384: 117-128.<\/li>\n\n\n\n<li>Heerspink HJL, et al: N Engl J Med 2020; 383: 1436-1446.<\/li>\n\n\n\n<li>EMPA-Kidney Collaborative Group: Nephrol Dial Transplant 2022; 37; 1317-1329.  <\/li>\n\n\n\n<li>Bakris G, et al: Clin J Am Soc Nephrol 2020; 15: 1705-1714.  <\/li>\n\n\n\n<li>Chertow GM, et al: J Am Soc Nephrol 2021; 32: 2352-2361.  <\/li>\n\n\n\n<li>Bakris GL, et al: N Engl J Med 2020; 383: 2219-2229.  <\/li>\n\n\n\n<li>Pitt B, et al: N Engl J Med 2021; 385: 2252-2263.  <\/li>\n\n\n\n<li>Rossing P, et al.: FIDELIO-DKD e FIGARO-DKD Investigadores: Diabetes Care. Publicado online, 15 de Agosto (2022), 10.2337\/dc22-0294<\/li>\n\n\n\n<li>Seidu S, et al: 2022 actualiza\u00e7\u00e3o da declara\u00e7\u00e3o de posi\u00e7\u00e3o por Primary Care Diabetes Europe: uma abordagem do estado da doen\u00e7a \u00e0 gest\u00e3o farmacol\u00f3gica da diabetes tipo 2 nos cuidados prim\u00e1rios. Diabetes de Cuidados Prim\u00e1rios 2022; 16(2): 223-244.<\/li>\n\n\n\n<li>&#8220;Chronic Kidney Diseaseassociated Pruritus: From Epidemiology To Treatment&#8221;, 25 Nov 2021, <a href=\"http:\/\/www.emjreviews.com\" target=\"_blank\" rel=\"noreferrer noopener\">www.emjreviews.com,<\/a>(\u00faltimo acesso 14 Dez 2022).  <\/li>\n\n\n\n<li>Sukul N, et al: Kidney Med 2020; 3(1): 42-53.e1<\/li>\n\n\n\n<li>Yan B, et al: J Am Heart Assoc 2021; 10(7): e016201.<\/li>\n\n\n\n<li>&#8220;CHMP Meeting Highlights February 2022&#8221;, 17\/03\/2022, <a href=\"http:\/\/www.basg.gv.at\" target=\"_blank\" rel=\"noreferrer noopener\">www.basg.gv.at,<\/a><a href=\"http:\/\/www.basg.gv.at\" target=\"_blank\" rel=\"noreferrer noopener\"> <\/a>(\u00faltimo acesso 14\/12\/2022).  <\/li>\n\n\n\n<li>Fishbane S; KALM-1 Trial Investigators: N Engl J Med 2020; 382(3): 222-232.<\/li>\n\n\n\n<li>Sociedade Americana de Nefrologia: Abstract FR-OR24, <a href=\"http:\/\/www.asn-online.org\" target=\"_blank\" rel=\"noreferrer noopener\">www.asn-online.org<\/a> (\u00faltimo acesso: 14 de Dezembro de 2022).<\/li>\n<\/ol>\n\n<p><\/p>\n\n<p><em>PR\u00c1TICA DO GP 2023; 18(1): 20-21<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diabetes \u00e9 a causa mais comum de doen\u00e7a renal cr\u00f3nica (CKD).A organiza\u00e7\u00e3o internacional Kidney Disease: Improving Global Outcomes (KDIGO) publicou recentemente novas directrizes sobre a gest\u00e3o da diabetes tipo&hellip;<\/p>\n","protected":false},"author":7,"featured_media":349467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Directrizes KDIGO 2022","footnotes":""},"category":[11397,11521,11524,11305,11426,11551],"tags":[65628,13003,11677,12023,11953,13010,65626,65627,11987,16408,24152,18638,11805],"powerkit_post_featured":[],"class_list":["post-352216","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologia-e-diabetologia-2","category-estudos","category-formacao-continua","category-medicina-interna-geral","category-nefrologia-pt-pt","category-rx-pt","tag-bpl-pt-pt","tag-ckd-pt-pt","tag-diabetes-pt-pt","tag-diabetes-tipo-2-pt-pt","tag-directrizes","tag-doenca-renal-cronica","tag-glp-1-ra-pt-pt","tag-kdigo-pt-pt","tag-medicamentos","tag-rim","tag-sglt-pt-pt","tag-sglt-2-i-pt-pt","tag-terapia-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:56:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":352228,"slug":"la-terapia-moderna-puede-ralentizar-la-progresion-de-la-nefropatia-diabetica","post_title":"La terapia moderna puede ralentizar la progresi\u00f3n de la nefropat\u00eda diab\u00e9tica","href":"https:\/\/medizinonline.com\/es\/la-terapia-moderna-puede-ralentizar-la-progresion-de-la-nefropatia-diabetica\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/352216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=352216"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/352216\/revisions"}],"predecessor-version":[{"id":352218,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/352216\/revisions\/352218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/349467"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=352216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=352216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=352216"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=352216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}