{"id":366762,"date":"2023-10-17T21:42:35","date_gmt":"2023-10-17T19:42:35","guid":{"rendered":"https:\/\/medizinonline.com\/?p=366762"},"modified":"2023-10-20T23:04:13","modified_gmt":"2023-10-20T21:04:13","slug":"doencas-auto-imunes-como-causa-de-anemia-2","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/doencas-auto-imunes-como-causa-de-anemia-2\/","title":{"rendered":"Doen\u00e7as auto-imunes como causa de anemia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A anemia \u00e9 uma ocorr\u00eancia comum nos cuidados m\u00e9dicos de rotina, cujas causas podem ser m\u00faltiplas. A anemia refere-se a uma redu\u00e7\u00e3o dos n\u00edveis de hemoglobina e hemat\u00f3crito. O valor de corte da hemoglobina para mulheres adultas \u00e9 &lt;12 g\/dl (&lt;7,44 mmol\/l) e para homens adultos &lt;13 g\/dl (&lt;8,06 mmol\/l). Este artigo abordar\u00e1 mais detalhadamente as doen\u00e7as auto-imunes, em particular, como causa de anemia.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n\n\n<p class=\"wp-block-paragraph\">A anemia \u00e9 uma ocorr\u00eancia comum nos cuidados m\u00e9dicos de rotina, cujas causas podem ser m\u00faltiplas. A anemia refere-se a uma redu\u00e7\u00e3o dos n\u00edveis de hemoglobina e hemat\u00f3crito. O valor de corte da hemoglobina \u00e9 &lt;12 g\/dl (&lt;7,44 mmol\/l) em adultos do sexo feminino e &lt;13 g\/dl (&lt;8,06 mmol\/l) em adultos do sexo masculino. Para o hemat\u00f3crito, o valor de corte foi fixado em &lt;38% para as mulheres adultas e &lt;42% para os homens adultos [1]. Uma outra classifica\u00e7\u00e3o \u00e9 efectuada com base no volume m\u00e9dio dos gl\u00f3bulos vermelhos (VCM) e na hemoglobina corpuscular m\u00e9dia (HCM). Este artigo abordar\u00e1 mais detalhadamente as doen\u00e7as auto-imunes, em particular, como causa de anemia.  <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1795\" height=\"773\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13.png\" alt=\"\" class=\"wp-image-365857\" style=\"width:500px;height:undefinedpx\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13.png 1795w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-800x345.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-1160x500.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-120x52.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-90x39.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-320x138.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-560x241.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-240x103.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-180x78.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-640x276.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-1120x482.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab1_OH4_s13-1600x689.png 1600w\" sizes=\"(max-width: 1795px) 100vw, 1795px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h3 id=\"anemia-microcitica-hipocromica\" class=\"wp-block-heading\">Anemia microc\u00edtica hipocr\u00f3mica  <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A causa mais comum de anemia microc\u00edtica hipocr\u00f3mica \u00e9 a anemia por defici\u00eancia de ferro (ADF). A defici\u00eancia de ferro de armazenamento deve ser distinguida da eritropoiese deficiente em ferro e da anemia por defici\u00eancia de ferro <strong>(Tab. 1)<\/strong>. A medi\u00e7\u00e3o da transferrina (TF), da satura\u00e7\u00e3o da transferrina, do recetor sol\u00favel da transferrina (sTfR), da ferritina e do \u00edndice de ferritina serve para classificar o est\u00e1dio atual e ajuda a esclarecer os diagn\u00f3sticos diferenciais. Um valor reduzido de ferritina \u00e9 t\u00edpico e muito sens\u00edvel para uma defici\u00eancia de ferro, mesmo numa fase inicial. No entanto, a ferritina pertence \u00e0s prote\u00ednas de fase aguda e pode estar elevada especialmente na inflama\u00e7\u00e3o cr\u00f3nica. A terap\u00eautica da eritropoiese deficiente em ferro ou da defici\u00eancia manifesta de ferro consiste na elimina\u00e7\u00e3o das causas e na substitui\u00e7\u00e3o do ferro por via oral ou intravenosa. Uma terapia bem sucedida mostra um aumento dos n\u00edveis de hemoglobina e reticul\u00f3citos ap\u00f3s apenas uma semana. A f\u00f3rmula de Ganzoni pode ser utilizada para estimar a necessidade de ferro <strong>(Fig. 1)<\/strong> [2].  <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13.png\"><img decoding=\"async\" width=\"1841\" height=\"245\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13.png\" alt=\"\" class=\"wp-image-365855 lazyload\" style=\"--smush-placeholder-width: 1841px; --smush-placeholder-aspect-ratio: 1841\/245;width:500px;height:undefinedpx\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13.png 1841w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-800x106.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-1160x154.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-120x16.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-90x12.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-320x43.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-560x75.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-240x32.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-180x24.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-640x85.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-1120x149.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb1_OH4_s13-1600x213.png 1600w\" data-sizes=\"(max-width: 1841px) 100vw, 1841px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">O diagn\u00f3stico diferencial da anemia hipocr\u00f3mica microc\u00edtica pode incluir a anemia inflamat\u00f3ria (ACD) e pode tamb\u00e9m ser combinado com a anemia por defici\u00eancia de ferro. Particularmente \u00fatil na distin\u00e7\u00e3o entre defici\u00eancia de ferro e DAC \u00e9 a medi\u00e7\u00e3o do recetor sol\u00favel da transferrina. Este valor \u00e9 um marcador da eritropoiese, que, no entanto, n\u00e3o \u00e9 afetada pela inflama\u00e7\u00e3o cr\u00f3nica [3].  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fisiopatologicamente, a DAC caracteriza-se por uma liberta\u00e7\u00e3o aumentada de hepcidina do f\u00edgado, desencadeada por v\u00e1rias citocinas (incluindo IL-6, IL-1\u03b2). A hepcidina liga-se ao transportador transmembranar de ferro (FP1), impedindo assim a absor\u00e7\u00e3o enteral de ferro. Al\u00e9m disso, verifica-se um aumento da reten\u00e7\u00e3o intracelular de ferro nos macr\u00f3fagos. Segue-se a fagocitose dos eritr\u00f3citos velhos e danificados pelos macr\u00f3fagos, sem, no entanto, haver reciclagem do ferro.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra causa \u00e9 a redu\u00e7\u00e3o da efic\u00e1cia da cascata de sinaliza\u00e7\u00e3o relacionada com JAK\/STAT no recetor da eritropoietina, que \u00e9 inibida por IL-1 e TNF, entre outros <strong>(Fig. 2)<\/strong> [4]. Devido a esta fisiopatologia, o tratamento da doen\u00e7a autoimune com a consequente redu\u00e7\u00e3o da atividade inflamat\u00f3ria deve ser o primeiro passo terap\u00eautico. Os doentes com anemia combinada por defici\u00eancia de ferro e DCA beneficiam da suplementa\u00e7\u00e3o de ferro. O n\u00edvel de hepcidina pode ser usado para ajudar a decidir sobre a suplementa\u00e7\u00e3o de ferro oral ou intravenosa. No entanto, n\u00e3o \u00e9 um instrumento de medi\u00e7\u00e3o definitivo  [4,5]. Num estudo aleat\u00f3rio, foi demonstrada a n\u00e3o inferioridade da suplementa\u00e7\u00e3o intravenosa de ferro em rela\u00e7\u00e3o \u00e0 suplementa\u00e7\u00e3o oral de ferro em doentes com doen\u00e7a inflamat\u00f3ria intestinal em remiss\u00e3o ou com atividade ligeira [6]. Para al\u00e9m da suplementa\u00e7\u00e3o com sais de ferro (II), que pode frequentemente provocar problemas gastrointestinais, a suplementa\u00e7\u00e3o oral com ferro (III) maltol \u00e9 agora tamb\u00e9m eficaz e aprovada [7].  <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13.png\"><img decoding=\"async\" width=\"1328\" height=\"1259\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13.png\" alt=\"\" class=\"wp-image-365856 lazyload\" style=\"--smush-placeholder-width: 1328px; --smush-placeholder-aspect-ratio: 1328\/1259;width:500px;height:undefinedpx\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13.png 1328w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-800x758.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-1160x1100.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-120x114.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-90x85.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-320x303.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-560x531.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-240x228.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-180x171.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-640x607.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb2_OH4_s13-1120x1062.png 1120w\" data-sizes=\"(max-width: 1328px) 100vw, 1328px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<h3 id=\"anemia-normocitica-normocromica\" class=\"wp-block-heading\">Anemia normoc\u00edtica normocr\u00f3mica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Na anemia normoc\u00edtica normocr\u00f3mica, a medi\u00e7\u00e3o da contagem de reticul\u00f3citos pode ser \u00fatil. Por exemplo, pode estar elevada na hemorragia subaguda ou na hem\u00f3lise. Uma contagem baixa de reticul\u00f3citos n\u00e3o exclui a possibilidade de hem\u00f3lise e depende das reservas de ferro, de infec\u00e7\u00f5es ou de reac\u00e7\u00f5es auto-imunes contra as c\u00e9lulas progenitoras hematopoi\u00e9ticas da medula \u00f3ssea. A medi\u00e7\u00e3o do<em> \u00cdndice de Rea\u00e7\u00e3o da Medula \u00d3ssea <\/em>(BMRI) \u00e9 \u00fatil para a diferencia\u00e7\u00e3o [8].  <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14.png\"><img decoding=\"async\" width=\"1281\" height=\"551\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14.png\" alt=\"\" class=\"wp-image-365858 lazyload\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/551;width:500px;height:undefinedpx\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14.png 1281w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-800x344.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-1160x499.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-120x52.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-90x39.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-320x138.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-560x241.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-240x103.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-180x77.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-640x275.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab2_OH4_s14-1120x482.png 1120w\" data-sizes=\"(max-width: 1281px) 100vw, 1281px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Os par\u00e2metros de hem\u00f3lise <strong>(Tab. 2) <\/strong>devem ser utilizados para diagnosticar a anemia hemol\u00edtica. Em particular, se houver suspeita de anemia hemol\u00edtica microangiop\u00e1tica, devem ser determinados os fragment\u00f3citos <strong>(Fig. 3) <\/strong>. As anemias hemol\u00edticas podem ser subdivididas em anemias hemol\u00edticas corpusculares e extracorpusculares.  <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14.png\"><img decoding=\"async\" width=\"2235\" height=\"1546\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14.png\" alt=\"\" class=\"wp-image-365859 lazyload\" style=\"--smush-placeholder-width: 2235px; --smush-placeholder-aspect-ratio: 2235\/1546;width:500px;height:undefinedpx\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14.png 2235w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-800x553.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-1160x802.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-2048x1417.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-120x83.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-90x62.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-320x221.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-560x387.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-1920x1328.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-240x166.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-180x125.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-640x443.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-1120x775.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb3_OH4_s14-1600x1107.png 1600w\" data-sizes=\"(max-width: 2235px) 100vw, 2235px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">As anemias hemol\u00edticas auto-imunes (AIHA) pertencem \u00e0s anemias extracorpusculares. Existem diferentes crit\u00e9rios de diagn\u00f3stico para a AIHA. Num SLR, o crit\u00e9rio mais comummente utilizado para uma AIHA \u00e9 &#8220;anemia hemol\u00edtica com teste direto de antiglobulina positivo e exclus\u00e3o de outras causas&#8221; [9]. Fisiopatologicamente, na AIHA existe uma resposta imunit\u00e1ria contra antig\u00e9nios de gl\u00f3bulos vermelhos aut\u00f3logos [10]. A distin\u00e7\u00e3o entre uma forma prim\u00e1ria e uma forma secund\u00e1ria \u00e9 incoerente. No entanto, a forma prim\u00e1ria \u00e9 geralmente referida como idiop\u00e1tica [9]. Mais pormenorizadamente, os anticorpos de calor distinguem-se dos anticorpos de frio <strong>(Tab. 3) <\/strong>. Raramente, existem tamb\u00e9m AIHA mistos, hemoglobin\u00faria parox\u00edstica pelo frio (PCH\/AIHA do tipo Donath-Landsteiner) e AIHA at\u00edpicos. Os anticorpos do frio com uma causa linfoproliferativa s\u00e3o por vezes tamb\u00e9m referidos na literatura como &#8220;doen\u00e7as da aglutinina do frio&#8221; (DAC). Os anticorpos contra o frio no l\u00fapus eritematoso sist\u00e9mico (LES), pneumonia por micoplasma, infe\u00e7\u00e3o por EBV ou linfoma agressivo s\u00e3o por vezes tamb\u00e9m referidos como &#8220;s\u00edndrome da aglutinina fria&#8221; (CAS) [9].  <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14.png\"><img decoding=\"async\" width=\"1269\" height=\"762\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14.png\" alt=\"\" class=\"wp-image-365860 lazyload\" style=\"--smush-placeholder-width: 1269px; --smush-placeholder-aspect-ratio: 1269\/762;width:500px;height:undefinedpx\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14.png 1269w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-800x480.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-1160x697.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-120x72.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-90x54.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-320x192.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-560x336.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-240x144.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-180x108.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-640x384.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/tab3_OH4_s14-1120x673.png 1120w\" data-sizes=\"(max-width: 1269px) 100vw, 1269px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Os anticorpos contra o frio s\u00e3o do tipo IgM e s\u00e3o principalmente dirigidos contra o antig\u00e9nio &#8220;I&#8221; ou &#8220;i&#8221; dos eritr\u00f3citos. As liga\u00e7\u00f5es ocorrem atrav\u00e9s de for\u00e7as de van der Waals e liga\u00e7\u00f5es de hidrog\u00e9nio, que s\u00e3o mais frequentes a temperaturas mais frias, tendo em conta o movimento molecular browniano. Os anticorpos contra o calor s\u00e3o, na sua maioria, do tipo IgG e dirigidos contra o complexo de Rhesus ou o antig\u00e9nio da glicoforina. A n\u00edvel celular, um desequil\u00edbrio das c\u00e9lulas T reguladoras CD4+\/CD25+, o aumento da atividade das c\u00e9lulas TH17, o mimetismo molecular e as &#8220;esp\u00e9cies reactivas de oxig\u00e9nio&#8221; (ROS) s\u00e3o discutidos como causas da AIHA [11].  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em termos de diagn\u00f3stico, \u00e9 necess\u00e1rio um teste direto de antiglobulina (DAT) se houver suspeita de AIHA. Este detecta imunoglobulinas (principalmente IgG, raramente tamb\u00e9m IgM, IgA ou C3d condicionalmente) na membrana dos eritr\u00f3citos. Em 5-10% das AIHAs, o DAT pode ainda ser negativo [11]. Os valores de corte para os t\u00edtulos de anticorpos no frio s\u00e3o definidos de forma diferente, mas situam-se geralmente num intervalo entre 64-500 (a 4 \u00b0C) [9].  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deve ser efectuada uma bi\u00f3psia da medula \u00f3ssea especialmente em casos de AIHA com uma causa pouco clara, em particular em casos de idade avan\u00e7ada (&gt;60 anos), sintomatologia B, hepatoesplenomegalia ou citopenias no sangue perif\u00e9rico, de modo a excluir uma causa hemato-oncol\u00f3gica.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O tratamento da AIHA depende do tipo de anticorpo e da gravidade. A suplementa\u00e7\u00e3o com \u00e1cido f\u00f3lico \u00e9 recomendada em todos os n\u00edveis de gravidade. A AHAI grave com anticorpos contra o calor \u00e9 inicialmente tratada com metil ou prednisolona. A preven\u00e7\u00e3o do frio na AIHA com anticorpos contra o frio deve ser considerada como profilaxia prim\u00e1ria. Na AIHA grave com anticorpos frios, pode ser administrada terap\u00eautica com rituximab. A plasmaf\u00e9rese tem apenas um benef\u00edcio tempor\u00e1rio e deve ser reservada para padr\u00f5es de doen\u00e7a graves. As abordagens terap\u00eauticas modernas consistem no bloqueio do sistema do complemento, do recetor de IL-2, da fosfatidilinositol 3-quinase ou do eixo mTOR [11].  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O LES, em particular, pode levar a uma anemia hemol\u00edtica com anticorpos contra o calor. Para a AHAI ligeira, uma inje\u00e7\u00e3o oral de prednisolona \u00e9 normalmente suficiente; para a AHAI grave, deve ser administrada terap\u00eautica com metilprednisolona intravenosa ou imunossupress\u00e3o acrescida com rituximab, azatioprina, micofenolato de mofetil (MMF) ou ciclofosfamida [12]. Uma revis\u00e3o sistem\u00e1tica da literatura mostrou tamb\u00e9m que os doentes com LES e s\u00edndrome antifosfolip\u00eddica t\u00eam um risco 2,8 vezes maior de anemia hemol\u00edtica [13].  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra causa de anemia extracorpuscular \u00e9 a anemia hemol\u00edtica microangiop\u00e1tica (MAHA). Clinicamente, para al\u00e9m da hem\u00f3lise, verifica-se trombocitopenia e fragmentocitos devido \u00e0 forma\u00e7\u00e3o de microtrombos. Um subtipo de MAHA \u00e9 a microangiopatia tromb\u00f3tica (TMA), que pode ser subdividida em p\u00farpura trombocitop\u00e9nica tromb\u00f3tica (PTT), TMA associada a infe\u00e7\u00e3o e TMA mediada por complemento (CM-TMA) <strong>(Fig. 4)<\/strong>. Para efeitos de diagn\u00f3stico, deve ser determinada a ADAMTS13, que est\u00e1 diminu\u00edda na PTT. A determina\u00e7\u00e3o de bact\u00e9rias produtoras de shigatoxina (incluindo O157:H7, Shigella dysenteriae tipo I) nas fezes pode ser \u00fatil no diagn\u00f3stico de TMA induzida por shigatoxina (tamb\u00e9m designada ST-HUS). Muito mais raramente, a infe\u00e7\u00e3o pneumoc\u00f3cica tamb\u00e9m pode levar a TMA associada \u00e0 infe\u00e7\u00e3o [14]. A determina\u00e7\u00e3o de diferentes factores do complemento, bem como de anticorpos contra o fator H, pode ser \u00fatil na CM-TMA. No entanto, um n\u00edvel normal de factores do complemento n\u00e3o exclui a CM-TMA. O anticorpo monoclonal C5 recombinante eculizumab est\u00e1 dispon\u00edvel para terap\u00eautica do CM-TMA. A terap\u00eautica do TTP consiste na imunossupress\u00e3o com prednisolona ou metilprednisolona, rituximab e o fragmento de anticorpo contra o FvW caplacizumab [15]. No caso da AMT associada a uma infe\u00e7\u00e3o, \u00e9 administrada uma terapia de suporte. H\u00e1 relatos de casos de um poss\u00edvel benef\u00edcio da plasmaf\u00e9rese com substitui\u00e7\u00e3o de albumina [16].  <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16.png\"><img decoding=\"async\" width=\"1781\" height=\"1574\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16.png\" alt=\"\" class=\"wp-image-365861 lazyload\" style=\"--smush-placeholder-width: 1781px; --smush-placeholder-aspect-ratio: 1781\/1574;width:500px;height:undefinedpx\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16.png 1781w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-800x707.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-1160x1025.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-120x106.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-90x80.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-320x283.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-560x495.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-240x212.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-180x159.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-640x566.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-1120x990.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/09\/abb4_OH4_s16-1600x1414.png 1600w\" data-sizes=\"(max-width: 1781px) 100vw, 1781px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Diferentemente, a MAHA tamb\u00e9m pode ser causada por determinadas doen\u00e7as auto-imunes. O termo para MAHA induzida por autoimunidade n\u00e3o \u00e9 uniforme. Entre outros, \u00e9 tamb\u00e9m utilizado o termo TMA induzida por autoimunidade. O l\u00fapus eritematoso sist\u00e9mico pode ser a causa de TMA\/MAHA, o que foi demonstrado particularmente na nefrite l\u00fapica. As manifesta\u00e7\u00f5es fisiopatol\u00f3gicas incluem a sobreactiva\u00e7\u00e3o das vias cl\u00e1ssica e alternativa da cascata do complemento. A deposi\u00e7\u00e3o renal de C4d e a redu\u00e7\u00e3o dos n\u00edveis s\u00e9ricos de fator H parecem estar associadas a um mau progn\u00f3stico renal [17]. Existem relatos de casos sobre a utiliza\u00e7\u00e3o de eculizumab, mas alguns deles n\u00e3o puderam ser reproduzidos [18]. A terapia imunossupressora intensificada com metilprednisolona, MMF ou ciclofosfamida \u00e9 frequentemente utilizada como alternativa [17]. Raramente, a s\u00edndrome antifosfolip\u00eddica catastr\u00f3fica (CAPS) pode acompanhar a TMA renal. A terap\u00eautica tripla composta por glucocortic\u00f3ides, anticoagula\u00e7\u00e3o e plasmaf\u00e9rese ou imunoglobulinas mostra uma melhoria da sobreviv\u00eancia [19,20].  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A esclerose sist\u00e9mica com crise renal pode apresentar-se clinicamente com hem\u00f3lise e trombocitopenia e fragment\u00f3citos [21]. Neste caso, \u00e9 necess\u00e1rio um esclarecimento do diagn\u00f3stico diferencial de outras causas de MAHA. De um modo geral, uma bi\u00f3psia renal para distinguir entre diferentes causas de AMT n\u00e3o \u00e9 \u00fatil nem objetiva.  <\/p>\n\n\n\n<h3 id=\"anemia-macrocitica-hipercromica\" class=\"wp-block-heading\">Anemia macroc\u00edtica hipercr\u00f3mica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Uma poss\u00edvel causa de anemia macroc\u00edtica hipercr\u00f3mica em doentes submetidos a terap\u00eautica com metotrexato \u00e9, para al\u00e9m de uma defici\u00eancia nutricional, a ingest\u00e3o incorrecta ou n\u00e3o ingest\u00e3o de \u00e1cido f\u00f3lico com a consequente defici\u00eancia de \u00e1cido f\u00f3lico. A substitui\u00e7\u00e3o do \u00e1cido f\u00f3lico (no dia seguinte \u00e0 toma do metotrexato) e a educa\u00e7\u00e3o sobre o modo de a\u00e7\u00e3o do metotrexato s\u00e3o geralmente suficientes para este efeito.  <\/p>\n\n\n\n<h3 id=\"pancitopenia\" class=\"wp-block-heading\">Pancitopenia  <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Um caso especial de anemia \u00e9 a pancitopenia imunomediada nas doen\u00e7as auto-imunes. O l\u00fapus eritematoso sist\u00e9mico, embora raro, pode apresentar-se com pancitopenia (geralmente tamb\u00e9m no diagn\u00f3stico inicial). Menos frequentemente, as doen\u00e7as auto-imunes, como a sarcoidose, a s\u00edndrome de Sj\u00f6gren, a esclerose sist\u00e9mica ou a artrite reumatoide, tamb\u00e9m podem levar a pancitopenia imunomediada, mas normalmente apresentam-se mais como monocitopenia ou bicitopenia. Para al\u00e9m de uma doen\u00e7a hemato-oncol\u00f3gica ou de uma causa infecciosa, deve ser sempre considerada para o diagn\u00f3stico diferencial uma causa t\u00f3xica relacionada com medicamentos devido a metotrexato, ciclofosfamida, azatioprina ou outras subst\u00e2ncias. A pancitopenia perif\u00e9rica no LES tamb\u00e9m pode ocorrer com o envolvimento de outros \u00f3rg\u00e3os, como polisserosite, nefrite l\u00fapica, artrite, envolvimento do SNC, esplenomegalia ou envolvimento da pele. A aspira\u00e7\u00e3o da medula \u00f3ssea deve ser efectuada em casos pouco claros e, classicamente, mostra um quadro hipocelular com necrose da medula \u00f3ssea no LES [22]. Uma complica\u00e7\u00e3o rara e potencialmente fatal do LES \u00e9 a s\u00edndrome de ativa\u00e7\u00e3o macrof\u00e1gica (HLH-MAS). N\u00edveis de ferritina muito elevados s\u00e3o um sintoma cl\u00e1ssico e uma express\u00e3o de atividade auto-inflamat\u00f3ria aumentada. A mielofibrose induzida por autoimunidade \u00e9 uma raridade, pelo que s\u00f3 deve ser diagnosticada ap\u00f3s a exclus\u00e3o de doen\u00e7as hemato-oncol\u00f3gicas [23].  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em termos terap\u00eauticos, a imunossupress\u00e3o \u00e9 o principal tratamento para a pancitopenia imunomediada devida ao LES. Recomenda-se uma terap\u00eautica de curto prazo com prednisolona e terapias imunomoduladoras b\u00e1sicas com hidroxicloroquina, MMF ou azatioprina [24,25]. Na doen\u00e7a persistente, pode ser administrada terap\u00eautica com ciclofosfamida, rituximab, belimumab ou anifrolumab [24\u201326].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Herold G: Innere Medizin 2021; 32.<\/li>\n\n\n\n<li>Ganzoni AM: Intravenous iron-dextran: therapeutic and experimental possibilities. Schweiz Med Wochenschr 1970; 100(7): 301\u2013303.<\/li>\n\n\n\n<li>Elstrott B, et al.: The role of iron repletion in adult iron deficiency anemia and other diseases. Eur J Haematol 2020; 104(3): 153\u2013161.<\/li>\n\n\n\n<li>Weiss G, et al.: Anemia of inflammation. Blood 2019; 133 (1): 40\u201350.<\/li>\n\n\n\n<li>Cappellini MD, et al.: Iron deficiency across chronic inflammatory conditions: International expert opinion on definition, diagnosis, and management. Am J Hematol 2017; 92(10): 1068\u20131078.<\/li>\n\n\n\n<li>Reinisch W, et al.: A randomized, open-label, non-inferiority study of intravenous iron isomaltoside 1,000 (Monofer) compared with oral iron for treatment of anemia in IBD (PROCEED). AM J Gastroenterol 2013; 108(12): 1877\u20131888.<\/li>\n\n\n\n<li>Gasche C, et al.: Ferric maltol is effective in correcting iron deficiency anemia in patients with inflammatory bowel disease: results from a phase-3 clinical trial program. Inflamm Bowel Disc 2015; 21(3): 579\u2013588.<\/li>\n\n\n\n<li>Barcellini W, et al: Aplica\u00e7\u00f5es cl\u00ednicas de marcadores hemol\u00edticos no diagn\u00f3stico diferencial e manejo da anemia hemol\u00edtica. Dis Markers 2015; 2015 635670.<\/li>\n\n\n\n<li>Hill QA, et al: Definindo anemia hemol\u00edtica autoimune: uma revis\u00e3o sistem\u00e1tica da terminologia usada para diagn\u00f3stico e tratamento. Blood Adv 2019; 3(12): 1897-1906.<\/li>\n\n\n\n<li>Jager U, et al: Diagn\u00f3stico e tratamento da anemia hemol\u00edtica autoimune em adultos: Recomenda\u00e7\u00f5es da Primeira Reuni\u00e3o de Consenso Internacional. Blood Rev 2020; 41 100648.<\/li>\n\n\n\n<li>Michalak SS, et al: Anemia hemol\u00edtica autoimune: conhecimentos e perspectivas actuais. Immune Ageing 2020; 17(1): 38.<\/li>\n\n\n\n<li>Fayyaz A, et al.: Haematological manifestations of lupus. Lupus Sci Med 2015; 2(1): e000078.<\/li>\n\n\n\n<li>Bernardoff I, et al.: Antiphospholipid antibodies and the risk of autoimmune hemolytic anemia in patients with systemic lupus erythematosus: A systematic review and meta-analysis. Autoimmun Rev 2022; 21(1): 102913.<\/li>\n\n\n\n<li>Thompson GL, et al.: Diagnosis and treatment of thrombotic microangiopathy. Int J Lab Hematol 2022; 44(1): 101\u2013113.<\/li>\n\n\n\n<li>Dutt T, et al.: Real-world experience with caplacizumab in the management of acute TTP. Blood 2021; 137(13): 1731\u20131740.<\/li>\n\n\n\n<li>Hopkins CK, et al.: A severe case of atypical hemolytic uremic syndrome associated with pneumococcal infection and T activation treated successfully with plasma exchange. Transfusion 2008; 48(11): 2448-2452.<\/li>\n\n\n\n<li>Song D, et al.: The spectrum of renal thrombotic microangiopathy in lupus nephritis. Arthritis Res Ther 2013; 15 (1): R12.<\/li>\n\n\n\n<li>Brocklebank V, et al.: Complement C5-inhibiting therapy for the thrombotic microangiopathies: accumulating evidence, but not a panacea. Clin Kidney J 2017; 10(5): 600\u2013624.<\/li>\n\n\n\n<li>Rodriguez-Pinto I, et al.: The effect of triple therapy on the mortality of catastrophic anti-phospholipid syndrome patients. Rheumatology (Oxford) 2018; 57(7): 1264\u20131270.<\/li>\n\n\n\n<li>Cervera R, et al.: Catastrophic antiphospholipid syndrome (CAPS): descriptive analysis of a series of 280 patients from the \u00abCAPS Registry\u00bb. J Autoimmun 2009; 32(3\u20134): 240-245.<\/li>\n\n\n\n<li>Helfrich DJ, et al.: Normotensive renal failure in systemic sclerosis. Arthritis Rheum 1989; 32(9): 1128-1134.<\/li>\n\n\n\n<li>Wanitpongpun C, et al.: Bone marrow abnormalities in systemic lupus erythematosus with peripheral cytopenia. Clin Exp Rheumatol 2012; 30(6): 825\u2013829.<\/li>\n\n\n\n<li>Vergara-Lluri ME, et al.: Autoimmune myelofibrosis: an update on morphologic features in 29 cases and review of the literature. Hum Pathol 2014; 45(11): 2183\u20132191.<\/li>\n\n\n\n<li>Fanouriakis A, et al.: Update omicronn the diagnosis and management of systemic lupus erythematosus. Ann Rheum Dis 2021; 80 (1): 14\u201325.<\/li>\n\n\n\n<li>Fanouriakis A, et al.: 2019 update of the EULAR recommendations for the management of systemic lupus erythematosus. Ann Rheum Dis 2019; 78 (6): 736-745.<\/li>\n\n\n\n<li>Chatham WW, et al.: Long-Term Safety and Efficacy of Anifrolumab in Adults With Systemic Lupus Erythematosus: Results of a Phase II Open-Label Extension Study. Arthritis Rheumatol 2021; 73(5): 816\u2013825.<\/li>\n<\/ol>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>HAUSARZT PRAXIS 2023; 18(9): 4\u20139<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A anemia \u00e9 uma ocorr\u00eancia comum nos cuidados m\u00e9dicos de rotina, cujas causas podem ser m\u00faltiplas. A anemia refere-se a uma redu\u00e7\u00e3o dos n\u00edveis de hemoglobina e hemat\u00f3crito. O valor&hellip;<\/p>\n","protected":false},"author":7,"featured_media":366269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Anemia","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11551,11521,22618,11365,11305,11403,11379],"tags":[71141,71139,71135,71138,13073,71140,46448,71136],"powerkit_post_featured":[],"class_list":["post-366762","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-pt","category-estudos","category-formacao-cme","category-hematologia-pt-pt","category-medicina-interna-geral","category-nutricao","category-oncologia-pt-pt","tag-acd-pt-pt","tag-anemia-hemolitica-microangiopatica","tag-anemia-microcitica-hipocromica","tag-anemia-normocitica-normocromica","tag-doencas-auto-imunes","tag-inflamacao-anemia","tag-maha-pt-pt","tag-pancitopenia-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:28:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":366759,"slug":"las-enfermedades-autoinmunes-como-causa-de-anemia-2","post_title":"Las enfermedades autoinmunes como causa de anemia","href":"https:\/\/medizinonline.com\/es\/las-enfermedades-autoinmunes-como-causa-de-anemia-2\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/366762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=366762"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/366762\/revisions"}],"predecessor-version":[{"id":367663,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/366762\/revisions\/367663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/366269"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=366762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=366762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=366762"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=366762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}