{"id":372518,"date":"2024-01-26T00:01:00","date_gmt":"2024-01-25T23:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=372518"},"modified":"2024-01-26T10:19:37","modified_gmt":"2024-01-26T09:19:37","slug":"disfagia-causa-central","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/disfagia-causa-central\/","title":{"rendered":"Disfagia \u2013 causa central"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A degluti\u00e7\u00e3o \u00e9 um processo sens\u00f3rio-motor com componentes volunt\u00e1rios e reflexivos. Para al\u00e9m das doen\u00e7as neurol\u00f3gicas e musculares, as perturba\u00e7\u00f5es da degluti\u00e7\u00e3o podem ser causadas por altera\u00e7\u00f5es tumorais ou cir\u00fargicas na zona da cabe\u00e7a e do pesco\u00e7o, do es\u00f3fago ou do est\u00f4mago. Os exames imagiol\u00f3gicos permitem visualizar as estruturas e os processos envolvidos. As medidas terap\u00eauticas podem ser derivadas dos resultados do diagn\u00f3stico da disfagia.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">Nos artigos sobre disfagia, foram descritas numerosas altera\u00e7\u00f5es locais no trato digestivo superior. Uma causa bastante rara da perturba\u00e7\u00e3o funcional \u00e9 uma altera\u00e7\u00e3o do tronco cerebral com poss\u00edvel afe\u00e7\u00e3o dos nervos cranianos respons\u00e1veis pelo ato de engolir. As les\u00f5es das vias corticobulbares descendentes para o tronco cerebral, por exemplo, uma massa ou altera\u00e7\u00f5es inflamat\u00f3rias ap\u00f3s um ataque card\u00edaco, podem causar problemas agudos de degluti\u00e7\u00e3o.<\/p>\n\n<p class=\"wp-block-paragraph\">O ato de engolir \u00e9 um processo complexo que requer a intera\u00e7\u00e3o precisa de numerosos m\u00fasculos, controlados por v\u00e1rios centros e vias nervosas. O sucesso da degluti\u00e7\u00e3o requer o encerramento da nasofaringe e o encerramento da laringe pela epiglote [1]. Normalmente, engolimos entre 600-2000 vezes por dia. Fora das refei\u00e7\u00f5es, engole cerca de 0,5-1,5 ml de saliva por tragada, aproximadamente uma vez por minuto, quando est\u00e1 acordado. Para uma refei\u00e7\u00e3o pequena de 6 minutos, s\u00e3o necess\u00e1rios cerca de 32 goles. Quase nenhuma saliva \u00e9 produzida e engolida durante o sono profundo [2]. Os n\u00facleos dos cinco nervos cranianos <em>(nervo trig\u00e9meo, nervo facial, nervo hipoglosso, nervo vago, nervo glossofar\u00edngeo)<\/em>, que irrigam os 100 m\u00fasculos dos \u00f3rg\u00e3os envolvidos na degluti\u00e7\u00e3o (bochechas, l\u00e1bios, mand\u00edbula, l\u00edngua, palato mole, faringe, laringe, osso hioide, es\u00f3fago), est\u00e3o localizados na zona do tronco cerebral.<\/p>\n\n<p class=\"wp-block-paragraph\">O processo de degluti\u00e7\u00e3o \u00e9 apresentado no <strong>Quadro 1<\/strong>.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1315\" height=\"1090\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45.png\" alt=\"\" class=\"wp-image-372479\" style=\"width:500px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45.png 1315w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-800x663.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-1160x962.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-120x99.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-90x75.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-320x265.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-560x464.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-240x199.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-180x149.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-640x530.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab1_HP12_s45-1120x928.png 1120w\" sizes=\"(max-width: 1315px) 100vw, 1315px\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">O reflexo de degluti\u00e7\u00e3o \u00e9 desencadeado pelo contacto do alimento com a parede da faringe. As vias aferentes e eferentes respons\u00e1veis s\u00e3o diferenciadas na <strong>Tabela 2<\/strong>.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45.png\"><img decoding=\"async\" width=\"1160\" height=\"532\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-1160x532.png\" alt=\"\" class=\"wp-image-372485 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-1160x532.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-800x367.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-120x55.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-90x41.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-320x147.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-560x257.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-240x110.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-180x83.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-640x293.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45-1120x514.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/tab2_HP12_s45.png 1302w\" data-sizes=\"(max-width: 1160px) 100vw, 1160px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1160px; --smush-placeholder-aspect-ratio: 1160\/532;\" \/><\/a><\/figure>\n<\/div><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12.jpg\"><img decoding=\"async\" width=\"958\" height=\"1112\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12.jpg\" alt=\"\" class=\"wp-image-372480 lazyload\" style=\"--smush-placeholder-width: 958px; --smush-placeholder-aspect-ratio: 958\/1112;width:400px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12.jpg 958w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12-800x929.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12-120x139.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12-90x104.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12-320x371.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12-560x650.jpg 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12-240x279.jpg 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12-180x209.jpg 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1A_HP12-640x743.jpg 640w\" data-sizes=\"(max-width: 958px) 100vw, 958px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n<h3 id=\"estudo-de-caso\" class=\"wp-block-heading\">Estudo de caso<\/h3>\n\n<p class=\"wp-block-paragraph\">O <strong>estudo de caso<\/strong> documenta o processo de diagn\u00f3stico por imagem numa doente de 76 anos com tosse, sensa\u00e7\u00e3o de globus e disfagia no exame inicial. O exame otorrinolaringol\u00f3gico n\u00e3o revelou quaisquer achados patol\u00f3gicos na cavidade oral e hipofaringe, e as imagens contrastadas do es\u00f3fago na \u00e1rea da coluna cervical n\u00e3o mostraram qualquer patologia relevante <strong>(Fig. 1A)<\/strong>. Cerca de 3 meses depois, o doente foi encaminhado para uma TAC dos tecidos moles do pesco\u00e7o <strong>(Fig. 1B e C) <\/strong>. Estas eram novamente normais. No entanto, um achado patol\u00f3gico na regi\u00e3o do \u00e2ngulo ponto-cerebelar (regi\u00e3o CACA) \u00e0 esquerda era evidente. Para melhor esclarecimento, foi efectuada uma resson\u00e2ncia magn\u00e9tica da cabe\u00e7a, que confirmou um grande neuroma ac\u00fastico degenerado \u00e0 esquerda, com uma parte extrameatal volumosa e uma parte intrameatal mais pequena. Isto resultou numa impress\u00e3o consider\u00e1vel do tronco cerebral. O facto de n\u00e3o haver edema significativo na regi\u00e3o do c\u00e9rebro sugeria uma massa de crescimento lento <strong>(Fig. 1D e E)<\/strong>.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12.jpg\"><img decoding=\"async\" width=\"1098\" height=\"2315\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12.jpg\" alt=\"\" class=\"wp-image-372481 lazyload\" style=\"--smush-placeholder-width: 1098px; --smush-placeholder-aspect-ratio: 1098\/2315;width:400px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12.jpg 1098w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-800x1687.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-971x2048.jpg 971w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-120x253.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-90x190.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-320x675.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-560x1181.jpg 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-240x506.jpg 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-180x380.jpg 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/abb1BC_HP12-640x1349.jpg 640w\" data-sizes=\"(max-width: 1098px) 100vw, 1098px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">O neuroma do ac\u00fastico (NAC) \u00e9 um tumor benigno do sistema nervoso perif\u00e9rico [4]. S\u00e3o respons\u00e1veis por 8% de todos os tumores intracranianos. Com um crescimento geralmente bastante lento, os sintomas aparecem muito tarde. Se os tumores permanecerem pequenos, pode n\u00e3o haver sintomas de tonturas ou perda de audi\u00e7\u00e3o. Se se notar um aumento lento da perda auditiva, um teste de audi\u00e7\u00e3o pode indicar a mudan\u00e7a. \u00c9 t\u00edpica uma deteriora\u00e7\u00e3o da gama de altas frequ\u00eancias (o canto dos p\u00e1ssaros \u00e9 menos percet\u00edvel). No entanto, tamb\u00e9m \u00e9 poss\u00edvel uma perda de audi\u00e7\u00e3o s\u00fabita. Um schwannoma intracoclear muito pequeno tamb\u00e9m deve ser considerado [6]. AKN tamb\u00e9m pode ser uma poss\u00edvel causa de zumbido, bem como causar vertigens de rota\u00e7\u00e3o e oscila\u00e7\u00e3o acompanhadas de n\u00e1useas e\/ou nistagmo. Em casos muito raros, os grandes neurinomas podem causar um dist\u00farbio da circula\u00e7\u00e3o do l\u00edquido cefalorraquidiano com um aumento da press\u00e3o, acompanhado de dores de cabe\u00e7a, rigidez do pesco\u00e7o, n\u00e1useas, v\u00f3mitos e vis\u00e3o deficiente. Foram descritas hemorragias subaracnoides causadas por um AKN [3]. No caso em apre\u00e7o, para al\u00e9m de um dist\u00farbio persistente da degluti\u00e7\u00e3o, havia apenas uma ligeira perda de audi\u00e7\u00e3o e tonturas ocasionais, que foram anteriormente interpretadas como queixas adequadas \u00e0 idade.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE.jpg\"><img decoding=\"async\" width=\"1160\" height=\"746\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-1160x746.jpg\" alt=\"\" class=\"wp-image-372482 lazyload\" style=\"--smush-placeholder-width: 1160px; --smush-placeholder-aspect-ratio: 1160\/746;width:500px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-1160x746.jpg 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-800x514.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-120x77.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-90x58.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-320x206.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-560x360.jpg 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-240x154.jpg 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-180x116.jpg 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-640x411.jpg 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-1120x720.jpg 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE-1600x1028.jpg 1600w, https:\/\/medizinonline.com\/wp-content\/uploads\/2023\/12\/Abb1DE.jpg 1836w\" data-sizes=\"(max-width: 1160px) 100vw, 1160px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><em>Os exames de tomografia computorizada<\/em> j\u00e1 n\u00e3o s\u00e3o o procedimento de imagem de elei\u00e7\u00e3o para o diagn\u00f3stico dos neuromas do ac\u00fastico. O contraste dos tecidos moles \u00e9 inferior ao da resson\u00e2ncia magn\u00e9tica. Os pequenos AKN podem escapar \u00e0 dete\u00e7\u00e3o por TC, especialmente no diagn\u00f3stico nativo, enquanto as massas maiores, como neste estudo de caso, podem ser detectadas em exames com contraste.<\/p>\n\n<p class=\"wp-block-paragraph\">A <em>resson\u00e2ncia magn\u00e9tica<\/em> \u00e9 o padr\u00e3o de ouro para o neuroma ac\u00fastico de imagem. A aplica\u00e7\u00e3o intravenosa do meio de contraste mostra um claro aumento do sinal e, frequentemente, as duas formas histol\u00f3gicas (Antoni tipo A e B) podem ser diferenciadas pelas altera\u00e7\u00f5es regressivas do tipo 2 [5,6]. A extens\u00e3o total com pe\u00e7as extra e intra-metais \u00e9 facilmente avali\u00e1vel. Se a AKN s\u00f3 tem uma parte extrameatal (cerca de 20% dos casos), a diferencia\u00e7\u00e3o em rela\u00e7\u00e3o a um meningioma pode ser problem\u00e1tica. <\/p>\n\n<p class=\"wp-block-paragraph\">O estudo de caso demonstra de forma impressionante a diferen\u00e7a na imagiologia. A RM mostra a extens\u00e3o intrameatal exacta do neurinoma e as altera\u00e7\u00f5es regressivas no interior do tumor devido ao maior contraste dos tecidos moles.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Mensagens para levar para casa<\/strong><\/p>\n\n<ul class=\"wp-block-list\">\n<li>O neuroma ac\u00fastico \u00e9 a massa intracraniana benigna mais comum.<\/li>\n\n\n\n<li>A disfagia pode ter in\u00fameras causas no trato digestivo superior como sintoma, mas tamb\u00e9m pode ser o resultado de uma perturba\u00e7\u00e3o central.<\/li>\n\n\n\n<li>Para al\u00e9m das les\u00f5es dos tratos corticobulbares, podem estar presentes les\u00f5es que ocupam espa\u00e7o na regi\u00e3o do \u00e2ngulo da ponte do cerebelo com altera\u00e7\u00e3o do tronco cerebral.<\/li>\n\n\n\n<li>No diagn\u00f3stico por imagem, a resson\u00e2ncia magn\u00e9tica com meio de contraste intravenoso \u00e9 o procedimento padr\u00e3o para a dete\u00e7\u00e3o destes tumores.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Literatura:  <\/p>\n\n<ol class=\"wp-block-list\">\n<li>\u00abSchluckakt\u00bb, <a href=\"https:\/\/flexikon.doccheck.com\/de\/Schluckakt\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/flexikon.doccheck.com\/de\/Schluckakt<\/a>, (letzter Abruf 22.11.2023) <\/li>\n\n\n\n<li>\u00abSchluckvorgang\u00bb, <a href=\"http:\/\/www.winvitalis.de\/ratgeber\/ernaehrung-bei-dysphagie\" target=\"_blank\" rel=\"noopener\">www.winvitalis.de\/ratgeber\/ernaehrung-bei-dysphagie<\/a>, (letzter Abruf 22.11.2023)<\/li>\n\n\n\n<li>Miller ME, et al.: Intracochlear schwannoma presenting as diffuse cochlear enhancement: diagnostic challanges of rare cause of deafness. Ir J Med Sci 2012; 181(1): 131\u2013134.<\/li>\n\n\n\n<li>Schwarz R: Akustikusneurinom. [online], <a href=\"http:\/\/www.netdoktor.de\" target=\"_blank\" rel=\"noopener\">www.netdoktor.de<\/a>, (letzter Abruf 22.11.2023)<\/li>\n\n\n\n<li>Thiel HJ: Akustikusneurinom. <a href=\"https:\/\/medizinonline.com\/pt-pt\/tonturas-e-perda-de-audicao-dos-sintomas-ao-diagnostico\/\">InFo Schmerz &amp; Geriatrie 2021; 3(2): 34\u201335<\/a>.<\/li>\n\n\n\n<li>Uhlenbrock D, Forsting M: MRT und MRA des Kopfes. 2., vollst\u00e4ndig \u00fcberarbeitete und erweiterte Auflage. Georg Thieme Verlag Stuttgart, New York 2007; pp. 89\u201391.<\/li>\n<\/ol>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>HAUSARZT PRAXIS 2023; 18(12): 45\u201347<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A degluti\u00e7\u00e3o \u00e9 um processo sens\u00f3rio-motor com componentes volunt\u00e1rios e reflexivos. Para al\u00e9m das doen\u00e7as neurol\u00f3gicas e musculares, as perturba\u00e7\u00f5es da degluti\u00e7\u00e3o podem ser causadas por altera\u00e7\u00f5es tumorais ou cir\u00fargicas&hellip;<\/p>\n","protected":false},"author":7,"featured_media":372520,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Do sintoma ao diagn\u00f3stico","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11536,11524,11407,11305,11439,11486,11551],"tags":[12009,12496,73578,73579,73576,73577],"powerkit_post_featured":[],"class_list":["post-372518","post","type-post","status-publish","format-standard","has-post-thumbnail","category-casos-pt-pt","category-formacao-continua","category-gastroenterologia-e-hepatologia","category-medicina-interna-geral","category-orl-pt-pt","category-radiologia-pt-pt","category-rx-pt","tag-disfagia","tag-disfagia-pt-pt","tag-engolir","tag-exames-imagiologicos","tag-refletor","tag-sensorio-motor","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:29:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":372524,"slug":"disfagia-causa-central","post_title":"Disfagia \u2013 causa central","href":"https:\/\/medizinonline.com\/es\/disfagia-causa-central\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/372518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=372518"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/372518\/revisions"}],"predecessor-version":[{"id":374323,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/372518\/revisions\/374323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/372520"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=372518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=372518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=372518"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=372518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}