{"id":375083,"date":"2024-03-31T00:01:00","date_gmt":"2024-03-30T23:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/qual-e-o-risco-dos-sglt2i-e-dos-glp1-ra\/"},"modified":"2024-03-31T00:01:10","modified_gmt":"2024-03-30T23:01:10","slug":"qual-e-o-risco-dos-sglt2i-e-dos-glp1-ra","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/qual-e-o-risco-dos-sglt2i-e-dos-glp1-ra\/","title":{"rendered":"Qual \u00e9 o risco dos SGLT2i e dos GLP1-RA?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Os inibidores do cotransportador s\u00f3dio-glicose 2 (SGLT2i) e os agonistas do recetor do p\u00e9ptido 1 semelhante ao glucagon (GLP1-RA) desempenham um papel importante na terapia da diabetes. No entanto, o seu efeito na neuropatia diab\u00e9tica e na retinopatia n\u00e3o \u00e9 claro. Num estudo do mundo real, cientistas brit\u00e2nicos investigaram a rela\u00e7\u00e3o entre os SGLT2i e os GLP1-RA e o risco a 5 anos de neuropatia diab\u00e9tica ou auton\u00f3mica, retinopatia diab\u00e9tica e edema macular, hospitaliza\u00e7\u00e3o e mortalidade por todas as causas na diabetes tipo 2.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">No tratamento da neuropatia diab\u00e9tica, h\u00e1 falta de estrat\u00e9gias terap\u00eauticas que visem o mecanismo subjacente \u00e0 les\u00e3o nervosa. Em vez disso, o tratamento limita-se ao tratamento sintom\u00e1tico com analg\u00e9sicos neurop\u00e1ticos, explicou Aikaterini Eleftheriadou, do Departamento de Medicina Cardiovascular e Metab\u00f3lica da Universidade de Liverpool, no in\u00edcio da sua apresenta\u00e7\u00e3o [1].<\/p>\n\n<p class=\"wp-block-paragraph\">Existem v\u00e1rias op\u00e7\u00f5es de tratamento para a retinopatia diab\u00e9tica, mas estas t\u00eam como objetivo a progress\u00e3o da doen\u00e7a. Estas incluem: Injec\u00e7\u00f5es de anti-VEGF e injec\u00e7\u00f5es intrav\u00edtreas de ester\u00f3ides, que podem ser dispendiosas. Existe tamb\u00e9m um grupo de doentes que n\u00e3o responde \u00e0s injec\u00e7\u00f5es anti-VEGF. A fotocoagula\u00e7\u00e3o a laser \u00e9 outra op\u00e7\u00e3o, mas desencadeia essencialmente um processo destrutivo.  <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Devemos, portanto, tentar evitar que estas doen\u00e7as ocorram em primeiro lugar ou, uma vez ocorridas, travar a sua progress\u00e3o.&#8221; O especialista citou v\u00e1rios estudos em que foi investigado o papel do controlo intensivo da glicose no sangue e da gest\u00e3o multifatorial:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>O estudo Steno-2 mostrou que o risco de retinopatia e neuropatia auton\u00f3mica era menor no grupo com controlo glic\u00e9mico intensivo.  <\/li>\n\n\n\n<li>No entanto, o estudo ADVANCE, o maior destes estudos, n\u00e3o mostrou efeitos significativos na retinopatia.<\/li>\n\n\n\n<li>No estudo ACCORD, foi observado um in\u00edcio tardio das complica\u00e7\u00f5es oculares e da neuropatia em algumas \u00e1reas.<\/li>\n\n\n\n<li>O estudo UKPDS-33 mostrou uma taxa mais baixa de fotocoagula\u00e7\u00e3o necess\u00e1ria.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Em termos de tratamento medicamentoso, os dados mostram que os inibidores da enzima de convers\u00e3o da angiotensina (IECA) podem reverter a retinopatia diab\u00e9tica e que os bloqueadores dos receptores da angiotensina (BRA) podem reduzir a melhoria da retinopatia em doentes que j\u00e1 tinham retinopatia no in\u00edcio do tratamento.<\/p>\n\n<h3 id=\"dados-contraditorios-ate-a-data\" class=\"wp-block-heading\">Dados contradit\u00f3rios at\u00e9 \u00e0 data<\/h3>\n\n<p class=\"wp-block-paragraph\">No que diz respeito a medicamentos espec\u00edficos para diab\u00e9ticos, alguns dados sugerem que os inibidores SGLT2 podem ter efeitos ben\u00e9ficos nos \u00edndices de neuropatia auton\u00f3mica e podem ser neuroprotectores. No entanto, o estudo CREDENCE, uma an\u00e1lise post-hoc de um RCT com 4401 participantes, mostrou que a canagliflozina n\u00e3o teve qualquer efeito no risco de eventos de neuropatia.<\/p>\n\n<p class=\"wp-block-paragraph\">No que diz respeito \u00e0 doen\u00e7a da retina, segundo Aikaterini Eleftheriadou, h\u00e1 tamb\u00e9m uma meta-an\u00e1lise atual que mostra uma influ\u00eancia positiva dos SGLT2i, enquanto meta-an\u00e1lises mais antigas n\u00e3o mostravam qualquer influ\u00eancia nesta doen\u00e7a.<\/p>\n\n<p class=\"wp-block-paragraph\">No caso dos agonistas dos receptores do p\u00e9ptido-1 semelhante ao glucagon (GLP1-RA), a maioria dos dados n\u00e3o mostra qualquer efeito nos resultados neurop\u00e1ticos e na doen\u00e7a da retina, com exce\u00e7\u00e3o do estudo Qatar, no qual o exenatido e a pioglitazona foram associados \u00e0 regenera\u00e7\u00e3o do nervo corneano. Em contraste, o estudo SUSTAIN-6 mostrou um aumento do risco de retinopatia com o semaglutido, embora este estudo se tenha centrado principalmente nos resultados cardiovasculares.  <\/p>\n\n<figure class=\"wp-block-table\"><table class=\"has-background\" style=\"background-color:#00d18421\"><tbody><tr><td><strong>Restri\u00e7\u00f5es<\/strong><\/td><\/tr><tr><td>Aikaterini Eleftheriadou chamou a aten\u00e7\u00e3o para as limita\u00e7\u00f5es do estudo: tratava-se de dados retrospectivos da pr\u00e1tica, pelo que n\u00e3o era poss\u00edvel a aleatoriza\u00e7\u00e3o e o controlo. Al\u00e9m disso, os dados foram extra\u00eddos de registos de sa\u00fade electr\u00f3nicos, o que pode levar a poss\u00edveis incompletudes. Al\u00e9m disso, os resultados basearam-se na codifica\u00e7\u00e3o da CID-10 &#8211; os dados relativos \u00e0 neuropatia podem, por conseguinte, ser tendenciosos.  <br \/>Os resultados da sua investiga\u00e7\u00e3o devem, por conseguinte, conduzir a novas investiga\u00e7\u00f5es. Por conseguinte, Eleftheriadou recomendou a realiza\u00e7\u00e3o de estudos espec\u00edficos sobre doen\u00e7as microvasculares para investigar o efeito dos SGLT2i na neuropatia diab\u00e9tica e na doen\u00e7a ocular em doentes com diabetes tipo 2.  <br \/>Em particular, devem ser investigadas duas quest\u00f5es:<\/td><\/tr><tr><td>1) Em que altura da evolu\u00e7\u00e3o da doen\u00e7a deve iniciar o tratamento com SGLT2i?<\/td><\/tr><tr><td>2. na realiza\u00e7\u00e3o de estudos: que par\u00e2metro de avalia\u00e7\u00e3o do estudo deve ser definido especificamente em rela\u00e7\u00e3o \u00e0 neuropatia?<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<h3 id=\"investigacao-em-grande-escala-no-mundo-real\" class=\"wp-block-heading\">Investiga\u00e7\u00e3o em grande escala no mundo real<\/h3>\n\n<p class=\"wp-block-paragraph\">Eleftheriadou e os seus colegas utilizaram dados da rede de investiga\u00e7\u00e3o internacional TriNetX para o seu estudo do mundo real. O objetivo era avaliar o efeito do SGLT2i e do GLP1-RA na neuropatia diab\u00e9tica e nas doen\u00e7as oculares. Os internamentos hospitalares devidos a insufici\u00eancia card\u00edaca foram tamb\u00e9m inclu\u00eddos como um resultado de controlo positivo.  <\/p>\n\n<p class=\"wp-block-paragraph\">A sua an\u00e1lise de coorte retrospetiva incluiu informa\u00e7\u00f5es de seis milh\u00f5es de pessoas com diabetes tipo 2 em 85 organiza\u00e7\u00f5es de cuidados de sa\u00fade. Dois grupos de interven\u00e7\u00e3o (SGLT2i, n=126 171; GLP1-RA, n=164 024) foram comparados com um grupo de controlo (sem SGLT2i\/GLP1-RA, n=1 665 412). As coortes foram emparelhadas 1:1 por propensity score matching para idade, sexo, doen\u00e7a card\u00edaca isqu\u00e9mica, complica\u00e7\u00f5es microvasculares, <sub>HbA1c<\/sub> &lt;7% e 7%, IMC, eGFR e utiliza\u00e7\u00e3o de medicamentos relevantes (IECA, agentes modificadores dos l\u00edpidos, metformina, pioglitazona):<\/p>\n\n<ul class=\"wp-block-list\">\n<li>SGLT2i vs. controlo: 141 &#8216;236 doentes em cada coorte  <\/li>\n\n\n\n<li>GLP1-RA vs. controlo: 160.970 doentes em cada coorte<\/li>\n\n\n\n<li>GLP1-RA vs. SGLT2i: 125.383 pacientes em cada coorte.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, foi efectuada uma sub-an\u00e1lise para comparar as duas coortes de interven\u00e7\u00e3o. Os principais resultados foram a neuropatia diab\u00e9tica, a neuropatia auton\u00f3mica, a retinopatia e o edema macular, e a defini\u00e7\u00e3o dos resultados baseou-se na codifica\u00e7\u00e3o da CID-10. &#8220;Come\u00e7\u00e1mos a nossa janela temporal h\u00e1 cerca de 20 anos, em setembro de 2003. Definimos o evento \u00edndice como o in\u00edcio do tratamento com insulina no grupo de controlo, o in\u00edcio do tratamento com SGLT2i e do tratamento com insulina na coorte SGLT2i e o in\u00edcio do tratamento com GLP1-RA e insulina na coorte GLP1-RA&#8221;. Os dados foram recolhidos 5 anos ap\u00f3s o evento \u00edndice, a janela temporal foi fechada em setembro de 2023.  <\/p>\n\n<h3 id=\"os-dados-falam-a-favor-da-utilizacao-de-sglt2i\" class=\"wp-block-heading\">Os dados falam a favor da utiliza\u00e7\u00e3o de SGLT2i  <\/h3>\n\n<p class=\"wp-block-paragraph\">O principal resultado foi um risco relativo ap\u00f3s cinco anos para SGLT2i e GLP1-RA. Os SGLT2i reduziram significativamente o risco de neuropatia diab\u00e9tica, neuropatia auton\u00f3mica, retinopatia diab\u00e9tica e edema macular <strong>(Fig. 1)<\/strong>. O GLP1-RA foi associado a um ligeiro aumento do risco de neuropatia diab\u00e9tica e a um aumento menor, n\u00e3o significativo, do risco de neuropatia auton\u00f3mica e de retinopatia diab\u00e9tica. No entanto, este facto tamb\u00e9m reduziu o risco relativo de edema macular.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1488\" height=\"928\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32.png\" alt=\"\" class=\"wp-image-375006\" style=\"width:500px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32.png 1488w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-800x499.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-1160x723.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-120x75.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-90x56.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-320x200.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-560x349.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-240x150.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-180x112.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-640x399.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/abb1_DE1_s32-1120x698.png 1120w\" sizes=\"(max-width: 1488px) 100vw, 1488px\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Tanto os SGLT2i como os GLP1-RA mostraram uma redu\u00e7\u00e3o significativa do risco relativo de insufici\u00eancia card\u00edaca, hospitaliza\u00e7\u00e3o e mortalidade por todas as causas. Uma an\u00e1lise direta entre a coorte de GLP1-RA e a coorte de SGLT2i ap\u00f3s 5 anos mostrou que o GLP1-RA est\u00e1 associado a um risco acrescido em compara\u00e7\u00e3o direta com o SGLT2i.  <\/p>\n\n<p class=\"wp-block-paragraph\">&#8220;Os nossos dados demonstram o benef\u00edcio real dos inibidores SGLT2 na neuropatia, neuropatia auton\u00f3mica, retinopatia e edema macular em doentes com diabetes tipo 2 tratados com insulina&#8221;, concluiu Aikaterini Eleftheriadou. Os GLP1-RA revelaram um risco acrescido de neuropatia e um risco mais baixo de neuropatia auton\u00f3mica e retinopatia, mas provaram ser protectores do edema macular. Os SGLT2i apresentaram melhores resultados nas complica\u00e7\u00f5es microvasculares em compara\u00e7\u00e3o direta com os GLP1-RA: A terap\u00eautica com SGLT2i foi associada \u00e0 maior redu\u00e7\u00e3o do risco de complica\u00e7\u00f5es microvasculares diab\u00e9ticas, bem como de insufici\u00eancia card\u00edaca, hospitaliza\u00e7\u00e3o e mortalidade por todas as causas. &#8220;Portanto, h\u00e1 um benef\u00edcio claro em todos os eventos analisados e estes dados apoiam ainda mais a utiliza\u00e7\u00e3o de SGLT2i nos nossos doentes com diabetes tipo 2&#8221;. Os futuros ensaios aleat\u00f3rios controlados de SGLT2i e GLP1-RA devem incluir biomarcadores substitutos sens\u00edveis da doen\u00e7a microvascular diab\u00e9tica para validar estes resultados. De acordo com o perito, os SGLT2i, em particular, devem geralmente ter maior prioridade no algoritmo de tratamento dos doentes com diabetes tipo 2.  <\/p>\n\n<p class=\"wp-block-paragraph\">Fonte:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Eleftheriadou A: Apresenta\u00e7\u00e3o &#8220;Risk of diabetic microvascular complications, heart failure, hospitalisation and all-cause mortality with SGLT2i and GLP1-ra in type 2 diabetes: a real-world data study&#8221;; Congresso EASD 2023, Hamburgo, 4.10.2023.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><em>Congresso: EASD 2023<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>InFo DIABETOLOGY &amp; ENDOCRINOLOGY 2024; 1(1): 32-33 (publicado em 12.2.24, antes da impress\u00e3o)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os inibidores do cotransportador s\u00f3dio-glicose 2 (SGLT2i) e os agonistas do recetor do p\u00e9ptido 1 semelhante ao glucagon (GLP1-RA) desempenham um papel importante na terapia da diabetes. No entanto, o&hellip;<\/p>\n","protected":false},"author":7,"featured_media":375088,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Neuropatia e retinopatia diab\u00e9ticas  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11397,11521,11374,11436,11529,11551],"tags":[74212,12023,74211,33459,74261,19386],"powerkit_post_featured":[],"class_list":["post-375083","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologia-e-diabetologia-2","category-estudos","category-neurologia-pt-pt","category-oftalmologia-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-agonistas-dos-receptores-glp1","tag-diabetes-tipo-2-pt-pt","tag-glp1-ra-pt-pt","tag-inibidores-sglt2-pt-pt","tag-neuropatia-diabetica","tag-retinopatia-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 18:37:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":375099,"slug":"que-riesgo-entranan-los-sglt2i-y-los-glp1-ra","post_title":"\u00bfQu\u00e9 riesgo entra\u00f1an los SGLT2i y los GLP1-RA?","href":"https:\/\/medizinonline.com\/es\/que-riesgo-entranan-los-sglt2i-y-los-glp1-ra\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/375083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=375083"}],"version-history":[{"count":2,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/375083\/revisions"}],"predecessor-version":[{"id":377143,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/375083\/revisions\/377143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/375088"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=375083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=375083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=375083"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=375083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}