{"id":375818,"date":"2024-03-06T00:01:00","date_gmt":"2024-03-05T23:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/terapia-precoce-e-proactiva-estudos-de-casos-do-hospital-pediatrico\/"},"modified":"2024-03-06T00:01:07","modified_gmt":"2024-03-05T23:01:07","slug":"terapia-precoce-e-proactiva-estudos-de-casos-do-hospital-pediatrico","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/terapia-precoce-e-proactiva-estudos-de-casos-do-hospital-pediatrico\/","title":{"rendered":"Terapia precoce e proactiva &#8211; estudos de casos do hospital pedi\u00e1trico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>O n\u00edvel psicossocial desempenha um papel importante no sucesso do tratamento da dermatite at\u00f3pica. No que diz respeito ao tratamento anti-inflamat\u00f3rio, a abordagem da ansiedade do tratamento \u00e9 um fator importante. Tanto os corticoster\u00f3ides t\u00f3picos como os inibidores da calcineurina podem ser utilizados sem hesita\u00e7\u00e3o. Nas formas mais graves, deve ser considerada a indica\u00e7\u00e3o de terapia sist\u00e9mica. O dupilumab est\u00e1 agora dispon\u00edvel como um medicamento biol\u00f3gico altamente eficaz e seguro para crian\u00e7as com dermatite at\u00f3pica.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">&#8220;Esta doen\u00e7a n\u00e3o deve e n\u00e3o tem de ser cr\u00f3nica e \u00e9, na verdade, bem trat\u00e1vel a todos os n\u00edveis&#8221;, sublinhou a Dra. Lisa Weibel, m\u00e9dica chefe do Centro de Dermatologia Pedi\u00e1trica do Hospital Pedi\u00e1trico Universit\u00e1rio de Zurique [1]. \u00c9 frequente haver incerteza quando se trata de cremes que cont\u00eam cortisona na dermatite at\u00f3pica (DA). Muitas vezes, as pessoas tentam adiar a utiliza\u00e7\u00e3o de cortisona durante o m\u00e1ximo de tempo poss\u00edvel por receio de efeitos secund\u00e1rios ou devido a outras preocupa\u00e7\u00f5es. No entanto, sabemos agora que os danos na pele at\u00f3pica aumentam se a terapia for adiada. No entanto, tamb\u00e9m aprendemos que os imunomoduladores t\u00f3picos s\u00e3o absolutamente &#8220;seguros&#8221; e t\u00eam uma boa reputa\u00e7\u00e3o no tratamento do eczema ligeiro e moderado. E sabemos agora que est\u00e3o dispon\u00edveis terapias sist\u00e9micas modernas que visam mol\u00e9culas relevantes para a doen\u00e7a, pelo que os casos graves podem agora ser tratados de forma muito eficaz&#8221;, afirma o Dr. Weibel [1]. A comich\u00e3o associada \u00e0 DA n\u00e3o s\u00f3 tem um efeito negativo na pele, como a comich\u00e3o nocturna tamb\u00e9m leva \u00e0 priva\u00e7\u00e3o cr\u00f3nica do sono em muitos doentes com neurodermatite. O facto de o dupilumab <sup>(Dupixent\u00ae<\/sup>), um medicamento biol\u00f3gico que pode ser utilizado como terap\u00eautica sist\u00e9mica desde a inf\u00e2ncia, estar agora dispon\u00edvel para as formas mais graves de DA \u00e9 muito agrad\u00e1vel, disse o orador [1].<\/p>\n\n<figure class=\"wp-block-table\"><table class=\"has-background\" style=\"background-color:#8dd2fc3d\"><tbody><tr><td>Para prevenir a cronifica\u00e7\u00e3o e o aparecimento de mais sintomas at\u00f3picos, o tratamento deve ser iniciado logo na inf\u00e2ncia se os sintomas estiverem presentes, de acordo com o Dr. Weibel [1]. O orador ilustrou este facto com o seguinte estudo de caso:  <br \/><em>Um beb\u00e9 de seis meses tinha eczema grave com infesta\u00e7\u00e3o grave na cabe\u00e7a [1]. O beb\u00e9 j\u00e1 tinha perdido 1 kg de peso corporal e o crescimento tinha estagnado. Al\u00e9m disso, os exames laboratoriais revelaram uma eosinofilia sangu\u00ednea muito acentuada. Um regime terap\u00eautico com banhos regulares e mometasona triplamente dilu\u00edda seguida de tacrolimus levou a uma cura do eczema, mas tamb\u00e9m do estado geral. &#8220;Ap\u00f3s dez dias, a eosinofilia no sangue desapareceu&#8221;, diz o Dr. Weibel. Al\u00e9m disso, o beb\u00e9 recuperou o peso corporal aos sete meses de idade.  <\/em><br \/>&#8220;A insufici\u00eancia de crescimento est\u00e1 completamente normalizada&#8221;, concluiu o orador [1]. Este \u00e9 um exemplo impressionante de como o eczema grave pode afetar a condi\u00e7\u00e3o geral e de como o tratamento adequado pode ser eficaz [1]. Se o eczema estiver associado a um atraso no crescimento, pode ser necess\u00e1rio investigar doen\u00e7as gen\u00e9ticas\/imunol\u00f3gicas em paralelo com um tratamento adequado da DA. Esta situa\u00e7\u00e3o foi igualmente tratada no caso descrito.  <\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">A progress\u00e3o da DA varia de pessoa para pessoa, mas existem alguns padr\u00f5es que ocorrem frequentemente na pr\u00e1tica cl\u00ednica di\u00e1ria. O Dr. Weibel e Corinne Brunner, enfermeira especialista em APN, tamb\u00e9m do Centro de Dermatologia Pedi\u00e1trica do Hospital Pedi\u00e1trico de Zurique, apresentaram alguns casos cl\u00e1ssicos de doentes com DA que foram encaminhados para o Hospital Pedi\u00e1trico de Zurique para tratamento [1].<\/p>\n\n<h3 id=\"o-bebe-nao-tratado\" class=\"wp-block-heading\">O beb\u00e9 n\u00e3o tratado  <\/h3>\n\n<p class=\"wp-block-paragraph\">Um doente que apresentava sintomas eczematosos desde os 2 meses de idade, sofreu de eczema generalizado, prurido e ins\u00f3nia associada aos 4 meses de idade. Era-lhe dado banho e hidratado regularmente, mas os sintomas ainda n\u00e3o tinham melhorado. Como explicou Brunner, foram utilizadas repetidamente novas e diferentes lo\u00e7\u00f5es corporais aquando da aplica\u00e7\u00e3o do creme, mas n\u00e3o foi utilizada qualquer terapia local e as pessoas convenceram-se de que os sintomas iriam provavelmente melhorar com a idade [1]. O medo da terapia por parte dos pais foi um fator significativo. O orador demonstrou que existe outra forma, utilizando uma menina de 8 meses que sofria de eczema desde os 2 meses de idade. No \u00e2mbito do tratamento prescrito pelo hospital pedi\u00e1trico de Zurique, foi iniciada uma terapia intensiva com a aplica\u00e7\u00e3o regular em grandes \u00e1reas de Elocom\u00ae misturado com Dexeryl\u00ae (numa propor\u00e7\u00e3o de 1:2) [1,2]. Posteriormente, o doente passou para uma terap\u00eautica de manuten\u00e7\u00e3o; foi utilizado Elidel\u00ae creme nos dias sem cortisona [2]. Este inibidor t\u00f3pico da calcineurina foi tamb\u00e9m utilizado no rosto [2]. No exame de acompanhamento, a condi\u00e7\u00e3o da pele estava curada ap\u00f3s oito semanas. Em casos como este, medidas proactivas precoces, uma terapia suficientemente eficaz (ou seja, um esteroide potente em vez de hidrocortisona) e uma terapia de manuten\u00e7\u00e3o subsequente provaram ser eficazes para um tratamento bem sucedido, explicou Brunner [1].  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2188\" height=\"1553\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36.png\" alt=\"\" class=\"wp-image-375541\" style=\"width:500px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36.png 2188w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-800x568.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-1160x823.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-2048x1454.png 2048w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-120x85.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-90x64.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-320x227.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-560x397.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-1920x1363.png 1920w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-240x170.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-180x128.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-640x454.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-1120x795.png 1120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/tab1_DP1_s36-1600x1136.png 1600w\" sizes=\"(max-width: 2188px) 100vw, 2188px\" \/><\/a><\/figure>\n<\/div>\n<h3 id=\"o-doente-cronico-mal-tratado\" class=\"wp-block-heading\">O doente cr\u00f3nico mal tratado<\/h3>\n\n<p class=\"wp-block-paragraph\">Brunner citou um menino de 6 anos que sofria de eczema desde os 3 meses de idade, que tinha sido submetido a uma ampla avalia\u00e7\u00e3o alergol\u00f3gica e a v\u00e1rias tentativas de tratamento, incluindo terapia com luz e uma estadia numa cl\u00ednica de altitude [1], como exemplo de um caminho errado prolongado. Tamb\u00e9m foi utilizada cortisona sist\u00e9mica e t\u00f3pica, mas o eczema nunca sarou verdadeiramente. &#8220;Passou noites sem dormir por causa da comich\u00e3o&#8221;, relatou Brunner [1]. Quando se apresentou no hospital pedi\u00e1trico, tinha uma infesta\u00e7\u00e3o em todo o corpo e havia zonas eczematosas com focos de bact\u00e9rias. O tratamento com creme de zinco e a aplica\u00e7\u00e3o selectiva de Advantan\u00ae creme n\u00e3o se revelaram eficazes. Depois de a crian\u00e7a ter sido hospitalizada, foi iniciada uma terapia t\u00f3pica intensiva com prepara\u00e7\u00f5es de cortisona dilu\u00eddas e n\u00e3o dilu\u00eddas, que foram aplicadas nas \u00e1reas cr\u00f3nicas. Foi ent\u00e3o organizada uma terapia de manuten\u00e7\u00e3o a longo prazo (durante um per\u00edodo de 1-2 anos). O caso foi conclu\u00eddo com \u00eaxito no hospital pedi\u00e1trico h\u00e1 dois anos. Nos casos cr\u00f3nicos, uma equipa de tratamento experiente e um plano de tratamento f\u00e1cil de compreender s\u00e3o importantes. O eczema cr\u00f3nico pode levar a perturba\u00e7\u00f5es do sono e do comportamento, bem como a outros sintomas secund\u00e1rios. As crian\u00e7as s\u00e3o geralmente facilmente irrit\u00e1veis, choronas e ansiosas. No entanto, \u00e9 frequentemente muito stressante n\u00e3o s\u00f3 para a crian\u00e7a, mas tamb\u00e9m para a fam\u00edlia.  <\/p>\n\n<h3 id=\"recusa-da-terapia-o-que-fazer-a-seguir\" class=\"wp-block-heading\">Recusa da terapia &#8211; o que fazer a seguir?  <\/h3>\n\n<p class=\"wp-block-paragraph\">Um menino de 2 anos de idade que sofria de eczema, prurido intenso e dist\u00farbios do sono desde os 3 meses de idade, estava a receber tratamento homeop\u00e1tico desde os 6 meses de idade, mas nunca tinha recebido terapia t\u00f3pica anti-inflamat\u00f3ria [1]. Os pais da crian\u00e7a recusaram ester\u00f3ides t\u00f3picos. O primeiro passo no processo de tratamento no Hospital Pedi\u00e1trico de Zurique foi uma entrevista com os pais. Em particular, tratou-se de discutir os receios associados \u00e0 terapia com cortisona. Entre outras coisas, os pais eram de opini\u00e3o que a cortisona era in\u00fatil, uma vez que apenas combate os sintomas e n\u00e3o trata as causas. Os pais foram informados sobre a l\u00f3gica do tratamento e a seguran\u00e7a dos corticoster\u00f3ides t\u00f3picos. Com o tempo, os pais cederam e foi poss\u00edvel iniciar a terapia t\u00f3pica com cortisona dilu\u00edda e n\u00e3o dilu\u00edda em combina\u00e7\u00e3o com Elidel\u00ae<sup> <\/sup>Creme. O doente est\u00e1 agora livre de eczema aos 5 anos de idade. Nos casos em que os pais recusam a terapia, a coopera\u00e7\u00e3o com o pediatra \u00e9 muito importante. Ao iniciar o tratamento, deve tamb\u00e9m considerar se \u00e9 adequado um tratamento em ambulat\u00f3rio (por exemplo, com o apoio de cuidados pedi\u00e1tricos ao domic\u00edlio) ou em regime de internamento. Os controlos de acompanhamento precoces e regulares e uma boa liga\u00e7\u00e3o s\u00e3o importantes.  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1.png\"><img decoding=\"async\" width=\"1477\" height=\"919\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1.png\" alt=\"\" class=\"wp-image-375540 lazyload\" style=\"--smush-placeholder-width: 1477px; --smush-placeholder-aspect-ratio: 1477\/919;width:500px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1.png 1477w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-800x498.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-1160x722.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-120x75.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-90x56.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-320x199.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-560x348.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-240x149.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-180x112.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-640x398.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/02\/Ubersicht1_DP1_s37-1-1120x697.png 1120w\" data-sizes=\"(max-width: 1477px) 100vw, 1477px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n<h3 id=\"osso-duro-de-roer-terapia-de-sistema-indicada\" class=\"wp-block-heading\">&#8220;Osso duro de roer&#8221;: terapia de sistema indicada  <\/h3>\n\n<p class=\"wp-block-paragraph\">Uma doente de 9 anos de idade, do sexo feminino, que sofria de eczema desde h\u00e1 algum tempo e que n\u00e3o tinha respondido adequadamente \u00e0s tentativas de tratamento anteriores, foi admitida como doente internada [1]. A terapia local intensiva era dif\u00edcil porque a pele estava t\u00e3o stressada que a aplica\u00e7\u00e3o de qualquer tipo de creme era dolorosa. Foi iniciado o tratamento com Ciclosporina oral; o plano era, de facto, fazer uma sobreposi\u00e7\u00e3o com Dupilumab, mas a doente tinha uma fobia pronunciada de injec\u00e7\u00f5es, pelo que este plano teve de ser adiado e estes medos tiveram de ser resolvidos primeiro. Ap\u00f3s cerca de dez dias, o estado da pele melhorou, mas o eczema e a comich\u00e3o continuavam presentes. Ao longo do tempo e com terapia psicol\u00f3gica para a fobia de injec\u00e7\u00f5es, o doente concordou com a terapia biol\u00f3gica e foi tratado com Dupixent\u00ae s.c. 300 mg <strong>(Vis\u00e3o Geral 1)<\/strong> de quatro em quatro semanas; a ciclosporina foi interrompida [1,2]. Ao fim de cerca de um ano, estava livre do eczema e quase n\u00e3o precisava de mais nenhum tratamento anti-inflamat\u00f3rio local. Ao mesmo tempo, a sua qualidade de vida e a da sua fam\u00edlia melhoraram significativamente. Neste caso, concluiu o orador, o tratamento t\u00f3pico isolado foi utilizado durante demasiado tempo e a terapia sist\u00e9mica deveria ter sido considerada mais cedo. Felizmente, o Dupixent\u00ae provou ser uma terapia sist\u00e9mica r\u00e1pida e eficaz a longo prazo [1,2].  <\/p>\n\n<p class=\"wp-block-paragraph\"><em>Congresso: Dia Pedi\u00e1trico da Pele em Zurique<\/em><\/p>\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>&#8220;Eczema at\u00f3pico: Porque \u00e9 que a terapia funciona t\u00e3o mal?&#8221;, PD Dr. med L. Weibel; Corinne Brunner, especialista em enfermagem APN. Dia da Pele das Crian\u00e7as de Zurique, 01.12.2023.<\/li>\n\n\n\n<li>Swissmedic: Informa\u00e7\u00f5es sobre o medicamento, <a href=\"http:\/\/www.swissmedicinfo.ch\" target=\"_blank\" rel=\"noopener\">www.swissmedicinfo.ch,<\/a>(\u00faltimo acesso em 17.02.2024)  <\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>DERMATOLOGIE PRAXIS 2024; 34(1): 35-37 (publicado em 21.2.24, antes da impress\u00e3o)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O n\u00edvel psicossocial desempenha um papel importante no sucesso do tratamento da dermatite at\u00f3pica. No que diz respeito ao tratamento anti-inflamat\u00f3rio, a abordagem da ansiedade do tratamento \u00e9 um fator&hellip;<\/p>\n","protected":false},"author":7,"featured_media":375825,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Dermatite at\u00f3pica em crian\u00e7as","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11344,11536,11356,11450,11529,11551],"tags":[26843,12492,74612,13525,20639,74615],"powerkit_post_featured":[],"class_list":["post-375818","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alergologia-e-imunologia-clinica","category-casos-pt-pt","category-dermatologia-e-venereologia-pt-pt","category-pediatria-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-corticosteroides-topicos","tag-dermatite-atopica","tag-dia-da-pele-das-criancas-de-zurique","tag-dupilumab-pt-pt","tag-inibidores-de-calcineurina-pt-pt","tag-nivel-psicossocial","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:05:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":375832,"slug":"terapia-precoz-y-proactiva-estudios-de-casos-del-hospital-pediatrico","post_title":"Terapia precoz y proactiva - estudios de casos del hospital pedi\u00e1trico","href":"https:\/\/medizinonline.com\/es\/terapia-precoz-y-proactiva-estudios-de-casos-del-hospital-pediatrico\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/375818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=375818"}],"version-history":[{"count":2,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/375818\/revisions"}],"predecessor-version":[{"id":376038,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/375818\/revisions\/376038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/375825"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=375818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=375818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=375818"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=375818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}