{"id":376794,"date":"2024-04-01T14:00:00","date_gmt":"2024-04-01T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=376794"},"modified":"2024-03-21T14:27:10","modified_gmt":"2024-03-21T13:27:10","slug":"o-risco-de-herpes-zoster-e-frequentemente-subestimado","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/o-risco-de-herpes-zoster-e-frequentemente-subestimado\/","title":{"rendered":"O risco de herpes z\u00f3ster \u00e9 frequentemente subestimado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>O &#8220;Shingles Misconception Survey&#8221; \u00e9 um inqu\u00e9rito em linha realizado entre 16 e 18 de agosto de 2023 junto de 3500 adultos com 50 anos ou mais. As an\u00e1lises mostram que 86% dos inquiridos subestimam o risco de herpes zoster e a sua poss\u00edvel gravidade. Os resultados do inqu\u00e9rito mostram tamb\u00e9m que a sensibiliza\u00e7\u00e3o para a dor que as herpes-z\u00f3steres podem causar \u00e9 baixa.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">Cerca de 1 em cada 3 pessoas em todo o mundo desenvolver\u00e1 herpes zoster durante a sua vida [1\u20134,9]. A doen\u00e7a manifesta-se normalmente por uma erup\u00e7\u00e3o cut\u00e2nea com bolhas dolorosas no peito, no abd\u00f3men ou no rosto. A dor \u00e9 frequentemente descrita como ardente, lancinante ou semelhante a um choque [1]. No entanto, os dados do inqu\u00e9rito em linha mostram que muitos adultos t\u00eam uma avalia\u00e7\u00e3o de risco distorcida [5,9]: Mais de um quarto (28%) acredita que o herpes-z\u00f3ster \u00e9 &#8220;essencialmente inofensivo&#8221;. Um quarto (26%) estima que o risco de contrair herpes-z\u00f3ster durante a sua vida \u00e9 de 1 em 100, quase um quinto (17%) pensa que \u00e9 de 1 em 1000 e quase metade (49%) pensa que \u00e9 improv\u00e1vel contrair herpes-z\u00f3ster [5,9].  <\/p>\n\n<p class=\"wp-block-paragraph\">Na realidade, a maioria dos adultos tem o v\u00edrus que causa as herpes z\u00f3steres no seu corpo aos 50 anos de idade, e sabe-se que a reativa\u00e7\u00e3o do v\u00edrus se torna mais prov\u00e1vel com o aumento da idade [6,7,9]. O herpes zoster \u00e9 causado pela reativa\u00e7\u00e3o do v\u00edrus varicela zoster (VZV), o mesmo v\u00edrus que causa a varicela [1]. Com o avan\u00e7ar da idade, a resist\u00eancia do sistema imunit\u00e1rio \u00e0 infe\u00e7\u00e3o diminui, aumentando o risco de desenvolver herpes zoster [1]. Existe, portanto, um risco acrescido para as pessoas com mais de 50 anos [1]. A erup\u00e7\u00e3o cut\u00e2nea do herpes-z\u00f3ster pode tamb\u00e9m ser seguida de nevralgia p\u00f3s-herp\u00e9tica (NPH), uma dor nervosa de longa dura\u00e7\u00e3o que pode durar semanas ou meses e que, por vezes, persiste durante v\u00e1rios anos [1]. A PHN \u00e9 a complica\u00e7\u00e3o mais comum do herpes-z\u00f3ster e, de acordo com os resultados de v\u00e1rios estudos, ocorre em 5-30% de todos os casos de herpes-z\u00f3ster [8].<\/p>\n\n<p class=\"wp-block-paragraph\">Adultos com mais de 50 anos de 12 pa\u00edses participaram no estudo de inqu\u00e9rito [5,9]. Os novos resultados do inqu\u00e9rito foram apresentados durante a Shingles Awareness Week (26 de fevereiro &#8211; 3 de mar\u00e7o de 2024) como parte de uma campanha de sensibiliza\u00e7\u00e3o para os riscos e efeitos do herpes zoster [9].<\/p>\n\n<p class=\"wp-block-paragraph\">Literatura:  <\/p>\n\n<ol class=\"wp-block-list\">\n<li>Harpaz R, et al: Comit\u00e9 Consultivo para as Pr\u00e1ticas de Imuniza\u00e7\u00e3o (ACIP), Centros de Controlo e Preven\u00e7\u00e3o de Doen\u00e7as (CDC). Prevention of herpes zoster: recommendations of the Advisory Committee on Immunisation Practices (ACIP) [Preven\u00e7\u00e3o do herpes zoster: recomenda\u00e7\u00f5es do Comit\u00e9 Consultivo para as Pr\u00e1ticas de Imuniza\u00e7\u00e3o (ACIP)]. MMWR Recomm Rep. 2008;57(RR-5): 1-30.<\/li>\n\n\n\n<li>Instituto Australiano de Sa\u00fade e Bem-Estar. Shingles in Australia, <a href=\"http:\/\/www.aihw.gov.au\/getmedia\" target=\"_blank\" rel=\"noopener\">www.aihw.gov.au\/getmedia,<\/a>(\u00faltimo acesso em 12\/03\/2024)  <\/li>\n\n\n\n<li>Lee C, et al: Risco de herpes zoster ao longo da vida na popula\u00e7\u00e3o de Pequim, China. Sa\u00fade P\u00fablica na Pr\u00e1tica 2023 Jun; 5: 100356.<\/li>\n\n\n\n<li>Curran D, et al: Meta-Regress\u00e3o da Incid\u00eancia de Herpes Zoster a n\u00edvel mundial. Infect Dis Ther 2022; 11(1): 389-403.<\/li>\n\n\n\n<li>Shingles Misconceptions Map Survey (Austr\u00e1lia, Brasil, Canad\u00e1, China, Alemanha, \u00cdndia, It\u00e1lia, Jap\u00e3o, Portugal, Coreia do Sul, Reino Unido, Estados Unidos), Pollfish em nome de GSK. 18 de agosto de 2023.  <\/li>\n\n\n\n<li>Mueller NH, et al: Infe\u00e7\u00e3o pelo v\u00edrus Varicela Zoster: Caracter\u00edsticas cl\u00ednicas, patog\u00e9nese molecular da doen\u00e7a e lat\u00eancia. Cl\u00ednicas Neurol\u00f3gicas 2008; 26; 675-697.<\/li>\n\n\n\n<li>Johnson RW, et al: Epidemiologia, gest\u00e3o e carga econ\u00f3mica e de doen\u00e7a do herpes zoster na Europa: uma perspetiva multidisciplinar. Ther Adv Vaccines 2015; 3(4): 109-120.<\/li>\n\n\n\n<li>Kawai K, Gebremeskel BG, Acosta CJ: Revis\u00e3o sistem\u00e1tica da incid\u00eancia e complica\u00e7\u00f5es do herpes zoster: rumo a uma perspectiva global. BMJOpen 2014; 4: e004833.<\/li>\n\n\n\n<li>&#8220;Inqu\u00e9rito global da GSK revela: 86% dos adultos inquiridos subestimam o risco e a gravidade potencial do herpes zoster&#8221;, GSK, 26\/02\/2024.  <\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>PR\u00c1TICA DE CL\u00cdNICA GERAL 2024; 19(3): 49<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O &#8220;Shingles Misconception Survey&#8221; \u00e9 um inqu\u00e9rito em linha realizado entre 16 e 18 de agosto de 2023 junto de 3500 adultos com 50 anos ou mais. As an\u00e1lises mostram&hellip;<\/p>\n","protected":false},"author":7,"featured_media":376801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"V\u00edrus da varicela zoster (VZV)  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11521,11524,11421,11551],"tags":[74966,74967,12056,74964,74965],"powerkit_post_featured":[],"class_list":["post-376794","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudos","category-formacao-continua","category-infecciologia","category-rx-pt","tag-inquerito-sobre-as-concepcoes-erradas-das-telhas","tag-nevralgia-pos-herpetica","tag-shingles-pt-pt","tag-virus-da-varicela-zoster-pt-pt","tag-vzv-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 16:58:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":376812,"slug":"a-menudo-se-subestima-el-riesgo-de-herpes-zoster","post_title":"A menudo se subestima el riesgo de herpes z\u00f3ster","href":"https:\/\/medizinonline.com\/es\/a-menudo-se-subestima-el-riesgo-de-herpes-zoster\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/376794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=376794"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/376794\/revisions"}],"predecessor-version":[{"id":376807,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/376794\/revisions\/376807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/376801"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=376794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=376794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=376794"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=376794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}