{"id":377537,"date":"2024-05-04T00:01:00","date_gmt":"2024-05-03T22:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/limites-obstaculos-e-solucoes-na-gestao-da-doenca\/"},"modified":"2024-05-03T21:45:37","modified_gmt":"2024-05-03T19:45:37","slug":"limites-obstaculos-e-solucoes-na-gestao-da-doenca","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/limites-obstaculos-e-solucoes-na-gestao-da-doenca\/","title":{"rendered":"Limites, obst\u00e1culos e solu\u00e7\u00f5es na gest\u00e3o da doen\u00e7a"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Todos os anos, o Forum of the<em> Americas Committee for Treatment and Research in Multiple Sclerosis<\/em> centra-se no ambiente din\u00e2mico da doen\u00e7a numa s\u00e9rie \u00fanica de apresenta\u00e7\u00f5es cient\u00edficas e cl\u00ednicas. O tema deste ano foi &#8220;Quebrar Barreiras na EM&#8221;. O programa cient\u00edfico incluiu debates sobre barreiras como as desigualdades nos cuidados de sa\u00fade e o acesso aos cuidados, os limites do SNC e as c\u00e9lulas associadas, as barreiras \u00e0 repara\u00e7\u00e3o dos nervos, as barreiras \u00e0 reabilita\u00e7\u00e3o e considera\u00e7\u00f5es sobre a conce\u00e7\u00e3o de ensaios cl\u00ednicos.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">As les\u00f5es paramagn\u00e9ticas do bordo (PRL) s\u00e3o consideradas biomarcadores de les\u00f5es cr\u00f3nicas activas (CAL) na esclerose m\u00faltipla (EM). No entanto, a liga\u00e7\u00e3o entre a CAL e a neurodegenera\u00e7\u00e3o na EM ainda n\u00e3o \u00e9 clara. As PRLs s\u00e3o uma forma de investigar esta rela\u00e7\u00e3o in vivo. A prova de uma tal liga\u00e7\u00e3o refor\u00e7aria a import\u00e2ncia de um ataque farmacol\u00f3gico \u00e0 PRL. Por conseguinte, foi analisada a rela\u00e7\u00e3o entre a PRL e as medidas de neurodegenera\u00e7\u00e3o e incapacidade cl\u00ednica no momento do diagn\u00f3stico de EM, s\u00edndrome clinicamente isolada (CIS) ou s\u00edndrome radiologicamente isolada (RIS) [1]. Para o efeito, 47 pessoas sem tratamento com EM, CIS ou RIS recentemente diagnosticada foram submetidas a resson\u00e2ncia magn\u00e9tica (RM) a 7,0 Tesla (7T), bem como a exames cl\u00ednicos e neurocognitivos. Foram detectadas PRL em 27 pessoas (57,4%). Os valores de PSR na NAWM adjacente \u00e0 PRL foram mais baixos do que na NAWM contralateral e na NAWM adjacente a les\u00f5es sem rebordo. Os valores de PSR medidos no n\u00facleo da PRL est\u00e3o correlacionados com os valores medidos no NAWM perto da PRL. Os indiv\u00edduos PRL+ apresentavam volumes normalizados mais baixos do t\u00e1lamo, caudado, globo p\u00e1lido, hipocampo e am\u00edgdala e espessura reduzida em algumas regi\u00f5es corticais. Tamb\u00e9m tiveram pior desempenho no teste do l\u00e1pis de 9 buracos e no teste de recorda\u00e7\u00e3o. No entanto, os resultados da Escala Expandida do Estado de Incapacidade, o volume cerebral, a PSR e R1f da NAWM e a subst\u00e2ncia cinzenta profunda (GM) de todo o c\u00e9rebro n\u00e3o diferiram entre os grupos. Assim, verificou-se que a PRL estava significativamente associada \u00e0 atrofia do GM e \u00e0 m\u00e1 sa\u00fade da NAWM circundante, levando provavelmente a algum grau de incapacidade cognitiva e f\u00edsica. No entanto, esta rela\u00e7\u00e3o entre a PRL e a atrofia do GM n\u00e3o se reflecte na perda regional de mielina. Os cientistas suspeitam que os indiv\u00edduos PRL+ t\u00eam um processo generalizado de microglia que acaba por conduzir \u00e0 neurodegenera\u00e7\u00e3o. Isto pode indicar indiretamente um estado mais avan\u00e7ado da doen\u00e7a no momento do diagn\u00f3stico.<\/p>\n\n<h3 id=\"que-papel-desempenha-a-substancia-branca-na-fadiga\" class=\"wp-block-heading\">Que papel desempenha a subst\u00e2ncia branca na fadiga?<\/h3>\n\n<p class=\"wp-block-paragraph\">A fadiga \u00e9 um dos sintomas mais importantes e incapacitantes dos doentes com EM e ocorre em 80% dos casos de esclerose m\u00faltipla recorrente-remitente (EMRR). Muitos estudos relacionaram a atrofia da massa cinzenta com a fadiga, mas a carga de les\u00e3o da massa branca (WM-LL) tem recebido menos aten\u00e7\u00e3o. Este facto foi agora investigado com mais pormenor num estudo que envolveu 63 doentes com EMRR [2]. Cada doente forneceu informa\u00e7\u00f5es demogr\u00e1ficas e foi avaliado utilizando a Escala Expandida do Estado de Incapacidade (EDSS) e a Escala de Gravidade da Fadiga (FSS). O VolBrain, um instrumento totalmente automatizado e independente do operador, foi utilizado para avaliar o volume cerebral total e o volume WM-LL. Os doentes foram divididos em tr\u00eas grupos: sem fadiga (FSS &lt;4), leichte bis mittlere Fatigue (FSS \u22654 \u22645) und starke Fatigue (FSS&gt;5). 33,3% dos doentes n\u00e3o apresentavam fadiga significativa, 25,4% apresentavam fadiga ligeira a moderada e 41,3% apresentavam fadiga significativa. A idade, a dura\u00e7\u00e3o da doen\u00e7a, as reca\u00eddas e o EDSS foram positivamente correlacionados com a gravidade da fadiga. O volume cerebral total, o volume total e o volume regional da subst\u00e2ncia branca (justacortical, periventricular, infratentorial) tamb\u00e9m foram correlacionados com a gravidade da fadiga. A an\u00e1lise de regress\u00e3o ordinal para a gravidade da fadiga mostrou que o EDSS e o volume da les\u00e3o infratentorial foram os melhores preditores. Os presentes resultados sublinham a import\u00e2ncia do EDSS e do volume das les\u00f5es infratentoriais (cerebelo e tronco cerebral) como factores de previs\u00e3o da gravidade da fadiga na EMRR.<\/p>\n\n<h3 id=\"esclerose-multipla-ou-uma-doenca-metabolica\" class=\"wp-block-heading\">Esclerose m\u00faltipla ou uma doen\u00e7a metab\u00f3lica?<\/h3>\n\n<p class=\"wp-block-paragraph\">Para desmistificar a esclerose m\u00faltipla (EM) \u00e9 necess\u00e1rio compreender os seus &#8220;m\u00edmicos da doen\u00e7a&#8221; heredit\u00e1rios, ou seja, o mimetismo. At\u00e9 \u00e0 data, foram descritas v\u00e1rias doen\u00e7as de um \u00fanico gene, tanto em adultos como em crian\u00e7as, com caracter\u00edsticas cl\u00ednicas e radiol\u00f3gicas que se sobrep\u00f5em \u00e0 EM progressiva prim\u00e1ria. Deste grupo, h\u00e1 cada vez mais provas de que as doen\u00e7as metab\u00f3licas e mitocondriais (DM) s\u00e3o comuns, pelo que deve ser dada especial aten\u00e7\u00e3o a estas doen\u00e7as no diagn\u00f3stico, tratamento e cuidados dos doentes. Devido ao envolvimento de v\u00e1rios sistemas e \u00e0 grande heterogeneidade gen\u00e9tica e cl\u00ednica, o diagn\u00f3stico da EM e das doen\u00e7as metab\u00f3licas \u00e9 frequentemente um desafio. No entanto, a lista de m\u00edmicos da esclerose m\u00faltipla est\u00e1 a aumentar, est\u00e3o a ser identificados novos genes causadores da doen\u00e7a e os fen\u00f3tipos relatados est\u00e3o a alargar-se, permitindo um diagn\u00f3stico preciso e exato dos m\u00edmicos da esclerose m\u00faltipla. Um estudo teve como objetivo caraterizar as caracter\u00edsticas gen\u00e9ticas, neurol\u00f3gicas e cl\u00ednicas de 8 adultos com suspeita de mimetismo gen\u00e9tico da EM [3].  <\/p>\n\n<p class=\"wp-block-paragraph\">Foram recrutados oito indiv\u00edduos adultos com caracter\u00edsticas at\u00edpicas de EM progressiva prim\u00e1ria encaminhados para a Cl\u00ednica de Doen\u00e7as da Mat\u00e9ria Branca n\u00e3o diagnosticadas do Instituto Neurol\u00f3gico de Montreal. A\u00ed, foram gerados dados de sequencia\u00e7\u00e3o de nova gera\u00e7\u00e3o (NGS): Em todos os doentes foi realizado um painel de NGS orientado para os genes associados a formas conhecidas de leucoencefalopatias gen\u00e9ticas, seguido de sequencia\u00e7\u00e3o do exoma completo (WES, num doente) ou de sequencia\u00e7\u00e3o do genoma completo (WGS, em cinco doentes) se o painel orientado fosse negativo. Os dados NGS foram analisados utilizando uma estrat\u00e9gia de filtragem destinada a identificar variantes raras e patog\u00e9nicas. Utilizando um painel direcionado, foram detectadas variantes nos genes candidatos <em>POLG <\/em>e<em> MT-CO2<\/em> em dois indiv\u00edduos, resultando num rendimento de diagn\u00f3stico de 25%. Al\u00e9m disso, foram identificadas variantes provavelmente patog\u00e9nicas no <em>ABCD1<\/em> num doente com dados WES dispon\u00edveis e variantes no PEX5 num doente com dados WGS dispon\u00edveis. A an\u00e1lise WGS de quatro doentes ainda n\u00e3o foi conclu\u00edda. Todos os genes identificados provaram ser fortes agentes causadores da doen\u00e7a, de acordo com as caracter\u00edsticas cl\u00ednicas e radiol\u00f3gicas dos indiv\u00edduos afectados. Os genes <em>MT-CO2<\/em> e <em>POLG<\/em> est\u00e3o envolvidos na fun\u00e7\u00e3o mitocondrial, enquanto <em>ABCD1<\/em> e <em>PEX5<\/em> s\u00e3o genes peroxissomais.  <\/p>\n\n<h3 id=\"importancia-da-barreira-hemato-encefalica-na-patogenese\" class=\"wp-block-heading\">Import\u00e2ncia da barreira hemato-encef\u00e1lica na patog\u00e9nese<\/h3>\n\n<p class=\"wp-block-paragraph\">A EM \u00e9 uma doen\u00e7a neuroinflamat\u00f3ria do sistema nervoso central (SNC) caracterizada pela rutura da barreira hemato-encef\u00e1lica (BHE), pela infiltra\u00e7\u00e3o de c\u00e9lulas imunit\u00e1rias atrav\u00e9s das barreiras do SNC e pela desmieliniza\u00e7\u00e3o. A resposta imunit\u00e1ria orquestrada na EM envolve a ativa\u00e7\u00e3o e a diferencia\u00e7\u00e3o de c\u00e9lulas imunit\u00e1rias em fen\u00f3tipos pr\u00f3 ou anti-inflamat\u00f3rios e modula a inflama\u00e7\u00e3o. A Stra6 \u00e9 um conhecido regulador do transporte de retinol, o metabolito ativo a jusante da vitamina A, e um precursor da mol\u00e9cula de sinaliza\u00e7\u00e3o ativa \u00e1cido retin\u00f3ico (AR). Foi demonstrado que a AR induz uma resposta reguladora das c\u00e9lulas T e suprime a resposta patog\u00e9nica no estado estacion\u00e1rio. No entanto, foi demonstrado que a AR promove a ativa\u00e7\u00e3o das c\u00e9lulas T durante a inflama\u00e7\u00e3o em curso e aumenta a resposta patog\u00e9nica das c\u00e9lulas T-helper de uma forma dependente da dose. Embora a maioria dos estudos tenha investigado principalmente o papel perif\u00e9rico da vitamina A, do retinol e do AR, a nossa compreens\u00e3o do transporte destas mol\u00e9culas para o SNC e dos seus efeitos imunomoduladores no compartimento do SNC na neuroinflama\u00e7\u00e3o \u00e9 ainda rudimentar. O objetivo era, portanto, compreender os mecanismos que regulam o transporte endotelial cerebral de retinol do sangue para o par\u00eanquima do SNC no estado saud\u00e1vel e num modelo de ratinho de EM, e determinar se as altera\u00e7\u00f5es nas concentra\u00e7\u00f5es de AR nos compartimentos do SNC controlam a resposta imunit\u00e1ria local pr\u00f3 ou anti-inflamat\u00f3ria [4].<\/p>\n\n<p class=\"wp-block-paragraph\">Para o efeito, foi efectuada a sequencia\u00e7\u00e3o de ARN em c\u00e9lulas endoteliais BBB purificadas por FACS da medula espinal de ratinhos que sofrem de encefalomielite autoimune experimental (EAE) e de ratinhos de controlo saud\u00e1veis. Foi demonstrado que a Stra6<em> (Stimulated by Retinoic Acid 6)<\/em> est\u00e1 fortemente regulada na BHE no pico da EAE, tanto a n\u00edvel de transcri\u00e7\u00e3o como de prote\u00ednas na medula espinal. Al\u00e9m disso, os resultados mostraram um aumento semelhante da express\u00e3o da prote\u00edna Stra6 nas CE do c\u00e9rebro e nas CE da espinal medula. A aus\u00eancia de Stra6 levou a um atraso e a uma melhoria na progress\u00e3o da EAE. Al\u00e9m disso, a aus\u00eancia de Stra6 nas c\u00e9lulas endoteliais conduziu a uma redu\u00e7\u00e3o significativa da gravidade da EAE, em compara\u00e7\u00e3o com os seus companheiros de ninhada. Os resultados preliminares sugerem que a aus\u00eancia de Stra6 nas CEs e, portanto, as concentra\u00e7\u00f5es alteradas de AR no par\u00eanquima do SNC modulam a resposta imunit\u00e1ria espec\u00edfica do SNC de uma forma anti-inflamat\u00f3ria.<\/p>\n\n<h3 id=\"fator-de-prognostico-doentes-com-mais-de-50-anos-de-idade\" class=\"wp-block-heading\">Fator de progn\u00f3stico doentes com mais de 50 anos de idade<\/h3>\n\n<p class=\"wp-block-paragraph\">Na esclerose m\u00faltipla, as reca\u00eddas e a atividade de RMN diminuem geralmente com o aumento da idade, mas s\u00e3o substitu\u00eddas por uma progress\u00e3o independente de reca\u00eddas (PIRA). No entanto, v\u00e1rios doentes idosos com EM (PwMS) continuam a sofrer reca\u00eddas cl\u00ednicas e o impacto na sua doen\u00e7a permanece indeterminado. O objetivo era, portanto, determinar os efeitos de uma recidiva \u00edndice na evolu\u00e7\u00e3o da doen\u00e7a em doentes com mais de 50 anos de idade e identificar factores de risco para uma evolu\u00e7\u00e3o desfavor\u00e1vel [5]. Para este efeito, foi efectuada uma an\u00e1lise secund\u00e1ria de tr\u00eas coortes prospectivas locais na Alemanha. Todas as pessoas com defici\u00eancia com idade \u226550 anos que tiveram uma reca\u00edda \u226460 dias antes do exame inicial e 18 meses ap\u00f3s o exame foram examinadas e comparadas com um grupo de controlo de pessoas com defici\u00eancia sem reca\u00edda. Os doentes foram estratificados de acordo com a idade ou a progress\u00e3o da doen\u00e7a. Foram analisadas as reca\u00eddas, a atividade da RMN, o agravamento associado \u00e0 reca\u00edda (RAW) e o PIRA. Foi realizada uma an\u00e1lise de regress\u00e3o para avaliar o impacto dos factores de risco espec\u00edficos de base e das altera\u00e7\u00f5es do regime de tratamento nos v\u00e1rios resultados da doen\u00e7a no m\u00eas 18.<\/p>\n\n<p class=\"wp-block-paragraph\">681 doentes foram inclu\u00eddos na &#8220;coorte de reca\u00eddas&#8221;. A coorte de controlo era constitu\u00edda por 232 doentes. Os par\u00e2metros epidemiol\u00f3gicos de base foram equilibrados entre as coortes e os subgrupos. Foi observada uma maior atividade inflamat\u00f3ria e uma progress\u00e3o da incapacidade independente da reca\u00edda na coorte com reca\u00edda, em compara\u00e7\u00e3o com a coorte de controlo. Na coorte de reca\u00eddas, 393 doentes foram classificados como est\u00e1veis (57,7%), 164 doentes como activos (24,1%) e 124 doentes como progressivos (18,2%) durante o seguimento. Os factores de risco cardiovascular e a idade mais avan\u00e7ada no in\u00edcio do estudo foram identificados como factores de risco para a doen\u00e7a progressiva, enquanto a administra\u00e7\u00e3o de DMT no in\u00edcio do estudo favoreceu a doen\u00e7a est\u00e1vel. O in\u00edcio ou a intensifica\u00e7\u00e3o do tratamento foi \u00fatil para prevenir a doen\u00e7a ativa mas n\u00e3o progressiva. A reca\u00edda em pessoas com incapacidades com mais de 50 anos foi associada a uma maior atividade inflamat\u00f3ria da doen\u00e7a e a um agravamento da incapacidade. O estudo mostra que as reca\u00eddas impulsionam o PIRA e a progress\u00e3o da doen\u00e7a em pessoas com defici\u00eancia. Estes resultados apoiam a continua\u00e7\u00e3o da DMT em doentes idosos com doen\u00e7a est\u00e1vel, uma vez que a reintrodu\u00e7\u00e3o da DMT em resposta a uma reca\u00edda n\u00e3o ajudou a prevenir a progress\u00e3o da doen\u00e7a.<\/p>\n\n<h3 id=\"efeitos-da-covid-19-no-sono\" class=\"wp-block-heading\">Efeitos da COVID-19 no sono<\/h3>\n\n<p class=\"wp-block-paragraph\">Existem algumas provas, embora contradit\u00f3rias, de que o sono e a sa\u00fade mental se deterioraram na popula\u00e7\u00e3o em geral em resultado da pandemia de COVID-19 e das restri\u00e7\u00f5es sociais associadas. Um estudo investigou agora se, e em que medida, os sintomas de ins\u00f3nia, depress\u00e3o, fadiga e parestesia em mulheres diagnosticadas com esclerose m\u00faltipla (EM) se alteraram antes e durante a pandemia de COVID-19 [6]. Para o efeito, um total de 90 mulheres com esclerose m\u00faltipla preencheram uma s\u00e9rie de escalas de autoavalia\u00e7\u00e3o em dois momentos. Nove meses antes do surto de COVID-19 em maio de 2019 (linha de base) e durante a pandemia de COVID-19 (fim do estudo; 12 meses ap\u00f3s a linha de base: maio de 2020). Os question\u00e1rios de autoavalia\u00e7\u00e3o inclu\u00edam informa\u00e7\u00f5es s\u00f3cio-demogr\u00e1ficas e relacionadas com a doen\u00e7a, bem como sintomas de ins\u00f3nia, depress\u00e3o, fadiga e parestesia.<\/p>\n\n<p class=\"wp-block-paragraph\">Os sintomas de depress\u00e3o aumentaram com o tempo, ao passo que os sintomas de ins\u00f3nia, fadiga e parestesia n\u00e3o aumentaram. O \u00fanico preditor de ins\u00f3nia durante a pandemia de COVID-19 foi a ins\u00f3nia antes da pandemia de COVID-19; o \u00fanico preditor de depress\u00e3o durante a pandemia de COVID-19 foi a ins\u00f3nia antes da pandemia de COVID-19. Por conseguinte, pode presumir-se que houve uma influ\u00eancia modesta &#8211; se \u00e9 que houve alguma &#8211; nos principais problemas dos participantes, nomeadamente ins\u00f3nia, depress\u00e3o, fadiga e parestesia.<\/p>\n\n<h3 id=\"ir-mais-longe-na-modificacao-da-doenca\" class=\"wp-block-heading\">Ir mais longe na modifica\u00e7\u00e3o da doen\u00e7a<\/h3>\n\n<p class=\"wp-block-paragraph\">As terap\u00eauticas modificadoras da doen\u00e7a revolucionaram o tratamento da esclerose m\u00faltipla recorrente-remitente, impedindo em grande medida o influxo de c\u00e9lulas imunit\u00e1rias perif\u00e9ricas para o sistema nervoso central (SNC). No entanto, a patologia recorrente-remitente da EM \u00e9 causada por processos cr\u00f3nicos e compartimentados no SNC para os quais n\u00e3o existem terapias eficazes. Os agregados men\u00edngeos desempenham um papel essencial nesta patologia, suportando les\u00f5es cr\u00f3nicas activas no par\u00eanquima do SNC. As Tregs s\u00e3o adequadas para abordar este aspeto da fisiopatologia da EM devido \u00e0 sua capacidade de suprimir a inflama\u00e7\u00e3o imunomediada atrav\u00e9s de v\u00e1rios mecanismos e \u00e0 sua estabilidade fenot\u00edpica. Foi levantada a hip\u00f3tese de que as Tregs que t\u00eam como alvo o SNC ir\u00e3o destruir os agregados men\u00edngeos [7]. O objetivo \u00e9 desenvolver uma terapia baseada em c\u00e9lulas T reguladoras (Treg) para o tratamento da esclerose m\u00faltipla progressiva (EM).<\/p>\n\n<p class=\"wp-block-paragraph\">Foi desenvolvido um produto Treg criado por TCR para atacar o antig\u00e9nio do SNC prote\u00edna b\u00e1sica da mielina (MBP) em liga\u00e7\u00e3o com o HLA-DRB1*15:01. Os receptores de c\u00e9lulas T (TCR) em quest\u00e3o foram analisados numa s\u00e9rie de testes para determinar a sua reatividade ao MBP e a sua capacidade de induzir uma atividade supressora nas Tregs humanas. O melhor TCR foi introduzido em Tregs isoladas de leucopatias de dadores saud\u00e1veis e de doentes com esclerose m\u00faltipla. Foi caracterizada a atividade supressora, a estabilidade fenot\u00edpica e a capacidade de produ\u00e7\u00e3o de Tregs cultivadas com TCR a partir de materiais de dadores saud\u00e1veis e de doentes com EM.<br\/>Resultados: O TCR espec\u00edfico para MBP selecionado induziu ativa\u00e7\u00e3o, atividade supressora em rela\u00e7\u00e3o \u00e0s c\u00e9lulas T convencionais e express\u00e3o de citocinas supressoras em Tregs prim\u00e1rias ap\u00f3s exposi\u00e7\u00e3o ao p\u00e9ptido MBP e a c\u00e9lulas apresentadoras de antig\u00e9nios. Foi poss\u00edvel produzir um produto Treg altamente purificado a partir de leucopaks de dadores saud\u00e1veis e de doentes com EM, conforme medido por citometria de fluxo e ensaios de desmetila\u00e7\u00e3o para regi\u00f5es desmetiladas espec\u00edficas de Treg (TSDR). A estabilidade funcional do produto de c\u00e9lulas Treg foi testada durante todo o processo de fabrico, bem como durante a ativa\u00e7\u00e3o e exposi\u00e7\u00e3o a citocinas inflamat\u00f3rias. Assim, foi demonstrado que as Tregs derivadas de TCR exibem uma atividade supressora quando expostas ao p\u00e9ptido MBP\/MHC e podem ser produzidas com elevada pureza tanto em dadores saud\u00e1veis como em doentes com EM. Este produto Treg \u00e9 fenotipicamente est\u00e1vel em condi\u00e7\u00f5es inflamat\u00f3rias.<\/p>\n\n<h3 id=\"idade-em-vista\" class=\"wp-block-heading\">Idade em vista<\/h3>\n\n<p class=\"wp-block-paragraph\">A idade \u00e9 o fator mais determinante da gravidade da doen\u00e7a na esclerose m\u00faltipla, estando tanto a idade cronol\u00f3gica como a biol\u00f3gica associadas \u00e0 taxa de reca\u00eddas e \u00e0 acumula\u00e7\u00e3o de incapacidade. Tanto o envelhecimento normal como o envelhecimento acelerado devido \u00e0 patologia da EM podem contribuir para este facto. O estudo dos extremos de idade na popula\u00e7\u00e3o com EM, incluindo crian\u00e7as, pode ajudar a compreender melhor estes aspectos do envelhecimento na EM. Se as crian\u00e7as com esclerose m\u00faltipla apresentarem sinais de envelhecimento acelerado, isso apoiar\u00e1 fortemente a hip\u00f3tese de que a patologia da esclerose m\u00faltipla conduz ao envelhecimento prematuro.<\/p>\n\n<p class=\"wp-block-paragraph\">Foi feita uma tentativa de medir as diferen\u00e7as no rel\u00f3gio epigen\u00e9tico entre participantes com EM pedi\u00e1trica (POMS) e controlos pedi\u00e1tricos com a mesma idade, para determinar se as pessoas com POMS apresentam um envelhecimento acelerado [8]. Foi realizado um estudo de caso-controlo transversal utilizando amostras de ADN e dados cl\u00ednicos da rede de centros de EM pedi\u00e1trica dos EUA. Todas as amostras foram recolhidas a partir de sangue total e processadas utilizando a tecnologia Infinium Methylation EPIC BeadChip da Illumina para gerar resultados quantitativos de metila\u00e7\u00e3o. Os valores de metila\u00e7\u00e3o foram pr\u00e9-processados com o pacote minfi em R para normaliza\u00e7\u00e3o noob. Estes dados foram depois processados utilizando pacotes R padr\u00e3o para calcular a idade epigen\u00e9tica com base em v\u00e1rios rel\u00f3gios epigen\u00e9ticos publicados para o tempo de vida e a sa\u00fade, incluindo Horvath, Hannum, PhenoAge e GrimAge. A idade epigen\u00e9tica de cada modelo foi regredida na idade cronol\u00f3gica para gerar um res\u00edduo de acelera\u00e7\u00e3o da idade que representa a diverg\u00eancia entre a idade epigen\u00e9tica e a idade cronol\u00f3gica. Os res\u00edduos da acelera\u00e7\u00e3o da idade foram comparados entre casos e controlos utilizando testes estat\u00edsticos padr\u00e3o em R.<\/p>\n\n<p class=\"wp-block-paragraph\">No total, foram analisadas amostras de 164 casos de POMS e 112 indiv\u00edduos de controlo pedi\u00e1trico. A idade cronol\u00f3gica m\u00e9dia foi de 15,2 anos no grupo POMS e de 14,0 anos no grupo de controlo. Os res\u00edduos da acelera\u00e7\u00e3o da idade foram significativamente maiores para os participantes do POMS em compara\u00e7\u00e3o com os controlos para cada um dos rel\u00f3gios utilizados: Diferen\u00e7a de acelera\u00e7\u00e3o Horvath = 0,85, IC 95% 0,13-1,59, p=0,02; Diferen\u00e7a de acelera\u00e7\u00e3o Hannum = 2,36, IC 95% 0,91-3,81, p=0,002; Diferen\u00e7a de acelera\u00e7\u00e3o Phenoage = 3,9, IC 95% 1,85-6,04, p=0,0003; Diferen\u00e7a de acelera\u00e7\u00e3o GrimAge = 1,05, IC 95% 0,34-1,76, p=0,004. Esta diferen\u00e7a na acelera\u00e7\u00e3o da idade manteve-se significativa mesmo depois de se ter em conta o sexo biol\u00f3gico. Uma vez que as crian\u00e7as s\u00e3o cronologicamente jovens e t\u00eam menos comorbilidades, estes dados sugerem que o estado de doen\u00e7a da EM pode conduzir a um envelhecimento biol\u00f3gico acelerado.<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Congresso: Comit\u00e9 das Am\u00e9ricas para o Tratamento e Investiga\u00e7\u00e3o da Esclerose M\u00faltipla (ACTRIMS)  <\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Kazimuddin HF, et al: Paramagnetic Rim Lesions and Their Relationship With Neurodegeneration and Clinical Disability at the Time of Multiple Sclerosis Diagnosis (Les\u00f5es paramagn\u00e9ticas da borda e sua rela\u00e7\u00e3o com a neurodegenera\u00e7\u00e3o e a incapacidade cl\u00ednica no momento do diagn\u00f3stico de esclerose m\u00faltipla). Poster P038. F\u00f3rum ACTRIMS 2024, West Palm Beach, 29 de fevereiro-2 de mar\u00e7o de 2024.<\/li>\n\n\n\n<li>Hassan SS, et al: EDSS e volume das les\u00f5es da subst\u00e2ncia branca infratentorial e fadiga na EM. Poster P069. F\u00f3rum ACTRIMS 2024, West Palm Beach, 29 de fevereiro-2 de mar\u00e7o de 2024.<\/li>\n\n\n\n<li>Hasan H, et al: An\u00e1lise de sequencia\u00e7\u00e3o de nova gera\u00e7\u00e3o numa s\u00e9rie de indiv\u00edduos com doen\u00e7a multifocal da subst\u00e2ncia branca, inicialmente suspeitos de terem SPP. P\u00f4ster P129. F\u00f3rum ACTRIMS 2024, West Palm Beach, 29 de fevereiro-2 de mar\u00e7o de 2024.<\/li>\n\n\n\n<li>Aydin S, et al: O Papel da Stra6 Endotelial na Modula\u00e7\u00e3o da Neuroinflama\u00e7\u00e3o. P\u00f4ster P426. F\u00f3rum ACTRIMS 2024, West Palm Beach, 29 de fevereiro-2 de mar\u00e7o de 2024.<\/li>\n\n\n\n<li>Pfeuffer S, et al: Association of Clinical Relapse on Disease Outcomes in People With Multiple Sclerosis Older Than 50 years. Poster P458. F\u00f3rum ACTRIMS 2024, West Palm Beach, 29 de fevereiro-2 de mar\u00e7o de 2024.<\/li>\n\n\n\n<li>Sadeghi Bahmani, et al: Sintomas de ins\u00f3nia e depress\u00e3o entre indiv\u00edduos com esclerose m\u00faltipla antes e durante a COVID-19 Poster P503. F\u00f3rum ACTRIMS 2024, West Palm Beach, 29 de fevereiro-<br\/>2 de mar\u00e7o de 2024.<\/li>\n\n\n\n<li>Moodley D, et al: Desenvolvimento pr\u00e9-cl\u00ednico de uma terapia com c\u00e9lulas T reguladoras criadas com receptores de c\u00e9lulas T para a patologia progressiva na EM Poster P136. F\u00f3rum ACTRIMS 2024, West Palm Beach, 29 de fevereiro-2 de mar\u00e7o de 2024.<\/li>\n\n\n\n<li>Goyne C, et al: Envelhecimento Epigen\u00e9tico Acelerado na Esclerose M\u00faltipla de In\u00edcio Pedi\u00e1trico Poster P211. F\u00f3rum ACTRIMS 2024, West Palm Beach, 29 de fevereiro-2 de mar\u00e7o de 2024.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>InFo NEUROLOGY &amp; PSYCHIATRY 2024; 22(2): 28-30 (publicado em 12.4.24, antes da impress\u00e3o)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos os anos, o Forum of the Americas Committee for Treatment and Research in Multiple Sclerosis centra-se no ambiente din\u00e2mico da doen\u00e7a numa s\u00e9rie \u00fanica de apresenta\u00e7\u00f5es cient\u00edficas e cl\u00ednicas.&hellip;<\/p>\n","protected":false},"author":7,"featured_media":250315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Esclerose m\u00faltipla","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11521,11374,11529,11551],"tags":[57732,12325],"powerkit_post_featured":[],"class_list":["post-377537","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudos","category-neurologia-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-desordem-metabolica","tag-esclerose-multipla","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 20:03:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":377545,"slug":"limites-obstaculos-y-soluciones-en-la-gestion-de-la-enfermedad","post_title":"L\u00edmites, obst\u00e1culos y soluciones en la gesti\u00f3n de la enfermedad","href":"https:\/\/medizinonline.com\/es\/limites-obstaculos-y-soluciones-en-la-gestion-de-la-enfermedad\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/377537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=377537"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/377537\/revisions"}],"predecessor-version":[{"id":377543,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/377537\/revisions\/377543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/250315"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=377537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=377537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=377537"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=377537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}