{"id":379502,"date":"2024-07-03T00:01:00","date_gmt":"2024-07-02T22:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=379502"},"modified":"2024-07-05T13:38:30","modified_gmt":"2024-07-05T11:38:30","slug":"reduzir-o-risco-de-trombose-aumentar-as-hipoteses-de-sobrevivencia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/reduzir-o-risco-de-trombose-aumentar-as-hipoteses-de-sobrevivencia\/","title":{"rendered":"Reduzir o risco de trombose, aumentar as hip\u00f3teses de sobreviv\u00eancia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Se a forma\u00e7\u00e3o de novas c\u00e9lulas sangu\u00edneas na medula \u00f3ssea for perturbada, a causa pode ser uma forma rara de cancro cr\u00f3nico do sangue. A hiperprolifera\u00e7\u00e3o das tr\u00eas s\u00e9ries celulares na medula \u00f3ssea causa eritrocitose, trombocitose e leucocitose na policitemia vera. O resultado \u00e9, entre outras coisas, um aumento significativo dos n\u00edveis de hemat\u00f3crito e, portanto, tamb\u00e9m do risco de eventos tromboemb\u00f3licos.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">A policitemia vera (PV) \u00e9 uma neoplasia mieloproliferativa cr\u00f3nica muito rara e caracteriza-se por um aumento da hematopoiese. A maioria dos doentes com PV tem uma muta\u00e7\u00e3o no gene <em>JAK2<\/em> tirosina quinase [1]. Resulta num aumento da prolifera\u00e7\u00e3o celular, bem como no aumento da produ\u00e7\u00e3o de citocinas pr\u00f3-inflamat\u00f3rias. A sobreprodu\u00e7\u00e3o de eritr\u00f3citos e o consequente aumento do hemat\u00f3crito aumentam a viscosidade do sangue. Desta forma, a ocorr\u00eancia de tromboembolismo \u00e9 favorecida: 45% de todas as mortes em PV s\u00e3o devidas a complica\u00e7\u00f5es tromboemb\u00f3licas [2]. No entanto, o progn\u00f3stico \u00e9 geralmente favor\u00e1vel. A idade m\u00e9dia do diagn\u00f3stico \u00e9 de 65 anos.  <\/p>\n\n<p class=\"wp-block-paragraph\">Embora os sintomas sejam variados, s\u00e3o geralmente pouco espec\u00edficos. Por conseguinte, o diagn\u00f3stico \u00e9 muitas vezes feito apenas por acaso. Os sintomas poss\u00edveis incluem dores de cabe\u00e7a, dist\u00farbios visuais, fadiga e prurido, bem como dores \u00f3sseas e dores na parte superior do abd\u00f3men. Estas s\u00e3o frequentemente causadas pela esplenomegalia t\u00edpica da PV [1,2]. O aumento da massa de c\u00e9lulas sangu\u00edneas pode causar dist\u00farbios circulat\u00f3rios que podem levar a tromboses venosas e arteriais graves, como embolia pulmonar, apoplexia ou enfarte do mioc\u00e1rdio. O diagn\u00f3stico precoce e o tratamento eficaz s\u00e3o, por conseguinte, indicados <strong>(Panorama 1)<\/strong> [3].  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"713\" height=\"693\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38.png\" alt=\"\" class=\"wp-image-379454\" style=\"width:400px\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38.png 713w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38-120x117.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38-90x87.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38-320x311.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38-560x544.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38-240x233.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38-180x175.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht1_OH2_s38-640x622.png 640w\" sizes=\"(max-width: 713px) 100vw, 713px\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Na fase cr\u00f3nica, que geralmente dura anos, as caracter\u00edsticas cl\u00ednicas de mieloprolifera\u00e7\u00e3o aumentada assumem um papel central. As complica\u00e7\u00f5es mais frequentes e potencialmente amea\u00e7adoras s\u00e3o o tromboembolismo arterial ou venoso em at\u00e9 40% dos doentes. Na fase tardia da doen\u00e7a, o principal problema reside na chamada fase &#8220;retardada&#8221;. Caracteriza-se por uma diminui\u00e7\u00e3o da eritrocitose e um aumento da esplenomegalia, combinados com fibrose da medula \u00f3ssea, que pode ser seguida de transforma\u00e7\u00e3o em mielofibrose (secund\u00e1ria) p\u00f3s-PV e\/ou leucemia aguda [1]. A taxa global de FPM p\u00f3s-PV \u00e9 de cerca de 15% ap\u00f3s um per\u00edodo m\u00e9dio de observa\u00e7\u00e3o de 10 anos e de 50% ap\u00f3s 20 anos.<\/p>\n\n<h3 id=\"tratamento-adaptado-ao-risco\" class=\"wp-block-heading\">Tratamento adaptado ao risco <\/h3>\n\n<p class=\"wp-block-paragraph\">Uma vez que a preven\u00e7\u00e3o do tromboembolismo \u00e9 primordial, a flebotomia \u00e9 muitas vezes considerada o tratamento de escolha. Isto pode baixar o hemat\u00f3crito (Hct) para menos de 45% e reduzir a hiperviscosidade do sangue. Estudos demonstraram que a fixa\u00e7\u00e3o de Hct abaixo de 45% pode reduzir a taxa de morte cardiovascular em PV para um quarto [4]. No entanto, uma flebotomia \u00e9 muito extenuante. Por conseguinte, tamb\u00e9m deve ser iniciado um tratamento inicial com \u00e1cido acetilsalic\u00edlico (AAS) em dose baixa. A recomenda\u00e7\u00e3o de tratamento \u00e9 ent\u00e3o baseada na pontua\u00e7\u00e3o de risco. Pode assumir-se um risco baixo para os doentes mais jovens, com menos de 60 anos de idade, que n\u00e3o tenham tido anteriormente uma trombose. Atualmente, est\u00e1 a ser discutido se o tratamento de redu\u00e7\u00e3o de citocinas tamb\u00e9m deve ser considerado para eles em determinadas condi\u00e7\u00f5es.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38.png\"><img decoding=\"async\" width=\"1459\" height=\"521\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38.png\" alt=\"\" class=\"wp-image-379455 lazyload\" style=\"--smush-placeholder-width: 1459px; --smush-placeholder-aspect-ratio: 1459\/521;width:500px\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38.png 1459w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-800x286.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-1160x414.png 1160w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-120x43.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-90x32.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-320x114.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-560x200.png 560w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-240x86.png 240w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-180x64.png 180w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-640x229.png 640w, https:\/\/medizinonline.com\/wp-content\/uploads\/2024\/05\/Ubersicht2_OH2_s38-1120x400.png 1120w\" data-sizes=\"(max-width: 1459px) 100vw, 1459px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/a><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">No entanto, a maioria dos doentes com PV apresenta um risco elevado. Nestes casos, \u00e9 indicado o in\u00edcio da terapia citoreducativa. Recomenda-se Hydroxyurea (HU) ou interferon alfa (INF) para tratamento prim\u00e1rio [5]. No entanto, a HU, em particular, n\u00e3o \u00e9 adequada para todos os doentes e pode causar efeitos secund\u00e1rios graves <strong>(Panor\u00e2mica 2) <\/strong>[6]. Para pacientes mais jovens que desejam ter filhos, a INF \u00e9, portanto, mais suscept\u00edvel de ser utilizada. Se a terapia de primeira linha n\u00e3o for tolerada ou se os sintomas cl\u00ednicos n\u00e3o regredirem o suficiente, o tratamento deve ser alterado. O inibidor JAK2 ruxolitinibe foi demonstrado em ensaios para controlar o aumento da mieloprolifera\u00e7\u00e3o, sendo ao mesmo tempo bem tolerado [1]. Muitos sintomas associados ao PV, tais como fadiga e prurido, tamb\u00e9m desapareceram. Al\u00e9m disso, a maioria dos pacientes experimentou o efeito muito rapidamente, dentro das primeiras quatro semanas. O Busulfan pode ser utilizado como terapia alternativa em pacientes de idade avan\u00e7ada. Aqui, no entanto, o potencial leucemog\u00e9nico est\u00e1 sempre em discuss\u00e3o, raz\u00e3o pela qual a subst\u00e2ncia s\u00f3 deve ser utilizada com conten\u00e7\u00e3o. O anagrelide pode ser considerado como um parceiro combinado para, por exemplo, a HU ou INF. Isto destina-se exclusivamente a reduzir a produ\u00e7\u00e3o de plaquetas e pode funcionar como um suplemento se n\u00e3o forem alcan\u00e7ados resultados satisfat\u00f3rios apenas com as outras subst\u00e2ncias. <\/p>\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.onkopedia.com\/de\/onkopedia\/guidelines\/polycythaemia-vera-pv\/@@guideline\/html\/index.html\" target=\"_blank\" rel=\"noopener\">www.onkopedia.com\/de\/onkopedia\/guidelines\/polycythaemia-vera-pv\/@@guideline\/html\/index.html<\/a> (\u00faltima chamada em 23\/04\/2024).<\/li>\n\n\n\n<li>Vannucchi AM, et al.: N Engl J Med 2015; 372: 426\u2013435.<\/li>\n\n\n\n<li>Stein BL, Moliterno AR, Tiu RV: Polycythemia vera disease burden: contributing factors, impact on quality of life, andemerging treatment options. Ann Hematol 2014; 93: 1965\u20131976.<\/li>\n\n\n\n<li>Marchioli R, Finazzi G, Specchia G, et al.: Cardiovascular events and intensity of treatment in polycythemia vera. N Engl J Med 2013; 368: 22\u201333.<\/li>\n\n\n\n<li>Barbui T, Tefferi A, Vannucchi AM, et al.: Philadelphia chromosome-negative classical myeloproliferative neoplasms: revised management recommendations from European Leukemia Net. Leukemia 2018; 32: 1057\u20131069.<\/li>\n\n\n\n<li>Barosi G, Birgegard G, Finazzi G, et al.: A unified definition of clinical resistance and intolerance to hydroxycarbamide in polycythaemia vera and primary myelofibrosis: results of a European LeukemiaNet (ELN) consensus process. Br J Haematol 2010; 148: 961\u2013963.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>InFo ONKOLOGIE &amp; H\u00c4MATOLOGIE 2024; 12(2): 38<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se a forma\u00e7\u00e3o de novas c\u00e9lulas sangu\u00edneas na medula \u00f3ssea for perturbada, a causa pode ser uma forma rara de cancro cr\u00f3nico do sangue. A hiperprolifera\u00e7\u00e3o das tr\u00eas s\u00e9ries celulares&hellip;<\/p>\n","protected":false},"author":7,"featured_media":379505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Policit\u00e9mia vera","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11521,11365,11379,11551],"tags":[24060,27489],"powerkit_post_featured":[],"class_list":["post-379502","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudos","category-hematologia-pt-pt","category-oncologia-pt-pt","category-rx-pt","tag-policitemia-vera-pt-pt","tag-trombose","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:29:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":379514,"slug":"reducir-el-riesgo-de-trombosis-aumentar-las-posibilidades-de-supervivencia","post_title":"Reducir el riesgo de trombosis, aumentar las posibilidades de supervivencia","href":"https:\/\/medizinonline.com\/es\/reducir-el-riesgo-de-trombosis-aumentar-las-posibilidades-de-supervivencia\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/379502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=379502"}],"version-history":[{"count":2,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/379502\/revisions"}],"predecessor-version":[{"id":382693,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/379502\/revisions\/382693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/379505"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=379502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=379502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=379502"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=379502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}