{"id":380517,"date":"2024-06-30T14:00:00","date_gmt":"2024-06-30T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/noticias-sobre-o-tratamento-da-esclerose-multipla-doenca-de-alzheimer-doenca-de-parkinson-ela-e-mg\/"},"modified":"2024-06-30T14:00:16","modified_gmt":"2024-06-30T12:00:16","slug":"noticias-sobre-o-tratamento-da-esclerose-multipla-doenca-de-alzheimer-doenca-de-parkinson-ela-e-mg","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/pt-pt\/noticias-sobre-o-tratamento-da-esclerose-multipla-doenca-de-alzheimer-doenca-de-parkinson-ela-e-mg\/","title":{"rendered":"Not\u00edcias sobre o tratamento da esclerose m\u00faltipla, doen\u00e7a de Alzheimer, doen\u00e7a de Parkinson, ELA e MG"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A Reuni\u00e3o Anual da AAN \u00e9 um dos maiores encontros de neurologistas do mundo. O interc\u00e2mbio centra-se nas \u00faltimas descobertas da ci\u00eancia e da investiga\u00e7\u00e3o, bem como em actualiza\u00e7\u00f5es cl\u00ednicas. O objetivo da confer\u00eancia da AAN \u00e9 promover cuidados neurol\u00f3gicos de elevada qualidade, centrados no doente, e melhorar a satisfa\u00e7\u00e3o profissional dos seus membros.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">At\u00e9 80% de todos os doentes com esclerose m\u00faltipla (EM) sofrem de dor e sintomas sensoriais, sendo a preval\u00eancia da dor neurop\u00e1tica de cerca de 26%. No passado, a dor na EM era geralmente atribu\u00edda a les\u00f5es centrais. Recentemente, foram efectuados v\u00e1rios estudos que investigaram neuropatias perif\u00e9ricas desmielinizantes de grandes fibras em doentes com EM. No entanto, h\u00e1 pouca investiga\u00e7\u00e3o sobre se as fibras pequenas, n\u00e3o mielinizadas, com dor neurop\u00e1tica e sintomas auton\u00f3micos, tamb\u00e9m s\u00e3o afectadas. Por conseguinte, um estudo caracterizou a neuropatia de fibras pequenas (NFC) em pessoas com esclerose m\u00faltipla (pwMS) que sofrem de dor neurop\u00e1tica e\/ou disautonomia [1]. Foram colhidas amostras de um local proximal e distal do membro inferior num total de 28 doentes e enviadas para avalia\u00e7\u00e3o da densidade das fibras nervosas intra-epid\u00e9rmicas e das gl\u00e2ndulas sudor\u00edparas. Os sintomas e a gravidade foram caracterizados atrav\u00e9s do registo das respostas ao MGH Small-Fibre Symptom Survey. Das 28 pessoas com SCP testadas, 18 tinham uma densidade de fibras nervosas intra-epid\u00e9rmicas ou das gl\u00e2ndulas sudor\u00edparas significativamente reduzida em pelo menos um dos locais biopsiados. Dois doentes apresentavam valores normais baixos em pelo menos um dos locais de amostragem, oito doentes apresentavam densidades de fibras nervosas normais. Dos doentes com resultados positivos, 90% eram do sexo feminino com uma dura\u00e7\u00e3o m\u00e9dia da doen\u00e7a de cinco anos. Os resultados do MGH SSS mostraram pontua\u00e7\u00f5es totais de gravidade dos sintomas que variaram entre 17 e 85. Esta pequena s\u00e9rie de casos aponta para a neuropatia de pequenas fibras como uma poss\u00edvel causa de dor neurop\u00e1tica e disautonomia em pessoas com defici\u00eancia.<\/p>\n\n<h3 id=\"fadiga-em-doentes-pediatricos-com-esclerose-multipla\" class=\"wp-block-heading\">Fadiga em doentes pedi\u00e1tricos com esclerose m\u00faltipla<\/h3>\n\n<p class=\"wp-block-paragraph\">Embora a fadiga seja frequentemente observada na doen\u00e7a de Parkinson pedi\u00e1trica, pouco se sabe sobre as causas patol\u00f3gicas nestes doentes. Por conseguinte, foi efectuada uma investiga\u00e7\u00e3o das anomalias da rede monoamin\u00e9rgica em doentes com esclerose m\u00faltipla pedi\u00e1trica (EMSP) em rela\u00e7\u00e3o ao seu estado de fadiga atrav\u00e9s de uma an\u00e1lise de componentes independentes (ICA) baseada na tomografia por emiss\u00e3o de positr\u00f5es (PET) sobre a resson\u00e2ncia magn\u00e9tica funcional (RMf) em estado de repouso (RS) [2]. Cinquenta e cinco doentes pedi\u00e1tricos de esclerose m\u00faltipla destros e 23 controlos pedi\u00e1tricos saud\u00e1veis (HC) foram submetidos a uma avalia\u00e7\u00e3o neurol\u00f3gica, da fadiga, da depress\u00e3o e da RMN-FS. Os doentes foram classificados como fatigados (F) ou n\u00e3o fatigados (nF) com base na sua pontua\u00e7\u00e3o na <em>Escala de Gravidade da Fadiga (FSS <\/em>). Os padr\u00f5es de conetividade funcional (CF) da RS relacionados com a dopamina, a noradrenalina e a serotonina foram derivados utilizando a ICA, que se restringiu aos atlas PET para os transportadores de dopamina, noradrenalina e serotonina obtidos nos c\u00e9rebros dos HC.  <\/p>\n\n<p class=\"wp-block-paragraph\">Nenhum dos pacientes com pedMS tinha depress\u00e3o e quinze deles eram F. Comparados com os pacientes com pedMS nF e com os HC, os pacientes com pedMS F mostraram uma redu\u00e7\u00e3o da FC RS relacionada com a dopamina no giro p\u00f3s-central direito. Al\u00e9m disso, foi observada uma redu\u00e7\u00e3o da FC do RS relacionada com a dopamina na \u00ednsula esquerda nos doentes com F-pedMS em compara\u00e7\u00e3o com os HC e um aumento da FC do RS relacionada com a dopamina no giro temporal m\u00e9dio esquerdo e no lobo cerebelar VI em compara\u00e7\u00e3o com os doentes com nF-pedMS. Na rede ligada \u00e0 noradrenalina, os doentes com F-pedMS mostraram uma redu\u00e7\u00e3o da RS FC no l\u00f3bulo parietal superior esquerdo e um aumento da RS FC no t\u00e1lamo direito em compara\u00e7\u00e3o com os HC e nF-pedMS, e uma redu\u00e7\u00e3o da RS FC no c\u00f3rtex calcarino direito e um aumento da RS FC no giro frontal m\u00e9dio direito em compara\u00e7\u00e3o com os HC. Finalmente, na rede relacionada com a serotonina, os doentes com F-pedMS apresentaram uma FC RS reduzida no giro angular direito e uma FC RS aumentada no giro p\u00f3s-central direito, em compara\u00e7\u00e3o com os doentes com nF-pedMS e os HC. Em suma, os doentes pedi\u00e1tricos com fadiga apresentaram anomalias espec\u00edficas nas redes monoamin\u00e9rgicas, fornecendo marcadores patol\u00f3gicos para este sintoma problem\u00e1tico e potenciais alvos para o seu tratamento.<\/p>\n\n<h3 id=\"reduzir-a-inflamacao-na-esclerose-multipla-e-na-doenca-de-alzheimer\" class=\"wp-block-heading\">Reduzir a inflama\u00e7\u00e3o na esclerose m\u00faltipla e na doen\u00e7a de Alzheimer<\/h3>\n\n<p class=\"wp-block-paragraph\">A esclerose m\u00faltipla e a doen\u00e7a de Alzheimer (DA) est\u00e3o no centro do interesse da investiga\u00e7\u00e3o neuropatol\u00f3gica. A esclerose m\u00faltipla \u00e9 a doen\u00e7a neuroinflamat\u00f3ria por excel\u00eancia, mas a inflama\u00e7\u00e3o \u00e9 cada vez mais reconhecida como um fator independente da patologia da doen\u00e7a de Alzheimer, desempenhando a ativa\u00e7\u00e3o microglial um papel fundamental. Seria de esperar que os amil\u00f3ides se depositassem no c\u00e9rebro com esclerose m\u00faltipla, uma vez que as caracter\u00edsticas patol\u00f3gicas das placas amil\u00f3ides e dos emaranhados neurofibrilares que ocorrem na doen\u00e7a de Alzheimer tamb\u00e9m se encontram, em menor grau, no c\u00e9rebro normal e envelhecido. Al\u00e9m disso, \u00e9 prov\u00e1vel a coexist\u00eancia da patologia da EM e da doen\u00e7a de Alzheimer, uma vez que existe uma sobreposi\u00e7\u00e3o anat\u00f3mica nas \u00e1reas corticais afectadas. O ambiente inflamat\u00f3rio cr\u00f3nico do c\u00f3rtex da EM constitui assim um modelo \u00fanico para investigar o papel da inflama\u00e7\u00e3o na fisiologia dos amil\u00f3ides. A carga A\u03b2 em amostras post-mortem do c\u00f3rtex temporal ou frontal na EM foi agora investigada e a sua rela\u00e7\u00e3o com a patologia cortical motora foi avaliada [3].  <\/p>\n\n<p class=\"wp-block-paragraph\">Foi utilizada uma coorte de aut\u00f3psias de casos de EM patologicamente confirmados (n=78) e de casos de controlo (n=67) em que a carga de A\u03b2 foi correlacionada com a densidade de neur\u00f3nios e de microglia\/macr\u00f3fagos. Foram efectuadas an\u00e1lises quantitativas e semi-quantitativas e correlacionadas com as caracter\u00edsticas patol\u00f3gicas. Foi encontrada uma carga reduzida de A\u03b2 na massa cinzenta de aspeto normal dos casos de EM que morreram abaixo da idade m\u00e9dia (64 anos) em compara\u00e7\u00e3o com os controlos correspondentes, com uma redu\u00e7\u00e3o adicional nas les\u00f5es desmielinizadas subpiais espec\u00edficas da EM. Foi encontrado um aumento da express\u00e3o de microglia\/macr\u00f3fagos CD68+ e da sobreviv\u00eancia neuronal relacionado com a redu\u00e7\u00e3o de A\u03b2 nos casos de EM que morreram abaixo da idade m\u00e9dia. Estes resultados sugerem que os factores relacionados com a EM, incluindo a inflama\u00e7\u00e3o microglial\/macrof\u00e1gica, influenciam a deposi\u00e7\u00e3o de A\u03b2 e a neurodegenera\u00e7\u00e3o, revelando assim novas perspectivas terap\u00eauticas relevantes tanto para a EM como para a doen\u00e7a de Alzheimer.<\/p>\n\n<h3 id=\"doenca-de-parkinson-em-doentes-com-doencas-auto-imunes\" class=\"wp-block-heading\">Doen\u00e7a de Parkinson em doentes com doen\u00e7as auto-imunes<\/h3>\n\n<p class=\"wp-block-paragraph\">A incid\u00eancia de Parkinson \u00e9 mais elevada em doentes auto-imunes, o que exige uma investiga\u00e7\u00e3o mais aprofundada sobre a influ\u00eancia da exposi\u00e7\u00e3o a medicamentos anti-inflamat\u00f3rios. Por conseguinte, foi realizada uma investiga\u00e7\u00e3o sobre a rela\u00e7\u00e3o entre a ocorr\u00eancia da doen\u00e7a de Parkinson e a utiliza\u00e7\u00e3o de medicamentos anti-inflamat\u00f3rios, em particular anti-fator de necrose tumoral (anti-TNF) e anti-interleucina (IL)-17, em pessoas diagnosticadas com uma doen\u00e7a autoimune (artrite reumatoide, colite ulcerosa, doen\u00e7a de Crohn, espondilite anquilosante ou psor\u00edase\/artrite psori\u00e1tica) [4]. Num estudo de coorte retrospetivo, foram utilizados dados da base de dados Komodo Health dos EUA para identificar pessoas a quem foram diagnosticadas doen\u00e7as auto-imunes entre 2015 e 2022. Para avaliar o risco comparativo de doen\u00e7a de Parkinson associado ao tratamento anti-TNF\/anti-IL-17, foram distinguidas duas coortes de doentes: os expostos a uma terapia anti-inflamat\u00f3ria espec\u00edfica e os n\u00e3o expostos. Para a an\u00e1lise de associa\u00e7\u00e3o, foram calculadas as taxas de incid\u00eancia da doen\u00e7a de Parkinson por pessoa e derivadas as taxas de incid\u00eancia (IRRs). As taxas de incid\u00eancia por 100 pessoas-ano (PY) foram calculadas utilizando quintis de exposi\u00e7\u00e3o a anti-TNF\/anti-IL-17.  <\/p>\n\n<p class=\"wp-block-paragraph\">Dos 2.105.677 doentes com doen\u00e7as auto-imunes, 114.082 receberam tratamento anti-TNF\/anti-IL-17, enquanto 1.991.595 permaneceram sem tratamento. A incid\u00eancia de DP foi de 0,661 por 100 anos na coorte exposta, em compara\u00e7\u00e3o com 0,949 por 100 anos na coorte n\u00e3o exposta. A TIR ao comparar o grupo exposto com o grupo n\u00e3o exposto foi de 0,696. As taxas de incid\u00eancia de DP para os receptores de medicamentos anti-inflamat\u00f3rios foram: anti-TNF apenas -0,665 e anti-IL-17 apenas -0,519. A TIR entre a terapia anti-IL-17 e anti-TNF mostrou que os pacientes tratados com anti-IL-17 tinham um risco menor de desenvolver a doen\u00e7a de Parkinson. A an\u00e1lise das taxas de incid\u00eancia por pessoa revelou uma potencial rela\u00e7\u00e3o entre o tratamento e a resposta, com uma taxa de incid\u00eancia de 5,295 no quintil de exposi\u00e7\u00e3o mais baixo e de 0,158 por 100 anos no quintil de exposi\u00e7\u00e3o mais elevado. Os resultados sugerem que o tratamento anti-TNF\/anti-IL-17 reduz a incid\u00eancia da doen\u00e7a de Parkinson em doentes com doen\u00e7a autoimune, sugerindo que a redu\u00e7\u00e3o da inflama\u00e7\u00e3o sist\u00e9mica pode potencialmente reduzir o risco de desenvolver a doen\u00e7a de Parkinson.<\/p>\n\n<h3 id=\"preditores-da-progressao-da-ela\" class=\"wp-block-heading\">Preditores da progress\u00e3o da ELA<\/h3>\n\n<p class=\"wp-block-paragraph\">A ELA \u00e9 uma doen\u00e7a neurodegenerativa fatal do sistema motor que leva \u00e0 morte por insufici\u00eancia respirat\u00f3ria neuromuscular progressiva na maioria dos doentes. O valor da capacidade vital for\u00e7ada (CVF) na apresenta\u00e7\u00e3o cl\u00ednica e a sua taxa de decl\u00ednio na previs\u00e3o da sobreviv\u00eancia na ELA foi agora analisado com mais pormenor [5]. O estudo retrospetivo incluiu 153 pacientes que foram atendidos na cl\u00ednica ALS entre 2016 e 2019 e para os quais estavam dispon\u00edveis conjuntos de dados completos. A CVF inicial e a sua varia\u00e7\u00e3o aos 3 meses foram utilizadas para a an\u00e1lise de sobreviv\u00eancia utilizando o m\u00e9todo de Kaplan-Meier e o modelo de regress\u00e3o de Cox. Foram definidos dois grupos principais de doentes com base na sua CVF inicial (&#8220;CVF elevada&#8221; se &gt; mediana, &#8220;CVF baixa&#8221; se &lt; mediana) e subgrupos com base na sua taxa de CVF: (I) &#8220;FVC inicial elevada\/decl\u00ednio r\u00e1pido&#8221;, (II) &#8220;CVF inicialmente elevada\/decl\u00ednio lento&#8221;, (III) &#8220;CVF inicial baixa\/decl\u00ednio r\u00e1pido&#8221; e (IV) &#8220;CVF inicial baixa\/decl\u00ednio lento&#8221;. Estes subgrupos foram comparados em termos de caracter\u00edsticas demogr\u00e1ficas, relacionadas com a doen\u00e7a e de sobreviv\u00eancia.<\/p>\n\n<p class=\"wp-block-paragraph\">Uma CVF inicial acima da mediana (&gt;85%) foi associada a um tempo de sobreviv\u00eancia de 39 meses, enquanto uma CVF abaixo da mediana foi associada a um tempo de sobreviv\u00eancia de 16 meses. A taxa de decl\u00ednio da CVF tamb\u00e9m foi significativamente associada \u00e0 sobreviv\u00eancia: Os doentes com uma inclina\u00e7\u00e3o da FVC de 3 meses \u2265 o valor mediano tiveram uma sobreviv\u00eancia mediana de 41 meses, enquanto os doentes com uma inclina\u00e7\u00e3o da FVC de 3 meses inferior ao valor mediano tiveram uma sobreviv\u00eancia de 16 meses. Uma an\u00e1lise de subgrupo mostrou que os doentes com &#8220;CVF inicial baixa\/decl\u00ednio r\u00e1pido&#8221; tinham um tempo de sobreviv\u00eancia mediano de 13 meses, enquanto era de 26 meses para os doentes com &#8220;CVF inicial baixa\/decl\u00ednio lento&#8221; e de 47 meses para os doentes com &#8220;CVF inicial alta\/decl\u00ednio lento&#8221;. Os resultados do estudo sugerem que a CVF inicial e a sua diminui\u00e7\u00e3o ap\u00f3s tr\u00eas meses s\u00e3o um preditor fi\u00e1vel de sobreviv\u00eancia.<\/p>\n\n<h3 id=\"assinatura-imunologica-da-miastenia-gravis-de-inicio-tardio\" class=\"wp-block-heading\">Assinatura imunol\u00f3gica da miastenia gravis de in\u00edcio tardio<\/h3>\n\n<p class=\"wp-block-paragraph\">A miastenia gravis (MG) \u00e9 uma doen\u00e7a autoimune heterog\u00e9nea com auto-anticorpos contra antig\u00e9nios p\u00f3s-sin\u00e1pticos na jun\u00e7\u00e3o neuromuscular. Cerca de 80% dos doentes com MG t\u00eam auto-anticorpos contra o AChR, e as suas caracter\u00edsticas cl\u00ednicas e a resposta ao tratamento podem variar em fun\u00e7\u00e3o das caracter\u00edsticas cl\u00ednicas.  <\/p>\n\n<p class=\"wp-block-paragraph\">Uma investiga\u00e7\u00e3o deve determinar se existe uma assinatura clara com base na presen\u00e7a de sintomas [6]. Para tal, as diferen\u00e7as na imunopatog\u00e9nese de doentes positivos para o recetor da acetilcolina (AChR) e para os auto-anticorpos com miastenia gravis de in\u00edcio precoce (in\u00edcio dos sintomas &lt;50 anos) e de in\u00edcio tardio (EOMG e LOMG) foram investigadas numa an\u00e1lise prote\u00f3mica explorat\u00f3ria aprofundada, utilizando o estudo bem caracterizado BeatMG.  <\/p>\n\n<p class=\"wp-block-paragraph\">Dos 52 doentes do estudo BeatMG com todos os pontos de dados necess\u00e1rios, foram inclu\u00eddas as amostras de base de 47 doentes. Vinte pacientes foram classificados como EOMG e 27 foram classificados como LOMG. O grupo da EOMG tinha uma percentagem mais elevada de doentes submetidos a timoidectomia (55% vs. 0%).  <\/p>\n\n<p class=\"wp-block-paragraph\">A an\u00e1lise de componentes principais mostrou uma separa\u00e7\u00e3o entre os grupos EOMG e LOMG e v\u00e1rias prote\u00ednas foram altamente expressas no grupo LOMG, incluindo CXCL17, JCHAIN, CD83 e TNFRSF11A. Estas prote\u00ednas est\u00e3o envolvidas na regula\u00e7\u00e3o da diferencia\u00e7\u00e3o dos leuc\u00f3citos, na produ\u00e7\u00e3o de interleucina-10 e nas vias de diferencia\u00e7\u00e3o e migra\u00e7\u00e3o dos leuc\u00f3citos miel\u00f3ides. O SNP TNFRSF11A foi previamente associado \u00e0 LOMG. Isto pode indicar que a LOMG pode ser mediada por um mecanismo imunopatog\u00e9nico diferente.<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Congresso: Reuni\u00e3o Anual da Academia Americana de Neurologia (AAN)<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Reyes K, et al: Characteristics of Small Fibre Neuropathy in a Cohort of Multiple Sclerosis Patients with Neuropathic Pain and\/or Autonomic Dysfunction (Caracter\u00edsticas da Neuropatia de Pequenas Fibras numa Coorte de Doentes com Esclerose M\u00faltipla com Dor Neurop\u00e1tica e\/ou Disfun\u00e7\u00e3o Auton\u00f3mica). Resumo S7.010. Reuni\u00e3o anual da Academia Americana de Neurologia (AAN). 13-18 de abril de 2024, Denver (EUA).<\/li>\n\n\n\n<li>Margoni M, et al: Monoaminergic Network Abnormalities Explain Fatigue in Pediatric Multiple Sclerosis (Anomalias da Rede Monoamin\u00e9rgica Explicam a Fadiga na Esclerose M\u00faltipla Pedi\u00e1trica). Resumo S8.008. Reuni\u00e3o Anual da Academia Americana de Neurologia (AAN). 13-18 de abril de 2024, Denver (EUA).<\/li>\n\n\n\n<li>Pansieri J, et al: Reduced A\u03b2 Amyloid Deposits Relate to Inflammation and Neuronal Survival in Multiple Sclerosis Cortex. Resumo S17.003. Reuni\u00e3o anual da Academia Americana de Neurologia (AAN). 13-18 de abril de 2024, Denver (EUA).<\/li>\n\n\n\n<li>Haas J, et al: Associa\u00e7\u00e3o do Uso de Terapia Anti-inflamat\u00f3ria com a Incid\u00eancia da Doen\u00e7a de Parkinson: Uma An\u00e1lise Pessoa-Tempo entre Pacientes com Doen\u00e7as Autoimunes. Resumo S2.003. Reuni\u00e3o Anual da Academia Americana de Neurologia (AAN). 13-18 de abril de 2024, Denver (EUA).<\/li>\n\n\n\n<li>Seyam M, et al: Valor da CVF e da sua taxa de decl\u00ednio para prever a sobreviv\u00eancia na ELA. Resumo S5.005. Reuni\u00e3o Anual da Academia Americana de Neurologia (AAN). 13-18 de abril de 2024, Denver (EUA).<\/li>\n\n\n\n<li>Roy B, et al: Proteomic Analysis Reveals a Distinct Immunological Signature for Late-onset Myasthenia Gravis (An\u00e1lise Prote\u00f3mica Revela uma Assinatura Imunol\u00f3gica Distinta para Miastenia Gravis de In\u00edcio Tardio). Resumo S15.003. Reuni\u00e3o Anual da Academia Americana de Neurologia (AAN). 13-18 de abril de 2024, Denver (EUA).<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>InFo NEUROLOGY &amp; PSYCHIATRY 2024; 22(3): 20-21<\/em> <em>(publicado em 30.5.24, antes da impress\u00e3o)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Reuni\u00e3o Anual da AAN \u00e9 um dos maiores encontros de neurologistas do mundo. O interc\u00e2mbio centra-se nas \u00faltimas descobertas da ci\u00eancia e da investiga\u00e7\u00e3o, bem como em actualiza\u00e7\u00f5es cl\u00ednicas.&hellip;<\/p>\n","protected":false},"author":7,"featured_media":263521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Neurologia","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11521,11374,11529,11551],"tags":[24541,13962,12325,11755],"powerkit_post_featured":[],"class_list":["post-380517","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudos","category-neurologia-pt-pt","category-relatorios-do-congresso","category-rx-pt","tag-als-pt-pt","tag-alzheimer-pt-pt","tag-esclerose-multipla","tag-parkinson-pt-pt","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 23:18:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"pt_PT","wpml_translations":{"es_ES":{"locale":"es_ES","id":380524,"slug":"noticias-sobre-el-tratamiento-de-la-em-el-alzheimer-el-parkinson-la-ela-y-la-mg","post_title":"Noticias sobre el tratamiento de la EM, el Alzheimer, el Parkinson, la ELA y la MG","href":"https:\/\/medizinonline.com\/es\/noticias-sobre-el-tratamiento-de-la-em-el-alzheimer-el-parkinson-la-ela-y-la-mg\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/380517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=380517"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/380517\/revisions"}],"predecessor-version":[{"id":380521,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/posts\/380517\/revisions\/380521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media\/263521"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=380517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/category?post=380517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=380517"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/pt-pt\/wp-json\/wp\/v2\/powerkit_post_featured?post=380517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}